{"id":17332,"date":"2025-08-01T22:04:42","date_gmt":"2025-08-01T22:04:42","guid":{"rendered":"https:\/\/www.machupicchuterra.com\/es\/?page_id=17332"},"modified":"2026-07-14T20:29:42","modified_gmt":"2026-07-14T20:29:42","slug":"promociones-machupicchu-terra","status":"publish","type":"page","link":"https:\/\/www.machupicchuterra.com\/es\/promociones-machupicchu-terra\/","title":{"rendered":"Promociones Machupicchu Terra"},"content":{"rendered":"<div class=\"banner\" data-video-src=\"https:\/\/media.machupicchuterra.com\/uploads\/videos\/1698356610_machupicchu-banner.mp4\" data-has-video=\"true\">\r\n            <div class=\"relative w-full banner-video overflow-hidden bg-black\">\r\n                <video class=\"absolute video-autoplay hidden\" poster=\"https:\/\/media.machupicchuterra.com\/uploads\/images\/1698356585_machupicchu-banner-foto.jpg\" muted loop style=\"display: none;\">\r\n                    <source src=\"https:\/\/media.machupicchuterra.com\/uploads\/videos\/1698356610_machupicchu-banner.mp4\" type=\"video\/mp4\">\r\n                <\/video>\r\n                <img decoding=\"async\" class=\"w-full h-full object-cover banner-poster\" src=\"https:\/\/media.machupicchuterra.com\/uploads\/images\/1698356585_machupicchu-banner-foto.jpg\" alt=\"Promociones Paquetes tur\u00edsticos\">\r\n                <div class=\"absolute top-0 left-0 w-full h-full flex flex-col justify-center items-center banner-content\">\r\n                    \r\n                    <h1 class=\"text-white text-video p-3\"><span class=\"text-year\">Promociones Paquetes tur\u00edsticos<\/span><\/h1>\r\n                    <p class=\"text-white section-title-36 text-center m-b-20\"><\/p>\r\n                    \r\n                    \r\n                    <div class=\"event-countdown-intiraymi text-white\">\r\n                <div class=\"js-countdown mt-inti-raymi\" data-day=\"D\u00edas\" data-hour=\"Horas\" data-minute=\"Minutos\" data-seconds=\"Segundos\" data-date=\"july 15, 2026 23:59:00\">\r\n                <div class=\"countdown-timer\">\r\n              <div class=\"countdown-section ds-element-days\">\r\n                <span class=\"ds-element-value ds-days\">11<\/span>\r\n                <span class=\"ds-element-title\">D\u00edas<\/span>\r\n              <\/div>\r\n              <div class=\"countdown-section ds-element-hours\">\r\n                <span class=\"ds-element-value ds-hours\">21<\/span>\r\n                <span class=\"ds-element-title\">Horas<\/span>\r\n              <\/div>\r\n              <div class=\"countdown-section ds-element-minutes\">\r\n                <span class=\"ds-element-value ds-minutes\">31<\/span>\r\n                <span class=\"ds-element-title\">Minutos<\/span>\r\n              <\/div>\r\n              <div class=\"countdown-section ds-element-seconds\">\r\n                <span class=\"ds-element-value ds-seconds\">13<\/span>\r\n                <span class=\"ds-element-title\">Segundos<\/span>\r\n              <\/div>\r\n            <\/div>\r\n                <\/div>\r\n            <\/div>\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n<div class=\"flex flex-wrap justify-center container mt-3\">\n\n    <!-- Tours Machupicchu -->\n    <div class=\"flex-none mr-2 w-28\">\n        <div class=\"mod-navigation__item-inner\">\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-machu-picchu\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n                <svg width=\"70px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 75.36 41.38\">\n                    <path fill=\"#077100\" d=\"M292.38 421.23a7.49 7.49 0 0 0 1.51.54c.76.17 2 .31 3.05.47s2.59.43 3.29.58a3.11 3.11 0 0 1 .89.32c.08.05.05.26 0 .27-.38.07-1.5.1-2.26.12s-2.26-.06-2.83 0a1 1 0 0 0-.6.38c0 .11.24.24.4.27a7.73 7.73 0 0 0 1.47.11c1 0 3.24-.09 4.27-.13.62 0 1.4-.11 1.87-.11a4.19 4.19 0 0 1 .93.07c.11 0 .26.12.23.23a1.43 1.43 0 0 1-.4.51 2.7 2.7 0 0 1-1 .69 29.21 29.21 0 0 1-3.33.24h-2.44a2.69 2.69 0 0 0-.91.26c-.09.07.09.23.2.27a4.28 4.28 0 0 0 1 .25c.69.08 2.28.17 3.11.2a17 17 0 0 0 1.89 0 9.08 9.08 0 0 0 1.95-.27 5 5 0 0 0 1.33-.8c.15-.12.21-.35.31-.48a1.26 1.26 0 0 1 .24-.3.39.39 0 0 1 .21-.06c.08 0 .19 0 .23.09a2.06 2.06 0 0 1 .22.91 1.44 1.44 0 0 1-.45.95 4.52 4.52 0 0 1-1.73.58c-.86.11-2.73 0-3.45 0a2.82 2.82 0 0 0-.87.23.43.43 0 0 0-.23.33.68.68 0 0 0 .21.41 1 1 0 0 0 .57.35 18 18 0 0 0 2.17-.18c.92-.1 2.64-.27 3.4-.45a3.66 3.66 0 0 0 1.17-.6 1 1 0 0 0 .29-.47 1.24 1.24 0 0 0 .07-.54c0-.2-.25-.66-.17-.67s.43.45.67.64a7 7 0 0 0 1.18.73c.92.41 3.4 1.36 4.33 1.69.4.15 1.58.47 1.25.29s-2.3-.92-3.27-1.4a25.5 25.5 0 0 1-2.58-1.48c-.6-.4-1.08-1-1.69-1.36a16.89 16.89 0 0 0-2-1.05c-1-.45-2.55-1.23-3.74-1.67a21.39 21.39 0 0 0-3.4-1c-1.25-.24-3.09-.38-4.07-.46a15.66 15.66 0 0 0-1.82 0 1.15 1.15 0 0 0-.5.21c-.15.06-.25.24-.17.29Zm-10.18-4.09s3.43-1.88 4.28-2.28a1.48 1.48 0 0 1 .85-.12 1.25 1.25 0 0 1 .73.32 31.32 31.32 0 0 1 2.14 2.52c.42.57.8 1.36 1.12 1.8s.51.79.79.84a1 1 0 0 0 .84-.51 14.79 14.79 0 0 0 .78-2.61c.1-.45-.05-.94.07-1.39a32.27 32.27 0 0 1 1.4-4.16c.78-1.81 2.64-5.53 3.31-6.75a1.56 1.56 0 0 1 .73-.59.6.6 0 0 1 .59.12 8.27 8.27 0 0 1 1 1.52c.83 1.56 3.2 6.48 4 7.82a.67.67 0 0 0 .63.2c.15 0 .25-.25.3-.42.12-.38.25-1.49.43-1.9s.48-.44.65-.6a2.84 2.84 0 0 1 .38-.39c.1-.06.27-.11.35 0a1.14 1.14 0 0 1 .18.59c.06 1.12.08 5.12.18 6.18 0 .14.28.24.4.15.37-.27 1.21-1.2 1.82-1.8s1.76-1.72 2.26-2.16a3 3 0 0 1 .71-.48c.17-.07.5-.14.57 0s-.11.42-.17.63a16 16 0 0 0-.63 2.2 13.22 13.22 0 0 0-.07 2.4 3.92 3.92 0 0 0 .25 1.18.52.52 0 0 0 .43.21.47.47 0 0 0 .34-.21 11.93 11.93 0 0 0 .68-1.13 17.93 17.93 0 0 1 1.25-2.41 6.12 6.12 0 0 1 1.71-1.27 3.72 3.72 0 0 1 1.21-.36.91.91 0 0 1 .54.15.28.28 0 0 1 .12.31c-.19.34-.87 1.11-1.22 1.71a15.44 15.44 0 0 0-1.23 2.52 9.32 9.32 0 0 0-.29 2.07 2.42 2.42 0 0 0 0 .91c.08.15.33.09.48 0 .52-.18 1.94-.79 2.62-1.14.53-.27 1.2-.79 1.5-1 .09-.06.22-.16.3-.1a.74.74 0 0 1 .22.52c-.11.92-.64 3.73-.88 5-.18.93-.52 2.13-.59 2.77a2.75 2.75 0 0 0 .16 1.1c.06.13.26.17.4.18s.51 0 .63-.11.07-.56.12-.83c.12-.64.33-2 .57-3a25.4 25.4 0 0 1 .87-3 3.13 3.13 0 0 1 .71-1 .92.92 0 0 1 .6-.19 1.41 1.41 0 0 1 .82.18 12.44 12.44 0 0 1 1.37 1.41c.94 1.05 3.28 3.84 4.27 4.85a7.49 7.49 0 0 0 1.65 1.27 8.88 8.88 0 0 0 1.9.78 2.29 2.29 0 0 0 1.18 0c.2-.11.13-.51 0-.7a11.27 11.27 0 0 0-2-2.15c-.93-.73-2.69-1.5-3.64-2.21a10.51 10.51 0 0 1-2.08-2.08c-.8-1.07-1.73-3-2.76-4.33a21.39 21.39 0 0 0-3.67-4.16 19.51 19.51 0 0 0-4.89-2.46c-1.92-.74-4.87-1.35-6.64-2a15.91 15.91 0 0 1-4-1.83 52 52 0 0 1-4.85-4.45c-1.05-1-2.34-2.64-3-3.23a1.5 1.5 0 0 0-1.11-.31 2.37 2.37 0 0 0-1.36.57c-.84.88-2.49 3.08-3.66 4.69-1.3 1.78-2.92 4.46-4.15 6a46.3 46.3 0 0 1-3.2 3.38c-.7.74-1.74 1.75-2.13 2.19a1.86 1.86 0 0 0-.17.58Zm-21.88 12.08a12.45 12.45 0 0 1 1.68-1.71c.88-.66 2.57-1.55 3.55-2.25a13.12 13.12 0 0 0 2.32-1.95 9.21 9.21 0 0 0 .9-2 45.48 45.48 0 0 1 2.09-4.41 29.28 29.28 0 0 1 2.92-3.77 5.08 5.08 0 0 1 1.44-1 4.52 4.52 0 0 1 1.4-.41.89.89 0 0 1 .7.3 9.45 9.45 0 0 1 .6 1.23 17.2 17.2 0 0 0 1.54 2.58 9 9 0 0 0 1.9 1.3c.77.52 2.13 1.37 2.74 1.78a5.33 5.33 0 0 1 .95.67.61.61 0 0 1 .1.49c0 .1-.19.1-.29.12a2.61 2.61 0 0 1-.56 0 3.74 3.74 0 0 1-.85-.26 20.27 20.27 0 0 1-2.38-1.33 9.25 9.25 0 0 1-1.89-1.64 20.46 20.46 0 0 1-1.43-2.45 10.34 10.34 0 0 0-.58-1.07 1.8 1.8 0 0 0-.64-.49.34.34 0 0 0-.37.15 5.3 5.3 0 0 0-.59 1.34 12.26 12.26 0 0 0-.29 2.35 2 2 0 0 0 .36 1.07 10.62 10.62 0 0 0 1.18 1.14c.25.26.52.58.71.8a3.85 3.85 0 0 1 .41.54c0 .08 0 .21-.05.25a.63.63 0 0 1-.38 0 2.84 2.84 0 0 1-.49-.25c-.24-.15-.64-.42-.94-.65a10.84 10.84 0 0 0-.94-.76 2.28 2.28 0 0 0-.79-.19 2.14 2.14 0 0 0-.67 0 1.41 1.41 0 0 0-.51.18 1.13 1.13 0 0 0-.29.25 23.4 23.4 0 0 0-2.08 2.12 3.74 3.74 0 0 0-.54 1.53 5.68 5.68 0 0 0 0 1.79 1.29 1.29 0 0 0 .64.7 1.78 1.78 0 0 0 .77.1c.37 0 1 .05 1.45 0s1.63-.22 2.21-.19a3.53 3.53 0 0 1 1.31.39 2.34 2.34 0 0 1 .72.65c.36.44 1.11 1.57 1.46 2a2.5 2.5 0 0 0 .68.53 2.77 2.77 0 0 0 1 .42c.52.07 1.42 0 2.14 0s1.76 0 2.24.1a1.6 1.6 0 0 1 .6.18 1.16 1.16 0 0 1 .46.41c.09.17 0 .4.06.59a4.85 4.85 0 0 0 .09.55 1.26 1.26 0 0 0 .15.45.84.84 0 0 0 .35.22 3 3 0 0 0 .45.14 4 4 0 0 1 .62.2 2.28 2.28 0 0 1 .68.47.75.75 0 0 1 .08.57c0 .12-.24.1-.36.14a5.48 5.48 0 0 0-.56.16 2.21 2.21 0 0 0-.48.34 7.93 7.93 0 0 0-1.56 1.34 12.84 12.84 0 0 0-.64 1.93c-.37.86-1.2 2.57-1.59 3.22a1.75 1.75 0 0 1-.74.71 4.24 4.24 0 0 1-1.33.25 3.77 3.77 0 0 1-1-.1 2 2 0 0 1-.48-.24.89.89 0 0 1-.27-.23.21.21 0 0 1 0-.23c.23-.29 1-1 1.44-1.51.62-.68 1.81-2 2.29-2.57a3.26 3.26 0 0 0 .61-1.07 11.43 11.43 0 0 0 .34-1.82 5.25 5.25 0 0 0 0-1.14.56.56 0 0 0-.24-.36 1.53 1.53 0 0 0-.57-.19c-.07 0-.09.11-.09.18s.13.36.14.55a6 6 0 0 1 0 1.56 4.81 4.81 0 0 1-.85 1.69c-.9 1.08-3.71 4-4.52 4.78a.74.74 0 0 1-.35.2c-.09 0-.23-.1-.21-.2a12.17 12.17 0 0 1 .51-1.68c.28-.78.87-2.2 1.17-3 .22-.57.5-1.33.62-1.72a1 1 0 0 0 .07-.57 6.87 6.87 0 0 0-.67-1.48 8.26 8.26 0 0 0-1-1.25 2.42 2.42 0 0 0-.48-.4.47.47 0 0 0-.27-.08.27.27 0 0 0-.21.1.37.37 0 0 0 0 .26 2.54 2.54 0 0 0 .2.53 5.27 5.27 0 0 0 .33.61c.17.28.49.72.67 1.08a4.24 4.24 0 0 1 .39 1.09 1.33 1.33 0 0 1-.1.71c-.28.66-1.18 2.49-1.58 3.25a9 9 0 0 1-.85 1.29.67.67 0 0 1-.46.27 2.33 2.33 0 0 1-.92-.13 2.3 2.3 0 0 1-.67-.5 1 1 0 0 1-.37-.51 1.05 1.05 0 0 1 .17-.67c.24-.42.89-1.22 1.32-1.85a21.58 21.58 0 0 0 1.32-2.06 2.49 2.49 0 0 0 .24-1.17 11.76 11.76 0 0 0-.39-1.74 2.35 2.35 0 0 0-.19-.55c-.07-.1-.23-.24-.3-.23s-.11.19-.14.29a1.07 1.07 0 0 0 0 .4 10.32 10.32 0 0 1 .28 1.31 2.13 2.13 0 0 1-.31 1c-.45.8-1.89 3.07-2.4 3.84a2.65 2.65 0 0 1-.64.77c-.2.11-.47 0-.7 0a18 18 0 0 1-1.82-.11c-.2 0-.48-.18-.51-.32s.21-.39.35-.56c.43-.57 1.66-2.07 2.27-2.86.48-.61 1.09-1.4 1.39-1.88a3 3 0 0 0 .45-1 4.12 4.12 0 0 0 0-1.12 1 1 0 0 0-.18-.43.69.69 0 0 0-.3-.23 7.71 7.71 0 0 0-.76-.18 4.54 4.54 0 0 1-.5-.12 1.58 1.58 0 0 1-.47-.23 5.39 5.39 0 0 1-.65-.7c-.1-.15-.1-.36-.22-.49a1.51 1.51 0 0 0-.54-.38 2.6 2.6 0 0 0-.63-.11c-.36 0-1.11-.1-1.55-.12a7.57 7.57 0 0 0-1.08 0 .57.57 0 0 0-.39.21.55.55 0 0 0 .08.43c.07.11.23.15.35.2a3.26 3.26 0 0 0 .47.09h1.48l.51.05a1.45 1.45 0 0 1 .29 0 .67.67 0 0 1 .28.1 4.87 4.87 0 0 1 .57.67 2 2 0 0 1 .17.48c.06.18.11.43.17.56a.41.41 0 0 0 .17.22 1.71 1.71 0 0 0 .36.22c.13.07.29.13.42.19l.4.18a.38.38 0 0 1 .18.12.58.58 0 0 1 .12.29 2.12 2.12 0 0 1-.1.4.5.5 0 0 1 0 .13c-.23.43-.81 1.66-1.32 2.42a15.73 15.73 0 0 1-1.76 2.21c-.21.16 0-.53-.06-.79a9.37 9.37 0 0 0-.09-1 1.21 1.21 0 0 0-.28-.49 1.47 1.47 0 0 0-.52-.43 2.81 2.81 0 0 0-.79-.09h-1.06a5.69 5.69 0 0 1-.7-.12 9.22 9.22 0 0 1-1-.24 1.7 1.7 0 0 1-.63-.37 1.23 1.23 0 0 1-.2-.5c-.07-.25-.15-.72-.21-1a4.32 4.32 0 0 0-.16-.51 1.62 1.62 0 0 0-.25-.47 1.14 1.14 0 0 0-.41-.21 6.2 6.2 0 0 0-.67-.19c-.23 0-.47 0-.71-.08s-.67-.1-.87-.14a1.52 1.52 0 0 1-.36-.12c-.34.12-.51.03-.45-.05Z\" style=\"fill-rule:evenodd\" transform=\"translate(-260.31 -399.82)\" \/>\n                <\/svg>\n                <p class=\"text-center mt-2 mb-0 font-semibold\" style=\"color: #077100\">Tours Machupicchu<\/p>\n            <\/a>\n        <\/div>\n    <\/div>\n\n    <!-- Tours Camino Inca -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-camino-inca-otros\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"45px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 125.21 148.96\">\n                <path fill=\"#515151\" d=\"M339 498.36c-.63-14.62-1.68-39.05-2-45.79a6.61 6.61 0 0 0-.37-1.75c-.14-.4-.52-.7-.64-1.1s0-1-.09-1.48a7.82 7.82 0 0 0-.83-2.85c-.54-.68-1.9-.65-2.39-1.2s-.25-1.45-.56-2.11a17.26 17.26 0 0 0-1.74-2.86 34.82 34.82 0 0 0-2.4-2.57c-.67-.72-1.56-1.63-2-2.12-.25-.27-.5-.54-.74-.83-.43-.52-1.47-1.72-1.84-2.3a4.38 4.38 0 0 1-.37-1.18c-.17-.6-.36-1.63-.64-2.41-.34-.95-1-2.33-1.38-3.31a13.09 13.09 0 0 0-1.11-2.58 3.74 3.74 0 0 0-1.84-1.29c-.45-.05-.74.59-.92 1a13.9 13.9 0 0 0-.55 2.49 15.41 15.41 0 0 0-.18 2.11c0 .65-.25 1.38.09 1.94s1.78 1.41 2.3 2 1 1.12.83 1.73-1.63 2-2.21 2.76c-.46.6-1.49 1.12-1.29 1.84.24.89 1.88 2.31 2.76 3.5s1.86 2.7 2.67 3.87 1.66 2.24 2.21 3.13a9.53 9.53 0 0 1 1.1 2.2c.06.31-.29.59-.55.74s-1 .72-1.47.46a11.22 11.22 0 0 1-1.75-2.3c-.63-.84-1.43-1.79-2-2.76s-1.07-2.56-1.56-3.13c-.31-.36-1.13-.67-1.38-.28a12.2 12.2 0 0 0-.65 3.5 22.76 22.76 0 0 0 .1 3.31 25.22 25.22 0 0 0 .37 3.13 17.89 17.89 0 0 0 .82 3.32c.49 1.24 1.43 2.75 2.12 4.14a47.64 47.64 0 0 1 2.49 5.06 26.4 26.4 0 0 1 1.38 5.71 18.74 18.74 0 0 1-.19 5.34c-.37 2-1.33 4.54-2 6.81s-1.45 4.87-2.3 7.27c-1 2.68-2.66 6.58-3.41 8.84-.47 1.41-.67 3.31-1 4.44h.49c.73 0 5.43-.87 5.43-.87l1.09-.64h2s1.9.45 2.47 0 3.76 0 3.76 0l4.41-.95 2.39-.51Zm-31.46 4.71v-.15c0-.89 0-2.09-.09-3.13s-.23-2.29-.28-3.13a14 14 0 0 1 0-1.94c.08-.79.31-2 .46-2.85s.25-1.49.46-2.21c.26-.87.81-2 1.11-3s.43-2 .64-3 .54-2.09.64-2.95-.06-1.62 0-2.21a5 5 0 0 1 .37-1.29 14.33 14.33 0 0 0 .92-1.84 6.17 6.17 0 0 0 .19-2.21 1.5 1.5 0 0 0-.74-.92c-.29-.13-.81-.18-1 .1a11.38 11.38 0 0 0-.92 2.57c-.24.85-.3 1.74-.55 2.58-.31 1-.92 2.25-1.29 3.41a34.89 34.89 0 0 0-1.11 3.95 24.5 24.5 0 0 0-.27 3.32c-.06 1.22 0 2.7-.1 4-.09 1.53-.36 3.43-.46 5.15s-.15 4.34-.18 5.89v.48l2.08-.58Zm54.84 2.39s-.38-.06-.04 0Zm-66.77 1.79c-.54-.27-1.1-.5-1.14-.84-.07-.67 1.77-1.4 1.72-2.15s-1.92-1.7-2-2.36.91-1.08 1.29-1.62.94-1 1-1.61c.06-1.82-.61-6.8-.64-9.34a36.53 36.53 0 0 1 .43-5.9 14.36 14.36 0 0 1 1.07-2.69 12.25 12.25 0 0 0 1.07-2.79c.09-.8-.47-1.56-.53-2.36a22.63 22.63 0 0 1 .11-3.44c.1-1.22.46-2.92.53-3.87a5.57 5.57 0 0 0-.11-1.82c-.16-.66-.7-1.39-.85-2.15a19.73 19.73 0 0 1-.33-3.65c0-1.12.61-2.49.43-3.33s-1-1.13-1.5-1.72c-.68-.8-1.92-2.2-2.58-3.11-.53-.74-1-2.67-1.39-2.36s-.68 3.7-1.18 4.18-1.79-.54-1.83-1.28c-.11-2.12 1.15-9.47 1.18-11.39 0-.32-.64-.13-1-.1a14.46 14.46 0 0 1-2.46.43 7.74 7.74 0 0 1-2.8-.76c-.79-.4-1.28-1.25-2-1.71-1-.61-3.08-1-4-1.94a6.53 6.53 0 0 1-1.4-3.65c-.16-1.22.47-2.84.43-3.7 0-.53-.5-.94-.64-1.45a40.67 40.67 0 0 1-.86-4.08 26 26 0 0 1-.43-4.83 13.57 13.57 0 0 1 1.07-3c.28-.82.53-1.64.76-2.47s.48-1.78.64-2.69.19-1.93.32-2.9c.16-1.16.38-3 .65-4.08.22-.92.75-1.84 1-2.68s.06-1.61.33-2.36a24.4 24.4 0 0 1 2-4.35 4.32 4.32 0 0 1 1.82-1.24 25.1 25.1 0 0 1 3.21-1.19 29.32 29.32 0 0 1 3.44-.75 20.72 20.72 0 0 1 3.43-.32 3.53 3.53 0 0 1 1.51.54 13.91 13.91 0 0 1 1.5 1.07 14.57 14.57 0 0 0 2.58 1.88 6.68 6.68 0 0 0 2.36 0 4.2 4.2 0 0 0 1.5 0 3.56 3.56 0 0 0 1.4-1.13 5.69 5.69 0 0 0 .86-1.93 4.72 4.72 0 0 0-.11-1.83c-.14-.7-.51-1.57-.75-2.36a17.61 17.61 0 0 1-1.18-4.08 6 6 0 0 1 1-3.71c.74-.89 2.63-1.2 3.44-1.66.51-.29.82-.94 1.4-1.07a54.59 54.59 0 0 1 5.9-.65 6.53 6.53 0 0 1 2.26.11c.4.16 1 .71.75 1.07-.36.55-2.67 1.84-2.9 2.2s1.05-.21 1.5 0a3.71 3.71 0 0 1 1.29 1.35c.2.38 0 .87.11 1.29s.46 1.14.64 1.71a13.47 13.47 0 0 1 .43 1.72c.05.32-.07.66 0 1a2.78 2.78 0 0 0 .43.86c.2.28.74.53.75.86s-.43.73-.64 1.07-.6.58-.65 1 .41 1.28.33 1.93a4.17 4.17 0 0 1-.86 2.31c-.5.38-1.76-.28-2.15 0a1.32 1.32 0 0 0-.21 1.66c.53.53 2.32.94 3.43 1.51s3 1.07 3.76 2.14.53 2.9 1 4.3c.66 2.13 2.88 6.92 3 8.48.07.8-2 .1-2.24.87-.28 1 .2 3.34.56 5a28.5 28.5 0 0 0 1.56 4.79 55.09 55.09 0 0 0 2.58 5.33c1.24 2.27 3.83 6.49 4.88 8.29a17.69 17.69 0 0 0 1.38 2.48c.42.49 1.12.65 1.65 1 .8.55 2.79 1.38 3.13 2.3s-.7 2.39-1.1 3.22a11.58 11.58 0 0 1-1.29 1.75l2.57 48.91 3.12-1.06 2-.36 1.67.14s1.3 2.1 2.75 2 5-.15 5-.15l4.74-.21h1.9l2.67.79 1.3.73.65.58.51.94 1 .59h26.36l-.58 1.22s-6.59.29-7.24.36-14.19.87-14.19.87l-7.46.51-2 .07-1 .22v.85l.71.16a41 41 0 0 0 4.64.43 12.43 12.43 0 0 1 2.23.08c1.75.14 4.36-.73 3.7.29s0 1.15-.87 1.15h-2.24c-.8 0-2.46.15-2.46.15a2.3 2.3 0 0 0-1.31.14 10.58 10.58 0 0 1-1.66.51s-3.12 0-3.84-.07-2.32-.07-2.32-.07l-3.22.14h-1.05l-1.23.36s-1 .37 0 .66 2.28.5 2.28.5.39.58 0 .65a5.53 5.53 0 0 1-1.34.08c-.8 0-3 .21-3 .21l-2.6.15s-2.25-.51-1.38.14.36.44 1.59.66 6.7.21 6.7.21h3.59l.86.29s-7.45 5-9.12 5a20.93 20.93 0 0 0-3.77 0c-2.53.22-5.35.36-5.35.36l-1.22.51s2.33.87 0 1.08-3.85.66-4.58.66-2.1.07-4.05.07h-3.77l-1.23-.07-.51 1.15a11.11 11.11 0 0 1-2.31 0 14.88 14.88 0 0 0-2-.14l-.65.36s-.94.51-.29.8-.58.22 1.23.29 3.11.22 3.84.22 2.75.28 2.75.28l-1.45.51s-1.45-.22-1.95-.22-2.11-.07-2.11-.07h-2.77l-1.66.51s-.72.58-.15 1.09 1.24.72.37.79-1.52.07-1.52.07a17.11 17.11 0 0 1-2.9.22c-1.09-.07-6.23 0-6.23 0l-3.47.07-1.16-.65.29-.79a7 7 0 0 1 3.76-1.24 34.9 34.9 0 0 0 5.51-.72 1 1 0 0 0-.95-.94c-.86-.07-1.23 0-3-.22s-5.44.15-7.17-.14a27.82 27.82 0 0 0-4.93 0c-1.23 0-6 .5-6 .5l-.65-.79-.36-.94-1.6-.66-4.41.44-1.38-.51-.29-.65a1.27 1.27 0 0 1 .94-.65 5.94 5.94 0 0 0 1.31-.44l-.37-1-.14-.8a.78.78 0 0 0-.72-.72c-.73-.15-14.42.22-14.42.22v-.87l3.55-1.16 14.05-3.33 5.94-1.6Z\" style=\"fill-rule:evenodd\" transform=\"translate(-269.63 -376.86)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\" style=\"color: #515151\">Tours<br>Camino Inca<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours populares -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-mas-populares\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"31.81px\" height=\"39.99px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 276.11 347.01\">\n                <path fill=\"#4778FF\" d=\"M109.03 346.62c0-7.35.1-14.31 0-21.28-.7-42.49-1.52-85-2.06-127.46-.06-4.49-1.58-5.64-5.73-5.79-13.65-.49-27.3-1.13-40.93-2.06-11.93-.81-20-7.36-23.54-18.57-5.83-18.4-11.55-36.87-16.42-55.54S11.47 78.35 7.47 59.47c-2.74-13-5-26.17-7.08-39.33S4.25-.03 16.55 0c6.55 0 11.79 4.33 14.46 12.4 5.77 17.38 11.11 34.92 17.14 52.21 7.32 21.06 15.32 41.89 22.77 62.91 2.46 6.94 7.06 10.4 14.12 11.59 18.87 3.17 37.71 4.44 56.64.6 1.37-.28 2.79-.33 5.06-.59-8.59 18.37-5 37.09-5.56 55.4-.46 15.66-.16 31.33-.06 47 0 2.79-.64 4.57-3.34 5.9-4.78 2.34-6.86 6.5-6.84 11.83.07 15.16.07 30.33.08 45.5 0 10.27 4.63 15 14.88 15.08h4.81c-.7-3.87-2.11-5.85-6.14-5.88-5.09 0-7.7-2.75-7.74-7.82q-.15-23.51.08-47c.05-5.06 2.42-7.4 7.47-7.42q39.25-.15 78.51 0c5.43 0 7.88 2.61 7.91 8.17q.12 23-.07 46c-.05 5.44-2.63 7.88-8 8.05-2.66.08-5.34 0-8 .09-4.31.15-4.3.18-6.68 6.2 7-.43 13.68-.1 20-1.44 5.52-1.18 8.39-6.07 8.44-11.73.16-16.16.23-32.33-.2-48.49-.09-3.13-2.65-6.19-4-9.31-1-2.29-2.67-4.62-2.69-6.94-.23-21.5-.24-43-.17-64.49 0-12.81.86-25.71-7.42-38.37 13.49 2.53 25.78 3.14 36.4 9.69 6.74 4.15 9.52 11.31 10.37 18.66 2.45 21.17 5.44 42.36 6.14 63.61 1.22 36.78.83 73.61 1.23 110.42 0 3.74-.78 5.23-4.95 5.22q-78.29-.18-156.56-.05c-1.35-.04-2.66-.19-5.61-.38Zm70.52-21.49a28.19 28.19 0 0 0 28.28-28.24 28.49 28.49 0 0 0-28.62-28c-15.46 0-28 12.91-27.93 28.63a28 28 0 0 0 28.27 27.61Zm33.63-56.2h3.48c5.71 0 8.65-3.77 5.77-8.79-1.06-1.84-5.68-2.24-8.67-2.22-3.15 0-8 .35-9.11 2.27-3 5.33-.13 8.87 6 8.73.87-.02 1.7 0 2.53.01Z\" \/>\n                <path fill=\"#4778FF\" d=\"M186.47 120.02a55 55 0 0 1-54.85-55.53c.25-31.38 25-55.24 56.94-54.85 29.94.37 54.18 25.31 53.88 55.44a55 55 0 0 1-55.97 54.94ZM167.74 245.7c-.36-1-.41-1.81-.83-2.2-1.66-1.55-3.46-4.17-5.16-4.14-2 0-4.1 2.31-6 3.74a21.31 21.31 0 0 0-2.43 2.5c-.5-1.08-1.42-2.16-1.43-3.24-.12-11.15-.11-22.31-.11-33.46 0-15.65-.07-31.3.13-46.94a33.67 33.67 0 0 1 1.72-10.76c3.08-8.64 7.45-15.66 18.51-15.45 8.74.17 17.37-2.26 26.3-.11 10.54 2.53 19 10.39 19.72 21.31.8 12.11.63 24.28.71 36.43.1 15.15 0 30.3 0 45.44 0 7 .07 7-6.72 7l-39-.12ZM179.53 315.04a18.31 18.31 0 0 1-18.14-17.62c-.24-9.95 8.26-18.47 18.35-18.4a18 18 0 0 1-.21 36Zm4-29.32c2.13 3.86 4 7.45 6.16 10.88.26.43 1.91 0 2.91-.06-.72-2.88-.9-6.06-2.3-8.56s-3.98-4.36-6.74-2.26Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours<br>populares<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours Valle Sagrado -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-valle-sagrado-incas\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"41.13px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 138 86.23\">\n                <path fill=\"#4778FF\" d=\"m227.94 200.41 3.75-4.92c-2.73-2.23-6-2.87-8.12-6.48a18.57 18.57 0 0 1-1.74-4.55c-3.22-12.6 8.9-17.75 19.43-15.85 4.83-8.12 15-16 23.89-7.53a36.53 36.53 0 0 1 5 6.53l3.94-4.16c-10.72-15.09-23.72-15.62-35.41-.53-7.29-1.43-10.65-.32-13.44 1.13-11.42 5.9-12.43 17.46-6.11 28 1.37 2.36 7.17 6.68 8.81 8.36Zm105.86 6.26 4.48 6.26c1.31-1.52 3.39-2 5-3 2.87-1.74 5.58-3.39 7.29-6.41 6.75-11.92.18-26.13-13.55-27.72-4-.46-7 2.46-10.64 2.58l-11.19-9.19-4.11 3.81 14.05 12.22c.79-.11 1.77-1.42 2.41-1.73a13.46 13.46 0 0 1 10.72-1.11c8.92 2.63 11.23 11.32 6.07 18.72-2.24 3.19-7.33 4.43-10.53 5.57Zm-39.92 29.72c-4.08-1-8.16-1.92-12.29-2.65-7.48-1.31-14.76-.83-21.2-5.54-1-.74-2.27-1.5-2.59-2.71-1.16-4.49 1.85-6.45 5.42-8 4-1.74 13.81-3.6 17.77-4.21 2.48-.38 5-.5 7.5-.78 1.74-.2 6.26-.05 5.07-1.33-1.44-1.56-4.08-1.23-6.17-1.63-5.33-1-11.19-1.32-16.37-3-2.72-.9-5-1.39-6-4.27-2.7-7.63 10.56-9.55 15-10.13.46-.06 6.11-.5 5.61-2.33-.62-2.3-4.52-1.56-6.87-2-6.52-1.06-10.07-1.35-14.28-6.9-2.19-2.89-4.1-7.54-8-8.91-2.55-.91-4.75 1.74-6 3.54-2.62 3.8-5.06 7.71-7.46 11.66-8.75 14.39-18 28.52-26 43.34-1.45 2.7-.73 6.38 2.71 6.57 12.59.69 25.22.55 37.82.66 13.31.11 26.63.51 39.93 0 1.38-.04-2.34-1.04-3.6-1.38Zm17 1.52c6.31-1.43 40 4.84 30.05-9.42-6.08-8.7-11.79-18.7-17.62-28-9.06-14.39-18.05-28.84-27.35-43.08a9.36 9.36 0 0 0-4.65-3.23c-2.69-.38-4.64 2-6.09 3.81-5.48 6.77-11.08 13.46-16.19 20.51-1.48 2.05 5.52 3.24 6.11 3.39 4.37 1.12 21 1.47 17.2 10.17-2.2 5-10.94 4.68-15.29 5.62-1.45.31-3.72.29-4.1 1.73-.81 3.06 7.06 3 8.32 3.17 5.91.95 21.36 1.19 19.7 10.89-.67 3.91-4.53 3.75-8.14 4.62a55.39 55.39 0 0 1-6 .77 93.81 93.81 0 0 0-13.23 2.62c-.39.11-5 1-5.18 1.11-.81.61 1 2.14 2 2.32 1.44.25 2.92.12 4.37.3s2.9.54 4.35.77c3 .5 6.07.81 9.07 1.42 3.79.77 7.57 1.64 11.28 2.72a23.23 23.23 0 0 1 9.1 4.87c.41.48 1.24 2.82 2.27 2.92Z\" style=\"fill-rule:evenodd\" transform=\"translate(-215.25 -151.86)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours Valle Sagrado<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours Monta\u00f1a 7 Colores -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-montana-7-colores\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"60px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 170.53 115.85\">\n                <path fill=\"#CA0031\" d=\"m221.93 140 20.27-21.23s11.56-9.82 15.29-12.5a23.66 23.66 0 0 1 7.1-3.59c2.11-.56 4.53-.88 6.55-.06 3.69 1.5 10.67 5.61 15.6 9s9.83 8 14 11.59c3.75 3.19 11.1 9.77 11.1 9.77l-16.14-11s-6.72-4.89-10.2-7.16-7.87-5-10.67-6.43a18.49 18.49 0 0 0-6.13-2.25 11.21 11.21 0 0 0-6.44.91c-3.83 2.13-12 8.27-16.56 11.84-3.79 3-7.2 6.39-10.8 9.58Zm-4.75-7.49c3-3.35 9-10 13.78-14.85 5.11-5.17 12.57-12.12 16.85-16.17 2.9-2.74 6.78-6.38 8.83-8.11a9.58 9.58 0 0 1 3.5-2.23 7.3 7.3 0 0 1 4.37.29 75.32 75.32 0 0 1 10.38 6.17c5.26 3.7 14.54 11.08 21.17 16.07 6.17 4.64 12.45 9.15 18.59 13.83 6.41 4.88 17.06 13.19 19.83 15.43 1 .8-3.23-2-3.23-2l-9.71-5.94-13.7-9.9-16.39-12.27-15.93-12s-8.24-5.74-10.52-7.06a4.65 4.65 0 0 0-3.15-.9c-1.11.26-2.42 1.54-3.53 2.45-2.89 2.38-9.35 7.69-13.79 11.81-4.84 4.48-11.45 11.37-15.26 15.1-2.5 2.45-5.55 5.56-7.57 7.27a42.63 42.63 0 0 1-4.52 3.01Zm12.29 15.84L246.92 131s6.35-4.66 8.81-6.35a47.69 47.69 0 0 1 6-3.8 27.67 27.67 0 0 1 6.44-2.18 8.93 8.93 0 0 1 4.56.29 40.29 40.29 0 0 1 6.92 4 87.46 87.46 0 0 1 7.2 5.59c3.4 2.91 13.18 11.86 13.18 11.86l-7-4.5-10.09-7.91s-5.62-3.85-7.53-5a11.8 11.8 0 0 0-3.92-1.71 9.89 9.89 0 0 0-4.78.32 69.7 69.7 0 0 0-10.25 5.39 87.44 87.44 0 0 0-9.32 6.91c-2.85 2.36-6.3 5.87-8.16 7.53-1 .86-3 2.45-3 2.45l-4.46 3.65ZM248.05 122l11.11-10.25a26.66 26.66 0 0 1 4.85-3.22 9.22 9.22 0 0 1 5-.42 21.32 21.32 0 0 1 6.37 2.91c4 2.61 11.66 8.53 17.54 12.74 6.47 4.65 14.2 10.48 21.3 15.11 6.92 4.52 14.58 8.79 21.29 12.68 6.29 3.65 13.68 7.74 19 10.68 4.28 2.37 12.92 7 12.92 7l-14.68-5.09-20.39-9.77s-8.37-4.08-12.26-6.62c-4.56-3-10.41-7.76-15.11-11.28-4.38-3.29-8.84-6.75-13.1-9.9s-9.11-6.85-12.5-9a40.81 40.81 0 0 0-7.89-3.76 9.83 9.83 0 0 0-5.4-.54c-2.42.62-6.09 2.85-9.11 4.3s-8.94 4.43-8.94 4.43Zm-42.52 57.24 18.13-20.4s9.38-7.64 13.88-11.61 9.44-9 13.12-12.21a80.14 80.14 0 0 1 9-7.28 17.62 17.62 0 0 1 7.06-2.66 17.32 17.32 0 0 1 7.73.91c2.31.89 4.13 2.84 6.07 4.4 3.29 2.65 9.19 7.64 13.66 11.46s9.11 8.37 13.12 11.45a95.46 95.46 0 0 0 10.92 7.05c5 2.89 12.75 7 19.27 10.24s20.17 9.26 20.17 9.26l-18.43-5.92s-8.57-4.25-12.82-6.45c-5.27-2.73-13.23-6.24-18.81-9.93-5.3-3.51-9.86-8.19-14.64-12.21s-10.77-9.14-14-11.91a70.43 70.43 0 0 0-5.54-4.71 7 7 0 0 0-3.26-.75c-1.45-.09-3.75-.41-5.46.22s-3.61 2.33-5.23 3.72c-3 2.55-8.42 7.77-12.67 11.61s-9.75 8.76-13.12 11.68c-2.33 2-4.85 3.78-7.13 5.84-2.75 2.46-6.08 6.12-9.33 8.95-3.57 3.01-11.69 9.26-11.69 9.26Zm7.1 10.07 14.94-15.1 11.53-11.75c4.11-4.2 9.28-10 13.13-13.43a73.7 73.7 0 0 1 9.93-7 18.87 18.87 0 0 1 6.15-2.66 13.37 13.37 0 0 1 6.14.61 21.12 21.12 0 0 1 6.07 3.34c3.57 2.78 11.37 9.73 15.39 13.35 3 2.69 5.89 5.48 8.73 8.34 3.21 3.24 10.54 11.07 10.54 11.07L305 167.93l-12.5-10.77s-6.79-7-9.63-9.26a37.92 37.92 0 0 0-7.43-4.47 12 12 0 0 0-5-1.14 22 22 0 0 0-6.9 1.37 24.37 24.37 0 0 0-6 3.64 91.21 91.21 0 0 0-9.78 8.64c-2.67 2.91-4.35 6.62-7 9.56a140 140 0 0 1-10.24 9.71c-2.46 2.2-5.06 4.25-7.66 6.3-2.97 2.35-10.23 7.81-10.23 7.81ZM335 192.54l.39.24a2.41 2.41 0 0 0-.39-.24l-22.09-14s-9-7.6-12.29-10.23c-2.35-1.9-4.87-3.82-7.18-5.53s-4.54-3.08-6.7-4.76c-2.42-1.88-5.72-4.86-7.82-6.51a36.76 36.76 0 0 0-4.75-3.34 9.44 9.44 0 0 0-3.89-1.27 8.73 8.73 0 0 0-3.83 1 21.48 21.48 0 0 0-5.83 3.55c-2.08 2.07-4.53 6-6.65 8.88s-4.16 5.85-6 8.16a70.91 70.91 0 0 1-5.14 5.68 17.39 17.39 0 0 1-3.3 2.42c-1.74 1-4.94 2.09-7.14 3.6-2.55 1.74-5.86 5.08-8.15 6.89a51.17 51.17 0 0 1-5.59 3.93c-1.34.77-3.18 1.15-4.32 1.7a14.69 14.69 0 0 0-2.47 1.6 17.52 17.52 0 0 0-3 2.57c-1.1 1.37-2.48 4.35-3.64 5.64a11.43 11.43 0 0 1-3.35 2.08c-1.39.72-5 2.25-5 2.25l10.43-2.61s6.53-4.12 9.72-6.28 6.68-4.64 10-7 7.48-5.3 10.41-7.68c2.52-2.05 4.81-4.38 7.16-6.62s4.87-5.43 7.77-7.6c3.09-2.31 8-4.58 10.78-6.28 2-1.23 3.72-3.12 5.93-3.91a14.74 14.74 0 0 1 7.35-.83 24.44 24.44 0 0 1 8.18 3.67c2.78 1.83 5.55 5 8.51 7.28s6.39 4.7 9.36 6.56c2.72 1.72 5.84 2.93 8.44 4.65 4.53 2.89 21.36 10.8 24.09 12.34Z\" style=\"fill-rule:evenodd\" transform=\"translate(-196.94 -90.95)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\" style=\"color:#CA0031\">Tours Monta\u00f1a 7 Colores<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours Per\u00fa -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-peru\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"75px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 266.45 253.83\">\n                <path fill=\"#4778FF\" d=\"M61.99 167.43a73.13 73.13 0 0 1 6.7-25.9c2.36-5.27 5.19-10.32 7.64-15.55 5.5-11.76 3.33-22.73-3.66-33.11a22.44 22.44 0 0 0-7.91-7.49c-1.18-.64-1.1-1.21-.21-2.06A298.56 298.56 0 0 0 89.89 55.8c.83-1 1.48-.88 2.46-.3a45.4 45.4 0 0 0 14.74 5.91c8.64 1.62 16.22-.44 22.63-6.52a9 9 0 0 0 1-1c1-1.26 1.73-1.24 2.83 0a23.89 23.89 0 0 0 12.51 7.38 29.36 29.36 0 0 0 17.82-1.87 85.35 85.35 0 0 0 8.14-4 1.55 1.55 0 0 1 2.32.42 301.17 301.17 0 0 0 25.33 27.52c.9.86.9 1.31-.18 2.07-11.31 7.92-15.75 19-14.15 32.45a29.85 29.85 0 0 0 3.48 9.78c4 7.69 7.86 15.39 10.38 23.7 2.33 7.7 3.47 15.52 1.93 23.55-1.64 8.57-6.29 15.21-13.08 20.5a41.18 41.18 0 0 1-19.8 8.06c-6.23.92-12.49 1.63-18.69 2.68a25.73 25.73 0 0 0-16 9.24c-1.41 1.7-1.51 1.73-2.88 0-4.86-6.16-11.53-8.77-19-9.85-6.45-.93-13-1.41-19.35-2.83-13.77-3.08-23.86-10.84-28.38-24.63-1.13-3.42-1.34-7.09-1.96-10.63Zm134.6-.2c-.5-3.27-.83-6.58-1.53-9.81-1.8-8.35-5.48-16-9.21-23.59a4.35 4.35 0 0 0-4.59-2.81q-47.94.12-95.87.05a29.74 29.74 0 0 0-4.12.08 3 3 0 0 0-2 1.2c-4.69 8.69-8.8 17.61-10.66 27.4-1.24 6.53-1.31 13.06 1.45 19.23 4.49 10 12.5 16 23.06 18.21 6.3 1.36 12.78 1.88 19.18 2.82s12.61 2.85 17.83 7c2 1.58 2 1.58 3.91.07.68-.53 1.37-1 2.09-1.51 6.15-4.09 13.17-5.28 20.3-6.25 5.78-.79 11.64-1.38 17.25-2.85 11.18-2.92 23.1-13.37 22.91-29.27Zm-41.27-68.31c2.76.75 2.48-1.11 2.52-3.09 1.3 2 2.51 2.06 3.93.35-.1 1.79 0 3.1 1.42 2.87-.57 1.74-1.61 3.51-1.64 5.3-.11 5.72.1 11.45.29 17.17a4 4 0 0 0 3.9 3.88c4.81.13 9.62.06 14.43.06.92 0 1.22-.48.95-1.35-.13-.44-.23-.89-.37-1.33a34.44 34.44 0 0 1-.65-17.31 41.75 41.75 0 0 1 10.95-20.65c.77-.8.78-1.32 0-2.14q-9.13-9.9-18.19-19.88a1.48 1.48 0 0 0-2-.49 70.73 70.73 0 0 1-7.76 3.2c-9.11 2.9-18 2.75-26.55-2.12a12.63 12.63 0 0 0-1.48-.59c-.06.69-.13 1.14-.13 1.59l-.12 59.09c0 1.47.45 2 2 2 5.21-.06 10.42 0 15.63 0 3.22 0 4.83-1.34 5-4.58.24-4.11.38-8.24.35-12.36-.05-3.34.68-6.84-2.48-9.62Zm-25.89-36.45c-1 .53-1.53.8-2.07 1.1a29.62 29.62 0 0 1-12.88 3.8 39.47 39.47 0 0 1-20.33-4.68 2.28 2.28 0 0 0-3.31.6c-5.74 6.45-11.6 12.81-17.48 19.13-1 1-1 1.54 0 2.63 10.07 11.27 14.19 24.08 9.73 39-.3 1 0 1.41 1 1.41h6.87c1 0 1.33-.58 1-1.5a32.29 32.29 0 0 0-2-5.47c-1.12-2-.9-3.55-.1-5.59 1.17-3 2.12-6.2.4-9.44-.66-1.25-1.05-2.64-1.6-3.94-.35-.82-.85-1.57-1.13-2.4-.15-.45-.21-1.2.05-1.47 3-3.17 6.82-6.84 12.91-4.49 3 1.17 6.31 1.62 9.48 2.35a3.7 3.7 0 0 0 3.91-1.57 7 7 0 0 0 1.83-5 27.68 27.68 0 0 1 0-5.15 50.93 50.93 0 0 1 1.26-6.35 4.84 4.84 0 0 1 1-1.51c.63.91.95 1.86 1.59 2.19 1.41.72 3 1.06 4.47 1.69.48.21 1.15.93 1.07 1.25a3.16 3.16 0 0 1-1.25 1.59 3 3 0 0 1-1.5.27c-1.59.1-2.27.83-2.32 2.51-.11 3.31-.66 6.62-.66 9.93a16.53 16.53 0 0 1-5.39 12.34 5.25 5.25 0 0 0-1.19 2.7c-.34 1.73-.14 3.63-.73 5.25-1.21 3.29-.61 6.56-.52 9.85 0 1.51.82 2.05 2.32 2 4.41-.07 8.82 0 13.23 0 2.08 0 2.19-.13 2.2-2.28q0-29.21.07-58.4c.08-.62.07-1.26.07-2.35Zm-29.64 42.56c-.65 3.29-1.33 6.45-3.2 9.18a2.58 2.58 0 0 0-.39 2.83c.54 1.19.8 2.5 1.25 3.73 2.11 5.7.57 4.51 6.74 4.72 1.61.06 2.1-.56 2.07-2.09q-.14-6.09-.08-12.17c0-1.69.23-3.38.35-5Zm-6.27 6.89c-.6 1.18-1.29 2.32-1.77 3.55a3.07 3.07 0 0 0 0 1.94c.82 2.37 1.72 4.71 2.72 7 .2.46 1 .68 1.49 1 .21-.57.64-1.17.57-1.71a18.47 18.47 0 0 0-.91-3.64c-.98-2.64-3.15-4.99-2.1-8.14Zm16 1.32c-1.77 3.42-1.68 7-1.59 10.49 0 .56.66 1.11 1 1.67.3-.61.86-1.21.87-1.83.05-2.68-.05-5.36-.12-8-.02-.81-.12-1.57-.18-2.37Z\" \/>\n                <path fill=\"#4778FF\" d=\"M163.05 240.84a21.57 21.57 0 0 0 4.05-.7 24.17 24.17 0 0 1 15-1.12c4.8 1.27 9.64 1 14.51.82a10.47 10.47 0 0 1 7.22 2.76c-.77.14-1.33.31-1.91.35-7.84.59-15.66.87-23.37-1.27a28.75 28.75 0 0 0-4.92-.72 11.8 11.8 0 0 0-2.12.17l-.05.51a10.77 10.77 0 0 1 1.62.3 31.36 31.36 0 0 1 5.69 2.16c2.31 1.35 2.74 3.76 2.12 6.2s-2.51 3.07-4.68 3.4c-3.2.49-6.1-.5-9-1.67s-5.67-2.15-8.45-3.35a5.64 5.64 0 0 0-4.12-.15c-5.77 1.7-11.44 1.7-16.61-1.87a7.35 7.35 0 0 1-2.24-2.95 18.21 18.21 0 0 0 17.47 3.66l.17-.55a7.64 7.64 0 0 0-2.32-.62 20.67 20.67 0 0 1-15.44-4.92 4.9 4.9 0 0 0-6.74.46c-3.5 3.81-7.53 6.79-12.88 7.14-2 .14-4.06-.46-6.09-.59a9.73 9.73 0 0 0-3.78.18c-3.72 1.3-7.38 2.79-11 4.28a14 14 0 0 1-7.57.88c-1.92-.29-3.54-1.06-4.17-3.07a5.45 5.45 0 0 1 1.14-5.76 10.42 10.42 0 0 1 6.62-2.91c1.19-.14 2.36-.4 3.54-.6v-.81a20.47 20.47 0 0 0-4.4-.23c-3.05.46-6.06 1.17-9.07 1.89-6.45 1.54-13 1.07-19.49.75a5.43 5.43 0 0 1-1.19-.5c2.62-1.17 4.46-3 7.32-2.74a46.14 46.14 0 0 0 15.8-1.49 21.43 21.43 0 0 1 15.81 2.12q4 2.18 7.82 4.66c3.9 2.52 8 3.11 12.23 1.19 2.94-1.32 5.77-2.88 8.65-4.33l-.29-.83a21.58 21.58 0 0 0-2.55.63c-2 .77-3.91 1.61-5.85 2.45a10.76 10.76 0 0 1-9.61-.43 52.8 52.8 0 0 1-7.93-4.62c-5.92-4.56-12.49-5-19.42-3.54a37.66 37.66 0 0 1-15.68-.15c-2.54-.54-4.06-2.52-6-3.89l.17-.46c1.48.24 3 .36 4.44.73 6.95 1.78 13.94 1.7 21 .77a20.22 20.22 0 0 1 14.18 3.51 18.69 18.69 0 0 1 2.2 1.34c2.69 2.34 5.71 2.45 9 1.65 2.22-.54 4.51-.8 6.76-1.21a4.83 4.83 0 0 0 2.29-1c-1-.28-1.95-.61-3-.83q-12.4-2.73-24.82-5.42c-6.7-1.46-13.52-2.51-20.07-4.46a115.52 115.52 0 0 1-37-19.22 1.77 1.77 0 0 1-.7-1.09c.85.43 1.71.82 2.54 1.29a137 137 0 0 0 29.18 12.69 76.43 76.43 0 0 0 17.69 3.08c3 .15 6 1.44 8.93 2.29 2.47.72 4.9 1.56 7.36 2.31a3.14 3.14 0 0 0 1 0c1.35-5.26 1.55-5.52 7.61-5.05a28.82 28.82 0 0 1 19.12 9.42 8.38 8.38 0 0 0 .75.7 1.48 1.48 0 0 0 .42.13 1.83 1.83 0 0 0 .44-2.88c-5.58-7.41-12.95-11.21-22.29-11a8.44 8.44 0 0 1-1.15-.13c1.15-2.26 3.63-3.15 6.92-2.43 7.05 1.54 12.83 5 16.85 11.17.33.51.7 1 1.21 1.72.6-.81 1.1-1.4 1.51-2.05 3.72-5.91 9.25-9.28 15.85-10.89 1.75-.43 3.79.14 5.66.46.59.1 1.07.87 1.58 1.56-11.71.18-20.05 5.36-25.22 15.78a1.67 1.67 0 0 0 2.62-.54 28.17 28.17 0 0 1 15-10.27 39.32 39.32 0 0 1 8.12-1.12c2.59-.17 2.95.21 3.91 2.66.26.69.43 1.41.71 2.36 1.07-.3 2.11-.52 3.11-.87 7.11-2.51 14.2-5.1 21.34-7.53 2.11-.72 2.56-2.28 3.05-4.1 1.11-4.14 2.11-8.33 3.59-12.34 2.34-6.31 7-11 11.93-15.27 2.45-2.14 4.92-4.26 7.31-6.47a3.84 3.84 0 0 0 1.32-3.53c-.27-2.08 1.38-2.93 3.1-3.68a5.48 5.48 0 0 0-.58-1.12c-7.79-8.86-10.5-19.47-10.82-30.94-.09-3.46-.35-6.92-.54-10.55a4.74 4.74 0 0 1 1.11.24 40.45 40.45 0 0 1 18.44 15.87 2.57 2.57 0 0 1 .16 2.82c-1 2.21-1.84 4.54-2.75 6.81-.16.39-.38.75-.79 1.52a49.7 49.7 0 0 0-8.65-15.86c1 2 2.1 4 3 6.11q2.44 5.94 4.64 12a5.93 5.93 0 0 1 .24 3c-.82 4 0 7.86.63 11.75.17 1 1.08 2.36-.75 3a2.63 2.63 0 0 0 .23 1.45 27.6 27.6 0 0 0 1.7 2.36l-.82.72a7.08 7.08 0 0 0-.63-1.33 2.58 2.58 0 0 0-3.09-1.15c-.83.26-1.87-.15-3-.28a9.83 9.83 0 0 0 .06 1.06c.25 1.29.5 2.58.8 3.86.64 2.75.5 5.09-2.37 6.7a19.94 19.94 0 0 0-4.58 3.71 15.46 15.46 0 0 0-2.13 3.7 18.21 18.21 0 0 1-5.62 6.66c-2.86 2.15-5 5.28-7.4 8-.74.84-1.36 1.78-2 2.67l.35.37a9.19 9.19 0 0 0 1.39-1.14c1.14-1.37 2.29-2.73 3.28-4.19 3.94-5.75 9.7-8.55 16.29-9.44a50 50 0 0 1 22.92 1.87c2.8.94 2.92 1.26 1.41 3.82-3.45 5.86-8.85 9.49-14.64 12.61-5 2.73-10.34 4.78-16.22 4.14a26.46 26.46 0 0 1-7.83-1.75c-3.55-1.58-6.81-1.14-10.24 0-10.19 3.44-20.37 6.89-30.59 10.25-4.23 1.39-8.55 2.54-12.83 3.81-.35.1-.69.25-1 .38v.47c2 .4 4.06.83 6.1 1.19 2.65.47 5.3 1 8 1.27a4.59 4.59 0 0 0 2.57-.49c2.47-1.33 4.75-3 7.29-4.17a23 23 0 0 1 6.86-1.89 35.82 35.82 0 0 1 7.88.12 43.19 43.19 0 0 0 15.32-1.28 35.86 35.86 0 0 1 5.91-.92c-2.09 2.2-4.2 4-7.4 4.69-5.87 1.18-11.63.52-17.42-.23a18.56 18.56 0 0 0-14.31 3.57c-.42.32-.82.68-1.23 1Zm30-23.13c.47 1.19 1.59 1 2.54.83a93 93 0 0 0 22.3-5.84c1.76-.71 3.49-1.5 5.28-2.28Zm-83 9.31a34.86 34.86 0 0 0 17.2 6.6c-2.2-3.75-13.19-7.51-17.17-6.6Zm26.38 6.5c4.73.44 15.84-4.39 16.7-7.11-6.14.68-11.7 2.6-16.67 7.11Zm-2.23 3.49c0-.79.63-2.09-1.11-1.9-.91.1-2.61-.73-2.45 1 .08 1-1.2 3 1.29 3.16 2.14.19 2.14.19 2.3-2.26Z\" \/>\n                <path fill=\"#4778FF\" d=\"M223.13 184.78c-.15-1-.3-2-.47-3q-.85-5.16-1.73-10.32c-1-6.07.17-11.88 2.38-17.47 4.83-12.19 14.15-19.63 26.15-24.11.69-.25 1.42-.41 2.13-.59.09 0 .2.08.49.22a37.3 37.3 0 0 0-1 3.84c-.7 4.29-1.31 8.6-1.93 12.9a49.68 49.68 0 0 1-14.24 28.85c-2.79 2.78-5.48 5.65-8.44 8.46.78-7.48 2.09-14.93 5.06-21.85s6.79-13.51 10.46-20.6a88.22 88.22 0 0 0-12.68 20.58c-3.26 7.35-4.53 15.22-5.38 23.18ZM238.59 130.2c1.32-1.34 3.24-2 3.49-4.43a3 3 0 0 1 4.05-2.31 3.2 3.2 0 0 1 2 4.28 3.08 3.08 0 0 1-4.54 1.6 2 2 0 0 0-3.1.36 18.84 18.84 0 0 0-2.91 4.32 4.59 4.59 0 0 1-2.66 2.49 20.18 20.18 0 0 1-.25-4.6c.82-4.61-.53-8.77-2.05-13-4.27-11.89-1.6-22.61 6-32.34a39 39 0 0 1 12.68-10.62c.53-.28 1.11-.46 2-.81-.12 1.39-.3 2.46-.29 3.52 0 4.46.15 8.92.16 13.38a45.35 45.35 0 0 1-9.34 27.45c-2.15 2.94-4.57 5.76-5.34 9.5-.06.32-.13.64-.19 1Zm6.4-40.08c-5.59 6.49-11.2 31.22-8.37 36.89a15.55 15.55 0 0 0 .83-3.95c.55-9.18 1.72-18.22 5.23-26.82.81-2.04 1.52-4.04 2.31-6.12ZM225.34 68.2a19 19 0 0 1-3.93-2.14c-6-5.37-11.91-10.86-17.85-16.31-.28-.26-.58-.5-.87-.74l-.3.29c1.7 1.94 3.3 4 5.13 5.8 4.16 4.09 8.43 8.06 12.66 12.08.81.77 2 1.4 1.16 2.83s-1.92.71-2.93.59c-10.35-1.25-17.14-7.45-22.17-16.06-3.09-5.28-5.6-10.75-5.53-17.07 0-1.35.47-2 1.83-1.7 11.6 2.29 21.94 6.78 29.08 16.8 2.21 3.09 2.71 6.73 3.32 10.33.29 1.66.54 3.32.81 5Z\" \/>\n                <path fill=\"#4778FF\" d=\"M233.36 178.62c8.09-9.46 15.62-19.08 21.86-29.63l-.41-.31-7.3 10.17-.47-.21c.25-.87.54-1.73.74-2.6.94-4.24 1.91-8.46 2.76-12.72a4.45 4.45 0 0 1 2.2-3.4c3.34-2 6.56-4.1 10-6.3 1.22 8.39-.23 16.49-3.5 24.37s-9.38 13.48-16.62 17.94l.43.53a12.72 12.72 0 0 0 1.59-.73 40.18 40.18 0 0 0 13.56-13.35c.77-1.26 1.16-2.75 1.94-4a4.15 4.15 0 0 1 2-1.51 35.59 35.59 0 0 1 4.3-1c-.6 1.59-1 2.86-1.54 4-3.75 8-9.34 14.06-17.86 17a22 22 0 0 1-2.16.55 2.74 2.74 0 0 0-2.24 1.79c-.72 2-3.44 2.69-4.82 1.19s-2.46-2.15-4.46-1.78ZM210.07 100.62c8.32 5.33 16.44 10.86 21.81 19.44.78 1.24 1.05 2.81 1.72 4.7-.92-.41-1.3-.72-1.69-.73a5 5 0 0 0-2.47.2c-2.44 1.42-4.46.65-5.29-2.07a2.74 2.74 0 0 0-1.31-1.59c-8.23-3.45-13.77-9.8-18.59-17-1.8-2.68-3.64-5.34-5.52-8.11a3.61 3.61 0 0 1 1-.41c11.13-1.21 21.17 1 29.14 9.46a4 4 0 0 1 .9 2.42c.11 2.44 0 4.89 0 7.78-5.51-6.24-11.88-11.21-19.7-14.09ZM4.99 115.41c2.09.1 3.85.28 5.21 1.58 8.79 8.34 16.2 17.76 21.05 28.91 2 4.65 3.67 9.56 3 14.93-.35 2.69.07 5.47.16 8.22 0 .83.14 1.66.21 2.49l-.45.22a8.35 8.35 0 0 1-1.32-1.55q-13.86-26.74-27.51-53.53a8.93 8.93 0 0 1-.35-1.27ZM50.39 202.5c-2.63-1.48-4.92-2.64-7-4.07-.62-.42-.86-1.56-1.05-2.43a131.38 131.38 0 0 1-2.87-28.45 79 79 0 0 1 2.09-19.75c2.37-9.07 6.66-16.78 15.59-21a25.42 25.42 0 0 1 2.56-1 4.54 4.54 0 0 1 1.05 0c-.5.57-.79.93-1.11 1.24a46.53 46.53 0 0 0-14.12 27.92 87.61 87.61 0 0 0 2.34 33c.7 2.8.69 5.77 1.15 8.64.26 1.83.81 3.6 1.37 5.9Z\" \/>\n                <path fill=\"#4778FF\" d=\"m231.93 94.74-2.42-7.34-.46.07c1.21 5.36 3.44 10.69.17 16.67-.47-.71-.78-1.64-1.43-2.1-2.55-1.79-5.18-3.5-7.85-5.12-.89-.53-1.6-.93-1.64-2.12-.28-8.49.73-16.76 4-24.67.8-1.92 1.06-2 2.9-.93 5.16 2.94 8.32 7.66 11.43 12.51 1.55 2.43 1.74 4.33-.4 6.43a15.43 15.43 0 0 0-2.15 3.29c-.62 1.07-1.15 2.2-1.73 3.3ZM29.88 112.54c-1-2.31-2.13-4.62-3.12-7a1.92 1.92 0 0 1 .22-1.29C32.3 91.62 38.9 79.76 48.55 69.89a47.68 47.68 0 0 1 25.23-13.42 6.52 6.52 0 0 1 2.56 0q-33.35 19.73-45.81 56.2ZM224.84 25.04c2.27 7.64 5.85 14.79 6.15 22.82a40.51 40.51 0 0 1-.29 4.79c-.09 1.12-.25 2.24-.39 3.47l1.51.12a2.88 2.88 0 0 1 2.88 2.26c.4 1.55 0 3.08-1.47 3.65a4.92 4.92 0 0 0-2.71 3c-.4.86-.94 1.67-1.48 2.62 1.47.59 2.47.46 3.35-1a2.87 2.87 0 0 1 3.6-1.23 3.06 3.06 0 0 1 2.2 3.13 3 3 0 0 1-2.28 3.07 2.82 2.82 0 0 1-3.65-1.45c-.79-1.66-1.85-1.75-3.35-1.32a6.49 6.49 0 0 1-1.76 0c.27-.49.53-1 .82-1.48a35.56 35.56 0 0 0 2.28-4c.16-.37-.57-1.13-.89-1.71-.34.34-.83.63-1 1a18.92 18.92 0 0 1-1.73 3.82c-.27-1.36-.63-2.7-.8-4.07a26.62 26.62 0 0 0-3-10.27 4.15 4.15 0 0 1-.41-2V37.7h-.68c-.32 3.74-.65 7.48-1 11.42-1.84-1.72-3.62-3.34-5.35-5a1.45 1.45 0 0 1-.21-1.12 32.8 32.8 0 0 1 8.93-17.61 3.29 3.29 0 0 1 .73-.35ZM34.22 151.8c-6.73-22.6-12.9-45.35-24.23-66.42 1.12 1 2.3 1.91 3.36 3 6.75 6.66 11.36 14.71 15 23.36a93.19 93.19 0 0 1 7.25 28.81c.31 3.73-.51 7.56-.81 11.35ZM31.28 87.87c-1-3.34-3.19-5.87-2.76-9.41a88.52 88.52 0 0 1 17.89-43.94c.4-.52.87-1 1.31-1.49l.41.18c-.48 2-1 4-1.45 6-2 8.17-3.81 16.37-6 24.48-.7 2.67-2.31 5.08-3.32 7.68-2.01 5.29-3.93 10.65-6.08 16.5ZM62.71 113.79a8.73 8.73 0 0 1-.88.94c-7.45 5.83-12.65 13.33-16.91 21.72-4.61 9.08-6.32 18.63-6.28 28.65v12.16c-1.94-1.74-3.24-3.45-3.27-5.9 0-4.35-.27-8.7-.09-13 .37-8.63 1.18-17.23 4.21-25.43 2.55-6.93 6.44-12.88 13.1-16.57a18.55 18.55 0 0 1 10.12-2.57ZM17.91 189.84c9.78-.08 45.64 20 52.42 29.29-8.34 1.41-46.79-20.02-52.42-29.29ZM40.99 197.42c-13.93-9-25.78-20.52-37.9-32.28a4.83 4.83 0 0 1 1.3-.06c10.86 3.55 20.92 8.55 29.38 16.41.67.62 1.25 1.35 2 1.92a13.26 13.26 0 0 1 5.12 10.17 22.1 22.1 0 0 0 .7 3.44Z\" \/>\n                <path fill=\"#4778FF\" d=\"M39.04 185.39c-.36-.33-.74-.65-1.07-1a70.67 70.67 0 0 0-16.18-12.87 23 23 0 0 1-5.35-4.74c-4.65-5.41-9.14-11-13.67-16.49a5.14 5.14 0 0 1-.65-1.2c-.06-.13 0-.31 0-.7a11.18 11.18 0 0 1 1.27.47 105.19 105.19 0 0 1 34 28.65c1.85 2.39 1.9 4.99 1.65 7.88ZM25.91 103.55c-1-3.92-1.93-7.51-2.92-11.07a210.3 210.3 0 0 0-10.13-28.74 6.86 6.86 0 0 1-.27-1.46 8.73 8.73 0 0 1 1.59-.24 5.35 5.35 0 0 1 4.46 2.68 117.71 117.71 0 0 1 12.59 26 3.12 3.12 0 0 1 0 2.11c-1.49 3.33-3.09 6.61-4.67 9.9a5.68 5.68 0 0 1-.65.82ZM62.99 73.26a68.74 68.74 0 0 0-19.44 23.63c-4.76 9.21-7.2 19.13-8.69 29.35l-.55-.11c-1.06-3.46-2.47-6.87-3-10.41-.3-1.91.59-4.16 1.37-6.08A119.28 119.28 0 0 1 48.51 81.3a23.76 23.76 0 0 1 12.68-8.29 9.82 9.82 0 0 1 1.63-.21ZM4.81 96.1c2.07 1.74 4.39 3.26 6.18 5.26a110.89 110.89 0 0 1 9.65 12c1.73 2.58 2.52 5.84 3.54 8.86 1.65 4.86 3.14 9.78 4.68 14.67a2.57 2.57 0 0 1-.07 1.82c-.3-.41-.64-.81-.9-1.25a118.66 118.66 0 0 0-13.79-18.1c-1.9-2.13-3-5.11-4.11-7.82-1.88-4.35-3.54-8.8-5.27-13.22a11.52 11.52 0 0 1-.4-1.89ZM69.13 45.2c-1.24.89-2.5 1.75-3.72 2.67-8.27 6.28-14.68 14.24-20.33 22.85-4 6.17-7.93 12.44-11.88 18.66-.14.23-.24.49-.37.74l-.62-.35c.35-1.37.67-2.75 1.06-4.12a95.73 95.73 0 0 1 7.78-19.73C46 56.79 53.8 50.8 63.22 46.77c1.86-.79 3.79-1.41 5.69-2.11ZM232.72 184.63c-.8 1.85-1.55 3.54-2.27 5.25-1.33 3.15-2.61 6.33-4 9.45a2.25 2.25 0 0 1-1.65 1.07c-2.56 0-5.13-.18-7.7-.31a9.41 9.41 0 0 1-1.21-.25l6.45-6.94-.37-.36c-2.11 2-4.3 4-6.29 6.15a5.65 5.65 0 0 1-3.92 2.05 34.21 34.21 0 0 0-5.13 1.16c-.76-6.89 16.87-18.7 26.09-17.27ZM60.99 210.09c-2.81-2-5.77-3.92-8.37-6.2-1.05-.92-1.48-2.67-1.91-4.13a38.73 38.73 0 0 1-.56-19.51 49.19 49.19 0 0 1 6.29-15.59c-3.12 15.61-2.56 30.8 4.55 45.43Z\" \/>\n                <path fill=\"#4778FF\" d=\"M58.16 185.7a48.91 48.91 0 0 0 9.14 20 79.84 79.84 0 0 0 15.69 15.42l-.22.51c-1.83-.18-3.66-.38-5.49-.53-2.69-.22-4.73-1.57-6.74-3.3-3.55-3.08-7.16-6-9.42-10.27-3.52-6.69-4.41-13.75-3.64-21.13a1.78 1.78 0 0 1 .28-.57ZM42.4 60.86c.86-3.53 1.63-7.09 2.63-10.58a8.9 8.9 0 0 1 2-2.78c7-8.3 15.21-14.81 25.62-18.27a37.29 37.29 0 0 1 6.36-1.47C64.91 36.71 52.6 47.53 42.9 61.21ZM55.24 100.85a14.6 14.6 0 0 1-.86 1.38c-4.83 6-8.08 12.84-10.83 20-.77 2-2.08 3.8-2.94 5.79-1.19 2.77-2.18 5.63-3.26 8.45-.14.35-.26.71-.51 1.38a6.52 6.52 0 0 1-.68-1.18 26.14 26.14 0 0 1 1.37-16.47c3.26-8.28 9.1-14.28 16.48-18.95a7 7 0 0 1 1.23-.4ZM243.33 122.02c1.8-2.9 3.77-5.71 5.35-8.73a68.66 68.66 0 0 0 4.39-10 18.29 18.29 0 0 0 .66-6.73c-.16-2.88 1.35-4.68 3.54-6.76a27.74 27.74 0 0 1-.29 19.51c-2.47 6.3-6.81 10.92-13.33 13.12ZM224.43 125.32c2.28 4.3 4.46 8.49 6.72 12.64a2.06 2.06 0 0 1-.41 2.84c-1.8 1.89-3.43 3.95-5.28 6.11-2-2.33-1.05-5.32-2.25-8.15-.08 1.58-.13 2.78-.21 4.39-1.71-1.9-3.16-3.46-4.55-5.08a1.33 1.33 0 0 1-.18-1.12 35.66 35.66 0 0 1 5.79-11.41 1 1 0 0 1 .37-.22ZM29.37 166.73c-.54-.48-1.07-1-1.63-1.44-4.46-3.64-9-7.2-13.38-10.94a58 58 0 0 1-5.86-6c-2.59-3-5-6.07-7.52-9.13-.37-.46-.66-1-1-1.48l.33-.35a13.84 13.84 0 0 1 1.47.91c7.11 5.74 14.24 11.45 21.27 17.28a14.19 14.19 0 0 1 3 3.88c1.33 2.25 2.43 4.63 3.63 6.95ZM185.28 54.8a20.27 20.27 0 0 1 7.75-2.74c.43-.06 1.18.78 1.48 1.36a44.15 44.15 0 0 0 8.05 10.8 24.23 24.23 0 0 0 12.71 6.64 16 16 0 0 1 4.17 1.3c-1.51-.09-3-.14-4.51-.28-9.05-.84-16.22-5.42-22.75-11.33-2.14-1.94-4.44-3.71-6.9-5.75ZM45.75 167.26c0-1.81-.07-3.63 0-5.43.3-7.27 1.53-14.37 5-20.84a21.59 21.59 0 0 1 4.83-5.43 32.87 32.87 0 0 1 6.27-4.25c-8.3 10.73-12.58 23.13-15.48 36.12ZM213.89 43.2c-1.74-1-3.37-1.84-4.83-2.88a2.46 2.46 0 0 1-.68-1.91c.26-3.12.72-6.23 1-9.35.13-1.51 0-3 0-4.88.92.49 1.63.81 2.26 1.23 1 .67 2 1.37 2.89 2.13 4 3.29 3.9 3.28 1.81 7.88a47.2 47.2 0 0 0-1.72 5.24c-.24.84-.46 1.64-.73 2.54ZM206.21 82.41c.42.27.81.56 1.24.78 2.33 1.21 4.63 2.46 7 3.58 3.62 1.7 2.88 1 2.94 4.46v4.35a5.37 5.37 0 0 1-1.56-.2c-2.18-1.18-4.61-.94-6.92-1.4-.76-.15-1.91-.77-2-1.35-.62-3.27-1-6.6-1.42-9.91ZM96.38 31.41a13.15 13.15 0 0 1-5.33-8.13c3.31 1.37 6.56 2.25 8.53 5.15a9.45 9.45 0 0 1 .79 3l-2.38.47a27.51 27.51 0 0 1 2.66 2.54 6.42 6.42 0 0 1 .7 2 6.55 6.55 0 0 1-2.21.49 11.34 11.34 0 0 1-8.71-6.59ZM166.17 31.81s-.05-.05-.1-.06l-2.18-.28c.19-.92.06-2.15.62-2.72a28.37 28.37 0 0 1 4.72-3.8 24.26 24.26 0 0 1 3.93-1.67 13.09 13.09 0 0 1-5.38 8.16l6.39-1.13a12 12 0 0 1-6.71 6 10.86 10.86 0 0 1-3.33.64c-1.43 0-1.81-.64-1-1.84a32.94 32.94 0 0 1 3.04-3.3ZM220.45 120.63c-6.22 1.75-17.84-5.93-19.06-12.61 2.53.28 5.25-.47 6.85 2.48s4.46 4.79 7 6.8c1.61 1.24 3.41 2.19 5.21 3.33Z\" \/>\n                <path fill=\"#4778FF\" d=\"M48.43 184.13c-3.59-7.38-.59-24.28 4.72-29-1.56 9.6-3.16 19.3-4.72 29ZM55.08 92.37c-5.75 7.95-11.59 16-17.33 23.93-.05-7.54 10.73-22.36 17.33-23.93ZM238.99 83.94c-1.07-1.84-2.12-3.59-3.09-5.38a1.54 1.54 0 0 1 0-1.26c1.36-2.48 2.79-4.91 4.37-7.66.62.93 1.21 1.72 1.69 2.58a25.74 25.74 0 0 1 1.5 3.08c1.45 3.71.8 5.29-2.8 7.18a10 10 0 0 0-1.67 1.46ZM164.74 43.42c-2.24 2.72-7.51 4.3-10.66 3.3-1.14-.36-1.11-1-.32-1.55a24.53 24.53 0 0 1 3.74-1.94 19.5 19.5 0 0 1 2.94-.68c-2.11-.79-1.55-1.77-.6-2.47a11.09 11.09 0 0 1 3.82-2.11 27.48 27.48 0 0 1 6.87-.44c-2 2.88-4.92 4.12-8 5.29Z\" \/>\n                <path fill=\"#4778FF\" d=\"M152.75 38.12c.73-1.75 1.41-3.4 2.1-5.08 3.27 1.79 4.56 5.59 3 8.07-1 1.6-1.48 1.68-2.94.49a6.77 6.77 0 0 1-.95-1c-.27-.35-.47-.76-.93-1.51-.26.9-.46 1.49-.59 2.1a5.45 5.45 0 0 1-3.31 3.88c-.92.44-1.47.18-1.9-.73a3.7 3.7 0 0 1 .68-4.29c1.09-1.21 2.4-2.23 3.72-3.43ZM93.71 37.61c3.76-.11 7.54-.5 10.56 2.3.73.69 1.85 1.56-.32 2.62a13.83 13.83 0 0 1 3.26.82 38.93 38.93 0 0 1 3.72 2.68 17.87 17.87 0 0 1-4.23.86c-2.76-.11-5.07-1.55-7.61-3.36l2.45-.68c-2.95-1.27-5.87-2.46-7.83-5.24ZM213.65 125.39c1.84 2.35 3.29 4.09 4.58 5.94a2.77 2.77 0 0 1 .29 2 28.85 28.85 0 0 1-1.29 3.4c-1.86-1.3-3.6-2.5-5.31-3.74a1.09 1.09 0 0 1-.41-.87c.63-2.12 1.33-4.23 2.14-6.73ZM229.99 181.69c2.45-.5 4.43.5 6.49 1.26a4.2 4.2 0 0 0 2.48.12c1.52-.45 2.84-.39 3.9.85a3.16 3.16 0 0 1 .31 3.82 3 3 0 0 1-3.55 1.39 2.82 2.82 0 0 1-2.35-3.12 2.26 2.26 0 0 0-1.54-2.4c-1.74-.71-3.67-1.25-5.74-1.92ZM153.99 3.2c3.21 1.15 6 5 5.77 7.82-.17 1.84-.79 2.18-2.42 1.32a7.19 7.19 0 0 1-3.35-9.14ZM109.81 2.65c2 4.11 0 9-3.78 10.06-.35.1-1.25-.37-1.25-.59 0-1.38-.36-3 .28-4.08 1.2-1.92 3-3.47 4.75-5.39ZM150.73 16.02c4.26-.28 8.2-.38 11.51 2.48a5 5 0 0 1 .79 1.4 5.86 5.86 0 0 1-1.45.7c-3.95.65-8.86-1.34-10.85-4.58ZM113.57 15.95c-2.2 3.47-8.32 5.72-11.62 4.56-1.25-.44-.87-1.13-.23-1.79a9.91 9.91 0 0 1 6.33-2.73 52.75 52.75 0 0 1 5.52-.04ZM218.99 74.94h-1.28c-1.55 0-2.83 0-3.4 2a3 3 0 0 1-4.26 1.56 3.24 3.24 0 0 1-1.49-4.37c.79-1.61 2.95-2.52 4.3-1.33 1.66 1.47 3.47 1.4 5.36 1.51a3.21 3.21 0 0 1 .79.22ZM99.99 23.52a11.07 11.07 0 0 1-.44 1.55c-.33.79-.81 1.07-1.74.59a7.54 7.54 0 0 1-3.84-8.21 1.72 1.72 0 0 1 1-.8c2 1.56 4.12 3.11 4.88 5.76a6.85 6.85 0 0 1 .14 1.11ZM169.55 15.9c1.79 3.9.25 8.23-3.31 9.77-.37.16-1.48-.33-1.51-.59-.13-1.26-.47-2.83.12-3.75a45.51 45.51 0 0 1 4.7-5.43ZM155.54 12.8c-2.08 3-8.39 2.84-12.17.42 1.85-2.11 9.87-3.43 12.17-.42ZM133.99 10.55c3.27-1.87 6.53-3.81 10.61-2.44a5.77 5.77 0 0 1 1.22.79 6 6 0 0 1-.93 1.31 9.13 9.13 0 0 1-7.11 1.69c-1.28-.15-2.55-.44-3.82-.67ZM120.99 12.98c-2.92 2.43-8.82 2.71-11.61.73-.84-.6-.95-1.24 0-1.63a13 13 0 0 1 3.9-1 14.56 14.56 0 0 1 7.71 1.9ZM144.99.36c2.7 1.07 5.27 2.26 6.74 4.91a5.89 5.89 0 0 1 .5 2.63 1.33 1.33 0 0 1-.91.87c-3.59.03-7.18-4.66-6.33-8.41ZM133.53 0c3.64.17 6.82.59 9.32 3a7.37 7.37 0 0 1 1.07 2.39 8.93 8.93 0 0 1-2.51.58c-3.63-.33-5.96-2.52-7.88-5.97ZM164.47 8.33c.58 2.11 1.18 4 1.59 5.9a3.13 3.13 0 0 1-.33 2.15 4.94 4.94 0 0 1-2.09 1.84c-.29.12-1.21-.86-1.61-1.48-1.84-2.85-.96-6.42 2.44-8.41ZM99.78 8.2c3.71 2.72 4.24 6.41 1.91 9.38-.7.9-1.49 1-2.1.2s-1.55-2.12-1.45-3.11a45.17 45.17 0 0 1 1.64-6.47ZM130.38 10.35c-2.92 2.45-9.14 1.87-11.41-.45-.84-.86-.63-1.53.44-1.7a12.93 12.93 0 0 1 4.69-.28 45 45 0 0 1 6.28 2.43ZM119.47.35c-.2 4.66-2.13 7.22-5.84 8.31-1.27.38-1.77-.09-1.69-1.28a4.59 4.59 0 0 1 .48-2c1.57-2.65 4.05-3.96 7.05-5.03ZM108.82 32.88c2.91 3.41 2.87 7.07.21 9-1 .7-1.63.71-2.37-.34a4.33 4.33 0 0 1-.4-5.09c.73-1.25 1.67-2.35 2.56-3.57ZM130.3.2c-1 3.4-5.73 6.38-9.07 5.72-1-.2-1.35-.78-.76-1.56A10.48 10.48 0 0 1 123 1.71 11.88 11.88 0 0 1 130.3.2ZM108.56 22.2c-.43 3.91-2.88 6.16-6.43 6-1.42 0-1.82-.7-1.53-2a4.66 4.66 0 0 1 .47-1.26c1.15-1.89 5.12-3.37 7.49-2.74ZM155.71 22.2c2.93-.7 7 1.25 7.85 3.74.53 1.61.08 2.27-1.59 2.31a6 6 0 0 1-6.26-6.05ZM107.04 27.76c1.57 4 .54 6.86-2.65 8.18-1.07.44-1.72.19-1.91-.84a6 6 0 0 1-.07-2.93c.74-2.16 2.58-3.3 4.63-4.41ZM157.51 27.51a45.12 45.12 0 0 1 4 4c1 1.3.67 4.23-.36 4.32a6.16 6.16 0 0 1-3.41-1.28c-1.56-1-1.88-4.82-.23-7.04Z\" \/>\n                <path fill=\"#4778FF\" d=\"M111.54 39.37a9.39 9.39 0 0 1 .09-1.19c.23-1.14.74-1.69 1.84-.76.82.7 1.66 1.38 2.43 2.13a5.17 5.17 0 0 1 1 1.35c.68 1.27.51 3.69-.39 4.14-1.5.75-2.61-.42-3.32-1.34a20.55 20.55 0 0 1-2-4.16ZM118.6 41.6c3.32.53 6.66.7 8.79 3.75a5.3 5.3 0 0 1 .45 1.89 7.33 7.33 0 0 1-1.77.28c-3.63-.32-6.84-2.79-7.47-5.92ZM155.75 49.09c-4.45 1.69-9.83 1.47-11.69-1.28 2.21-2.61 8.69-1.61 11.69 1.28ZM135.31 49.84c2.27-2.26 9.17-1.15 11.68 1.9-3.53 1.75-9.66.79-11.68-1.9ZM120.28 47.92c-3.66 3.29-7.73 2.22-11.8 1.38 1.51-2.96 9.05-3.93 11.8-1.38ZM117.29 51.79c1.93-3 8.79-4.21 11.5-2-.8 2.67-7.1 3.52-11.5 2ZM145.33 41.29a7.93 7.93 0 0 1-8 6.32c-1.09-.1-1.3-.82-.88-1.54a5.72 5.72 0 0 1 2.08-2.38c2.18-.98 4.52-1.62 6.8-2.4ZM137.51 6.5c-3 1.33-5.57 2.16-8.29.88-.55-.25-.92-.89-1.37-1.35.48-.37.9-.91 1.44-1.07 2.79-.85 5.33-.11 8.22 1.54ZM12.21 65.27c1.86 2.49 2.45 4.89 1.38 7.05l-1.81-6.93ZM132.15 49.93l-1.69-1.63c.56-.45 1.09-1.19 1.69-1.24s1 .75 1.57 1.17Z\" \/>\n                <path fill=\"#4778FF\" d=\"m193.04 217.71 30.12-7.29c-1.79.78-3.52 1.57-5.28 2.28a93 93 0 0 1-22.3 5.84c-.95.13-2.07.36-2.54-.83ZM134.23 237.01c-.16 2.45-.16 2.45-2.27 2.31-2.49-.16-1.21-2.16-1.29-3.16-.16-1.78 1.54-.95 2.45-1 1.74-.24 1.1 1.04 1.11 1.85ZM244.99 90.12c-.77 2-1.48 4.11-2.31 6.12-3.51 8.6-4.68 17.64-5.23 26.82a15.55 15.55 0 0 1-.83 3.95c-2.85-5.67 2.76-30.4 8.37-36.89Z\" class=\"cls-1\" \/>\n                <path fill=\"#4778FF\" d=\"M119.65 190.99a6.75 6.75 0 0 1-7.59 2.46c-2.1-.55-3.42-1.84-3.1-4.49-.75.13-1.33.19-1.89.33-2.32.58-4.39.8-6.14-1.53-.71-.95-2.34-1.31-3.63-1.68-1.93-.56-3.83-.94-3.93-3.56 0-.36-1-.87-1.58-1-3.35-.72-3.88-1.54-3.45-4.93a7.37 7.37 0 0 0-.27-3.69 14 14 0 0 1 .87-13.49c5.39-9 12.55-15.92 23-18.71 9.77-2.62 19-1.07 27.81 3.92 6.62 3.76 12.28 8.75 18 13.66a32.87 32.87 0 0 0 4.73 3.39 3.05 3.05 0 0 0 4.56-1.53 6.38 6.38 0 0 0-1.37-6.83 2.88 2.88 0 0 0-4.67.6 4.25 4.25 0 0 0-.44.74c-.48 1.17-1.44 1.88-2.55 1.38a3.93 3.93 0 0 1-2-2.2c-.82-3.06 1.73-6.42 5.15-7.45 7.17-2.15 13.22 2.72 15 8.79a17.14 17.14 0 0 1-18.48 21.78c-5.39-.59-10.25-2.69-15.14-4.81a42.82 42.82 0 0 0-5.09-2 6.12 6.12 0 0 0-6.91 2.56 6 6 0 0 0-.43 1.56 7 7 0 0 0 1.6.39c1.53 0 3.08-.19 4.6-.09a5.51 5.51 0 0 1 4 2.28c1.92 2.38 4 4.6 6.07 6.89 0 0 .08.11.13.11 2.84.27 4.55 2.58 6.88 3.75s2.45 2.28.73 4.27c-2.93 3.4-5.89 2.56-9.13.84a1.26 1.26 0 0 0-1.14.2 6.5 6.5 0 0 1-8.59.89 2.42 2.42 0 0 0-1.71-.09c-.92.22-1.81.88-2.71.89a60.14 60.14 0 0 1-7.35-.29 4.59 4.59 0 0 1-3.84-3.31Zm-31.38-22.13.52.1c.19-.52.44-1 .58-1.55a10.75 10.75 0 0 1 4.34-6 18.65 18.65 0 0 1 9.79-3.29c6.79-.52 12.48 2.25 17.87 5.91a3.15 3.15 0 0 1 1.17 1.61 2.52 2.52 0 0 0 2.39 2.22c1.53.18 3 .8 2.5 2.9 0 .17.26.42.4.63h.51a11.5 11.5 0 0 0 .2-2.46 15.73 15.73 0 0 0-5.92-10.14 25.17 25.17 0 0 0-21.58-5.38c-4.94.93-9.15 3.3-11.67 7.94a10.76 10.76 0 0 0-1.1 7.51Zm41.43-1.66.43-.12a24.42 24.42 0 0 0 .23-3 12.34 12.34 0 0 0-2.62-7.13c-5-6.6-12-9.14-20-9a18.28 18.28 0 0 0-12 4.38 15.57 15.57 0 0 0-1.31 1.38l.21.41a26.58 26.58 0 0 1 20.51-1.07c7.01 2.47 12.2 6.86 14.55 14.15Zm2.42-4.31c.09-.65.19-1.19.23-1.73a12.62 12.62 0 0 0-3.28-9.13c-5.25-6.32-15.71-9.3-23.63-6.69-1.46.48-2.85 1.2-4.27 1.8 14.03-1.94 25.14 1.26 30.95 15.78Zm2.2-3.07a7.89 7.89 0 0 0 .25-2.73 22.9 22.9 0 0 0-2.27-6.37c-4.19-6.52-13.31-9.52-20.88-8.32-.16 0-.29.23-.66.53 11.39.92 20.4 4.73 23.56 16.92Zm-25.46 28c2-.21 3.75-1.18 4.24-2.49.68-1.83-1-2-1.89-2.72a4 4 0 0 0-5.45.68 2 2 0 0 0 .2 2.93 16.93 16.93 0 0 0 2.9 1.65Zm17.74-6.6a19.2 19.2 0 0 0-3.28 1.68c-1.28 1-1.05 2.38.32 3.21a5.33 5.33 0 0 0 5.89-.81 1.88 1.88 0 0 0-.39-3.16 18.64 18.64 0 0 0-2.54-.87Zm-4.42-39.42c7.76 3.09 13.63 7.62 14.07 16.75 1.48-3.6.39-6.75-1.56-9.66-2.7-4.01-9.26-7.69-12.51-7.04Zm22.21 28.21a10.32 10.32 0 0 0 9.84-4.42 6.42 6.42 0 0 0-.18-7.31c.23 6.72-3.69 9.84-9.66 11.78Zm-1.73-1.62c4.32.12 8.38-2.55 9.53-6 .86-2.59.55-5-.89-6.15.44 6.45-3.08 10.03-8.64 12.2Zm-23.4 11.64a18.77 18.77 0 0 0 2.89-1.11 2 2 0 0 0 .94-1.58 1.91 1.91 0 0 0-1.36-1.27 14.24 14.24 0 0 0-4.27.5c-.72.2-1.24 1.09-1.84 1.67a23.1 23.1 0 0 0 2 1.59c.29.24.76.16 1.64.25Zm37.38-19.34c.22 6.13-3.5 9.06-9.12 10.84a9.43 9.43 0 0 0 9.68-4.71c1.09-2.15.94-4.68-.56-6.08Zm-8.24-7.08c1 6.53-2 10.45-7.54 13.1 2.89.31 6.62-2.13 8.19-5.09a7.07 7.07 0 0 0-.65-7.96Zm-14.18 30.45a7 7 0 0 0 1.75 1.26 17.43 17.43 0 0 0 3.32.66c.46.06 1.12.11 1.37-.15a1.72 1.72 0 0 0 .17-1.39 4.62 4.62 0 0 0-4.22-3c-1.31.13-2.12.81-2.39 2.67Zm-15.87-20c-1.81 0-3.32.9-3.34 2s1.54 2.2 3.22 2.24 3.3-1 3.32-2.07-1.43-2.13-3.2-2.15Zm-22.85 2.06a8.71 8.71 0 0 0-2.18.79 2.45 2.45 0 0 0-1.11 1.67c0 .54.76 1.21 1.35 1.49a4 4 0 0 0 4.18-.53 1.57 1.57 0 0 0-.22-2.85 11.53 11.53 0 0 0-2.02-.55Zm56.37 6.81c2.41.63 6.12-1.23 7.67-3.85 1.26-2.14 1.22-4.61-.08-5.92-1.35 6.79-2.36 6.86-7.59 9.79Zm-51 6.73a17.68 17.68 0 0 0-1.51-2.08c-.45-.45-1.08-1-1.62-1a6.56 6.56 0 0 0-2.76.73c-1.35.69-1.31 1.88.06 2.54a6.17 6.17 0 0 0 5.81-.17Zm15.48 7.62c1.47-.6 2.64-1 3.75-1.56a1.23 1.23 0 0 0 .55-1 2 2 0 0 0-2.76-1.52 7.39 7.39 0 0 1-1.67.34c-1.32.1-2.22.78-1.87 2.05.19.71 1.27 1.14 1.98 1.71Zm28.93-36c1.89 6.22-.54 10.53-5.29 13.92 5.9-1.11 9.82-9 5.27-13.92Zm-7.29 7.79c4.15-5.44-1.64-14-6.39-15.28 4.83 4.15 7.84 8.79 6.39 15.28Zm-6.12 17.2c1.22 1.94 5 2.94 6.74 1.77a1.37 1.37 0 0 0 .25-1.33c-1.25-1.65-5.19-1.89-7.01-.44Zm-6.16 2.3c1.79 0 4.2-1.24 4-2.24-.27-1.56-1.72-1.65-2.83-1.55s-2.49.5-3 1.26c-.51.91.84 2.51 1.81 2.53Zm14-15.46c4.85-1.86 7-9.74 2.36-13.9 2.16 5.31 1.41 9.87-2.41 13.9Zm-37.43 15.09c1.52-.7 3.08-1.35 4.57-2.14.34-.18.43-.82.64-1.26-.45-.19-1-.63-1.33-.53a38.25 38.25 0 0 0-4.78 1.59 1.52 1.52 0 0 0-.65 1.35c.13.42.84.61 1.55.99Zm12.21-2.51c1.51-.46 2.76-.78 4-1.25a1.27 1.27 0 0 0 .65-1 1.31 1.31 0 0 0-.94-.81 12.18 12.18 0 0 0-3.72.07 9.39 9.39 0 0 0-2.58 1.65Zm-11.92-13.49c-1 .34-3 .08-2.9 1.73s1.89 1.56 3.16 1.51 2.85-.14 2.84-1.56-1.68-1.5-3.1-1.68Zm29.85 28.09c1.26-.83 2.45-1.3 3.12-2.17.46-.61-1.39-1.72-3.12-1.58-1.2.09-2.92 0-2.91 1.6 0 .64 1.71 1.29 2.91 2.13Zm-6.93-1.81c-1.89-.35-4.07.59-4.19 1.84-.14 1.52 1.06 2 2.21 2.42s2-.12 2-1.45Zm17.58 1.59c1.58-.42 3-.46 3.48-2 .27-.84-1.64-1.78-3.35-1.55-1.11.15-2.8.1-2.67 1.64.05.72 1.65 1.28 2.54 1.89Zm-3.41-29.5c3.16-1.69 3.47-10-.93-13.16.61 2.07 1.65 4.23 1.79 6.45s-.53 4.6-.86 6.69Zm22.59 4.85c-.69 1.73-1.1 3.64-2.15 5.1s-2.79 2.51-4.23 3.74c4.94-.28 8.46-5.28 6.38-8.86Zm-57.71 18a22.87 22.87 0 0 0-3.67-1 2.13 2.13 0 0 0-1.61.82c-.26.37-.16 1.54 0 1.59a8.49 8.49 0 0 0 3.5.61c.65-.16 1.13-1.24 1.78-2.07Zm2.15-3.79c1.7 1.15 4.33.8 6.25-.67a5.38 5.38 0 0 0 1-1.44c-.62-.17-1.35-.64-1.83-.46-1.79.66-3.47 1.57-5.42 2.52Zm44.69 11.26a5.53 5.53 0 0 0 1.3-.09c.55-.23 1.05-.55 1.58-.83-.43-.46-.79-1.23-1.29-1.34a20.71 20.71 0 0 0-4-.32 1.21 1.21 0 0 0-.92.76 1.29 1.29 0 0 0 .69 1 25.21 25.21 0 0 0 2.64.77Zm-57.81-14.28a10.37 10.37 0 0 0-3 .07c-.59.2-.93 1.11-1.37 1.71a21.6 21.6 0 0 0 2.63 1.62c.11.05.77-.93 1.08-1.49a15.11 15.11 0 0 0 .66-1.96Zm24.63 5.07a15.47 15.47 0 0 1-2.66-1.35c-1.12-.89-2.05-.42-3 .19s-.88 1.25.16 1.62a7.14 7.14 0 0 0 5.5-.51Zm-1.28 9.72-5-1.7c-.54-.19-1.08-.35-1.63-.53.21.65.23 1.49.66 1.9a5.18 5.18 0 0 0 5.97.28Zm-6.71-18.73.06-.53a14.67 14.67 0 0 0-3.07-1.73c-.68-.21-1.6.26-2.37.53-.17.06-.33.79-.25.84a4.48 4.48 0 0 0 1.76.85 38.4 38.4 0 0 0 3.87-.01Zm4.33-3.86c-.49-2.57-1.78-3.34-3.85-2.47-.86.35-1.08 1-.29 1.51a5.3 5.3 0 0 0 4.14.91Zm45.7 5.9a5.82 5.82 0 0 0 4.26-3.34c.66-1.34 1.19-2.8 0-4.4a23.08 23.08 0 0 1-1.38 4.14 26.25 26.25 0 0 1-2.88 3.55Zm-15.91 10.8c.11-.14 1-1 .91-1.1a19.82 19.82 0 0 0-2.22-2.27c-.43.45-1.25.94-1.21 1.34.1.96.25 2.24 2.52 1.98Zm7.42 7c-1.63-.63-3.13-1.26-4.67-1.77a1.51 1.51 0 0 0-1.17.44c-.14.15 0 .77.16 1 1.01 1.09 4.32 1.29 5.68.24Zm-14.84-12.13a20.4 20.4 0 0 0 3 1.23 1.87 1.87 0 0 0 1.6-.46 1.89 1.89 0 0 0 0-1.67 1.59 1.59 0 0 0-1.39-.62 26.75 26.75 0 0 0-3.21 1.43Zm-18 7.75a16.82 16.82 0 0 1-2.77.17c-.88-.11-1.72-.51-2.6-.7a1 1 0 0 0-.88.29 1 1 0 0 0 .08.89c1.12 1.42 4.86 1.13 6.25-.74Zm15.38-7.48a20.73 20.73 0 0 0-3 .53 1.3 1.3 0 0 0-.43 1.19 11.47 11.47 0 0 0 1.59 1.84 6.39 6.39 0 0 0 1-1.13 20.63 20.63 0 0 0 .87-2.52Zm-6.53-7.48a9.67 9.67 0 0 0-1.12-1c-1.7-1.1-2.55.38-3.57 1.24-.2.17-.21.57-.3.86a2.52 2.52 0 0 0 .9.22c1.05-.15 2.11-.33 3.15-.58.33-.2.57-.52.97-.83Zm-26.25 8.41a30.55 30.55 0 0 0 3.38-.05c.35 0 .93-.62.9-.89a1.49 1.49 0 0 0-.89-1c-1.34-.44-2.59-.19-3.36 1.85Zm24.53-12c-2.39-1.33-4.18-1.29-5.46 0a5 5 0 0 0 5.49-.05Zm6.44 22.62c-2.14-1-4.86-.58-5.67.7 2.02.81 4.5.54 5.67-.7Zm-40.62-18.92c2.23.75 5.09 0 6.12-1.44a8.71 8.71 0 0 0-6.12 1.41Zm8.22-4.51c2.06.89 4.63.59 5.71-.65-1.96-1.06-4.86-.73-5.71.62Zm-3.43 6.15c2.23.42 4.89-.49 5.57-1.8a6.33 6.33 0 0 0-5.57 1.77Zm1.8 7.35c-1.24-.14-2.06-.28-2.89-.3a1 1 0 0 0-.81.44 1.16 1.16 0 0 0 .22 1c.64.39 1.45.95 2.06.81s.83-1.09 1.42-2.02Zm42.88 10.78-4.62-1.54a2.78 2.78 0 0 0-.91 0c.07.34 0 .78.24 1 1 1.06 4.06 1.26 5.29.51Zm-16.21-12.85c-1.81.06-3.28.46-4.25 1.9-.17.25 0 .71 0 1.07.3 0 .69.08.88-.08 1.09-.84 2.11-1.77 3.37-2.89Zm21.15 5.4c1.29 1.93 1.86 2.07 3.89.95-1.3-1.35-2.69-1.65-3.89-.92Zm-33.28-15.29c-1.26-.57-2.51-1.17-3.79-1.69-.22-.08-.57.16-.86.26.1.29.12.7.33.86a4.48 4.48 0 0 0 4.32.57Zm51.86 3.57c2.23-1.45 3.05-4 2-5.56Zm-48.32-2.63 4 .83.13-.66c-1.31-.35-2.36-1.97-4.13-.17Zm-4.34-7.9h4.71c-1.79-1.32-2.98-1.31-4.71 0Zm26.24 25c-.35.73-.94 1.42-.78 1.7.62 1.11 1.68 1.27 3 .85Zm-48.37-18.88c-1.06.65-1.36 1.42-.59 2.15.4.39 1.19.36 1.8.52l.2-.51Zm20.52-5.27.37-.43c-.28-.4-.57-1.14-.84-1.13a6.76 6.76 0 0 0-1.91.62l.15.62Zm18.24 26.27.38-.71a8.46 8.46 0 0 0-1.69-1c-.21-.06-.62.52-.93.8a5.82 5.82 0 0 0 1.16 1.21c.25.16.71-.18 1.08-.3Zm-26.75-3 3 1c-.87-2.27-1.15-2.42-3-1.04Zm20.48 0-.09-.58c-.53 0-1.21-.2-1.55.05s-.39 1-.57 1.47l.53.26Zm-14.26-10.86.74.51c.45-.62.92-1.23 1.33-1.88 0 0-.44-.4-.68-.61Zm-8.58-5.58.05.56h3.11v-.56Zm67.7-19.07 3.34-1.74c-1.76-.48-2.76-.02-3.34 1.74Zm2.24 2.93h3.95c-1.61-1.29-2.68-1.25-3.95 0Zm-77.84 20.7.24-.74-2.23-.8a3.81 3.81 0 0 0-.13.75c.69.3 1.41.54 2.12.79Zm47.24 11.43-2.64-.74c.23 2.09 1.08 1.84 2.64.74ZM162.58 90.57c-1.83-1.82-.2-3.71 0-5.77-.44.32-.71.5-1 .69-1 .76-1.52.31-1.57-.73a12.56 12.56 0 0 1 .28-2.72c.29-1.58 1.36-2.95.18-4.82-.46-.74.68-2.5 1.1-3.8h.64c.25.58.85 1.28.7 1.74-.92 2.82 1.31 5.49-.09 8.72l6.07-3.9c1.65 2.81-1.9 8.56-6.31 10.59ZM143.88 106.29c1-4.71 5.91-7.75 9.86-6.58a1.21 1.21 0 0 1 .65 2.13 7.84 7.84 0 0 1-2.88 2.33c-2.37.87-4.87 1.38-7.63 2.12ZM150.86 80.2l-.28-4.28.53-.18 2.78 2.23v-4.3c2.16.68 3.09 2.85 1.88 4.34a2.24 2.24 0 0 0-.32 2.58 8.29 8.29 0 0 1 .43 2.85 1.93 1.93 0 0 1-.79 1.36c-.19.13-1-.27-1.23-.61-1.07-1.31-2-2.69-3-4ZM142.51 82.56a6.59 6.59 0 0 1 8.19 6.27c0 1.26-.9 1.72-1.84 1.27a9.35 9.35 0 0 1-3.38-2.4 39.37 39.37 0 0 1-2.97-5.14ZM143.71 91.89c4.16-1.69 8.23.35 9.21 4.28.31 1.21-.39 2-1.64 1.81a4.47 4.47 0 0 1-2.23-.8c-1.82-1.65-3.5-3.45-5.34-5.29ZM171.22 88.2c.44 4.14-3.89 7.78-7.69 6.67a1.2 1.2 0 0 1-.7-2 10.76 10.76 0 0 1 3.12-2.79 37 37 0 0 1 5.27-1.88ZM173.82 106.74c-3.65 1.22-8.61-1.5-9.21-4.86a1.74 1.74 0 0 1 1-1.4 2.62 2.62 0 0 1 1.77.31c2.71 1.23 4.37 3.65 6.44 5.95ZM156.74 83.63c3.32 1.88 5 7.61 3.42 10.46-.59 1.06-1.64 1.07-2.21-.14a11.77 11.77 0 0 1-1.16-3.9c-.19-2.04-.05-4.11-.05-6.42ZM137.62 96.35l4.41-1.93-1.78-1 .26-.74a4.89 4.89 0 0 1 1.88.06c.44.19.64.9 1 1.32a14.83 14.83 0 0 0 1.28 1.22l1.2 1.09c-.47.36-.89.89-1.42 1-2.77.89-5.14.54-6.83-1.02Z\" \/>\n                <path fill=\"#4778FF\" d=\"M174.28 81.6c-.26 3-2 5.22-4.36 5.81-.81.19-1.58.32-1.36-.94.37-2.08 3.43-4.74 5.72-4.87ZM173.08 99.78c-3 .76-5.29.49-7.15-1.53a4.6 4.6 0 0 1-.59-1.45c.45-.14 1-.5 1.36-.38a49.91 49.91 0 0 1 5.05 1.84c.48.21.76.85 1.33 1.52ZM150.37 83.71c2.82.48 5.13 2.79 5.22 5.09a4.53 4.53 0 0 1-.43 1.37 3.92 3.92 0 0 1-1.22-.43c-1.87-1.54-3.49-3.21-3.57-6.03ZM176.54 92.7c-1.43 2.49-4.08 3.9-6.43 3.34-.4-.1-1-1-.89-1.26.83-1.73 5.29-2.98 7.32-2.08ZM168.3 110.04c-2.65-1-4.79-1.82-5.61-4.27a6.39 6.39 0 0 1 0-2c.6.17 1.37.17 1.78.54a33.32 33.32 0 0 1 3.36 3.57c.3.45.25 1.17.47 2.16ZM149.84 109.33c1.47-1.94 2.89-3.93 4.44-5.8.3-.36 1.12-.28 1.7-.4a4.83 4.83 0 0 1-.12 1.72 9 9 0 0 1-5.4 5ZM151.7 91.57c3-.17 4.51 1.23 4.55 3.44 0 .41-.17 1.16-.35 1.18-.51.07-1.31 0-1.54-.28-.98-1.38-1.79-2.88-2.66-4.34ZM168.44 75.01c-.68 1.82-1.16 3.36-1.85 4.8-.2.43-1 .58-1.53.86a5.52 5.52 0 0 1-.59-1.61c-.08-2.31 1.18-3.72 3.97-4.05ZM157.41 76.1c2.49 1.29 3.08 4.38 1.53 6-.2.21-.72.43-.84.34-.41-.34-1-.81-1-1.23-.02-1.64.18-3.28.31-5.11ZM139.29 85.86c2.81-.59 4.54.35 5.17 2.42a5.1 5.1 0 0 1-.05 1.6c-.6 0-1.42.18-1.74-.14-1.14-1.1-2.11-2.39-3.38-3.88ZM150.82 80.14l-.86 2.28a11.71 11.71 0 0 1-2.05-2.44c-.29-.63.06-1.57.13-2.38l.44-.12 2.38 2.71ZM178.42 84.66a4.52 4.52 0 0 1-4.94 2.5c.06-2.09 1.86-3.03 4.94-2.5ZM148.63 98.57a3.8 3.8 0 0 1-5.47 1.18c.99-1.55 3.36-2.09 5.47-1.18ZM177.46 99.89a4.65 4.65 0 0 1-4.81-2.71 3.46 3.46 0 0 1 4.81 2.71ZM176.84 87.59c-.07 2.39-1.22 3.6-3 3.65-.35 0-.95-.15-1-.36-.11-.36 0-1 .21-1.2 1.12-.72 2.31-1.29 3.79-2.09ZM170.62 80.62c.55-.79 1.09-1.59 1.74-2.55.91 1.75.5 2.43-1.74 2.55ZM173.22 103.39c-.73-.43-1.48-.83-2.18-1.32-.08-.05.14-.54.22-.83l2.48 1.18ZM142.39 103.46a5.33 5.33 0 0 1-.33-.79c.73-.51 1.47-1 2.21-1.5.15.25.46.72.44.73-.72.52-1.45 1-2.32 1.56ZM144.93 79.45c2.15-.24 2.66.45 1.95 2.44ZM170.81 76.46l-1.65 2.74c-.73-1.88-.48-2.37 1.06-3.08ZM147.55 74.59a4.59 4.59 0 0 1 .75-.26l1.79 2.16a4.2 4.2 0 0 1-.75.44c-.59-.73-1.12-1.45-1.79-2.34ZM154.64 109.56c.38-.81.74-1.63 1.18-2.4 0-.08.55.11.85.18l-1 2.62ZM141.49 79.26c1.68-.5 2.39.22 2.8 1.66-1.59.46-2.16-.48-2.8-1.66ZM147.73 108.26c-.17-.52-.22-.62-.21-.62l2.23-1.48.44.79ZM159.35 75.33c-1.27-1.26-.64-2.19-.07-3.31 1.39 1.18 1.01 2.1.07 3.31ZM164.7 110.13c-1.62.77-2.15 0-2.42-1-.06-.2.27-.5.43-.76Z\" \/>\n                <path fill=\"#4778FF\" d=\"M99.71 171.03h3.14v.56h-3.11ZM91.81 175.59c-.71-.25-1.43-.49-2.12-.79a3.81 3.81 0 0 1 .13-.75l2.23.8ZM139.05 187.02c-1.56 1.1-2.41 1.35-2.64-.74Z\" class=\"cls-1\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours<br>Per\u00fa<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours familiares -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-familiares\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"27.3px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 435.22 637.61\">\n                <path fill=\"#4778FF\" d=\"M45.15 408.1v-200a17.82 17.82 0 0 0-1.28-7.24c-.58-1.27-2.82-2.41-4.3-2.4-.88 0-2 2.28-2.52 3.72-.43 1.18-.15 2.63-.15 4 0 46.66-.1 93.33.12 140 0 10.62-7 21.35-19.77 20.6-7-.42-14.65-5.43-15.59-12.36a196.26 196.26 0 0 1-1.47-25.31q-.24-62.74-.12-125.5c0-14.65 2.07-29 9.88-41.7 7-11.38 16.25-20.63 28.32-26.75s24.8-8.07 38.17-7.89c22.33.28 44.66.14 67 .24 21.6.1 39.27 8.78 53.58 24.71 3.17 3.53 5.72 3.8 8.73.51 15.95-17.58 36.11-25.46 59.54-25.46 20.33 0 40.67-.08 61 .2 20.79.3 38.47 8.42 53.16 22.85 11.59 11.38 17.75 25.78 21.7 41.34 4 15.79 8.35 31.49 12.58 47.23 4.91 18.3 9.9 36.59 14.76 54.9 2.26 8.52 4.55 17 6.35 25.66 1.68 8.06-2.3 17.33-11.38 20.05-9.7 2.91-19.27-.5-22.25-9.32-4.08-12.1-7.33-24.48-10.75-36.79-5.17-18.65-10.17-37.29-15.17-55.92-2.82-10.44-5.45-20.93-8.43-31.32a16.06 16.06 0 0 0-3.84-6.21c-.89-.93-3.31-1.54-4.26-1s-1.59 2.91-1.28 4.21c1.92 8.1 4.16 16.12 6.29 24.17 3.44 13 6.81 26.07 10.35 39.07 3.19 11.69 6.68 23.31 9.85 35 3.29 12.17 6.31 24.41 9.56 36.6 3.43 12.83 7 25.62 10.48 38.45 3.23 12 6.33 24.11 9.51 36.16.93 3.54 1.89 7.07 2.92 10.58 1.55 5.28.6 6.6-4.88 6.6h-47c-8.2 0-9 .79-8.94 8.81q.09 83 .19 166c0 10.8-2.67 20.33-12.07 27s-19.53 7.42-29.73 2.57c-9.37-4.46-14.58-12.38-15.81-22.72a72.77 72.77 0 0 1-.22-8.49q0-82.26-.05-164.5c0-3.28 1.71-8.31-4.22-8.28s-4.13 5.09-4.13 8.33c-.09 55.84-.26 111.67.07 167.5.12 20-15 32.28-30.66 31.28-5.2-.33-10.43-3.1-15.18-5.62-1.62-.86-2.37-4.34-2.55-6.7-.25-3.27.65-6.61.66-9.92 0-56 .3-112-.23-168-.09-10.16 3.26-17 10.38-23.63 12.9-12 25.08-24.78 37.55-37.24 5.41-5.39 10.67-10.93 16.26-16.12 8.59-8 10.58-17.39 5.09-25.74-7.21-11-20.13-12.16-29.4-2.88-15.4 15.43-30.83 30.83-46.44 46a11.84 11.84 0 0 1-7.37 3.09q-26.73.45-53.49.12a11.22 11.22 0 0 1-6.91-3.16c-15.33-15.06-30.15-30.64-45.74-45.4-9.26-8.77-14.61-9.43-25-3.45-6 3.48-9.69 13-6.85 21.24 1.34 3.88 4.41 7.43 7.39 10.43 20.08 20.19 40.38 40.16 60.47 60.34a11.07 11.07 0 0 1 2.92 6.4c.45 5.63.28 11.32.28 17v162a18.14 18.14 0 0 0 .13 4.49c1.88 7.33.06 9.87-8.62 13.84-21.28 9.73-41.74-6.08-41.66-28.56.18-52.66.16-105.33.21-158a102 102 0 0 0-.35-13c-.21-1.58-2.3-2.93-3.53-4.38-1.43 1.52-3.88 2.91-4.09 4.58-.62 4.94-.41 10-.42 15 0 52.33-.12 104.66.07 157 .07 17.43-10.19 27.77-25.83 30.14-10.07 1.52-18.7-2.77-25.53-10.7-5.48-6.36-6-13.82-6-21.51q-.09-49.76 0-99.5v-97.5Zm155.8-98.24c-24.1-.19-37.9 19.09-37.48 37.53.49 22.22 17.93 38.15 39.12 37.23 20.51-.89 36.63-18 36.39-37.48-.28-22.29-20.55-38.87-38.03-37.28ZM106.05 114.84c-31.08.41-56.68-26.74-56.53-57.58C49.68 25.01 75.8.19 106.01.01c33.23-.21 59.56 26.25 58.45 59-1.06 31.48-25.46 56.37-58.41 55.83ZM292.85 114.89c-32.72-.07-57-27.07-56.61-57.8A57.24 57.24 0 0 1 291.51.02c34.91-.86 60.45 27.28 59.48 59.81-.92 31.09-28.7 56.32-58.14 55.06Z\" \/>\n                <path fill=\"#4778FF\" d=\"M201.37 536.06c.46 2.15 1.31 4.31 1.32 6.47.05 25-.28 49.94.18 74.9.08 4.63 3.11 9.25 5 13.79.72 1.77 2 3.32 3.63 6h-20.79c.95-1.82 1.24-3.08 2-3.75 5.79-4.85 6.17-11.35 6.13-18.21-.15-24.48-.14-49-.13-73.46a42.48 42.48 0 0 1 .73-5.57Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours<br>familiares<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours aventura -->\n    <div class=\"flex-none ml-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-deportes-aventura\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 251.05 207.57\">\n                <path fill=\"#4778FF\" d=\"M83.62 77.94c.49-.06.68 0 .79-.1 7.08-5.12 15.08-5.21 23.28-4.33 3.71.4 7.44.57 11.16.87 1.29.11 1.67-.54 1.36-1.64-.36-1.3-.88-2.57-1.27-3.87q-2.47-8.11-4.91-16.25c-.26-.85-.49-1.65-1.7-1.31-2.17.6-4.35 1.11-6.51 1.72-.33.1-.59.5-.85.79q-8.74 9.81-17.47 19.64c-1.25 1.4-2.43 2.84-3.88 4.48Zm-1.38-10.75c.45 1.8-.43 3.32-2 4.74a80.26 80.26 0 0 0-5.66 5.86 5 5 0 0 1-5 1.64 14.73 14.73 0 0 1-7.75-3.55c-4-3.54-4.05-8-2.64-12.64a11.14 11.14 0 0 1 9-8 11.62 11.62 0 0 1 11.73 3.79c1.92 2.24 2.42 5 2.32 8.16Zm77.43 32.84c0 6.77-5 11.61-11.8 11.57-6.28 0-10.68-4.87-10.62-11.64.06-6.38 4.48-11.33 10.33-11.19 7.04.2 12.15 5.26 12.09 11.26Zm-104.05 12a2.81 2.81 0 0 0 2.54 3.22c3.18.51 6.37.92 9.57 1.33 1.8.24 2.22-.12 1.71-1.86-1.44-4.88-3-9.72-4.55-14.58-.39-1.23-1.09-1.35-2-.4a60.89 60.89 0 0 1-4.51 4.84c-2.31 2.02-2.9 4.55-2.76 7.45Zm58.71 13.78h.76c3.18-2.25 6.36-4.49 9.47-6.81a1.5 1.5 0 0 0 0-1.43c-2.39-3.36-4.82-6.69-7.32-10-1.13-1.49-1.89-1.32-2.57.45a3.78 3.78 0 0 0-.33 1.3c-.02 5.43-.01 10.89-.01 16.48Zm71.34 5.61a10.14 10.14 0 0 1-10.55-10.09 10.85 10.85 0 0 1 10.78-10.83c5.65 0 10.48 5.21 10.51 11.37.04 5.57-4.34 9.49-10.74 9.54Zm15.67 2.8c1.92 1 3.55 1.86 5.23 2.64 3.08 1.43 6.13 2.92 9.29 4.15 2 .77 2.47.29 2.74-1.85.55-4.53 1.14-9.06 1.6-13.6.06-.57-.58-1.71-.87-1.71-1.54 0-3.38-.12-4.54.66-4.51 2.98-8.81 6.3-13.45 9.7Zm-32.1 33c3.88.77 7.66 1.67 11.5 2.23a75.1 75.1 0 0 0 24.8-.56c5.28-1 10.56-2 15.88-2.71s10.63-.14 15.12 3.44a12.53 12.53 0 0 1 2.53 17.16c-2.94 4.21-7.27 6.38-11.92 8-6.95 2.37-14.18 3.35-21.44 4.19a3.39 3.39 0 0 1-3.78-1.81 34.38 34.38 0 0 0-16.86-12.94 19.1 19.1 0 0 1-10.83-9.37c-1.44-2.67-3.32-5.1-5-7.65ZM0 183.22a24.29 24.29 0 0 1 8.88-5.67c7.95-3.06 16.28-4.25 24.73-4.83 15.29-1.05 30.25 1.32 45.07 4.62 11.93 2.65 23.72 6 35.61 8.85q20 4.86 40 9.47c7.22 1.68 14.49 3.17 21.74 4.73.69.15 1.41.2 2.31.33a16.13 16.13 0 0 0-.69-2.64 2.06 2.06 0 0 0-1.27-1c-18.31-3.05-36.31-7.97-54.31-12.52-17.73-4.48-35.47-8.95-53.31-13-11-2.48-22.16-4.09-33.5-3.61-6.86.28-13.66.94-20.25 3a2.17 2.17 0 0 1-1.8-.3c-6.09-5.5-10.47-12-11.86-20.28-1.6-9.46 1.91-16.76 9.63-22.12 6.11-4.23 13.11-6.08 20.38-7 11.58-1.42 22.78.6 33.78 4.1 14.27 4.53 27.48 11.45 40.77 18.19a347.56 347.56 0 0 0 50.37 21.27c.72.23 1.48.33 2.33.52a2.62 2.62 0 0 0-2-3.12c-7.95-2.84-15.87-5.75-23.81-8.64-.26-.09-.53-.18-.79-.29-4.64-2-4.83-2.37-4.05-7.35.64-4.08 1.26-8.16 1.81-12.25.09-.64 0-1.7-.38-1.92a2.77 2.77 0 0 0-2.13.06c-4.66 1.93-9.24 4.05-13.93 5.88-4.92 1.93-6.69.47-7.12-4.89-.89-11.28 1.19-22.22 3.58-33.13a2.88 2.88 0 0 0-.78-2.89c-1.9-2.09-3.69-4.29-5.54-6.43-.39-.46-.82-.88-1.57-1.67-1 17-2.93 33.5 1.15 50.37-4.34-1.92-8.18-3.58-12-5.29-7.91-3.55-15.71-7.33-23.74-10.58-4.32-1.76-9-2.59-13.51-3.92-2-.58-3.87-1.35-6-2.09a5.62 5.62 0 0 1-1.88 1c-.78.13-2.27-.11-2.35-.46a8.34 8.34 0 0 1 .2-3.53c-1.52-3.1-1.46-3.75.83-6.67l.2-.28c2.69-3.33 2.74-3.34 6.38-.88 1.93-2.08 3.9-4.16 5.83-6.28 4-4.44 8.05-8.9 12.09-13.33q8.3-9.11 16.61-18.18c4.08-4.47 8.14-9 12.23-13.43 1.79-2 3.65-3.87 5.38-5.9a1.87 1.87 0 0 0 .08-1.71c-1.62-2.77-.46-7.67 2.32-9.33 1.45-.86 2.86-.43 4.19.32.64.36 1.21.82 2 1.34.91-1 1.8-1.9 2.67-2.84 2.13-2.28 4.32-4.5 6.34-6.87a6 6 0 0 0 .93-2.63c1.22-5.83 2.52-11.64 5.81-16.75A35.47 35.47 0 0 1 137.12.66a3.74 3.74 0 0 1 4.17-.25 31.67 31.67 0 0 1 10 8.8c1.53 2 .92 4.14-.37 6a34.35 34.35 0 0 1-12 11.08c-4.27 2.29-8.9 3.89-13.35 5.84a6.14 6.14 0 0 0-2.2 1.42c-2.66 3.07-5.23 6.22-7.83 9.33 1.74 2.05 3.74 3.79 4.94 6 2.24 4 4.13 8.3 6 12.56 2 4.73 3.94 9.53 5.72 14.36 1.66 4.51-.11 7.64-4.8 8.07-6 .55-12 1.49-18 2.28a5.39 5.39 0 0 0-1.77.51c-.93.5-1.27 1.17-.44 2.16 1.82 2.16 3.53 4.43 5.38 6.57a3.14 3.14 0 0 0 1.86.89 6.14 6.14 0 0 1 5 3.8c.1.2.25.47.2.64-1 3 1.35 4.7 2.74 6.65 10.68 14.93 21.46 29.78 32.18 44.68a2.33 2.33 0 0 0 2.38 1.23 6.87 6.87 0 0 1 1.36 0c1.08.07 2.5.63 3.19.15a38.12 38.12 0 0 0 5.37-4.88c.3-.31.16-1.35-.12-1.86-1.6-2.93-3.28-5.83-5-8.67-.33-.54-1.12-.8-1.92-1.34-.62 2.66-1.1 4.86-1.65 7.05s-1.09 4.3-1.79 6.8l-25.51-34a7.57 7.57 0 0 1 1-.56 36.21 36.21 0 0 1 23.18.17c5.68 1.88 8.76 6.29 11.47 11.2 2.82 5.11 5.83 10.1 8.92 15.42a3.75 3.75 0 0 0 .25-1.15c-.41-2.07.67-3.15 2.33-4.15 3.92-2.34 7.89-4.5 12.54-4.87a16.18 16.18 0 0 1 4.56.16 4 4 0 0 0 3.57-.73c5-3.74 10-7.4 14.53-10.72.2-1.67-.08-3.23.56-3.92a18.81 18.81 0 0 1 5.28-4c.66-.32 2.15 1 3.46 1.71a11 11 0 0 0 3.61-4.55c3.12-7.63 7.94-13.71 15.94-16.67a2.58 2.58 0 0 1 2.09.24 17.33 17.33 0 0 1 6.84 10.22 2.92 2.92 0 0 1-.7 2.34c-5.64 5.75-12.66 8.62-20.55 9.46a10.22 10.22 0 0 0-5.41 2.15 1.83 1.83 0 0 0-.54 1.62c1.22 2.8 1.22 5.72 1.24 8.68 0 5.44.18 10.88.23 16.32 0 5.12-2.32 7-7.19 5.54-4-1.16-8-2.49-12-3.74l-1.95-.62c-.14 1.21-.32 2.24-.35 3.28-.18 5.33-.36 10.65-.43 16 0 1.29-.38 1.76-1.7 1.9a95 95 0 0 1-22.35-.78 1.61 1.61 0 0 1-1.66-1.68c-.3-3.15-.79-6.28-1.21-9.42-.08-.58-.23-1.16-.35-1.72l-13.78 8.31c1.32 1.8 2.68 3.58 4 5.42 3.27 4.68 6.46 9.43 9.8 14.07a8.53 8.53 0 0 0 2.93 2.47c2.42 1.23 4.95 2.23 7.45 3.32 8.08 3.5 14.66 8.71 18.95 16.57a2.18 2.18 0 0 0 1.55.91 41.24 41.24 0 0 0 12.8-1.21 8.65 8.65 0 0 1 1.27-.15c.06.17.12.34.19.51a32.23 32.23 0 0 1-4.21 1.79 65 65 0 0 1-26.77 1.05c-9.89-1.5-19.81-3-29.59-5.05-14.45-3.08-28.78-6.72-43.18-10-16.11-3.71-32.2-7.53-48.38-10.9-8.51-1.78-17.17-2.94-25.82-3.93-10.68-1.24-21.37-.92-31.78 2.14-3.92 1.05-7.65 2.76-11.5 4.22Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours<br>aventura<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours Inti Raymi -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-inti-raymi\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"60px\" height=\"40px\" data-name=\"Capa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 243.01 117.12\">\n                <path fill=\"#C3971F\" d=\"M205.63,330.93l-15.81,1,10.41,11.49A73.61,73.61,0,0,1,205.63,330.93Zm18.15-21.88-14.54-5.21,5,14.59A75.57,75.57,0,0,1,223.78,309.05Zm24.84-13.45-11.63-10-.51,15A74.43,74.43,0,0,1,248.62,295.6ZM264,292.52c2.3-.22,4.64-.33,7-.33,2.07,0,4.11.09,6.13.25l-6.54-13.59Zm28.68,2.88a73.91,73.91,0,0,1,12.18,4.93l-.51-14.91Zm25.11,13.34a75.25,75.25,0,0,1,9.43,9.12l4.88-14.25Zm18.42,22a73.69,73.69,0,0,1,5.29,12l10-11.06ZM196.62,363c.07-1.35.17-2.68.3-4l-9,4ZM345,358.78c.14,1.4.25,2.82.32,4.24h10.16ZM177.6,363l20-8.86c.36-2.09.8-4.16,1.32-6.19l-17.74-19.58,27-1.68c1-1.54,2-3,3.11-4.51l-8.56-25,24.92,8.94c1.54-1.11,3.12-2.15,4.74-3.14l.88-25.9,20.11,17.21c1.92-.46,3.86-.85,5.84-1.17l11.37-23.63L281.84,293c2.05.3,4.07.69,6.06,1.15l20.18-17.28.87,25.76q2.54,1.51,4.94,3.21L338.62,297l-8.42,24.62q1.83,2.4,3.45,4.94l26.5,1.65-17.32,19.11c.27,1,.52,2,.74,3L366.34,326l-33.09-2.64-.54,0h0L344,292l-32.16,10.79v-.38h0l-1.19-34.13L288.23,287.5h0l-.37.3-2.82,2.43,0,0h0l-.65-1.4-1.16-2.39,0,0L270.49,259.3l-13.06,26.53h0l-1.13,2.27-.72,1.46-3.19-2.78,0,0-22.36-19.9-1.91,33.68,0,.68-32.54-10.38,12,31.51h0l.33.83-34.14,2.37,22.82,24.84-4,1.63-25.32,11Zm160.24,0a66.84,66.84,0,0,0-4.28-20.27l-1.1-2.7a67.26,67.26,0,0,0-33.22-34.17l-2.71-1.19A67,67,0,0,0,204.07,363h15.21a51.42,51.42,0,0,1,102.83,0Zm35.71,0-26.5-10.54h0l-3.26-1.27c.2,1,.38,1.92.54,2.89L365.19,363Zm-224.5,3.92,8.86-3.92L189.77,349l-24.65-26.88,37-2.57-13.39-35.1,35.6,11.35,2.09-37.55,27.8,24.8,16.31-33.06,15.85,33.72,28-24,1.31,37.53,35-11.78-12.43,34.22,36.78,2.94-25.16,26.82L382.19,363l9.59,4h-243Z\" transform=\"translate(-148.77 -249.94)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0 font-semibold\" style=\"color:#C3971F\">Tours Inti Raymi<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours para peruanos -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-peruanos\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 337.02 486.67\">\n                <path fill=\"#4778FF\" d=\"M296.6 212.8c2.23 1.68 4.24 4.33 6.71 4.86 6 1.28 8.33 7.24 13.45 9.41.48.2.67 1.14.94 1.76 1 2.23 2 4.48 3.2 7.28l-.93 1.22c1.24 1.73 2.41 3.42 5.06 2.5a2 2 0 0 1 1.82.64c.65 1.7 1.82 2 3.46 2.16.64.06 1.13 1.5 1.82 2.49 3.61 0 6 1.71 7.52 5.59a4.51 4.51 0 0 0 1.17 1.69c1.44 1.34 2.06 2.63.46 4.34-.38.41-.42 1.84-.14 2 1.47.87 3.15 2.2 4.65 2.06 4.51-.4 6 .75 5.76 5.35a2.69 2.69 0 0 0 .16 1.17c1.06 2.28.84 4.23-1.57 5.64l7 4.27 8.27-1.61c2.82.5 7.1 2.56 11.06.78 3.41-1.54 7.44-2.66 9.58-6.44a2.78 2.78 0 0 1 2.62-.61c2.94 1.45 5.6 3.55 8.65 4.66 1.68.61 4 0 5.86-.59s3.23-2 5-2.43c3.46-.77 5.41 2.26 7.86 3.87a17.71 17.71 0 0 0 7.74 2.72c1.44.19 2.68 2 4 3.07.78.64 1.44 1.75 2.3 1.93 2.56.53 3 1.07 1.53 3.33-1.81 2.89-3.73 5.72-5.6 8.58-3.73 5.69-7.45 11.4-11.31 17.29 2.26 1.15 4 2.55 6.61.75 2.22-1.52 4.68 0 7.21 3.68 1.45 2.1 3 4.12 4.58 6.16 1.11 1.45 2.59 3 .87 4.72s-3.32.87-4.69-1.19c-1.84 2.71-3.52 1.27-4.29-.33-1.48-3.07-3.39-3.44-6.41-2.46-1.61.53-3.55 0-5.33.09-.68 0-1.81.46-1.91.91-1 4.33-4.67 4.34-7.92 5.08-2.12.48-4.65 2-6.25 1.28-3.81-1.63-6.34 2.85-10.36 1.13-2.67-1.14-5.84 1.59-8.41 3.48a14 14 0 0 1-3.45 2.26c-4.68 1.57-7.66 5.35-11.32 8.25-1.21 1-3.1 1-4.69 1.49-.82.22-1.68.31-1.85.35-1.67 5.84-.94 11.65-4 16.53-1.46 2.33-3.58 4.23-5.35 6.37-1.33 1.61-1.05 2.83.21 4.71a12.69 12.69 0 0 1 2 7.45c-.15 2.15-2.78 2.7-4.9 3.6-3.88 1.65-7.41 4.26-10.84 6.81-1.6 1.18-1.67 6.2-.69 8a14.24 14.24 0 0 1 1.06 2.48c.51 1.64.14 2.75-1.82 2.93-1.49.13-3 .43-4.39.65 0 .82.27 1.74-.05 2.34-1.7 3.2.79 4.22 2.74 5.49.83.55 1.87.79 2.64 1.4 2.16 1.69 2.07 3.25-.35 5.05 4.7 1.3 3.65 6.23 6 9.06s5.7 5.18 6.12 9.35c4.65.33 4.61 5.64 8 7.49 1.56.87 1.34 4.65.11 6.21-1.45 1.83-2.86 3.69-4.59 5.92 2.86 0 5.35-.19 7.79.06s4.83.95 7.24 1.42a31.67 31.67 0 0 0 3.2.48c3.44.28 6.25 4.06 5.11 7.17 2 1 3.48 2.41 2.8 5.08-.09.35 1.2 1.54 1.85 1.53q10 0 19.91-.42a5.75 5.75 0 0 0 2.84-1.48c5.05-4 10-8.09 15.09-12 .81-.63 2.1-.65 4-1.19a37.72 37.72 0 0 1-1.61 3.44c-.75 1.25-1.4 2.23-.11 3.73.5.58.17 2.86-.47 3.26-1.74 1.08-1.72 2.49-1.71 4.12v24.89c1.3.78 2.69 1.25 3.52 2.2 2.13 2.45 4.41 2.61 7.24 1.37a37.74 37.74 0 0 1 8.59-3c2.24-.38 4.69.4 7 .76.38.06.79.59 1 1q10.89 19.59 21.72 39.21c.78 1.41 1.26 2.69-.45 3.88-.4.27-.23 1.27-.54 1.81-.56 1-1.07 2.38-2 2.78-3.87 1.74-4.47 3.23-4.33 7.38a88.12 88.12 0 0 1-.89 13.36c-.14 1.13-1.35 2.14-1.86 2.89.53 1.71.89 3.31 1.5 4.81.94 2.33 2.09 4.58 3.08 6.9.83 2 .62 3.45-1.81 4.14-.64.18-1.11 1.16-1.55 1.84-.73 1.15-1.12 2.69-2.12 3.46-2.68 2-5.05 4.12-4.43 7.86-4.82 2.36-5 6.13-.75 9.35a30.46 30.46 0 0 1 2.86 2.64c-2.29 3.31-4.4 6.21-6.32 9.23a4.05 4.05 0 0 0-.54 2.93c1.18 3.83 2.57 7.6 3.93 11.37.63 1.74 1.52 2.86 3.79 2.42 2.53-.49 4.2 1.48 5.83 3 .22.21-.45 2.1-1 2.24-3.35.93-4.67 2.7-3.49 6.19a2.62 2.62 0 0 1-1.08 2.27c-4.33.93-5.45 5.3-8.47 7.59-1.42 1.09-2.77 2.28-4.15 3.43-1 .81-1.9 1.64-3 2.63a24.11 24.11 0 0 0 2.12 1.72 3.51 3.51 0 0 1 1.23 5.23c-1.45 2-3.17 4.37-6.27 4.24-2.15-.08-2.7.42-1.73 2.66a7.78 7.78 0 0 1-.58 8c-2.13 3.34-4.81 5.8-8.23 6.77-2.65.76-6.05 1.09-8.62-.87-4.19-3.18-8-6.83-12.29-9.9-3.66-2.65-7.7-4.77-11.62-7.14 2.36-4.9-.46-10.27-6.77-11.69a11.44 11.44 0 0 1-6.32-3.56c-1.76-1.88-4.39-2.92-6.48-4.53-1.15-.89-1.82-2.39-3-3.26-1.63-1.23-3.44-2.86-5.3-3-4.91-.48-8.79-3.2-13-5.1-5.46-2.45-10.13-6.43-16.38-7.45-2.52-.42-5.05-2.56-7-4.52-2.64-2.74-5.85-4.07-9.24-5.28a4.41 4.41 0 0 1-1.63-.72c-5.14-5.22-12.45-6.69-18.29-10.65-1.67-1.13-2.83-3-4.18-4.6-.57-.65-1-1.42-1.54-2.1a226.48 226.48 0 0 0-4.17-5.11 14.12 14.12 0 0 0-2.51-2.71c-2.61-1.83-5.37-3.45-8-5.24-.51-.35-.68-1.17-1.08-1.71-1.42-2-2.9-3.87-4.32-5.82-.39-.53-.94-1.15-.93-1.73 0-2-.07-3.6-2.82-3.43-.32 0-1.14-2.1-1.08-3.18.12-1.94.67-3.6-2.15-4.18-1.41-.29-1.13-3.15.44-3.52 1.86-.44 3.55-.73 3.8-3 .39-3.36 1.12-6.78-1.67-9.63-1.54-1.57-3-3.24-4.43-4.88-.34-.37-.84-.81-.85-1.22-.07-4.3-3.26-7.05-5.15-10.43-1.6-2.84-3.22-5.68-5-8.41a10.27 10.27 0 0 0-2.48-2.06c-.78-.61-2.2-1.18-2.23-1.81-.11-2.7-1.76-3-3-2.89a55.32 55.32 0 0 1-1-7.1c0-2.46-.58-4.63-2.37-6.28s-3.92-3.22-5.92-4.79c-1.15-.9-2.4-1.7-3.53-2.64a1.89 1.89 0 0 1-.6-1.32c.11-7.63-.2-8-4.58-14.15-3.29-4.64-6.14-9.6-9.06-14.5-.63-1.06-.62-2.48-1.05-3.68-1.82-5-3.66-9.94-5.56-14.89a4.86 4.86 0 0 0-1.39-2.23c-3.51-2.42-4.15-6.25-5.19-9.93-.25-.88-.86-1.65-1.15-2.52-.5-1.51-.84-3.07-1.34-4.57s-.77-3.14-1.69-4.28a19.28 19.28 0 0 1-3.42-5.11c-1.26-3.08-3.87-5.82-6.44-8.1-3.17-2.82-6.13-5.48-7.64-9.71-1.59-4.45-4-8.6-6.06-12.89-.13-.27-.16-.63-.35-.82-5.47-5.31-8.75-12.63-16.87-15.55-7.17-2.58-13.79-6.78-20.47-10.59a5.78 5.78 0 0 1-2.23-4.47c0-1.65 1.38-3.3 2.32-4.85.14-.22 1.32 0 1.88.26 2.62 1.28 4 .51 4-2.48 0-3.64-1.91-6.44-4.55-8.79a23.08 23.08 0 0 1-3.5-3.25c-1.61-2.19-.58-4.8 2.45-5.47l-7.44-8.56c.6-3.05 1.53-6 1.64-8.91.12-3.32 2.62-4.7 4.32-6.79 2.47-3 4.83-6.14 7.31-9.16a15 15 0 0 1 2.12-1.59c1.9-1.59 3.77-3.22 5.64-4.84a8.22 8.22 0 0 1 1.33-1.19c1.92-1 3.88-1.94 6.17-3.08 2.25 1.38 3.79 5.36 3.58 8.51-.11 1.67.94 3.42 1.51 5.25-1.38.94-3.08 2.14-4.83 3.26a2.11 2.11 0 0 1-1.41.16c-3.18-.68-3.38-.49-2.73 2.6a13.24 13.24 0 0 1 .14 1.59l4.35-.61-4.73 7.36c1.58-.22 3.19 0 3.51-.56 3.32-5.75 7.48-3.75 11.3-1.07 2.09 1.48 3.63 2 5.84.6.46-.3 1.62.35 2.37.72 1.15.58 2.22 1.3 3.5 2.06-.83 4.3 1.39 7.52 4.28 10.42 1.62 1.63 6.89 1 8.34-.81a11.38 11.38 0 0 0 1.79-3.69c.62-1.72 2.6-3.17 4.3-4.24 2-1.25 3.42-2.17 2.33-4.92a5.75 5.75 0 0 1 .51-4c1.88-4 3.22-8.29 5.44-12.26 1.77-3.15 1.73-7.31 2.52-11.2 5.18 1.54 6.29-3.14 8.57-5.57 2.5-2.65 4.77-5.07 8.44-6.22 8.32-2.59 16.55-5.5 24.77-8.42a30.82 30.82 0 0 0 5.8-3 88.81 88.81 0 0 0 23.41-21.87 25 25 0 0 0 3.63-7c1.38-4 2.32-8.06 3.52-12.4a12.61 12.61 0 0 0 1.11.64c.76.31 1.52.59 2.28.88.08-.89.52-2 .18-2.65a6.31 6.31 0 0 1-.12-6c.28-.57-.84-2.34-1.73-2.86a6.69 6.69 0 0 1-3.55-4.86 4.51 4.51 0 0 0-2.55-2.82c-1.52-.53-2.58-1.2-1.63-2.57a3.69 3.69 0 0 1 3.33-.88c4.51 1.58 5.67 1.38 8.82-2.35Zm49.58 247.89a29.21 29.21 0 0 1 1.68-2.77c1.42-1.79 2.84-3.59 4.39-5.26a3 3 0 0 0-.33-4.68c-2.78-2.38-3.59-6.77-7.82-7.62-.69-3.62-3.3-5.75-5.6-8.38-2.62-3-2.27-8.14-6.51-10.41-.29-.15-.28-.88-.43-1.39l2.85-1.67a39.55 39.55 0 0 1-4.05-2.52c-1.45-1.18-3.38-2.34-3.91-3.91-.64-1.89-.08-4.21.13-6.33 0-.23 1.14-.45 1.77-.52 1.64-.18 3.29-.28 5.3-.44-.57-1.38-.87-2.34-1.34-3.19-1.61-2.88-1.46-7.7.91-9.74 3.68-3.17 7.44-6.28 12.5-7.31 2.15-.44 3.9-1.93 2.9-4.6-.61-1.62-1.8-3.05-2.25-4.69s-.82-3.6-.18-4.91c1-2.08 3.14-3.6 4.4-5.6s2.6-4.05 2.61-6.1c.18-26.33.13-52.66.09-79a3.94 3.94 0 0 0-.68-2.38c-1.82-2.12-6.06-3.54-1.75-7.15.11-.09.09-.39.05-.58-.6-2.68-1.22-5.35-2-8.61-4.17 3.08-6.81.88-8.91-1.43-.82-.9-.14-3.15-.14-4.78a12.66 12.66 0 0 0-2.09-5.06c-1.2-1.7-2.79-2.21-5.14-2.57-2.67-.4-4.91-3.6-7.51-5.73-2.4 1.06-4.27-.6-5.75-2.5-.67-.86-.52-2.37-.79-3.81l-1.57-4c-.4-1-.57-2.28-1.29-3-3-2.93-7.63-4-9.49-8.29-.09-.22-.71-.2-1.06-.34a29.77 29.77 0 0 1-3.93-1.68c-1.78-1-3.43-2.32-5.17-3.51-3.19 4.11-7 3.84-10.9 2.07 1.25 1.4 3 2.48 3.37 3.93.62 2.27 1.32 4 3.56 5.14 1.05.54 2.4 2.53 2.1 3.26-1.07 2.68-.63 5 .32 7.5.78 2-.19 3-2.25 3.13-.76 0-1.52-.06-2.43-.11-.4 1.47-.78 2.92-1.21 4.36-1 3.36-1.21 7.27-3.15 9.94a98 98 0 0 1-14 16.1c-7.81 6.88-16.26 13.15-26.88 15.3-2.31.46-2.92 1.66-2.92 4q.09 112.92.06 225.83c0 .88-.17 2.1.31 2.6 2.57 2.64 2.09 6.14 2.53 9.24a11.37 11.37 0 0 0 4.33 7 21.69 21.69 0 0 1 5.44 6.9c1.43 2.68 3.29 5.12 4.89 7.7.92 1.47 1.72 3 2.56 4.52 1 1.78 1.61 3.86 2.95 5.3 5.9 6.36 6.78 10 2.82 18.87a8.8 8.8 0 0 0 .53 6.91c1.86 3.35 5.55 5.82 6.9 9.27 1.9 4.88 6 6.61 9.64 9.28 1.35 1 2.32 2.54 3.67 3.56 1.84 1.39 1.73 4.59 4.74 4.93.54.06 1.08 1.11 1.41 1.8a12.76 12.76 0 0 0 5.86 6.18c5.25 2.77 11.31 4.22 15.46 8.92.35.4 1.07.48 1.63.7 3.34 1.29 6.66 2.44 9.25 5.27 1.71 1.86 4.07 3.75 6.43 4.24 6.55 1.36 11.83 5.14 17.55 8.08a24.69 24.69 0 0 0 2.49.95V460.69Z\" style=\"fill:#4778FF;stroke:#4778FF;stroke-miterlimit:10;stroke-width:3px\" transform=\"translate(-129.07 -211.3)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours para peruanos<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Arequipa -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-arequipa\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"60px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 79.48 52.84\">\n                <path fill=\"#4778FF\" d=\"M242.71 324.3c.36.36-.05.23-.65-.06a6.88 6.88 0 0 0-1.78-.83 1.83 1.83 0 0 0-1.42.53c-.18.32.43 1.08.3 1.36s-.69.37-1.07.36a4.29 4.29 0 0 1-1.47-.41 10.87 10.87 0 0 1-1.48-.95c-.56-.39-1.39-1.26-1.89-1.36s-.78.47-1.13.77-.84 1-1.24 1.24a1.56 1.56 0 0 1-1.19.18c-.37-.12-.66-.65-1.06-.89a6.46 6.46 0 0 0-1.89-.89 1.33 1.33 0 0 0-1.07.59c-.34.47-.54 1.75-1 2.23a3.25 3.25 0 0 1-1.78.67 2.41 2.41 0 0 1-1.6-.06c-.4-.25-.54-1-.82-1.48s-.47-1.13-.89-1.18-1.13.56-1.66.89-1.32.92-1.66 1.16a3.27 3.27 0 0 1-.35.3c-.22.15-.64.41-1 .59-.19.11.29-.13.34-.19.21-.22.28-.22.52-.48s.44-.42.63-.65.65-.74.94-1.11.6-.8.87-1.18.61-.72.84-1a4.35 4.35 0 0 1 .5-.55 5.13 5.13 0 0 1 .58-.43c.22-.15.45-.28.67-.4s.36-.19.53-.29.66-.41.88-.58a7.31 7.31 0 0 0 .72-.64c.24-.26.6-.55.92-.91a17.08 17.08 0 0 0 1.15-1.43 10.39 10.39 0 0 1 1.11-1.26 7.19 7.19 0 0 1 4.9-1.74c2.43.05 4.28 1.52 4.55 2.21a10.21 10.21 0 0 0 1.41 1.68c.38.47.85 1 1.27 1.5s.83 1 1.21 1.44.94.88 1.29 1.27l1.13 1.22c.33.31.53.46.84.76Zm20.21 11.44 1.92-.32.06-7.05a1.92 1.92 0 0 0-.38-.63 1.07 1.07 0 0 0-.73-.2 1 1 0 0 0-.59.42 1.42 1.42 0 0 0-.24.74c-.05 1.3-.04 7.04-.04 7.04Zm-6.5.76 3.74.05.06-7.53c0-1.82-4.11-1.81-4.08 0l.13 7.44Zm-4.83-4.14v-6.7l-.88-.92 1-.75.47-5 .51 4.5.62-.14.3-.45.51-4.19.43 4.08h.82l.52-.51.73-3.15-.73-.61 1.17-.71 2.55-8.87a2.82 2.82 0 0 1-2.67-2.73 2.79 2.79 0 0 1 2.15-2.65v-5.06h-.73v-.74h-3v-1.08h2.91v-1.15h.87v-3.19h1.62v3.17h.73v1.21h3.07v1.09h-3v.72h-.86v5.06a2.79 2.79 0 0 1 2.22 2.66 2.82 2.82 0 0 1-2.7 2.73l3 9 .76.44-.66.54.9 3.1.75 1.07.45-.09.62-4.85.17 4.51.49 1 .48-3.51.12 3.85.32.8 1.15 1.06-1.05.87v11.54l1 .76-1 .71v2l.29.16c1.18.64.92.79 1.76 1.21.38.19 1.44 1.05 1.7 1.2s.19.45 0 .45c-9.62.12-41.7.38-56.18.34-9.57 0-17.83.06-22-.23-1.19-.08-1.59 0-.45-.38 1.4-.46 2.24-2.16 3.6-2.88a24.15 24.15 0 0 0 3.47-2.49c1.15-.9 1.58-1.79 2.79-2.55s1.59-1.39 2.76-2.07a34.71 34.71 0 0 0 4.74-2.91c1.23-1 2.29-2.95 3.1-3.72a2.31 2.31 0 0 1 .54-.36c.12-.14.45-.39.67-.6s.68-.68.95-1 .46-.55.68-.82.67-.8 1-1.22.77-1 1-1.41.41-.59.61-.81a3.34 3.34 0 0 1 .56-.5c.23-.17.56-.37.83-.53l.79-.43a4.47 4.47 0 0 0 .77-.51c.44-.42 1.28-1.31 1.87-2s1.32-1.61 1.86-2.36a8.2 8.2 0 0 1 5.8-2c2.61.2 5.19 2.22 5.17 2.69 0 .3.35.33.53.57.33.44 1 1.26 1.53 1.88s1.28 1.47 1.87 2.12 1.31 1.4 1.67 1.8c.17.18.31.4.48.59s.81.85 1.12 1.15.53.51.74.7l.49.46c.16.15.32.29.47.45l.34.41a18.93 18.93 0 0 1 1.73 1.29 23.66 23.66 0 0 1 2 2c.69.79 1.55 1.92 2.2 2.71Z\" style=\"fill-rule:evenodd\" transform=\"translate(-192.05 -292.33)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en Arequipa<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Lima -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-lima\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"60px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 371.84 354.11\">\n                <path fill=\"#4778FF\" d=\"M192.02 21.12a15.09 15.09 0 0 0-.93-2.08c-1.22-1.93-2.5-3.82-3.76-5.72-1-1.55-1.81-1.57-2.84 0-1.31 2-2.57 4-3.88 5.92a3.11 3.11 0 0 0 0 3.8c1.34 2 2.62 4.1 3.93 6.15.91 1.42 1.8 1.45 2.72 0 1.32-2 2.64-4.09 3.92-6.16a14.36 14.36 0 0 0 .84-1.91Zm-18.41 8.25c-.06-1.1-.07-1.91-.14-2.7-.66-6.69-.61-13.36 2.72-19.4a16.52 16.52 0 0 1 5.42-5.95c5.07-3.11 11-.51 14.06 5.51 3 5.87 3.49 12.07 2.91 18.47-.1 1.06-.14 2.13-.17 3.19 0 .19.21.38.4.68 2.28-.74 4.53-1.6 6.84-2.19a12.22 12.22 0 0 1 14.27 6.33c1.88 3.9 1.36 7.91-.79 11.61a19.14 19.14 0 0 1-8.55 7.66 5.38 5.38 0 0 1-5.2-.22c-10.94-5.72-22.27-6.26-33.87-2.36a31.83 31.83 0 0 0-5 2.3 5.28 5.28 0 0 1-5.19.3c-4.81-2.33-8.64-5.71-10-11-2.79-10.59 6.44-16.51 14.48-14.73 2.52.6 4.9 1.57 7.81 2.5Zm12.23 21c7.45.35 14.39 2 20.36 6.31 4.93 3.55 7 8.88 7.18 14.86 0 1-.93 2.09-1.43 3.14a12.19 12.19 0 0 1-2.41-1.41A31.14 31.14 0 0 0 191.15 65c-9.08-.93-17.79.09-25.49 5.57-1.36 1-2.58 2.13-3.85 3.21-1.63 1.39-2.79 1.15-3.2-.94a11.65 11.65 0 0 1 .07-4.52c1.81-8.68 7.38-13.74 15.8-15.78 3.74-.87 7.57-1.43 11.36-2.14Zm-85.69 1.77a4.76 4.76 0 0 1 4.84 4.52 8.72 8.72 0 0 0 .15 2.48 3.71 3.71 0 0 0 1.8 1.78 10.94 10.94 0 0 0 2.71.15 4.7 4.7 0 0 1 4.25 4.83 4.54 4.54 0 0 1-4.36 4.68c-.3 0-.61 0-.91.05-3.43.1-3.43.1-3.59 3.55-.13 2.94-1.29 4.54-3.81 5.26a4.14 4.14 0 0 1-4.91-1.89 6.72 6.72 0 0 1-.8-3.23c-.16-3.56-.13-3.39-3.76-3.75a7.14 7.14 0 0 1-4.33-1.92c-2.47-2.75-.55-6.95 3.22-7.51 1.48-.23 3.4.07 4.32-.76s.42-2.69.58-4.11a4.31 4.31 0 0 1 4.6-4.1Zm174.47 28c-2.54-.44-4.76-2.28-5.16-4.43a10.55 10.55 0 0 1-.13-1.59c-.11-3.45-.11-3.45-3.58-3.53s-5.41-1.93-5.38-4.87c0-2.74 2.18-4.64 5.36-4.73 3.52-.1 3.52-.1 3.61-3.73.08-3.16 1.79-5.08 4.59-5.16 3-.07 4.86 1.81 5 5s-.72 3.9 3.95 3.89a4.8 4.8 0 0 1 5 4.81c-.05 2.77-2 4.64-5.05 4.76-.61 0-1.22.06-1.83 0-1.45-.06-2.05.62-2.07 2.05s.21 2.86-.41 3.8c-.96 1.57-2.57 2.59-3.9 3.8Zm7.36 6.73a15.13 15.13 0 0 1-2.08.88c-.3.07-.73-.18-1.06-.35-3.14-1.67-6.22-1.42-9.36.07-.69.33-1.68 0-2.53 0a9.88 9.88 0 0 1 .45-2.93 5.59 5.59 0 0 1 2-2.05c3.44-2.18 9.58-1.08 11.52 2a20.37 20.37 0 0 1 1.06 2.45Zm-175.9 1.75a8.09 8.09 0 0 0-8.47-2c-1.32.54-2.67 1-4 1.5-1.31-2-.88-3.71 1.19-5.23 2.52-1.84 8-1.87 10.59-.06s2.8 3.7.66 5.79l.05.05h-.06Zm0 .05h.05Zm-45.89 1.46a4.63 4.63 0 0 1-4.64-4.16 15.06 15.06 0 0 1-.1-2.51c.06-1.56-.67-2.13-2.2-2.21a13.19 13.19 0 0 1-4.19-.79 4.21 4.21 0 0 1-2.45-4.89 4.34 4.34 0 0 1 4-3.8c4.41-.52 4.4-.54 4.95-4.85a5.08 5.08 0 0 1 4.76-4.37 5.19 5.19 0 0 1 4.73 4.48c.52 4.36.52 4.36 4.74 4.79a4.63 4.63 0 0 1 4.31 4.51c.1 2.47-1.7 4.43-4.49 4.9-1.39.24-3.21 0-4 .83s-.39 2.57-.55 3.91a4.53 4.53 0 0 1-4.84 4.23Zm259.79 0c-2.75 0-4.64-2-4.83-5-.22-3.59-.22-3.56-3.8-3.89-2.14-.2-4.09-.89-4.82-3.18-.66-2-.36-4.07 1.48-5.33a7.33 7.33 0 0 1 3.6-1c3.42-.19 3.35-.12 3.56-3.63a7.71 7.71 0 0 1 1-3.39 4 4 0 0 1 4.87-2c2.09.65 3.6 2 3.67 4.41v.69c.13 3.79.13 3.79 3.94 3.92 3 .1 5 1.8 5.08 4.44a5.08 5.08 0 0 1-4.85 5.08h-.46c-3.55.17-3.55.17-3.71 3.86-.1 3.21-1.89 5.11-4.7 5.1ZM202.32 78.2a17.13 17.13 0 0 0-2.42-2c-8.34-4.39-16.95-4.31-25.59-1.13-1.55.57-3.79.95-4.15 3.41a42.73 42.73 0 0 1 14.32 11.94c1.1 1.43 1.94 1.33 3-.07a43 43 0 0 1 14.84-12.15Zm117.61 13.85c2.89.18 5.55.63 7 3.31.4.75.19 1.84.25 2.77a6.81 6.81 0 0 1-2.56-.06 10.55 10.55 0 0 0-9.24 0 6.85 6.85 0 0 1-2.57.07 8.4 8.4 0 0 1 .29-2.73c1.37-2.94 4.22-3.02 6.83-3.36Zm-259.44-.19c2.65.56 5.52.81 6.86 3.74a7.25 7.25 0 0 1 .14 2.57c-.8 0-1.73.31-2.37 0a10.67 10.67 0 0 0-9.67 0c-.64.3-1.56 0-2.36 0a7.45 7.45 0 0 1 .23-2.62c1.37-3 4.36-3.17 7.17-3.69ZM210.8 80.05c-2.36 1-4.29 1.8-6.22 2.64-7.82 3.42-13 9.52-17.29 16.65-.31.53-.88 1.23-1.33 1.24s-1.11-.66-1.4-1.18c-4.32-7.52-10-13.57-18.06-17.13-1.68-.75-3.42-1.37-5.45-2.17 6.16-8.91 14.58-12.08 24.29-12.2 10.14-.13 18.98 2.93 25.46 12.15Zm-104.69 8.69a20.55 20.55 0 0 1 2.71 3.14c1.12 1.93 1.95 4 3 6.33a21.86 21.86 0 0 0 2.28-1.32c12.9-9.22 27.37-12.44 42.89-10.63 10.9 1.28 19 7.42 24.75 16.61 1 1.54 1.79 3.18 2.77 4.72a9.22 9.22 0 0 0 1.46 1.47 7.31 7.31 0 0 0 1.28-1.4 43 43 0 0 1 12.2-15.17 33.27 33.27 0 0 1 18-6.54 61.88 61.88 0 0 1 28.23 4.29 52.92 52.92 0 0 1 14.82 8.87c.68.59 1.42 1.09 2.72 2.06v-2.88a9.78 9.78 0 0 1 5.69-9.47 10.51 10.51 0 0 1 14.1 4.73 9.22 9.22 0 0 1 .83 7.72c-.62 1.76.28 1.92 1.74 1.76 5.38-.59 10.75-1.3 16.15-1.61a81.16 81.16 0 0 1 26.74 2.74c14.8 4.15 26.15 12.55 32.63 27 4.8 10.69 8.54 21.64 10.08 33.31a69.67 69.67 0 0 1-2.81 31.08c-5.35 16.39-16.2 28.58-29.67 38.72-11.15 8.4-23.61 14.37-36.6 19.31a4.11 4.11 0 0 1-2.66.07c-5.9-2.2-11.75-4.52-17.62-6.82a7.57 7.57 0 0 1-1.06-.73l8-4.72c14.16-8.38 27.39-17.93 37.86-30.83 6.85-8.43 11.82-17.84 12.64-28.84a50.83 50.83 0 0 0-1-14.5 73.08 73.08 0 0 0-7.89-20.86c-4.67-8.14-10.68-15-19.68-18.22a46.38 46.38 0 0 0-12.94-2.38 43 43 0 0 0-18.76 3.4c-.75.31-1.31 1.86-1.41 2.9-.52 5.06-.54 10.19-1.31 15.21-1.19 7.73-4.18 14.93-7.72 21.86-12.3 24.06-30 43.9-49 62.77-2.56 2.55-5.37.84-8.68.84.9-1.14 1.38-1.89 2-2.5 12.05-11.72 23.23-24.17 32-38.6 7-11.53 12.25-23.71 12.61-37.46.24-8.85-1.56-17.29-6.48-24.82-2.05-3.13-4.81-5.69-8.92-4.39a15.82 15.82 0 0 0-5.71 3.61c-5.09 4.75-8.35 10.81-11.54 16.89a241.56 241.56 0 0 0-14.85 36c-3.35 10-6.19 20.24-8.92 30.45-1.59 5.95-2.46 12.08-3.8 18.09a2.63 2.63 0 0 1-1.83 1.68c-6.25.07-12.51 0-18.77-.07a1.83 1.83 0 0 1-2.08-1.86 210.29 210.29 0 0 0-9.2-37.43c-3.28-9.81-6.47-19.67-10.26-29.28-4-10.26-8.52-20.4-15.16-29.31a37.85 37.85 0 0 0-8.13-7.85c-3.32-2.4-6.85-1.85-9.3 1.45a41.65 41.65 0 0 0-5.7 10.29c-3.12 8.51-3.22 17.38-1.44 26.18a81 81 0 0 0 8.65 22.76c9 16.35 21.15 30.1 34.34 43.08a12.2 12.2 0 0 1 1.25 1.74c-.72.31-1.42.67-2.15.92-2.88.94-5-.1-7.08-2.21-14.8-15-28.81-30.63-40.09-48.52a117.23 117.23 0 0 1-12.89-26.64c-2.31-7.21-3.7-14.64-3.09-22.29.18-2.23-.48-3.27-2.78-4.09a47.57 47.57 0 0 0-24.33-2.28c-9.37 1.61-16.71 6.86-22.15 14.55-7.87 11.14-12.47 23.58-12.78 37.25-.22 9.64 3.28 18.37 8.49 26.37 7.18 11 16.75 19.7 27.41 27.19 5.78 4 11.93 7.58 17.88 11.39a9.92 9.92 0 0 1 1.6 1.85c-3.65 1.2-6.95 2.26-10.24 3.37s-6.61 2.3-9.93 3.39a3.43 3.43 0 0 1-2.15.17c-14.22-5.69-27.5-13-39.09-23.12-9.61-8.4-17.31-18.26-21.84-30.28a69.9 69.9 0 0 1-3.75-34.41c1.6-11.92 5.43-23.09 10.47-33.91a44.75 44.75 0 0 1 22.11-22.18c14.12-6.63 29-7.66 44.27-5.92 3.85.44 7.68 1.09 11.53 1.61a11.12 11.12 0 0 0 1.93-.09c-.13-.6-.18-1-.31-1.43-2.24-6.86 1.84-13.79 9.86-14.38 1.79-.06 3.72.7 5.58 1.05Zm82.08 161.92a6.12 6.12 0 0 0-5.69-5.82 5.91 5.91 0 0 0-5.66 5.78 6.12 6.12 0 0 0 5.51 5.76c2.74.06 5.81-2.94 5.84-5.72Zm30.39 8a5.85 5.85 0 0 0 5.74-5.67 6.25 6.25 0 0 0-5.55-5.72 6 6 0 0 0-5.8 5.66 5.69 5.69 0 0 0 5.61 5.73Zm-66.61-5.71a6 6 0 0 0-5.81-5.64 6.1 6.1 0 0 0-5.56 5.68 5.69 5.69 0 1 0 11.37 0Zm65.86-11a142.3 142.3 0 0 0-30.93-1.56c7.79 5.07 8.54 14.67.06 20.35 8.38.74 16.74 1.66 25.68 1.53-7.9-7.91-4.82-17.29 5.19-20.32Zm-114.24 17a5.6 5.6 0 0 0 5.54 5.76 6.18 6.18 0 0 0 5.72-5.75 5.81 5.81 0 0 0-5.59-5.55 5.35 5.35 0 0 0-5.67 5.57Zm152.15-5.55a5.81 5.81 0 0 0-5.67 5.71 6.28 6.28 0 0 0 5.63 5.63 5.81 5.81 0 0 0 5.69-5.7 5.55 5.55 0 0 0-5.65-5.61Zm-103.12 8.29c2.43 1 23.88-.25 25.24-1.37-8.13-4.88-7.9-14.79.29-20-22.85-.51-45.31 2.54-67.68 7.52 3.83 1.82 7.45 3.72 8.66 8a11.51 11.51 0 0 1-2.81 11.26l.53.36 25.17-4.08c-7-7.15-8-12.42-3.48-17.36 4.31-4.71 8.69-5.09 13.94-1.41a12 12 0 0 1 4.06 6.08c1.28 4.3-.68 7.97-3.92 11Zm70.76-18.59c3.58 2.63 5.78 5.71 5.74 10.21 0 4.65-2.84 7.41-6.26 10.27l25.48 4.2c0-1-.12-1.35-.36-1.62-4.53-5-3.19-14.14 3.76-16.81.65-.25 1.11-1 2-1.79-10.42-1.82-20.18-4.34-30.36-4.46Zm69.12 31.25c2.8-.09 5.71-3.19 5.58-5.95a6.13 6.13 0 0 0-5.75-5.48 5.64 5.64 0 0 0-5.57 5.75 5.83 5.83 0 0 0 5.74 5.68Zm-219.88 0a5.93 5.93 0 0 0 5.54-5.88 5.6 5.6 0 0 0-5.58-5.51 5.85 5.85 0 0 0-5.74 5.67 6.16 6.16 0 0 0 5.78 5.72Zm2.54-16.8c3.37 2.46 6.54 4.32 7.6 8.08s-.33 7.18-2.27 10.45l.49.43 24.84-6.72c-8.15-5.57-10.06-11.95-3.28-19.79-9.17 1.4-17.8 4.47-27.38 7.55Zm187.44-7.28c.51.82.85 1.48 1.29 2.06 4.23 5.48 2.94 12.29-3 15.84-.79.47-1.5 1.09-2.48 1.81l27 7.48c-5.6-7.35-5-12.23 2.14-18.25 1.26-1.06.31-1.75-.68-2.14s-2.32-.71-3.48-1.06q-9.72-2.91-19.43-5.79a4.92 4.92 0 0 0-1.36.06ZM71.26 279.55c-5.1-1.7-8.46-4.61-9.36-9.83-2.55 2.89-2.91 7.47-1 10.1s4.98 2.46 10.36-.27Zm221.48.4c.87.38 1.75.8 2.65 1.15 4.91 1.93 8.9-1.2 8.14-6.41-.07-.51-.56-1-.85-1.43a7.93 7.93 0 0 0-1.38.93c-.73.75-1.23 1.83-2.08 2.35-2.03 1.2-4.2 2.19-6.48 3.37Zm-119.93-45.17a313.69 313.69 0 0 1 44.51 2.13c10.5 1.33 21 2.9 31.4 4.8 6.8 1.24 13.51 3.09 20.16 5 7.83 2.22 15.6 4.66 23.33 7.21 7 2.32 11.75 7.29 14.34 14.07a25.2 25.2 0 0 1 1.53 9.12c0 5.78-4.14 9.59-9.91 9.19-3.05-.21-6.07-1.27-9.06-2.13-9.28-2.66-18.49-5.61-27.83-8.05-7.5-2-15.12-3.61-22.76-5s-15.53-2.34-23.33-3.24a318.42 318.42 0 0 0-49.6-1.34 274.9 274.9 0 0 0-42.89 5.05c-9.4 1.89-18.82 3.78-28.09 6.21-8.09 2.12-16 5-24 7.52-3.94 1.24-7.88 1.94-11.63-.62a8.38 8.38 0 0 1-3.74-6c-1.24-9.38 2.69-16.68 10.11-21.78 3.91-2.69 8.76-4.17 13.35-5.67 7.3-2.39 14.69-4.55 22.15-6.41s15-3.42 22.56-4.74c8-1.4 16.11-2.62 24.22-3.45 9.19-.95 18.34-1.38 25.18-1.87Zm8.64 49.3c-7.93.23-15.91 0-23.78.81-12.56 1.29-25.13 2.87-37.57 5.06-10.84 1.91-21.56 4.61-32.23 7.37-6.54 1.69-12.88 4.16-19.31 6.27l-.43.15c-4.14 1.33-5.61.12-4.67-4.09A16 16 0 0 1 74.9 287.2c6.39-2 12.74-4.15 19.16-6 4.66-1.37 9.4-2.52 14.14-3.61 5.56-1.28 11.15-2.45 16.75-3.57 3.06-.61 6.16-1.08 9.25-1.52a327.53 327.53 0 0 1 70.52-2.58c10.63.76 21.26 2.06 31.77 3.81 9.45 1.57 18.78 3.92 28.08 6.26 6.93 1.74 13.7 4.09 20.58 6 6.12 1.73 11.3 4.57 13.87 10.79a12.7 12.7 0 0 1 .87 2.81c.72 4.52-.71 5.51-5.09 4.09-8.75-2.84-17.49-5.75-26.37-8.12q-13.89-3.71-28-6.37c-7.92-1.49-16-2.53-24-3.23-11.61-1-23.27-1.52-34.91-2.25Zm-4.85 9.26c22.51.25 39.41 1.39 56.12 4.25 10.87 1.86 21.69 4.18 32.38 6.9 8.61 2.19 17 5.22 25.45 8 4.91 1.63 9.41 8.09 9.53 13.22.07 2.94-1.07 3.78-3.8 2.82a354.88 354.88 0 0 0-36.74-10.84 362.62 362.62 0 0 0-57.36-8.5 310.35 310.35 0 0 0-52.1.87 344.78 344.78 0 0 0-37.27 5.63c-12.27 2.55-24.29 6.28-36.39 9.6-3.22.88-6.33 2.16-9.49 3.26-2.58.9-3.8 0-3.73-2.73.13-5.32 4.84-11.73 9.85-13.49 13.07-4.61 26.28-8.79 39.94-11.28 11.22-2.06 22.48-4.11 33.81-5.43 11.72-1.35 23.52-1.82 29.8-2.28Zm115.18 44.5c-.82 2.63-3.16 2.82-4.84 3.32-7.34 2.2-14.7 4.5-22.21 6-37.05 7.29-74.54 7.75-112.08 6.33-11-.41-22.07-1.42-33-2.64a243.89 243.89 0 0 1-25.93-4.19c-7.31-1.62-14.39-4.29-21.56-6.54-.5-.16-.87-.7-1.3-1.06.49-.51.89-1.29 1.48-1.47 8.22-2.52 16.37-5.33 24.72-7.31 12.28-2.92 24.62-5.79 37.09-7.67a303.38 303.38 0 0 1 72.76-2.39c9.7.89 19.42 1.94 29 3.43 8.11 1.25 16.17 3 24.14 5 8.78 2.18 17.43 4.88 26.13 7.39 1.81.51 3.58 1.13 5.6 1.8Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Lima<\/p>\n        <\/a>\n    <\/div>\n\n\n\n\n\n\n\n\n    <!-- Tours en Cusco -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-ciudad-cusco\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n<!--             <svg width=\"60px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 371.84 354.11\">\n                <path fill=\"#4778FF\" d=\"M192.02 21.12a15.09 15.09 0 0 0-.93-2.08c-1.22-1.93-2.5-3.82-3.76-5.72-1-1.55-1.81-1.57-2.84 0-1.31 2-2.57 4-3.88 5.92a3.11 3.11 0 0 0 0 3.8c1.34 2 2.62 4.1 3.93 6.15.91 1.42 1.8 1.45 2.72 0 1.32-2 2.64-4.09 3.92-6.16a14.36 14.36 0 0 0 .84-1.91Zm-18.41 8.25c-.06-1.1-.07-1.91-.14-2.7-.66-6.69-.61-13.36 2.72-19.4a16.52 16.52 0 0 1 5.42-5.95c5.07-3.11 11-.51 14.06 5.51 3 5.87 3.49 12.07 2.91 18.47-.1 1.06-.14 2.13-.17 3.19 0 .19.21.38.4.68 2.28-.74 4.53-1.6 6.84-2.19a12.22 12.22 0 0 1 14.27 6.33c1.88 3.9 1.36 7.91-.79 11.61a19.14 19.14 0 0 1-8.55 7.66 5.38 5.38 0 0 1-5.2-.22c-10.94-5.72-22.27-6.26-33.87-2.36a31.83 31.83 0 0 0-5 2.3 5.28 5.28 0 0 1-5.19.3c-4.81-2.33-8.64-5.71-10-11-2.79-10.59 6.44-16.51 14.48-14.73 2.52.6 4.9 1.57 7.81 2.5Zm12.23 21c7.45.35 14.39 2 20.36 6.31 4.93 3.55 7 8.88 7.18 14.86 0 1-.93 2.09-1.43 3.14a12.19 12.19 0 0 1-2.41-1.41A31.14 31.14 0 0 0 191.15 65c-9.08-.93-17.79.09-25.49 5.57-1.36 1-2.58 2.13-3.85 3.21-1.63 1.39-2.79 1.15-3.2-.94a11.65 11.65 0 0 1 .07-4.52c1.81-8.68 7.38-13.74 15.8-15.78 3.74-.87 7.57-1.43 11.36-2.14Zm-85.69 1.77a4.76 4.76 0 0 1 4.84 4.52 8.72 8.72 0 0 0 .15 2.48 3.71 3.71 0 0 0 1.8 1.78 10.94 10.94 0 0 0 2.71.15 4.7 4.7 0 0 1 4.25 4.83 4.54 4.54 0 0 1-4.36 4.68c-.3 0-.61 0-.91.05-3.43.1-3.43.1-3.59 3.55-.13 2.94-1.29 4.54-3.81 5.26a4.14 4.14 0 0 1-4.91-1.89 6.72 6.72 0 0 1-.8-3.23c-.16-3.56-.13-3.39-3.76-3.75a7.14 7.14 0 0 1-4.33-1.92c-2.47-2.75-.55-6.95 3.22-7.51 1.48-.23 3.4.07 4.32-.76s.42-2.69.58-4.11a4.31 4.31 0 0 1 4.6-4.1Zm174.47 28c-2.54-.44-4.76-2.28-5.16-4.43a10.55 10.55 0 0 1-.13-1.59c-.11-3.45-.11-3.45-3.58-3.53s-5.41-1.93-5.38-4.87c0-2.74 2.18-4.64 5.36-4.73 3.52-.1 3.52-.1 3.61-3.73.08-3.16 1.79-5.08 4.59-5.16 3-.07 4.86 1.81 5 5s-.72 3.9 3.95 3.89a4.8 4.8 0 0 1 5 4.81c-.05 2.77-2 4.64-5.05 4.76-.61 0-1.22.06-1.83 0-1.45-.06-2.05.62-2.07 2.05s.21 2.86-.41 3.8c-.96 1.57-2.57 2.59-3.9 3.8Zm7.36 6.73a15.13 15.13 0 0 1-2.08.88c-.3.07-.73-.18-1.06-.35-3.14-1.67-6.22-1.42-9.36.07-.69.33-1.68 0-2.53 0a9.88 9.88 0 0 1 .45-2.93 5.59 5.59 0 0 1 2-2.05c3.44-2.18 9.58-1.08 11.52 2a20.37 20.37 0 0 1 1.06 2.45Zm-175.9 1.75a8.09 8.09 0 0 0-8.47-2c-1.32.54-2.67 1-4 1.5-1.31-2-.88-3.71 1.19-5.23 2.52-1.84 8-1.87 10.59-.06s2.8 3.7.66 5.79l.05.05h-.06Zm0 .05h.05Zm-45.89 1.46a4.63 4.63 0 0 1-4.64-4.16 15.06 15.06 0 0 1-.1-2.51c.06-1.56-.67-2.13-2.2-2.21a13.19 13.19 0 0 1-4.19-.79 4.21 4.21 0 0 1-2.45-4.89 4.34 4.34 0 0 1 4-3.8c4.41-.52 4.4-.54 4.95-4.85a5.08 5.08 0 0 1 4.76-4.37 5.19 5.19 0 0 1 4.73 4.48c.52 4.36.52 4.36 4.74 4.79a4.63 4.63 0 0 1 4.31 4.51c.1 2.47-1.7 4.43-4.49 4.9-1.39.24-3.21 0-4 .83s-.39 2.57-.55 3.91a4.53 4.53 0 0 1-4.84 4.23Zm259.79 0c-2.75 0-4.64-2-4.83-5-.22-3.59-.22-3.56-3.8-3.89-2.14-.2-4.09-.89-4.82-3.18-.66-2-.36-4.07 1.48-5.33a7.33 7.33 0 0 1 3.6-1c3.42-.19 3.35-.12 3.56-3.63a7.71 7.71 0 0 1 1-3.39 4 4 0 0 1 4.87-2c2.09.65 3.6 2 3.67 4.41v.69c.13 3.79.13 3.79 3.94 3.92 3 .1 5 1.8 5.08 4.44a5.08 5.08 0 0 1-4.85 5.08h-.46c-3.55.17-3.55.17-3.71 3.86-.1 3.21-1.89 5.11-4.7 5.1ZM202.32 78.2a17.13 17.13 0 0 0-2.42-2c-8.34-4.39-16.95-4.31-25.59-1.13-1.55.57-3.79.95-4.15 3.41a42.73 42.73 0 0 1 14.32 11.94c1.1 1.43 1.94 1.33 3-.07a43 43 0 0 1 14.84-12.15Zm117.61 13.85c2.89.18 5.55.63 7 3.31.4.75.19 1.84.25 2.77a6.81 6.81 0 0 1-2.56-.06 10.55 10.55 0 0 0-9.24 0 6.85 6.85 0 0 1-2.57.07 8.4 8.4 0 0 1 .29-2.73c1.37-2.94 4.22-3.02 6.83-3.36Zm-259.44-.19c2.65.56 5.52.81 6.86 3.74a7.25 7.25 0 0 1 .14 2.57c-.8 0-1.73.31-2.37 0a10.67 10.67 0 0 0-9.67 0c-.64.3-1.56 0-2.36 0a7.45 7.45 0 0 1 .23-2.62c1.37-3 4.36-3.17 7.17-3.69ZM210.8 80.05c-2.36 1-4.29 1.8-6.22 2.64-7.82 3.42-13 9.52-17.29 16.65-.31.53-.88 1.23-1.33 1.24s-1.11-.66-1.4-1.18c-4.32-7.52-10-13.57-18.06-17.13-1.68-.75-3.42-1.37-5.45-2.17 6.16-8.91 14.58-12.08 24.29-12.2 10.14-.13 18.98 2.93 25.46 12.15Zm-104.69 8.69a20.55 20.55 0 0 1 2.71 3.14c1.12 1.93 1.95 4 3 6.33a21.86 21.86 0 0 0 2.28-1.32c12.9-9.22 27.37-12.44 42.89-10.63 10.9 1.28 19 7.42 24.75 16.61 1 1.54 1.79 3.18 2.77 4.72a9.22 9.22 0 0 0 1.46 1.47 7.31 7.31 0 0 0 1.28-1.4 43 43 0 0 1 12.2-15.17 33.27 33.27 0 0 1 18-6.54 61.88 61.88 0 0 1 28.23 4.29 52.92 52.92 0 0 1 14.82 8.87c.68.59 1.42 1.09 2.72 2.06v-2.88a9.78 9.78 0 0 1 5.69-9.47 10.51 10.51 0 0 1 14.1 4.73 9.22 9.22 0 0 1 .83 7.72c-.62 1.76.28 1.92 1.74 1.76 5.38-.59 10.75-1.3 16.15-1.61a81.16 81.16 0 0 1 26.74 2.74c14.8 4.15 26.15 12.55 32.63 27 4.8 10.69 8.54 21.64 10.08 33.31a69.67 69.67 0 0 1-2.81 31.08c-5.35 16.39-16.2 28.58-29.67 38.72-11.15 8.4-23.61 14.37-36.6 19.31a4.11 4.11 0 0 1-2.66.07c-5.9-2.2-11.75-4.52-17.62-6.82a7.57 7.57 0 0 1-1.06-.73l8-4.72c14.16-8.38 27.39-17.93 37.86-30.83 6.85-8.43 11.82-17.84 12.64-28.84a50.83 50.83 0 0 0-1-14.5 73.08 73.08 0 0 0-7.89-20.86c-4.67-8.14-10.68-15-19.68-18.22a46.38 46.38 0 0 0-12.94-2.38 43 43 0 0 0-18.76 3.4c-.75.31-1.31 1.86-1.41 2.9-.52 5.06-.54 10.19-1.31 15.21-1.19 7.73-4.18 14.93-7.72 21.86-12.3 24.06-30 43.9-49 62.77-2.56 2.55-5.37.84-8.68.84.9-1.14 1.38-1.89 2-2.5 12.05-11.72 23.23-24.17 32-38.6 7-11.53 12.25-23.71 12.61-37.46.24-8.85-1.56-17.29-6.48-24.82-2.05-3.13-4.81-5.69-8.92-4.39a15.82 15.82 0 0 0-5.71 3.61c-5.09 4.75-8.35 10.81-11.54 16.89a241.56 241.56 0 0 0-14.85 36c-3.35 10-6.19 20.24-8.92 30.45-1.59 5.95-2.46 12.08-3.8 18.09a2.63 2.63 0 0 1-1.83 1.68c-6.25.07-12.51 0-18.77-.07a1.83 1.83 0 0 1-2.08-1.86 210.29 210.29 0 0 0-9.2-37.43c-3.28-9.81-6.47-19.67-10.26-29.28-4-10.26-8.52-20.4-15.16-29.31a37.85 37.85 0 0 0-8.13-7.85c-3.32-2.4-6.85-1.85-9.3 1.45a41.65 41.65 0 0 0-5.7 10.29c-3.12 8.51-3.22 17.38-1.44 26.18a81 81 0 0 0 8.65 22.76c9 16.35 21.15 30.1 34.34 43.08a12.2 12.2 0 0 1 1.25 1.74c-.72.31-1.42.67-2.15.92-2.88.94-5-.1-7.08-2.21-14.8-15-28.81-30.63-40.09-48.52a117.23 117.23 0 0 1-12.89-26.64c-2.31-7.21-3.7-14.64-3.09-22.29.18-2.23-.48-3.27-2.78-4.09a47.57 47.57 0 0 0-24.33-2.28c-9.37 1.61-16.71 6.86-22.15 14.55-7.87 11.14-12.47 23.58-12.78 37.25-.22 9.64 3.28 18.37 8.49 26.37 7.18 11 16.75 19.7 27.41 27.19 5.78 4 11.93 7.58 17.88 11.39a9.92 9.92 0 0 1 1.6 1.85c-3.65 1.2-6.95 2.26-10.24 3.37s-6.61 2.3-9.93 3.39a3.43 3.43 0 0 1-2.15.17c-14.22-5.69-27.5-13-39.09-23.12-9.61-8.4-17.31-18.26-21.84-30.28a69.9 69.9 0 0 1-3.75-34.41c1.6-11.92 5.43-23.09 10.47-33.91a44.75 44.75 0 0 1 22.11-22.18c14.12-6.63 29-7.66 44.27-5.92 3.85.44 7.68 1.09 11.53 1.61a11.12 11.12 0 0 0 1.93-.09c-.13-.6-.18-1-.31-1.43-2.24-6.86 1.84-13.79 9.86-14.38 1.79-.06 3.72.7 5.58 1.05Zm82.08 161.92a6.12 6.12 0 0 0-5.69-5.82 5.91 5.91 0 0 0-5.66 5.78 6.12 6.12 0 0 0 5.51 5.76c2.74.06 5.81-2.94 5.84-5.72Zm30.39 8a5.85 5.85 0 0 0 5.74-5.67 6.25 6.25 0 0 0-5.55-5.72 6 6 0 0 0-5.8 5.66 5.69 5.69 0 0 0 5.61 5.73Zm-66.61-5.71a6 6 0 0 0-5.81-5.64 6.1 6.1 0 0 0-5.56 5.68 5.69 5.69 0 1 0 11.37 0Zm65.86-11a142.3 142.3 0 0 0-30.93-1.56c7.79 5.07 8.54 14.67.06 20.35 8.38.74 16.74 1.66 25.68 1.53-7.9-7.91-4.82-17.29 5.19-20.32Zm-114.24 17a5.6 5.6 0 0 0 5.54 5.76 6.18 6.18 0 0 0 5.72-5.75 5.81 5.81 0 0 0-5.59-5.55 5.35 5.35 0 0 0-5.67 5.57Zm152.15-5.55a5.81 5.81 0 0 0-5.67 5.71 6.28 6.28 0 0 0 5.63 5.63 5.81 5.81 0 0 0 5.69-5.7 5.55 5.55 0 0 0-5.65-5.61Zm-103.12 8.29c2.43 1 23.88-.25 25.24-1.37-8.13-4.88-7.9-14.79.29-20-22.85-.51-45.31 2.54-67.68 7.52 3.83 1.82 7.45 3.72 8.66 8a11.51 11.51 0 0 1-2.81 11.26l.53.36 25.17-4.08c-7-7.15-8-12.42-3.48-17.36 4.31-4.71 8.69-5.09 13.94-1.41a12 12 0 0 1 4.06 6.08c1.28 4.3-.68 7.97-3.92 11Zm70.76-18.59c3.58 2.63 5.78 5.71 5.74 10.21 0 4.65-2.84 7.41-6.26 10.27l25.48 4.2c0-1-.12-1.35-.36-1.62-4.53-5-3.19-14.14 3.76-16.81.65-.25 1.11-1 2-1.79-10.42-1.82-20.18-4.34-30.36-4.46Zm69.12 31.25c2.8-.09 5.71-3.19 5.58-5.95a6.13 6.13 0 0 0-5.75-5.48 5.64 5.64 0 0 0-5.57 5.75 5.83 5.83 0 0 0 5.74 5.68Zm-219.88 0a5.93 5.93 0 0 0 5.54-5.88 5.6 5.6 0 0 0-5.58-5.51 5.85 5.85 0 0 0-5.74 5.67 6.16 6.16 0 0 0 5.78 5.72Zm2.54-16.8c3.37 2.46 6.54 4.32 7.6 8.08s-.33 7.18-2.27 10.45l.49.43 24.84-6.72c-8.15-5.57-10.06-11.95-3.28-19.79-9.17 1.4-17.8 4.47-27.38 7.55Zm187.44-7.28c.51.82.85 1.48 1.29 2.06 4.23 5.48 2.94 12.29-3 15.84-.79.47-1.5 1.09-2.48 1.81l27 7.48c-5.6-7.35-5-12.23 2.14-18.25 1.26-1.06.31-1.75-.68-2.14s-2.32-.71-3.48-1.06q-9.72-2.91-19.43-5.79a4.92 4.92 0 0 0-1.36.06ZM71.26 279.55c-5.1-1.7-8.46-4.61-9.36-9.83-2.55 2.89-2.91 7.47-1 10.1s4.98 2.46 10.36-.27Zm221.48.4c.87.38 1.75.8 2.65 1.15 4.91 1.93 8.9-1.2 8.14-6.41-.07-.51-.56-1-.85-1.43a7.93 7.93 0 0 0-1.38.93c-.73.75-1.23 1.83-2.08 2.35-2.03 1.2-4.2 2.19-6.48 3.37Zm-119.93-45.17a313.69 313.69 0 0 1 44.51 2.13c10.5 1.33 21 2.9 31.4 4.8 6.8 1.24 13.51 3.09 20.16 5 7.83 2.22 15.6 4.66 23.33 7.21 7 2.32 11.75 7.29 14.34 14.07a25.2 25.2 0 0 1 1.53 9.12c0 5.78-4.14 9.59-9.91 9.19-3.05-.21-6.07-1.27-9.06-2.13-9.28-2.66-18.49-5.61-27.83-8.05-7.5-2-15.12-3.61-22.76-5s-15.53-2.34-23.33-3.24a318.42 318.42 0 0 0-49.6-1.34 274.9 274.9 0 0 0-42.89 5.05c-9.4 1.89-18.82 3.78-28.09 6.21-8.09 2.12-16 5-24 7.52-3.94 1.24-7.88 1.94-11.63-.62a8.38 8.38 0 0 1-3.74-6c-1.24-9.38 2.69-16.68 10.11-21.78 3.91-2.69 8.76-4.17 13.35-5.67 7.3-2.39 14.69-4.55 22.15-6.41s15-3.42 22.56-4.74c8-1.4 16.11-2.62 24.22-3.45 9.19-.95 18.34-1.38 25.18-1.87Zm8.64 49.3c-7.93.23-15.91 0-23.78.81-12.56 1.29-25.13 2.87-37.57 5.06-10.84 1.91-21.56 4.61-32.23 7.37-6.54 1.69-12.88 4.16-19.31 6.27l-.43.15c-4.14 1.33-5.61.12-4.67-4.09A16 16 0 0 1 74.9 287.2c6.39-2 12.74-4.15 19.16-6 4.66-1.37 9.4-2.52 14.14-3.61 5.56-1.28 11.15-2.45 16.75-3.57 3.06-.61 6.16-1.08 9.25-1.52a327.53 327.53 0 0 1 70.52-2.58c10.63.76 21.26 2.06 31.77 3.81 9.45 1.57 18.78 3.92 28.08 6.26 6.93 1.74 13.7 4.09 20.58 6 6.12 1.73 11.3 4.57 13.87 10.79a12.7 12.7 0 0 1 .87 2.81c.72 4.52-.71 5.51-5.09 4.09-8.75-2.84-17.49-5.75-26.37-8.12q-13.89-3.71-28-6.37c-7.92-1.49-16-2.53-24-3.23-11.61-1-23.27-1.52-34.91-2.25Zm-4.85 9.26c22.51.25 39.41 1.39 56.12 4.25 10.87 1.86 21.69 4.18 32.38 6.9 8.61 2.19 17 5.22 25.45 8 4.91 1.63 9.41 8.09 9.53 13.22.07 2.94-1.07 3.78-3.8 2.82a354.88 354.88 0 0 0-36.74-10.84 362.62 362.62 0 0 0-57.36-8.5 310.35 310.35 0 0 0-52.1.87 344.78 344.78 0 0 0-37.27 5.63c-12.27 2.55-24.29 6.28-36.39 9.6-3.22.88-6.33 2.16-9.49 3.26-2.58.9-3.8 0-3.73-2.73.13-5.32 4.84-11.73 9.85-13.49 13.07-4.61 26.28-8.79 39.94-11.28 11.22-2.06 22.48-4.11 33.81-5.43 11.72-1.35 23.52-1.82 29.8-2.28Zm115.18 44.5c-.82 2.63-3.16 2.82-4.84 3.32-7.34 2.2-14.7 4.5-22.21 6-37.05 7.29-74.54 7.75-112.08 6.33-11-.41-22.07-1.42-33-2.64a243.89 243.89 0 0 1-25.93-4.19c-7.31-1.62-14.39-4.29-21.56-6.54-.5-.16-.87-.7-1.3-1.06.49-.51.89-1.29 1.48-1.47 8.22-2.52 16.37-5.33 24.72-7.31 12.28-2.92 24.62-5.79 37.09-7.67a303.38 303.38 0 0 1 72.76-2.39c9.7.89 19.42 1.94 29 3.43 8.11 1.25 16.17 3 24.14 5 8.78 2.18 17.43 4.88 26.13 7.39 1.81.51 3.58 1.13 5.6 1.8Z\" \/>\n            <\/svg>\n -->\n\n\n\n\n<svg width=\"60px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 198.58 223.24\"><path fill=\"#4778FF\" d=\"m178.12 88.63-1.92-2.25c0 2.93 0 5.65 1.58 8a49.15 49.15 0 0 0 2.74 3.82 26.67 26.67 0 0 1 4.42 8.59c.76 2.4 1.6 4.79 2.23 7.22a18.29 18.29 0 0 1 0 9.9c-.77 2.63-1.31 5.32-2.1 7.94a27.58 27.58 0 0 1-5.12 9.28 9.41 9.41 0 0 0-2 6 44.49 44.49 0 0 0 6.83 25.61c1.35 2.21 3 4.26 4.53 6.34a15.13 15.13 0 0 1 3.37 8.14 24.06 24.06 0 0 1-.21 6.46 1.07 1.07 0 0 1-.06.32c-1.16 2.21-1.81 4.65-3.37 6.7a43.47 43.47 0 0 1-6.4 6.18c-2 1.74-4.39 2.73-6.5 4.21a6.93 6.93 0 0 1-2.9 1c-3.11.42-6.25.74-9.3-.35-1.87-.67-3.69-1.48-5.56-2.16a2.13 2.13 0 0 0-1.45 0 162.07 162.07 0 0 1-18.22 7.6 117.07 117.07 0 0 1-27 5.58 111.7 111.7 0 0 1-58.11-10.41c-2-.92-3.93-1.86-5.87-2.84a2 2 0 0 0-2 0c-1.78.89-3.61 1.67-5.43 2.49a1.67 1.67 0 0 1-.71.19c-3.16-.17-6.38 0-9.46-.61a19.66 19.66 0 0 1-10.78-5.91c-1.36-1.44-3-2.75-3.93-4.43-3.13-5.55-4.46-11.43-2.36-17.73 3.52-10.57 6.67-21.28 11.74-31.26a3.91 3.91 0 0 0-.22-4.59 73.24 73.24 0 0 1-3.88-7.34c-1.88-3.56-4-7-5.63-10.66a31.24 31.24 0 0 1-.47-25.78c1.68-4.12 3.34-8.25 4.89-12.41a38.23 38.23 0 0 0 1.11-4.59 4 4 0 0 0-.33-2.77Q13.6 70.21 6.98 56.27a21.43 21.43 0 0 0-6.28-7.3c-.19-.16-.36-.34-.7-.67 1.11-.94 2.12-1.94 3.27-2.73 2.57-1.79 5.15-3.57 7.82-5.2a148.25 148.25 0 0 1 25.11-12 198.68 198.68 0 0 1 34.45-9.49c2.59-.47 5.22-.71 7.84-1 .8-.07 1-.44 1.12-1.09A24 24 0 0 1 85.6 5.35c2.34-2.43 5.32-3.59 8.5-4.42a30.54 30.54 0 0 1 14.9 0c6 1.43 9.82 5.33 11.95 11a34.48 34.48 0 0 1 1.25 4 1.46 1.46 0 0 0 1.34 1.22c7.63 1.55 15.33 2.88 22.87 4.78 15.16 3.82 29.7 9.26 43.11 17.42 2 1.22 4.07 2.36 6 3.66a25.59 25.59 0 0 1 3 2.55.89.89 0 0 1 0 .74c-.47 1.23-1 2.43-1.49 3.65a36.83 36.83 0 0 0-1.43 3.79c-2 7.42-5.38 14.31-8.56 21.27a57.87 57.87 0 0 1-7.82 12.44c-.33.36-.7.74-1.1 1.18Zm-35.75 73.46a27.79 27.79 0 0 1 .42-10.82c1-3.5 3.47-5.78 6.32-7.79a39.13 39.13 0 0 0 5.27-4c5.81-5.82 7.72-13 7-21-.25-2.9-.94-5.8-.91-8.69.05-3.93.62-7.86.91-11.79.17-2.48.38-5 .31-7.45-.1-3.33-2-5.86-4.23-8.14-5.31-5.45-11.91-8.72-19-11-10.15-3.27-20.65-4.39-31.24-4.63-4.94-.11-9.89.11-14.83.31a104.52 104.52 0 0 0-23.58 3.65c-8.21 2.24-15.94 5.54-22.48 11.14a31.06 31.06 0 0 0-4.45 4.58c-2.28 3-1.95 6.5-1.24 9.95a77.41 77.41 0 0 1 1.96 12.23c.23 5 .47 9.95 1 14.9a26.79 26.79 0 0 0 8.38 17.52c1.82 1.7 3.67 3.37 5.4 5.15 3.7 3.82 4.59 8.49 3.92 13.79-2.84-3.57-5.38-7.26-10-9 .21 3.12.35 6 .62 8.92a23.85 23.85 0 0 0 8.47 16.8 60.82 60.82 0 0 0 10.37 6.74A66.64 66.64 0 0 1 83.6 192a11.28 11.28 0 0 0 2.24 1.44c3.6 1.89 7.53 2.28 11.5 2.24q6.57-.06 13.13-.36a16.72 16.72 0 0 0 11.13-4.29 44.8 44.8 0 0 1 9.49-6.66c3.93-2.15 7.87-4.31 11.64-6.72a19.26 19.26 0 0 0 7.8-9.23 45.37 45.37 0 0 0 2.79-11.27 13.81 13.81 0 0 0-.27-6.13c-.5-1.51-1.42-1.94-2.67-1a16.15 16.15 0 0 0-3.64 3.5 44.52 44.52 0 0 0-2.9 5.57Zm42.68-92.81c-.71-.39-1.3-.7-1.89-1-3-1.76-5.83-3.75-8.93-5.22-4.76-2.25-9.64-4.24-14.54-6.16-8-3.13-16.11-5.92-24.63-7.29a201.45 201.45 0 0 0-39-2.42 234.56 234.56 0 0 0-24.55 2c-10.65 1.5-21.11 3.8-31 8.12-5.89 2.58-11.54 5.69-17.3 8.57l-5.9 3c1.41 3.19 2.71 6.38 4.22 9.48 1.38 2.83 1.6 2.81 4.24 1.14 2.47-1.57 4.84-3.31 7.42-4.64 16.88-8.69 34.95-12.74 53.83-13.42 4.55-.17 9.11-.18 13.67-.19 2.88 0 5.76.24 8.64.14a101.68 101.68 0 0 1 19.27 1.19 131.65 131.65 0 0 1 41.11 13.44c3 1.59 5.9 3.42 8.92 5.19 3.06-3.33 4.64-7.65 6.42-11.93ZM144.6 187.56l-.32-.16-1 .39a92.88 92.88 0 0 0-17.12 10.09 44.12 44.12 0 0 1-9.15 5.46 40.69 40.69 0 0 1-18.34 2.6 35.62 35.62 0 0 1-17.07-5.46c-3.29-2.12-6.52-4.35-9.89-6.34-3.62-2.13-7.37-4-11.07-6-.77-.4-1.59-.7-2.44-1.07a1.93 1.93 0 0 0-.06.48 31.33 31.33 0 0 0 4 11.76c6.72 11 16.56 17.29 29.24 19.2a70.68 70.68 0 0 0 17.56-.05 42.82 42.82 0 0 0 17.2-5c8.24-4.67 14.35-11.16 17.27-20.33.52-1.81.81-3.71 1.19-5.57Zm42-121.43a17.6 17.6 0 0 1 .7-1.86 1.14 1.14 0 0 0-.55-1.74c-2.58-1.44-5.11-3-7.72-4.34-.82-.44-1-.84-.64-1.65.57-1.3 1-2.68 1.63-3.94 1-1.86 2-3.66 3.11-5.46a1.66 1.66 0 0 1 2.29-.73c.88.39 1.77.74 2.65 1.14 1.39.63 2.74 1.37 4.16 1.92 1.25.48 1.76 0 1.45-1.35a4.78 4.78 0 0 0-2.59-3c-2.7-1.58-5.44-3.11-8.13-4.71a114.87 114.87 0 0 0-26-11.77c-6.31-1.87-12.72-3.44-19.12-4.94-4.64-1.09-9.36-1.84-14-2.76-.84-.16-1.18 0-1.24 1a54.44 54.44 0 0 1-2.79 14.74c-.69 2-1.29 4-2 6 1.08.16 2 .27 2.9.43 9.8 1.81 19.66 3.35 29.37 5.52 9.13 2 17.45 6.28 25.52 10.95 3.69 2.15 7.31 4.3 11 6.55ZM16.1 65.01c2.37-1.44 4.6-2.85 6.87-4.18A106.73 106.73 0 0 1 46.1 50.45c10.92-3.31 22.15-5.25 33.39-7.08 1.85-.3 3.71-.53 5.62-.8-1.24-3.6-2.68-7-3.57-10.59s-1.23-7.26-1.82-10.93a77 77 0 0 0-14.41 2.36 233.38 233.38 0 0 0-49.36 18.55 67.7 67.7 0 0 0-7.29 4.61c-1 .7-.94 1.3.07 2a1.41 1.41 0 0 0 1.22.07c2.57-1.19 5.11-2.44 7.73-3.71a37.32 37.32 0 0 1 6.76 10.37.8.8 0 0 1-.37 1.14c-1 .66-2 1.38-3 2-1.94 1.27-3.88 2.51-5.85 3.78Zm15.18 89.46h-.55c-.42.95-.91 1.89-1.25 2.88A34.24 34.24 0 0 1 26 165a22.34 22.34 0 0 0-2.4 4.88 36.29 36.29 0 0 1-5.49 10.08c-3.42 4.55-4.41 9.56-2.46 15a18.87 18.87 0 0 0 7.32 9.22c4.81 3.33 10.1 4.83 16 3.63 8.86-1.82 15-11.92 13.49-21.06a43.65 43.65 0 0 0-3.92-11.48c-2.49-5.29-4.83-10.63-6-16.4-.33-1.64-.75-3.25-1.13-4.87h-.26c-.12 1.27-.2 2.54-.37 3.8a35.38 35.38 0 0 1-.94 5.66 4.42 4.42 0 0 1-8.65-1.59c0-1.88.4-3.74.52-5.62a7.63 7.63 0 0 0-.4-1.78Zm129.66-.09h-.26c-.08.45-.19.9-.25 1.35a78.15 78.15 0 0 1-4.8 18.44 73.93 73.93 0 0 0-3.53 10.95 18.56 18.56 0 0 0 3.68 16.29c3.44 4.45 8 6.87 13.62 6.71 6.7-.19 12.09-3.17 16.27-8.32a16.35 16.35 0 0 0 3.84-11.47 15.7 15.7 0 0 0-4.15-9.62 34.3 34.3 0 0 1-6.14-10.06 13.23 13.23 0 0 0-1.76-3.16 32.56 32.56 0 0 1-4.75-8.55 25.86 25.86 0 0 0-1.5-2.9c-1 .86-.78 1.76-.66 2.63a52.69 52.69 0 0 1 .77 5.27 4.33 4.33 0 0 1-3.09 4.58 4.57 4.57 0 0 1-5.37-2.66 12.74 12.74 0 0 1-.93-3c-.33-2.2-.63-4.34-.96-6.48Zm1.82-9.73c3.66 2.23 6.83 2.08 10.25-.63 3.72-2.94 6.16-6.88 8.12-11.1a37.73 37.73 0 0 0 3.2-14 12.82 12.82 0 0 0-1-6.16 2 2 0 0 0-2.43-1.39c-1.16.21-2.33.35-3.47.62a12.3 12.3 0 0 0-5 2.57c1 .88 2 1.65 2.86 2.53a8.84 8.84 0 0 1 2.5 8.73 18.83 18.83 0 0 1-6.69 10.51c-.67.53-1.6 1.27-2.39.53s-.1-1.72.41-2.48c.93-1.39 2-2.71 2.82-4.15 1.68-2.87 2-6.58-2.36-8.8-.89-.46-1.74-1-2.58-1.51a4.33 4.33 0 0 1-1.24-3.53 12.9 12.9 0 0 1 6.15-7.48 6.72 6.72 0 0 1 6.64-.19 7.38 7.38 0 0 0 1.69.65c1.12.29 1.53-.11 1.15-1.19a10.17 10.17 0 0 0-3.59-5.07 4 4 0 0 0-3.92-.58c-3.57 1.31-6.49 3.67-9.5 5.88a1 1 0 0 0-.27.74 36 36 0 0 0 .33 5.31 52.25 52.25 0 0 1 .67 19c-.59 3.72-1.51 7.42-2.32 11.19Zm-43.5-121.68a26.25 26.25 0 0 0-1.4-9.35c-1.76-5-5-8.38-10.2-9.76a24.44 24.44 0 0 0-13.59.22 14.25 14.25 0 0 0-6.51 3.74 18.43 18.43 0 0 0-4.86 14.35 69.52 69.52 0 0 0 1.68 10.08 29.41 29.41 0 0 0 3.74 9.38 1.44 1.44 0 0 0 1 .64c4.2-.09 8.4-.32 12.59-.34 2.91 0 5.81.22 8.71.37 1.06.05 2.13.15 3.18.27a1.15 1.15 0 0 0 1.3-.81 44.92 44.92 0 0 0 4.39-18.79ZM37.14 129.26a42.21 42.21 0 0 1-2.66 3.31 4.27 4.27 0 0 1-6.07.39 12.44 12.44 0 0 1-4.17-6.2 46.34 46.34 0 0 1-2.47-18.28c.19-3.05.9-6 3.05-8.36 1.5-1.64 3.24-2.66 5.59-2.07a8.31 8.31 0 0 0 1.3.11 4.09 4.09 0 0 0-4.72-2 9.84 9.84 0 0 0-6.4 5.83c-1.84 4.09-2.1 8.4-1.85 12.77a63.65 63.65 0 0 0 3.28 16 42.16 42.16 0 0 0 4.4 10.15c1.54 2.38 3.44 4.36 6.29 5.17a4 4 0 0 0 4.6-1.37 11.67 11.67 0 0 0 1.89-3.83 15.29 15.29 0 0 0 0-7.18 10 10 0 0 0-2.06-4.44Zm-10.77-14.81-.38-.12a4.76 4.76 0 0 1 1.63-6.23 3.49 3.49 0 0 1 5 1.09 8.54 8.54 0 0 1 1.36 3.42c.22 2 .63 4.13-1.64 5.72a3.48 3.48 0 0 0 .29 5.69 2.08 2.08 0 0 0 2.58.12c.88-.68.58-1.54.3-2.43a5.08 5.08 0 0 1-.27-2.14 34.26 34.26 0 0 0 .08-10.11c-.45-2.74-1.25-5.36-3.43-7.28a3.67 3.67 0 0 0-5.69.57 10.13 10.13 0 0 0-1.95 5 38.58 38.58 0 0 0 1.35 14.91 33.16 33.16 0 0 0 2.45 6 5.77 5.77 0 0 0 1.81 1.91 2.09 2.09 0 0 0 2.79-.47c.71-.88 0-1.43-.51-2a17.52 17.52 0 0 0-1.38-1.48 7.19 7.19 0 0 1-2.22-7.28 16.72 16.72 0 0 1 2.81-5.47c.7-1 .65-1.53-.25-2.54a11.51 11.51 0 0 1-.3 1.16c-.33.95-.88 1.06-1.53.28a7.32 7.32 0 0 1-.55-.91l-1-1.63Zm-3.65-21.4c6.1-1.92 10.6.54 14.75 4.4a54.83 54.83 0 0 0-.26-7.18c-.28-2.21-1.34-3-3.55-3-3 0-6 .18-8.95.32-.26 0-.69.23-.74.43-.43 1.55-.79 3.12-1.25 5.03Zm136.15-16.86-.17.36c.94.53 1.86 1.09 2.83 1.57 1.27.64 2.58 1.18 3.86 1.81a1.67 1.67 0 0 1 .72.72c2.34 5.06 3.74 10.3 2.92 15.94-.19 1.32-.36 2.64-.54 4 .12 0 .21 0 .25-.09 3.81-5.15 4.68-10.87 3.17-17a5 5 0 0 0-2.52-3.31 40.77 40.77 0 0 0-4.48-2c-1.99-.75-4.03-1.31-6.04-2Zm-115.27.34-.12-.25c-.87.28-1.74.54-2.6.85a50 50 0 0 0-11.7 5.62 16.51 16.51 0 0 0-1.42 1.28 3.91 3.91 0 0 0 3.79-.24c4.05-2.38 8.05-4.83 12.05-7.26Zm121.27 80.35c-.23 2.07-.33 4 .63 5.84a1.69 1.69 0 0 0 3-.18 7.54 7.54 0 0 0-.38-5 1.5 1.5 0 0 0-1-.74 13.35 13.35 0 0 0-2.25.08ZM37.72 160c-.08-.79-.13-1.36-.19-1.92s.09-1.23-.84-1.33c-1.32-.14-2.47.18-2.59 1a31.11 31.11 0 0 0-.21 4.1c0 .79.17 1.59 1.21 1.69a1.75 1.75 0 0 0 2.18-1.37 18.15 18.15 0 0 0 .44-2.18Zm.85-10.55c-1.92.45-3.69.84-5.45 1.32a4.64 4.64 0 0 0-1.21.86 13.88 13.88 0 0 1 1.38.58 4.33 4.33 0 0 1 1 .77c.28.29.39.82.7 1a1.46 1.46 0 0 0 1.86-.12c1.18-1.17 1.5-2.58 1.75-4.42Zm131.51 2.08v-.44a15.27 15.27 0 0 0-6.84-1.25 6.48 6.48 0 0 0 1.85 4c.78.66 2.62.26 2.54-.56-.11-1.14.56-1.15 1.31-1.3a6.33 6.33 0 0 0 1.14-.46Z\"\/><path fill=\"#4778FF\" d=\"M46.28 95.88a16.2 16.2 0 0 1 2.67-1.18c4.49-1.06 9-2.1 13.53-3a45.32 45.32 0 0 1 12.41-1 25.31 25.31 0 0 1 12.24 4 25.67 25.67 0 0 0 3.17 1.74 4.66 4.66 0 0 0 1.6.12c-.23-.47-.35-1.1-.72-1.39a66.74 66.74 0 0 0-6.48-4.66c-6.38-3.72-13.37-4.84-20.67-4.5a68.75 68.75 0 0 0-15.9 3c-.41.12-.82.23-1.24.33-.06 0-.13 0-.48-.07 1.12-.95 2-1.88 3.08-2.6 5.73-4 12.2-5.67 19.07-6.08a33.93 33.93 0 0 1 14.25 2.07 22.48 22.48 0 0 1 14.56 20.22c.09 4.39-.37 8.79-.53 13.19-.06 1.73.05 3.48 0 5.22a9 9 0 0 1-.36 2.3 1.19 1.19 0 0 1-.9.68 1.32 1.32 0 0 1-.95-.75 30.63 30.63 0 0 1-.45-3.7 60.66 60.66 0 0 0-.55-7.53c-.77-3.74-3-6.79-5.53-9.61-3.94-4.4-8.63-7.48-14.61-8.34a43.17 43.17 0 0 0-12.43.47c-4.29.63-8.59 1.26-12.89 1.84a7.17 7.17 0 0 1-1.86-.25ZM110.28 97.55c2.2-1.19 4.33-2.49 6.58-3.52 6.6-3 13.5-4.84 20.81-4.18a22.23 22.23 0 0 1 16.62 9.67 9 9 0 0 1 .78 1.91l-.27.24c-.67-.4-1.35-.78-2-1.19-2.12-1.31-4.2-2.69-6.36-3.93-5.75-3.32-11.79-3.58-18-1.6a48.43 48.43 0 0 0-18.07 10.63 3.17 3.17 0 0 0-.86 2.79q.08 7.08.1 14.17a7.8 7.8 0 0 1-.22 1.34l-.33.12a4.76 4.76 0 0 1-.67-1.25 53.38 53.38 0 0 1-.86-5.58 78.52 78.52 0 0 1 .81-20.31c.55-3 1.27-5.88 3.42-8.15a18 18 0 0 1 7.57-4.45 49.72 49.72 0 0 1 15.38-2.84 27 27 0 0 1 17.81 6.11 32.21 32.21 0 0 1 3.06 3.22l-.22.3c-.88-.4-1.79-.72-2.63-1.19-5.6-3.15-11.62-3.77-17.89-3.16a55.26 55.26 0 0 0-19.43 5.18c-1.11.55-2.13 1.3-3.23 1.86a3.32 3.32 0 0 0-1.9 3.81ZM93.22 140.76c-2 2.43-4.33 2.29-7 1.55-4.93-1.38-6.73-5-4.62-9.75a13.86 13.86 0 0 1 3.74-4.87c1.7-1.47 5.74-1.8 7.59-.58a1.92 1.92 0 0 1 .69 1.46c0 .59-.5.89-1.17.55a15.53 15.53 0 0 0-2-.94 3.83 3.83 0 0 0-4.42 1.27 4.47 4.47 0 0 0-1.06 4.93 3.23 3.23 0 0 0 4.3 1.65 29.65 29.65 0 0 0 3.1-1.87c1.46-.92 2.13-.87 3.39.35.77.73 1.46 1.55 2.27 2.24 2.39 2 4.15 2.11 6.75.34 1.06-.72 2.11-1.46 3.15-2.21a8.35 8.35 0 0 1 5.72-1.22 1.57 1.57 0 0 1 .77.32c.46.32.9.69 1.34 1 .86.7 1.62 1.91 2.89 1.36a4.6 4.6 0 0 0 2.7-3.86 3.28 3.28 0 0 0-1.66-3.34c-1.66-1.05-3.58-1.09-5.45-1.27a4.94 4.94 0 0 1-.95-.11 3.46 3.46 0 0 1-.73-.44c.18-.24.3-.56.54-.7 2.44-1.49 7.4-.85 9.63 1.21a7.77 7.77 0 0 1 1.47 8.79c-1.42 3-3.93 4.53-6.94 5.41-2 .6-4.16 1.4-6.25.43-1.34-.63-2-.09-2.74.82-.91 1.14-1.82 2.28-2.76 3.4-2.61 3.09-5.08 2-6.95-.08-1.22-1.34-2.33-2.78-3.52-4.15-.53-.57-1.13-1.03-1.82-1.69Z\"\/><path fill=\"#4778FF\" d=\"M113.72 108.11c2.38-2.56 4.78-4.61 8-5.08 4.11-.59 8.26-1 12.4-1.32a95 95 0 0 1 10.11-.48 26.4 26.4 0 0 1 13.27 3.51 8.54 8.54 0 0 1 .78.56 2.38 2.38 0 0 1 .28.35c-.34.06-.6.07-.85.14-2.23.55-4.48 1.08-6.69 1.7-.35.1-.63.62-.84 1a44.46 44.46 0 0 1-3 5.28c-1.83 2.39-4.59 3.31-7.5 3.62-6.74.72-12.63-1.39-17.87-5.54-.44-.35-.86-.74-1.29-1.12 0 0 0-.12-.11-.38 1.34.4 2.57.79 3.82 1.12a69.44 69.44 0 0 0 8.88 2.22c5.06.64 9.44-1.41 13.45-4.41-5.42.7-10.82 1.4-16.28.79s-10.81-1.28-16.56-1.96ZM48.06 103.88a8.64 8.64 0 0 1 2-.39c6.79.49 13.36-1.1 20-2a46.76 46.76 0 0 1 6.48-.37 11.29 11.29 0 0 1 7.3 2.62 52.58 52.58 0 0 1 5.23 5.12c-4.73-.59-9.09 1.31-13.62 1.38a71.12 71.12 0 0 1-8.47-.7c-2.19-.23-4.37-.53-6.61-.66a42 42 0 0 0 10.84 5.7c4.05 1.24 8.07.66 12.22-.39a3.44 3.44 0 0 1-1.64 2.37 12.69 12.69 0 0 1-7.05 2.1 20.92 20.92 0 0 1-14.61-4.65c-3.64-2.9-7.29-5.79-10.92-8.71a9.68 9.68 0 0 1-1.15-1.42ZM71.36 161.29a12.49 12.49 0 0 1 2.2-1c4.29-1 7.88-3.39 11.71-5.32a52.42 52.42 0 0 1 7.05-3 5.47 5.47 0 0 1 6.53 2.09 14.79 14.79 0 0 0 1.52 1.65 2.28 2.28 0 0 0 3.56.17 9.07 9.07 0 0 0 1.56-1.6c2-2.85 4.73-3.27 7.86-2.42a36.56 36.56 0 0 1 8.39 3.89c3.59 2 7.21 4 10.82 6 .12.07.22.16.46.33a10.77 10.77 0 0 1-6.14 1.56c-3.76-.11-7.09-1.71-10.54-2.92-.94-.33-1.89-.62-2.84-.93a11.91 11.91 0 0 0-8.26 0c-2.77 1.06-5.54.52-8.31 0a13.87 13.87 0 0 0-7.64.65c-4.21 1.53-8.51 2.88-13.08 2.77a10.71 10.71 0 0 1-3.11-.6c-.58-.16-1.02-.73-1.74-1.32ZM122.26 165.74a15.13 15.13 0 0 1-7.94 3.89 52.19 52.19 0 0 1-26.15-.75 21.25 21.25 0 0 1-4.09-2c-.38-.2-.63-.63-1.1-1.13ZM78.28 76.79h4.41a47.57 47.57 0 0 1 15.17 3.17 10.06 10.06 0 0 0 6.91-.19c6.16-2.11 12.55-2.71 19-3.09a1.1 1.1 0 0 1 .86.3c-.8.32-1.58.69-2.4.94-2.76.84-5.6 1.45-8.26 2.49a59.74 59.74 0 0 0-7.13 3.63c-4.24 2.39-8.29 1.86-12.33-.52-2.9-1.71-5.71-3.63-9-4.54-2.1-.57-4.2-1.1-6.3-1.65l-.94-.27ZM103.11 172.04a23 23 0 0 1 10.95 2.52 12.16 12.16 0 0 1 3.09 2.55c.85.94.43 1.73-.86 1.66a25.57 25.57 0 0 1-4.84-.7 33.21 33.21 0 0 0-10.31-1.41c-2.61.16-5.18.86-7.77 1.27a34.4 34.4 0 0 1-3.49.36 3.09 3.09 0 0 1-1-.34c.13-.36.15-.82.39-1a16.72 16.72 0 0 1 2.82-2.24 23 23 0 0 1 11.02-2.67ZM161.51 61.01c2.27 0 4.33 1.86 4.33 3.85a3.4 3.4 0 0 1-3.49 3.29c-2.31 0-4.28-1.77-4.22-3.79a3.42 3.42 0 0 1 3.38-3.35ZM140.27 54.31a4.15 4.15 0 0 1 4.17 3.86 3.17 3.17 0 0 1-3.19 3c-2.32-.13-3.84-1.35-3.8-3.31s1.33-3.55 2.82-3.55ZM42.53 66.88c-.63-.08-1-.11-1.41-.18a2.56 2.56 0 0 1-2.28-1.67 3 3 0 0 1 1-3.09 3.86 3.86 0 0 1 5.62 0 2.64 2.64 0 0 1-.86 4.46 14.4 14.4 0 0 1-2.07.48ZM27.11 74.57c-1.77 0-2.85-1.13-2.87-3.07s1-3.5 2.59-3.53a3.71 3.71 0 0 1 3.81 3.5 3.39 3.39 0 0 1-3.53 3.1ZM123.05 57.94a3.34 3.34 0 0 1-3.39-3.24 3 3 0 0 1 2.77-3 3.29 3.29 0 0 1 3.56 3.17 3.06 3.06 0 0 1-2.94 3.07ZM80.73 57.88a3.18 3.18 0 0 1-3.34-3 3.53 3.53 0 0 1 3.14-3.19 2.84 2.84 0 0 1 3.14 2.86 3.42 3.42 0 0 1-2.94 3.33ZM58.41 57.88c0-1.61 1.31-3.15 2.6-3.13 2 0 3.71 1.35 3.68 2.83s-1.74 3.41-3.09 3.38a3 3 0 0 1-3.19-3.08ZM101.36 56.82a3.2 3.2 0 0 1-3.28-3.2c0-1.29 1.34-2.91 2.37-2.89 2 0 3.79 1.59 3.76 3.33a3 3 0 0 1-2.85 2.76ZM125.72 39.13c.72-4.05 1.43-8 2.1-11.95.15-.84.42-1.17 1.38-1.05a94 94 0 0 1 19.07 4c3 1 3.51 1.61 3 4.66a91.47 91.47 0 0 1-2.2 9c-.05.2-.75.4-1.08.33q-6.6-1.35-13.16-2.79c-2.64-.57-5.27-1.19-7.9-1.79-.33-.08-.65-.22-1.21-.41Zm14.43.75.71.17c1.93.41 2.72-.1 3.1-2 .23-1.12.43-2.24.63-3.36a2 2 0 0 0-1.85-2.66c-2.34-.45-4.69-.87-7-1.32-1.59-.3-2.44.24-2.76 1.84-.21 1.09-.39 2.17-.59 3.26-.39 2.2.48 3.16 2.77 3-.66-2.45-.18-4.05 1.46-4.89a3.41 3.41 0 0 1 4.22 1c1.09 1.47.89 3.18-.69 4.96ZM156.6 47.15c1-3.17 1.8-6.14 2.78-9.06 1.27-3.82.49-3.35 4.28-2.52a45.11 45.11 0 0 1 13.17 4.8c.31.17.61.38.9.57a2.58 2.58 0 0 1 1.19 3.38c-1.11 2.88-2.27 5.74-3.41 8.61a1.12 1.12 0 0 1-1.63.68c-3.29-1.15-6.59-2.25-9.86-3.46-2.53-.95-5.04-2.04-7.42-3Zm8.23-.08c-.08-2.64.59-3.88 2.34-4.43a3.1 3.1 0 0 1 3.82 1.5 4.54 4.54 0 0 1 .29 2.85c-.24.84-1.13 1.49-1.76 2.25.15.08.36.2.58.3 1.82.85 2.63.57 3.47-1.24.49-1.07 1-2.12 1.46-3.2a1.89 1.89 0 0 0-1-2.81c-2.27-1.09-4.56-2.15-6.86-3.2a1.85 1.85 0 0 0-2.74.94c-.64 1.27-1.26 2.55-1.82 3.86a1.89 1.89 0 0 0 1 2.6c.36.21.78.39 1.24.58ZM52.01 30.25c6.41-1.76 12.63-3.69 19.18-4.07 2.62-.15 4 .66 4.7 3.21.81 2.9 1.29 5.89 1.95 9-1.52.37-2.85.71-4.19 1-5.26 1.25-10.52 2.48-15.77 3.74-2.07.49-2.91.14-3.67-1.83a44.65 44.65 0 0 1-2.2-11.05Zm16.18 7.91c2.37 0 3.17-1 2.73-3.23-.22-1.12-.44-2.24-.68-3.35a1.9 1.9 0 0 0-2.33-1.66q-3.94.73-7.84 1.63a1.79 1.79 0 0 0-1.42 2.27c.2 1.16.45 2.31.69 3.46.46 2.27 1.69 2.88 3.81 1.88-1.48-1.76-1.73-3.56-.67-4.9a3.43 3.43 0 0 1 4.13-1c1.76.85 2.27 2.42 1.58 4.9ZM28.79 54.12a49.69 49.69 0 0 1-5.42-11.8c-.24-.75.16-1 .65-1.21 3.4-1.46 6.77-3 10.21-4.32 2-.77 4.08-1.24 6.12-1.87 1-.32 1.73-.17 2.16 1 1.13 3 2.34 6 3.53 9 .28.7-.24.89-.67 1.11-4.06 2-8.12 4.11-12.2 6.12-1.4.73-2.85 1.29-4.38 1.97Zm9.69-6.87c2.11-.4 3-1.43 2.54-2.87s-1-2.8-1.63-4.17a1.86 1.86 0 0 0-2.55-1.05c-2.39.91-4.78 1.83-7.16 2.79a1.94 1.94 0 0 0-1.18 2.77c.39 1 .8 2.05 1.2 3.08.85 2.22 2.05 2.59 4.08 1.25-1.85-1.45-2.37-3.25-1.41-4.89a3.42 3.42 0 0 1 4.19-1.39c1.7.65 2.4 2.23 1.92 4.48ZM48.77 191.64c-.16 4.72-1.7 9.08-6 12.11a14.28 14.28 0 0 1-6.58 2.3 16 16 0 0 1-17-10.59 12.11 12.11 0 0 1 .72-8.93c2-4.3 4.78-8 9.16-9.9 5.93-2.6 14.76-1.05 18.09 7.24a21.47 21.47 0 0 1 1.61 7.77Zm-2.69-1.34c.12-6.53-5.56-14.12-14.26-11.15a14.43 14.43 0 0 0-9.75 11 7.58 7.58 0 0 0 1 5.75 13.18 13.18 0 0 0 8.39 6 11.81 11.81 0 0 0 14.62-11.6ZM42.75 165.24c-.31 1.57-.59 3.14-.94 4.69a2 2 0 0 1-2.13 1.73c-2 0-3.91 0-5.86-.1s-3.41-1.34-4.73-2.67c-.57-.57-.2-1.82.64-2.51s1.19-.12 1.45.44c1.63 3.44 6.84 2.95 9.06.32a21.72 21.72 0 0 1 1.73-1.73 2.68 2.68 0 0 1 .52-.32ZM169.8 206.03a13.78 13.78 0 0 1-14-12.2 18.55 18.55 0 0 1 2.24-12.05c2.3-4.16 6-5.87 10.59-6.34 6.12-.62 10.08 2.71 13.52 7 2.15 2.69 3.66 5.73 3.51 9.29-.19 4.75-2.58 8.36-6.26 11.15a15.25 15.25 0 0 1-9.6 3.15Zm-1-27.65a19.32 19.32 0 0 0-2 .23c-4.91 1-8.35 5.27-8.69 10.68a12.11 12.11 0 0 0 7.54 11.9c4.92 1.82 9.2.6 13-2.73 2.84-2.47 4.28-5.48 3.47-9.28-1.16-5.73-7.41-10.73-13.29-10.8ZM160.35 165.34c.79.69 1.62 1.34 2.36 2.08a6.07 6.07 0 0 0 4.45 1.74 4.55 4.55 0 0 0 4.32-2.42c.23-.41.93-1 1.06-.94a4.26 4.26 0 0 1 1.39 1.35 1.18 1.18 0 0 1-.23 1.53c-2.15 2.58-5.09 3-8.18 3.17h-.64c-3.17 0-3.41-.17-4.2-3.28-.25-1-.41-2-.61-3ZM110.73 14.88c1.2 0 2.23-.07 3.25 0 1.42.11 1.78.88 1 2.1-.52.83-1.12 1.61-1.87 2.66 1 .07 1.68.07 2.35.19a5.06 5.06 0 0 1 1.12.5c-.17.37-.24.88-.53 1.08-.82.57-1.73 1-2.61 1.5.57.38 1.28.76 1.9 1.26 1 .81.88 1.55-.3 2.07-.7.32-1.44.56-2.34.9.38.68.7 1.34 1.09 1.95.71 1.14.55 1.83-.68 2.37-.64.28-1.34.44-2.23.72.38 1 .81 1.93 1.11 2.92a1.9 1.9 0 0 1-.07 1.33c-1.82 3.4-5 4.49-8.53 4.72-1.92.12-3.84.05-5.77 0a7.54 7.54 0 0 1-6.91-4.39 2.47 2.47 0 0 1 .15-2.81 5.48 5.48 0 0 0 .46-.72c.48-.95.28-1.36-.76-1.52-.52-.08-1.06-.06-1.59-.11a1.42 1.42 0 0 1-1.42-1.9 3.36 3.36 0 0 1 .24-.82 1.78 1.78 0 0 0-.66-2.54 1.43 1.43 0 0 1 .07-2.49c.53-.35.78-.74.55-1.3a3 3 0 0 1 .72-3.12 7.33 7.33 0 0 1-1.35-1.05c-.43-.52-1.09-1.3-1-1.74s1-1 1.67-1.21a10.63 10.63 0 0 1 2.3-.35c-.14-.7-.29-1.28-.36-1.88-.12-.92.29-1.42 1.26-1.37h.32c2.18.08 2.16 0 2.39-2.14.06-.49.44-1.32.71-1.34a3.65 3.65 0 0 1 1.62.65c.17.09.26.34.38.51.53.7 1.11.78 1.6 0 .76-1.2 1.47-2.43 2.19-3.65.21-.36.39-.74.71-1.35.84 1.48 1.6 2.75 2.3 4.06s.82 1.42 2.06.45a5.83 5.83 0 0 1 1.15-.78 7.89 7.89 0 0 1 1.39-.37 5 5 0 0 1 .25 1.5 21.37 21.37 0 0 1-.62 2.59c1-.26 2-.55 2.91-.71 1.34-.22 1.73.27 1.27 1.56a20.48 20.48 0 0 1-.89 2.07Zm-2.23 3.08c0-2.66-.06-2.82-2.44-2.68a4.29 4.29 0 0 1-3.68-1.71c-1.24-1.35-1.6-1.4-2.81 0a4.61 4.61 0 0 1-4.21 1.7c-1.58-.11-2 .35-1.91 1.93a4.18 4.18 0 0 1-1.72 4.17 2.13 2.13 0 0 0-.29.31c-.86.94-.86 1.3 0 2.25a5.46 5.46 0 0 0 .68.68 3.07 3.07 0 0 1 1.26 3.08 6.15 6.15 0 0 0 0 1c0 1.26.4 1.76 1.67 1.63a4.94 4.94 0 0 1 4.67 1.89c.89 1.08 1.52 1 2.46 0a4.65 4.65 0 0 1 4.26-1.86c1.78.18 2.11-.19 2-2a4.25 4.25 0 0 1 1.65-4c1.42-1.13 1.35-1.91-.07-3.09-1.08-.96-1.83-1.98-1.52-3.26ZM95.68 36.88c1.46 2.45 7.13 2.49 11.33.63l-.65-.8.87-1.09c-.92.16-1.55.33-2.18.37-2.51.16-5 .25-7.53.43a10.53 10.53 0 0 0-1.84.46Z\"\/><path fill=\"#4778FF\" d=\"M33.92 193.79a3.45 3.45 0 0 1-2.85-2.22c-.2-.94.39-1.87 1.69-2.39a4.05 4.05 0 0 1 2-.37 2.4 2.4 0 0 1 2.1 2.64 2.76 2.76 0 0 1-2.94 2.34ZM179.11 191.79a8.43 8.43 0 0 1-12.28 7.31 10.25 10.25 0 0 1-5.23-11.72 7.65 7.65 0 0 1 8.27-5.62 10.61 10.61 0 0 1 9.24 10.03Zm-9.64-6.9a9 9 0 0 0-1.56.56 6.12 6.12 0 0 0-2 8.55c1.79 2.55 5.79 3 8.37.85a4.35 4.35 0 0 0 1.75-4.13 7.13 7.13 0 0 0-6.56-5.84Z\"\/><path fill=\"#4778FF\" d=\"M169.88 188.5c1.67 0 3.41 1.2 3.42 2.44 0 1-1.71 2.63-2.83 2.65-1.75 0-2.94-.95-3-2.47a2.58 2.58 0 0 1 2.41-2.62Z\"\/><\/svg>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Cusco<\/p>\n        <\/a>\n    <\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n    <!-- Tours en Puno -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-puno\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"75px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 65.58 32.46\">\n                <path fill=\"#4778FF\" d=\"m279.07 424.25.09 3.05h3.76v-3.08Zm10.89.09.84-.22h2.33l.6.38.12 6.22.1.32.06 3-3.77.16-.12-3.19-.16-3.59-.11-.65Zm17.34 5.56.18 3.06.08.87.06 1.08v.55l2.82-.16c.81 0 2.44-.09 2.44-.09a14.75 14.75 0 0 0-1.34-2.07 13.39 13.39 0 0 0-2.06-2 15 15 0 0 0-2.18-1.24Zm0-.27a6.73 6.73 0 0 1 .76.27 13.78 13.78 0 0 1 2.95 1.83 17.74 17.74 0 0 1 2.15 2.38 9.12 9.12 0 0 1 .68 1.06 11 11 0 0 0-.43-1.16c-.3-.67-.91-2-1.39-2.84a25.87 25.87 0 0 0-1.47-2.44 19.18 19.18 0 0 0-1.67-2.13 9.08 9.08 0 0 0-1.77-1.5 14.79 14.79 0 0 0-2.5-1.12 3.42 3.42 0 0 0-1.15-.06c-.42 0-1.37.16-1.37.16a9.35 9.35 0 0 1 1.48-.39 3.28 3.28 0 0 1 1.21 0 8.64 8.64 0 0 1 2.35.83 19.26 19.26 0 0 1 3.18 2.68 18.33 18.33 0 0 1 2.08 2.86c.67 1.1 1.53 2.84 2 3.69.26.47.76 1.43.76 1.43-.19-.73-.56-2.19-.92-3.26-.44-1.34-1.09-3.22-1.77-4.76a46.48 46.48 0 0 0-2.28-4.52 41.15 41.15 0 0 0-2.34-3.51c-.74-1-1.61-2.1-2.37-3s-2.18-2.12-2.18-2.12c.84.65 2.5 1.94 3.37 2.72a20.76 20.76 0 0 1 1.83 1.94c.52.6 1 1.24 1.47 1.88s1.05 1.43 1.44 2 .93 1.45.93 1.45c0-.38-.06-1.15-.09-1.54s-.09-.81-.09-.81a1.56 1.56 0 0 1-.43 0 .53.53 0 0 1-.23-.19 1 1 0 0 1-.19-.36c-.1-.5-.29-1.73-.43-2.6s-.34-2.3-.47-3.16c-.1-.67-.25-1.62-.29-2a.57.57 0 0 1 .05-.34 1.45 1.45 0 0 1 .35-.35 1 1 0 0 1 .29-.1c-.06-.3-.18-.92-.25-1.33s-.12-.88-.14-1.11a.53.53 0 0 1 0-.27s.13 0 .15.05a7.44 7.44 0 0 1 .24.88c.09.43.28 1.72.28 1.72a1.19 1.19 0 0 1 .25 0 .51.51 0 0 1 .25.1.88.88 0 0 1 .33.4c.16.82.49 3.39.67 4.54.13.79.33 1.8.42 2.36a9 9 0 0 1 .14 1 .67.67 0 0 1-.1.34.8.8 0 0 1-.18.23c-.1.07-.38.21-.38.21.06.47.17 1.42.22 2s.05 1.34.05 1.34a5.45 5.45 0 0 1 .29.48c.29.57 1.45 2.93 1.45 2.93V417.12h-.11a1.47 1.47 0 0 1-.27 0 .69.69 0 0 1-.2-.13.46.46 0 0 1-.15-.16.74.74 0 0 1-.1-.26v-7.99a.35.35 0 0 1 .06-.14 1.2 1.2 0 0 1 .13-.21.54.54 0 0 1 .15-.15.85.85 0 0 1 .22-.09 1 1 0 0 1 .21 0V406.7a2.56 2.56 0 0 1 0-.42s.07-.07.11-.08.09 0 .12 0a.44.44 0 0 1 .08.21v1.57h.2a.75.75 0 0 1 .27.13 1.07 1.07 0 0 1 .28.42 4.31 4.31 0 0 1 0 .83v4.17c0 1.06 0 2.58-.06 3.17 0 .17-.24.27-.35.35a1.31 1.31 0 0 1-.33.15v12.14l.57 1.28c0-.17.11-.5.16-.75.12-.53.33-1.65.56-2.45s.69-2.18.92-2.83c.13-.37.43-1.1.43-1.1v-.64l-.08-2.81-.11-3.65v-1.3a3.54 3.54 0 0 1-.38-.09.41.41 0 0 1-.13-.1 1 1 0 0 1-.14-.2.64.64 0 0 1-.1-.24c0-.19 0-.61-.06-.92-.05-.47-.13-1.24-.19-1.85s-.2-1.69-.2-2.44-.14-1.62-.17-2.1a6.54 6.54 0 0 1 0-.77.5.5 0 0 1 .13-.26 1.68 1.68 0 0 1 .21-.18l.12-.11c0-.26-.12-.77-.16-1s-.07-.18-.08-.26a.57.57 0 0 1 0-.23s.09-.1.13-.07a.59.59 0 0 1 .14.25c0 .16.06.48.11.7l.14.62h.45a.42.42 0 0 1 .25.09c.1.09.31.26.34.44.13.9.36 3.7.47 5 .08.86.21 2 .22 2.59a2.26 2.26 0 0 1-.14.78.72.72 0 0 1-.33.27 1.11 1.11 0 0 1-.31.07c0 .66.12 2 .16 2.75s0 1.22 0 1.83v2c0 .33.07 1 .07 1 .14-.28.42-.85.64-1.27s.62-1.14.84-1.51.36-.46.49-.7a4.63 4.63 0 0 0 .26-.74c.09-.28.19-.71.27-1s.22-.62.22-.62a3.15 3.15 0 0 1-.33-.22.5.5 0 0 1-.17-.21 1 1 0 0 1 0-.39.73.73 0 0 1 .07-.29c.1-.26.35-.84.53-1.26.26-.65.73-1.77 1.08-2.62s.76-1.92 1-2.51a7 7 0 0 1 .52-1 .49.49 0 0 1 .31-.16.82.82 0 0 1 .35 0 1.19 1.19 0 0 1 .26.09 6.17 6.17 0 0 1 .23-.69c.1-.23.29-.52.39-.7a2.19 2.19 0 0 1 .23-.38s.09.11.08.18a2.21 2.21 0 0 1-.11.49 7 7 0 0 1-.3.7c-.09.18-.3.51-.3.51a1.44 1.44 0 0 1 .36.41.84.84 0 0 1 .05.52c-.09.29-.37.81-.54 1.22l-1.12 2.81c-.28.66-.59 1.41-.84 2a16 16 0 0 1-.66 1.47c-.09.12-.3.13-.43.16s-.32-.11-.38 0a12.14 12.14 0 0 0-.38 1.5 7.44 7.44 0 0 1 1.38-1.21 10 10 0 0 1 2.69-1.14 5.46 5.46 0 0 1 2.47.18 11.79 11.79 0 0 1 2.45 1.16 13.23 13.23 0 0 1 1.4 1.08c-.68-.36-2.05-1.07-2.8-1.38a5.32 5.32 0 0 0-1.7-.43 8.88 8.88 0 0 0-2.2.19 3.91 3.91 0 0 0-1.35.68 9.91 9.91 0 0 0-1.69 1.54 14.77 14.77 0 0 0-1.5 2.35 23.83 23.83 0 0 0-1.18 2.82c-.36 1.05-.72 2.37-1 3.43s-.52 2.24-.66 2.94c-.08.43-.14 1.31-.14 1.31a27.13 27.13 0 0 1 1.54-3.26 12.86 12.86 0 0 1 2-2.6A14.94 14.94 0 0 1 323 424a11.06 11.06 0 0 1 3-1.19 18.86 18.86 0 0 1 3.35-.26 9.22 9.22 0 0 1 1.36.16c-.37 0-1.1 0-1.59.09a12 12 0 0 0-1.36.2 19.61 19.61 0 0 0-2.81.81 11.41 11.41 0 0 0-2.43 1.43 13.37 13.37 0 0 0-2.11 2 17.7 17.7 0 0 0-1.73 2.62 22.15 22.15 0 0 0-1.09 2.55c-.22.62-.43 1.42-.54 1.89a8.85 8.85 0 0 0-.14 1c.75-1.36 2.25-4.08 3-5.19a6.74 6.74 0 0 1 1.5-1.47 8 8 0 0 1 1.6-.94 5.82 5.82 0 0 1 1.54-.4 9 9 0 0 1 1.69.07 2.78 2.78 0 0 1 .74.19 14 14 0 0 1 1.46.65c.33.18.94.63.94.63a16.54 16.54 0 0 0-2-.74 6.7 6.7 0 0 0-1.64-.18 5.26 5.26 0 0 0-1.37.18 4.75 4.75 0 0 0-1.46.6 13.83 13.83 0 0 0-2.11 1.81 8.84 8.84 0 0 0-1.29 1.9 28.27 28.27 0 0 0-1.34 2.94c0 .12.25 0 .37 0h1.45c1.06 0 3.65.09 4.9.17.87.05 2.6.28 2.6.28l-19.92-.05v.12l-8.81.21-.16-1.83 6.18-.41-.23-4.63-4.47.29-1.87.16-.34-2.63-.32-5-.16-2.7 9.46-.92.05 1.66v1.2l-6.62.59.21 4.87 6.52-.41.19 2.92Zm-19.87-7.91 8.82-.19.09 2.87v1.79l.17 1.73v8.16l-8.77.39-.17-2.27.08-3.13-.08-3.58-.2-3.09Zm-11.1-.19.36 15h2.64l-.15-6.52h.72l2.77 6.31 2.91.08-2.87-6.41h3.14l-.3-.85v-.78l-.08-1.08v-5.68Zm-10.8-2.48 2.8.26v15.07h3.76l-.26-15.17 2.66.08.24 17.28-9.5.19.33-2.73Z\" style=\"fill-rule:evenodd\" transform=\"translate(-265.21 -404.28)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Puno<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Ica -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-ica\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"40px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 268.83 229.19\">\n                <path fill=\"#4778FF\" d=\"M239 229.19c-2.22-7.47-4.78-14.86-6.57-22.44a105.37 105.37 0 0 1-3.2-20.13 61.8 61.8 0 0 0-5.85-24.56 95.27 95.27 0 0 1-4.19-10.18c-3.37-10-2.32-18.81 5.86-26.45 7.7-7.19 14.51-15.21 18.07-25.43.86-2.47 2.22-4.86-1.18-6.84s-5.3-.45-7.39 1.75a58.94 58.94 0 0 1-4.92 5c-5.55 4.58-7.48 4.07-13.57.26-2.88-1.8-7.55-2.73-10.67-1.73-8 2.56-15.61 6.08-19 15.07-1.72 4.54-4.81 8.57-7.38 12.77-.94 1.55-2.16 2.92-3.24 4.39-1.34 1.84-2.67 3.69-3.45 4.77-.94-.76-2.47-2.62-4.45-3.52-5.26-2.38-7.23-5.93-4.89-11.2 1.53-3.44 4-6.48 6.13-9.64 3.42-5.1 6.91-10.15 9.59-16-.32 2.25-.63 4.51-1 7.4 4-1.45 7.11-2.36 8-7.12a97.1 97.1 0 0 1 6-19.44l-4.05 20.23 1.21.86c3.6-1.88 8.55-2.91 10.43-5.88s.84-8 1.81-12.19q.6 5.46 1.22 10.91c16.08-1.77 26.24-12.95 26.49-28.57 0-2.46-.38-3.95-3.22-4.55-5.12-1.08-8.3-4.68-10.35-9.34-1.2-2.74-2.26-5.56-3.56-8.25-3.4-7.07-8-9.56-15.88-7.78-13.21 3-24.38 9.42-32.94 20.23s-17.21 21.29-26.26 31.53c-3.22 3.62-7.72 6.36-12.08 8.67-7.33 3.89-13.74 1.75-18.79-4.7a21.25 21.25 0 0 0-8-6.22c-11.18-4.75-14.61-10.76-11-22.5 2-6.46 5.38-12.48 7.93-18.78.66-1.64.52-3.61.75-5.43-1.87-.09-4.21-1-5.56-.16C67.4 47.26 49.22 64 44.14 91.64l12.74-9.83 3.6 9.28-1.54-.78c-5.6 3.88-11.27 7.64-16.7 11.72-.93.7-1 2.74-1.19 4.2-5.55 40.29-13.54 80.11-22.89 119.68a32.79 32.79 0 0 1-1.16 3.28H0c4.1-13.34 8.37-26.64 12.24-40.05 5.34-18.47 6.78-37.58 9.18-56.58 3.51-27.8 9.18-55.17 22.47-80.32 14.65-27.71 38-43.33 68.36-49.2 23.55-4.56 47.1-3.6 70.54.37 6.45 1.09 12.47 4.54 18.84 6.38 7.14 2.07 14.37 4.18 21.71 5.13 9.7 1.25 16.64 5.09 19.55 15a22.67 22.67 0 0 0 4.15 8.42c10.14 11.52 9.5 24.59 6 38.12-1.62 6.26-3.69 12.41-5.39 18.66a63.33 63.33 0 0 1-19.38 30.89c-9.12 8.19-10.39 17.49-5.48 27.9a100.22 100.22 0 0 1 9.62 38.83c.48 9.88 4.83 19.58 7.48 29.36.64 2.39 1.4 4.76 2.1 7.13ZM138.08 38.33a85.78 85.78 0 0 0-.77-9.2c-1.52-8.72-6.45-11.54-14.74-8.2a50.85 50.85 0 0 0-24.32 20.7c-6.18 9.89-3.16 21.79 6.21 27.54 9.81 6 20.69 3.55 27.48-6.28 4.09-5.92 5.42-12.58 5-19.84-3.31 3.65-7.11 7.16-8.89 11.51-3.23 7.88-9 11.47-17.12 9-7.8-2.33-10.44-11.87-4.49-17.47 2.57-2.42 6-4.7 9.36-5.36 7.03-1.33 14.28-1.59 22.28-2.4Zm107.83 49.85c8.79-18.89 10-40.66-2.74-49-1.43 4.49-1.53 10.78-4.68 13.35-5.11 4.17-5.55 9-6.58 14.42a67.68 67.68 0 0 1-3.61 10.82 53.23 53.23 0 0 1-2.57 5.18Z\" \/>\n                <path fill=\"#4778FF\" d=\"M257.87 101.5c.41 17.15-6.72 35.62-13.76 54.11ZM260.87 111.28v-27.1c3.49 8.76 2.2 18 1.76 27.16ZM251.54 101.88a39 39 0 0 1-8.71 25.71c2.92-8.66 5.74-16.96 8.71-25.71ZM260.58 66.37a20.36 20.36 0 0 1 8.25 16.4c-2.92-5.81-5.59-11.1-8.25-16.4ZM133.08 182.88c-1.05-16.36 4.27-32.43 10.72-47.87 6.36-15.21 14.62-29.63 22.15-44.61-27.47 33.12-49.5 70.05-74.79 104.62 26.16-43.52 50.92-88.14 91.66-122.59-24.62 34.55-42.47 70.6-49.74 110.45ZM70.08 195.08C102.74 150.27 139.4 108.91 177.73 69l1 .88ZM103.08 134.02c19.15-28.39 42.47-52.5 72.21-70-26.67 20.64-49.77 44.99-72.21 70ZM204.87 132.69c-.32-1.23-.67-2.57-1.07-4.08l-8.85 1c5.49-9.66 17.78-8.63 22.68-18.07 1.28 1.84 2.12 3.21 3.12 4.46 2.48 3.14 1.87 4.48-1.91 6.44-5.01 2.59-9.23 6.67-13.97 10.25Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Ica<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours Lineas de Nazca -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-lineas-nazca\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"75px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 68.13 49.07\">\n                <path fill=\"#4778FF\" d=\"M30.72 45.87c.43.17.86.33 1.28.52.19.08.47.11.39.43s-.31.27-.54.25a10.44 10.44 0 0 0-1.61-.11c.25.17.49.35.75.5a.44.44 0 0 1 .24.62.4.4 0 0 1-.59.18 10.94 10.94 0 0 1-1.51-.9 2.25 2.25 0 0 0-1.77-.39 5.62 5.62 0 0 1-1.42 0 .63.63 0 0 1-.43-.32 1.48 1.48 0 0 1 1-2.12 6.36 6.36 0 0 1 1.31-.06c.83 0 1.19-.19 1.44-1 .19-.59.38-1.18.52-1.77a4.52 4.52 0 0 0-.87-3.53 17.25 17.25 0 0 1-2-4 26.73 26.73 0 0 1-.56-2.69 2.52 2.52 0 0 0-.13-.47.39.39 0 0 0-.54-.26 4.1 4.1 0 0 1-2.95-.55 2.33 2.33 0 0 0-.91-.3c-1.12-.06-2.25 0-3.36-.11a23.57 23.57 0 0 1-7.42-1.84 25.67 25.67 0 0 1-4.56-2.67 24.56 24.56 0 0 1-3.8-2.94 9.29 9.29 0 0 1-2.56-6C.04 14.92 0 13.49.03 12.07a10.54 10.54 0 0 1 3-7.22 14.65 14.65 0 0 1 4.08-3.14A14 14 0 0 1 11.36.17 30.26 30.26 0 0 1 14.52 0a12.37 12.37 0 0 1 7 2.05 7 7 0 0 1 2.55 2.84 8.62 8.62 0 0 1 .74 2.88 11 11 0 0 1-.21 3.47 23.84 23.84 0 0 0-.2 2.82 6.22 6.22 0 0 1-1.06 3.32 7.34 7.34 0 0 1-3 2.5 40 40 0 0 1-3.92 1.56 6 6 0 0 1-4.79-.17c-.94-.52-1.83-1.13-2.73-1.73-.57-.38-1.11-.8-1.67-1.2a6.69 6.69 0 0 1-2.33-3c-.16-.43-.35-.86-.53-1.29a7.93 7.93 0 0 1-.42-5.38 6.43 6.43 0 0 1 2.84-3.75c.76-.48 1.58-.88 2.37-1.3a8.52 8.52 0 0 1 3.52-.85 9.39 9.39 0 0 1 7.3 2.75 5.38 5.38 0 0 1 1.55 4.62 11.7 11.7 0 0 1-.37 2.43c-.54 1.75-1.23 3.41-3.06 4.31a9.51 9.51 0 0 1-3.38 1.09 7.19 7.19 0 0 1-5.76-1.72 2.89 2.89 0 0 1-.64-.79c-.59-1.07-1.19-2.15-1.72-3.26a3 3 0 0 1 .08-2.59 5.71 5.71 0 0 1 4.58-3.4 8.18 8.18 0 0 1 3.74.18 4.28 4.28 0 0 1 3.06 3 5.49 5.49 0 0 1 .22 2.87 3.81 3.81 0 0 1-3.38 3 4.19 4.19 0 0 1-4.9-2.64 3.25 3.25 0 0 1 2.19-4.25 2.28 2.28 0 0 1 2.35.45 3 3 0 0 1 1 2.21 5.56 5.56 0 0 1-.45 1.51.81.81 0 0 1-.44.34 2.21 2.21 0 0 1-2.42-.67 1.2 1.2 0 0 1-.17-1.21.53.53 0 0 1 .8-.23c.22.13.38.36.61.48a.82.82 0 0 0 .61.12c.13 0 .22-.37.19-.56a1.16 1.16 0 0 0-.87-1.08 1.74 1.74 0 0 0-1.84.36 2.08 2.08 0 0 0 .51 3.27 7.58 7.58 0 0 0 2.31.77c1.24.18 2-.46 2.36-1.83a4.94 4.94 0 0 0-.57-3.4 3.2 3.2 0 0 0-2.62-1.74 2.12 2.12 0 0 0-.93.08c-.72.21-1.44.45-2.15.7a3.43 3.43 0 0 0-2 5 7.06 7.06 0 0 0 3 2.86 6.63 6.63 0 0 0 3.8.82 3.55 3.55 0 0 0 2.66-1.45 8.53 8.53 0 0 0 1.86-5.33 5.64 5.64 0 0 0-4-5.2 10 10 0 0 0-4.66-.18 7.36 7.36 0 0 0-5.35 3.93 5.19 5.19 0 0 0 .05 4.83 14 14 0 0 0 2 3.19 9.4 9.4 0 0 0 6.78 3.26 7.66 7.66 0 0 0 7.46-5 13.68 13.68 0 0 0 1-5.16 7.71 7.71 0 0 0-3.15-6.3 12 12 0 0 0-4.19-1.79 8.43 8.43 0 0 0-3.64 0 14.16 14.16 0 0 0-4.93 1.74 9.39 9.39 0 0 0-3.72 3.35 10.2 10.2 0 0 0-1.51 5.14 15.62 15.62 0 0 0 1.37 7.07 7.42 7.42 0 0 0 2.29 2.6c.63.48 1.29.92 1.94 1.38a16.06 16.06 0 0 0 4.66 2 19.16 19.16 0 0 0 4.71.57 11.74 11.74 0 0 1 1.17.16c1 .13 2 .25 2.93.41a2.75 2.75 0 0 1 1.77 1.1c.25.31.48.64.73.94a1.45 1.45 0 0 0 1.34.58.75.75 0 0 0 .71-.54 4.32 4.32 0 0 1 1.18-1.79 69.63 69.63 0 0 1 5.7-5.16c1.27-1 2.48-2.15 3.76-3.18a12.15 12.15 0 0 1 2.26-1.5 4.18 4.18 0 0 1 2.88-.29 6.88 6.88 0 0 1 2.18.92 49.65 49.65 0 0 1 5 3.7 2.18 2.18 0 0 0 .69.25c0-.26 0-.56-.12-.75a8.89 8.89 0 0 0-.84-1 5.28 5.28 0 0 1-.66-.77c-.23-.39-.1-.69.33-.79a1.52 1.52 0 0 0 1-.78l.32-.48a4.48 4.48 0 0 1 3.38-2 2.38 2.38 0 0 1 1.08.15 5.22 5.22 0 0 1 3 2.23 9.21 9.21 0 0 0 .75 1 .84.84 0 0 0 .9.34.86.86 0 0 1 1.05 1 3 3 0 0 1-.2.71c-.27.66-.17.93.5 1.2.83.34 1.68.62 2.46 1a10.83 10.83 0 0 1 4.92 4.45 8.92 8.92 0 0 1 .86 5.94 5.08 5.08 0 0 1-1.23 2.19c-.24.3-.52.57-.78.85a2.48 2.48 0 0 0-.7 1.82 5.37 5.37 0 0 1-.25 1.69 25.06 25.06 0 0 1-1.09 2.43.6.6 0 0 1-.49.22c-.25 0-.25-.27-.21-.5a11.54 11.54 0 0 0 .16-1.18c0-.15-.07-.39-.17-.43a.58.58 0 0 0-.51.07 5.06 5.06 0 0 1-3 1c-.16 0-.43-.06-.48-.17a.55.55 0 0 1 .11-.51 3.27 3.27 0 0 1 1-.53 1.34 1.34 0 0 0 .92-.73c0-.08.08-.2.05-.25a.31.31 0 0 0-.25-.09c-.34.06-.67.18-1 .21-.66.05-1.33.07-2 .06a.92.92 0 0 1-.53-.28.31.31 0 0 1 .17-.56c.61-.09 1.22-.14 1.83-.2a5.42 5.42 0 0 0 .81-.05.4.4 0 0 0 .23-.31c0-.07-.16-.23-.26-.24a9.38 9.38 0 0 0-1.06 0c-.57 0-1.14.11-1.72.13a.45.45 0 0 1-.38-.2.51.51 0 0 1 .15-.42 2.91 2.91 0 0 1 2.11-.6 10.71 10.71 0 0 0 1.27 0c.12 0 .29-.11.31-.2a.42.42 0 0 0-.14-.35 1.21 1.21 0 0 0-1.27-.2c-.61.2-1.19.5-1.79.71a2 2 0 0 1-.88.11.42.42 0 0 1-.28-.73 3.94 3.94 0 0 1 6.12-.27l.17.19c.45.53.67.54 1.1 0a13.06 13.06 0 0 0 1.32-1.83 4.51 4.51 0 0 0-.2-5 17.1 17.1 0 0 0-5.84-5.38c-.83-.46-1.09-.35-1.65.43a5 5 0 0 1-2.83 1.93 3.16 3.16 0 0 1-1.84-.23l-1.29-.44a.88.88 0 0 0-.95.21c-1.39 1.48-2.8 2.93-4.14 4.45a5.17 5.17 0 0 0-1.09 2.33 1.28 1.28 0 0 0 .16 1.13c.81 1.08 1.61 2.15 2.44 3.2 1.1 1.4 2.23 2.77 3.34 4.17.45.56.78.58 1.4.19s1.55-.91 2.34-1.35a.73.73 0 0 1 .47-.1.78.78 0 0 1 .47.27.45.45 0 0 1-.07.43c-.41.35-.86.67-1.29 1-.08.06-.2.07-.26.13a3.47 3.47 0 0 0-.26.37c.18.05.41.21.52.14a5.44 5.44 0 0 0 1.05-.75c.38-.33.7-.73 1.06-1.08a1.1 1.1 0 0 1 .46-.25.48.48 0 0 1 .41.07.46.46 0 0 1 0 .4 3.88 3.88 0 0 1-1.5 2.1c-.17.12-.33.27-.5.4l.05.16c.46-.07.92-.13 1.37-.22s.85-.19 1.28-.24a.53.53 0 0 1 .42.23.51.51 0 0 1-.16.46 9.92 9.92 0 0 1-1.69.78c-.68.21-1.39.27-2.09.43a1.17 1.17 0 0 0-.41.27c.11.11.2.29.33.34.49.21 1 .36 1.5.57.14.06.22.25.33.39-.15.09-.3.27-.44.26a8.1 8.1 0 0 1-3.34-.89 3 3 0 0 1-.71-.49 3.64 3.64 0 0 1-.8-1 7.7 7.7 0 0 0-2-2.84A43.72 43.72 0 0 1 44 34.69a3.58 3.58 0 0 1-.93-2.76 7 7 0 0 1 1.68-4.49c.55-.56 1.17-1 1.75-1.55s1.44-1.27 2.12-1.94c.52-.52.5-.84 0-1.36a4.11 4.11 0 0 0-.74-.58c-1.08-.67-2.17-1.33-3.27-2A9.46 9.46 0 0 0 41 18.84a4.35 4.35 0 0 0-3.46 1.11c-1.29 1.1-2.51 2.29-3.74 3.45a5.13 5.13 0 0 0-.56.66c-.42.54-.42.71 0 1.26l2 2.55a49.22 49.22 0 0 1 4.08 5.91 6.74 6.74 0 0 1 .73 3.41 13.39 13.39 0 0 1-.73 3.81c-.36 1.32-.68 2.65-1 4-.12.49 0 .7.5.8s.71.12 1.06.17a1.77 1.77 0 0 1 .52.07 1.74 1.74 0 0 1 .43.34c-.14.1-.28.27-.44.29a8.67 8.67 0 0 0-1 .09c.33.14.66.29 1 .42s.4.26.28.49a.54.54 0 0 1-.49.14c-.4-.1-.79-.26-1.18-.4l-.05.09 1.33 1a1.83 1.83 0 0 1 .24.31c-.11.07-.22.21-.33.21a1.65 1.65 0 0 1-.74-.12 9.07 9.07 0 0 0-4.64-1.16 5 5 0 0 1-1-.08.87.87 0 0 1-.75-.94 3 3 0 0 1 .17-1.07.89.89 0 0 1 1-.51c.88.12 1.24-.09 1.54-.92a24.93 24.93 0 0 0 1.13-4.83c.1-.71.24-1.43.33-2.15a2.45 2.45 0 0 0-.39-1.68c-1.21-1.87-2.41-3.76-3.61-5.64l-1.78-2.76c-.35-.55-.66-.61-1.18-.24a7.42 7.42 0 0 0-2 1.89 1.37 1.37 0 0 0-.21 1.32c.61 1.65 1.2 3.32 1.87 5 .42 1 1 2 1.46 2.94a5.63 5.63 0 0 1 .31 3.81c-.13.73-.4 1.42-.58 2.14-.12.44 0 .66.45.82a7 7 0 0 1 .81.27c.15.07.23.27.34.41a1.64 1.64 0 0 1-.49.22h-1.54Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours Lineas <br>de Nazca<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en La Libertad -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-la-libertad\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"75px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 150.47 155.6\">\n                <path fill=\"#4778FF\" d=\"M106.83 128.89c-7.37-.4-14.2-3.07-21-6.1-5-2.26-10.17-4.15-15.6-2.6a97 97 0 0 0-9.87 3.76c-6.44 2.62-12.95 5.24-19.85 4.52a31.15 31.15 0 0 1-11-3.23c-6.16-3.18-8.85-11.22-7.44-20.12a57.11 57.11 0 0 1 6.55-18.84c3.32-6 2.9-11.71.51-17.77-1.81-4.61-3.87-9.16-5.14-14-3.4-12.94 1.29-23.08 12.1-26.87a40.21 40.21 0 0 1 5.7-1.41c8.09-1.5 15.92-.67 23.15 4.29a46.11 46.11 0 0 1 5.55 4.79c2.6 2.48 5.2 2.67 7.69.09 10.84-11.25 23.21-12 36.15-7 9.5 3.62 13.51 13.31 10.74 25.25-1 4.23-2.9 8.15-4.21 12.3a61.45 61.45 0 0 0-2.9 11.11 15.18 15.18 0 0 0 1.58 7.43c3.05 6.68 6.08 13.31 7.15 20.94 1.59 11.28-2.89 19.42-12.3 22.07a77 77 0 0 1-7.56 1.39ZM67.76 44.55c-.72-1-1.37-2.13-2.14-3.07a34.11 34.11 0 0 0-2.78-3c-7.75-7.44-23.27-5.42-29.15-1-3 2.28-4.15 5.69-4 9.73a22 22 0 0 0 .92 5.8c1.14 3.52 2.48 7 3.92 10.33 4 9.21 4.67 18.09-.3 27.37a63.94 63.94 0 0 0-5.37 15.15c-1.69 7 .89 12 6.8 13.6 3.17.87 6.71 1.4 9.83.63a138.29 138.29 0 0 0 18.33-6.21c7.12-2.84 14.1-3 21.17 0 3.64 1.56 7.29 3.16 11 4.48 5.77 2.06 11.63 3.26 17.59 1.07 5.42-2 7.6-6.43 6.56-13.08s-3.81-12.5-6.66-18.25a23.21 23.21 0 0 1-2.41-10.33c-.05-5.81 1.77-10.89 3.88-16a67.58 67.58 0 0 0 3.83-11.4c1.58-7.09-.82-12.25-6.82-14.59-6.58-2.6-13.32-3.22-20.05-.81a19.89 19.89 0 0 0-11.34 9.8c.69 1 1.31 1.92 1.9 2.83 4.21 6.46 8.45 12.88 12.61 19.39a10.17 10.17 0 0 1 .69 10.4 5.39 5.39 0 0 1-5.85 3.27 5.11 5.11 0 0 1-4.86-3.44c-.45-1.08-2-1.83-3.13-2.08-1.41-.31-2.65.43-3.23 2.34-.77 2.55-2.32 4.19-4.67 4.14s-3.77-1.71-4.48-4.14a2.93 2.93 0 0 0-3.23-2.4c-1.39 0-2.7.3-3.28 2.32a4.2 4.2 0 0 1-1.71 2.34c-4.32 2.4-9.79.51-9.72-6.58a13.64 13.64 0 0 1 1.9-6.54c4.58-7.4 9.38-14.57 14.25-22.07Z\" \/>\n                <path fill=\"#4778FF\" d=\"M25.67 116.54c3.82 7.39 9.74 9.56 16.32 10.13 7.23.62 14-1.73 20.73-4.54 2.57-1.07 5.15-2.1 8-3.26-.52 9.84-1.41 19.12-5.54 27.49-2.53 5.13-6.23 8.37-11.4 9.14-6.56 1-11.48-5.62-9.58-13 .84-3.28 3.24-5.73 6.17-5.9.9-.06 1.84.77 2.76 1.19a29.3 29.3 0 0 1-1.37 3.57c-.28.54-1 .72-1.51 1.15-1.28 1.13-2.44 2.34-1.68 4.53s2.68 3.54 4.5 3.22c5.06-.89 9.05-8.8 7.27-14.4a7.84 7.84 0 0 0-9.66-5.13c-4.71 1.3-8.18 4.65-10.87 9.23-3.13 5.31-7.28 8.09-13 7.14a5.42 5.42 0 0 1-4.61-4 8.1 8.1 0 0 1 1.22-7.51 3.29 3.29 0 0 1 2.08-1.22c1.16-.17 1.81.54 1.38 2a6.07 6.07 0 0 0-.33.86c-.18 1.48-.91 3.58-.35 4.3.76 1 2.53 1.27 3.84 1.17 3-.21 5.43-3.74 5.46-7.4 0-2.77-2.61-5.5-6.09-5.7a28.29 28.29 0 0 0-7.6.72c-3.44.78-6.82 1.23-10.17-.26-5.48-2.43-7.48-10.31-4.07-15.89 2-3.32 6-4.35 9-2.31a4.17 4.17 0 0 1 1.61 5c-.87 2-2.22 1.82-3.81 1.31a2.62 2.62 0 0 0-2.42.48c-1 1.19-.79 2.75 0 4.09a4.88 4.88 0 0 0 6.82 1.4c2.07-1.51 3.76-3.74 5.58-5.7a12.74 12.74 0 0 0 1.32-1.9ZM80.19 118.86c2.23.9 4.18 1.68 6.13 2.49 6 2.5 12.09 5.05 18.59 5.32 8.07.33 15.53-1.2 20.34-9.88 1.41 1.85 2.66 3.71 4.1 5.35a6.9 6.9 0 0 0 6.45 2.66 4.26 4.26 0 0 0 3.7-4c.12-2.35-1.12-3.49-3-2.68-1.58.67-3 .65-3.8-1.29a4.28 4.28 0 0 1 1.52-4.91 6.41 6.41 0 0 1 9.08 2.14c4.22 6.76.56 16-6.8 16.78a24.35 24.35 0 0 1-7.61-.77c-3.09-.7-6.14-1.1-9.19 0-3.63 1.3-4.88 3.89-3.8 7.64s4.72 6.16 7.74 4.92a2.62 2.62 0 0 0 1.55-3.34c-.15-.68-.59-1.27-.69-2a21.38 21.38 0 0 1-.07-2.78c.93.19 2.11 0 2.74.64 2.05 2 2.28 4.8 1.65 7.58a5.28 5.28 0 0 1-4.43 4.26c-5.74 1.08-10-1.68-13.18-7.06-2.66-4.49-6-8-10.68-9.13a10 10 0 0 0-5 .09c-3.64 1-5.45 4.2-5.25 8.59.22 4.8 3.28 9.36 7 10.47a4.13 4.13 0 0 0 5-2.74c.7-1.92.09-3.49-2-5.07a6.73 6.73 0 0 1-1.93-1.65 4 4 0 0 1-.52-2.75 2.75 2.75 0 0 1 2.11-1.33c3.24-.17 6.41 3.1 6.94 7 1.18 8.57-4.61 14-12.19 11.51-4.3-1.44-7.21-4.83-9.3-9.25-3.14-6.62-4.23-13.9-4.88-21.31-.07-1.68-.17-3.39-.32-5.5ZM94.96 25.89a69.14 69.14 0 0 0-6.56 2.81c-2.11 1.14-4.06 2.68-6.28 4.18-.29-8.64-.52-17 2.75-24.92 2.85-6.86 8.6-9.56 14.55-7a7.92 7.92 0 0 1 4.86 6.67c.48 3.67-.16 7.1-2.57 9.77-1 1.13-2.4 1.58-3.48.42a5.54 5.54 0 0 1-1.09-3.23c0-.57 1-1.76 1.48-1.7 1.39.19 1.48-.9 1.61-1.83a4 4 0 0 0-2.22-4.51c-1.8-.89-3.38-.38-4.47 1.44-2.15 3.59-2.15 7.57-1 11.54.59 2.2 1.61 4.26 2.42 6.36ZM68.11 33.46l-12.58-6.78c.81-2.73 2-5.82 2.61-9.05a11.83 11.83 0 0 0-1.61-8.75 3.25 3.25 0 0 0-4.7-1.21 4.23 4.23 0 0 0-1.86 4.73 3.51 3.51 0 0 0 1.08 1.46c.64.61 1.83 1 1.92 1.68a4.15 4.15 0 0 1-.87 3.05 2.77 2.77 0 0 1-2.75.39c-2.47-1.32-3.26-4.12-3.54-7-.84-8.58 5-11.45 10.62-10.82 3.85.43 6.58 3 8.44 6.88 2.17 4.5 2.91 9.47 3.19 14.51.21 3.73.05 7.4.05 10.91ZM46.3 28.61l-15.57 3.31a88 88 0 0 0-4.44-8.55 8.45 8.45 0 0 0-4-2.83c-.6-.24-1.59.88-2.4 1.38.48 1 .76 2.36 1.48 2.84 1.9 1.26 2.6 2.43 1.89 4.18a2.93 2.93 0 0 1-4.65 1.43c-3.94-2.66-4.8-9-1.61-12.89 3.41-4.15 7.66-5.36 12.26-3.49 6.94 2.82 12.1 8.61 17.04 14.62ZM115.96 29.63l-16-3.35c5.36-6.33 10.75-12.66 18.42-15 4-1.26 7.79.16 10.77 3.69a9.11 9.11 0 0 1-1.24 12.93c-1.34 1-2.92 1.44-4-.14a5.73 5.73 0 0 1-.67-3.52c.06-.63 1.24-1 1.73-1.71a25.06 25.06 0 0 0 1.53-2.86c-.81-.52-1.65-1.52-2.4-1.44a5.71 5.71 0 0 0-3 1.63 17.88 17.88 0 0 0-5.14 9.77ZM125.07 52.28c1-6.74.39-13-3.74-18.24 4-.46 7.85-.86 11.7-1.39 2.67-.37 5.31-1.17 8-1.3a8 8 0 0 1 8.36 5.36 14 14 0 0 1-1 12.79 5.43 5.43 0 0 1-6.69 2.57 3.55 3.55 0 0 1-2.34-3.92c.16-1.89 1.14-3.07 2.77-3.13a2.27 2.27 0 0 0 2.53-2.34c.15-1.77-.4-3.43-1.89-3.68a11.63 11.63 0 0 0-5.5.27c-5.05 1.66-8.32 5.93-10.87 11.05-.3.61-.59 1.24-.9 1.85-.02.04-.12.03-.43.11ZM28.77 34.48c-3.84 5-4.52 11.17-3.84 18-.33-.71-.65-1.43-1-2.13-2.95-5.88-6.86-10.38-12.86-11.57a5.11 5.11 0 0 0-3.85.6c-.84.64-1.34 2.43-1.4 3.75s1 1.9 2.29 2a3.13 3.13 0 0 1 2.92 3.46 3.59 3.59 0 0 1-3 3.74c-4.43.6-7.6-2.94-8-8.9-.5-8.36 4.34-13.21 12-11.93 5.61.91 11.17 1.98 16.74 2.98ZM77.36 95.62h2.6v7.54h1.88v-7.51h2.92v7.56l1.93.1v-7.63h5.57c.11 5.63.93 11 3.88 15.76l-.31.45c-2.23-.76-4.48-1.48-6.7-2.28-3.78-1.36-7.49-3-11.34-4.09-4.5-1.22-9-.37-13.34 1.43-3.73 1.54-7.51 2.92-11.28 4.34a22.64 22.64 0 0 1-2.36.58 28.13 28.13 0 0 0 3.8-16.17h5.67c0 1.93.06 3.93 0 5.93 0 1.48.4 2 1.87 1.53v-7.52h3.12v7.4c1.45.59 2 .14 1.94-1.48-.07-1.94 0-3.89 0-5.93h2.54v7.55l2.22.15v-7.71h3.16v7.51h2.25Z\" \/>\n                <path fill=\"#4778FF\" d=\"M106.42 86.37a36.25 36.25 0 0 1 5.71 13.22c1.57 6.9-.54 10.94-6.49 12.38h-.18l-6.4.07a20.64 20.64 0 0 1-1.44-9.92 19.17 19.17 0 0 1 .69-2.7c2.95 4.31 4.06 5.14 6.74 5.05a14.49 14.49 0 0 0-4.09-10.01l2.4-3.46-1.4-1.42A21.66 21.66 0 0 0 95.48 104h-.52c-.24-2.23-.88-4.51-.65-6.67a41 41 0 0 1 2.06-8.46c.43-1.32.41-2-.73-2.54-1.26.87-1.26 3.56-3.48 3.23a34.11 34.11 0 0 0-5-.05v-5.07h6.47c1.87 0 3.73.09 5.59 0 2.59-.16 5.06.09 7.22 2ZM45.27 89.71l-1.39 1.47 2.29 3.27c-2.73 2.61-3.72 6.12-4.25 10.17 3.28.11 5.13-2.14 6.79-5.23a15.11 15.11 0 0 1 .45 8.84c-.88 4.61-.95 4.68-4.92 4.19a20 20 0 0 1-5.06-1.3c-3.56-1.44-5.22-4.62-4.64-9a34.86 34.86 0 0 1 4.74-13.54c1.68-2.75 3.9-4.25 7-4.13 4.53.17 9.06 0 13.9 0a25.41 25.41 0 0 1-.05 3.73 1.88 1.88 0 0 1-1.19 1.31 19 19 0 0 1-4.46 0c-.6-.08-1.21-.77-1.69-1.33a14.76 14.76 0 0 1-1.21-2l-1.4 1.26a21.31 21.31 0 0 1 1.71 16.69 23 23 0 0 0-6.62-14.4ZM39.44 86.67c4.18-9.77 2-18.74-1.12-27.34l11.56 6.95a83.33 83.33 0 0 1-10.44 20.39ZM108.41 86.19c-.29-.55-.56-1.12-.87-1.65-2.94-5.1-5.91-10.18-8.83-15.3a15.63 15.63 0 0 1-.88-2.16l13.32-6.86c-.23.66-.6 1.77-1 2.84-1.7 4.37-3.06 9-2.66 14a56.28 56.28 0 0 0 1.58 7.81 19.43 19.43 0 0 0 1.05 2.63l-1.74-1.41ZM48.5 41.88a8.1 8.1 0 1 1 .11 16.19 8.1 8.1 0 1 1-.11-16.19ZM65.17 84.68v4.74h-2.85v-4.74ZM75.07 89.44h-2.94v-4.79h2.94ZM81.96 84.57h2.73v4.83h-2.73ZM69.59 89.46h-2.25v-4.8h2.25ZM79.88 89.42h-2.4v-4.73h2.4ZM17.48 56.52a10 10 0 1 1-10.14 9.85 9.84 9.84 0 0 1 10.14-9.85Zm5.37 10a5.42 5.42 0 1 0-5.38 5.34 5.34 5.34 0 0 0 5.38-5.35Z\" \/>\n                <path fill=\"#4778FF\" d=\"M17.51 76.49a10 10 0 1 1-10.15 9.86 9.84 9.84 0 0 1 10.15-9.86Zm5.36 10a5.42 5.42 0 1 0-5.38 5.34 5.35 5.35 0 0 0 5.38-5.35ZM98.43 41.88a8.1 8.1 0 1 1 .11 16.19 8.1 8.1 0 1 1-.11-16.19ZM130.54 55.65a10 10 0 1 1-10.15 9.86 9.84 9.84 0 0 1 10.15-9.86Zm5.36 10a5.42 5.42 0 1 0-5.38 5.35 5.34 5.34 0 0 0 5.38-5.36Z\" \/>\n                <path fill=\"#4778FF\" d=\"M130.56 75.62a10 10 0 1 1-10.15 9.86 9.84 9.84 0 0 1 10.15-9.86Zm5.36 10a5.42 5.42 0 1 0-5.38 5.35 5.34 5.34 0 0 0 5.42-5.36Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>La Libertad<\/p>\n        <\/a>\n    <\/div>\n\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-lambayeque\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 383.03 312.09\">\n                <path fill=\"#4778FF\" d=\"M374.03 197.94h-55.14l-1.06-4.76H64.95l-.6 4.74H9C2.82 149.81 22.45 78.01 86.14 33.07c60.15-42.45 142.24-44.32 204.67-3.95 66.04 42.7 89.38 114.84 83.22 168.82Zm-112-27c-.42-27.32-26.38-63.15-68.68-64.32-40.59-1.13-71.32 31.67-72.51 64.32ZM207.77 50.8l22.12 4.69c-2.49-7.57-4.64-14.14-7-21.44ZM82.95 106.36h-22.5l11.28 19.43c3.89-6.68 7.35-12.66 11.22-19.43Zm239.34.13h-22.34c3.83 6.63 7.31 12.64 11.18 19.32Zm-2.24 45.49 15.22-16.85-22-4.66c2.33 7.35 4.4 13.9 6.82 21.51Zm1.11 4.82c.84 7.7 1.61 14.67 2.46 22.44L341.95 166ZM153.01 55.49l22.1-4.74-15.09-16.72c-2.38 7.28-4.52 13.83-7.01 21.46Zm100-11.73-18.38 13.28 20.7 9.14c-.79-7.51-1.5-14.41-2.33-22.4Zm27.37 15.78-20.64 9.25 18.27 13.23 2.36-22.46ZM104.95 82.08l18.25-13.35-20.66-9.11c.82 7.79 1.55 14.63 2.41 22.46Zm92-60c3.12 7 5.95 13.44 9.15 20.65l13.34-18.3ZM50.19 106.59l-9.17 20.65 22.41-2.42Zm35.83-4.39 15.19-16.83-22.16-4.56Zm-16.31 28.22-22.15 4.75 15.19 16.63c2.4-7.37 4.48-13.78 6.96-21.38Zm78.52-73.33-18.28-13.35c-.83 7.9-1.55 14.83-2.35 22.47Zm-88.92 122.2c.82-7.9 1.54-14.8 2.34-22.46l-20.64 9.18Zm42.47-129.92 19.34 11V38.29ZM37.6 137.49c-1.57 7.66-3 14.47-4.52 22.1l21.38-6.9Zm125.94-113.1 13.27 18.32 9.14-20.68Zm-15.39 24.36c1.63-7.7 3.07-14.53 4.67-22.09l-21.43 7Zm86.6 0 16.73-15.16-21.43-6.9Zm26.86 11.8 19.5-11.26c-6.9-3.95-13-7.4-19.5-11.16ZM97.75 77.85c-1.66-7.69-3.13-14.48-4.76-22.09L76.21 70.82Zm209-7-16.9-15.08c-1.63 7.75-3.07 14.63-4.63 22.07Zm-237.8 8.08c-4.43 6.09-8.57 11.77-13.32 18.31l22.41 2.18Zm212.75 6.5 15.19 16.75 6.92-21.47Zm45.6 11.86-13.35-18.4c-3.1 7-5.9 13.33-9.09 20.54Zm14.61 30-9.2-20.62-13.28 18.16Zm-13.43 25.41 21.39 6.95c-1.59-7.63-3-14.47-4.59-22.08ZM191.28 30.96c-3.85 6.66-7.27 12.61-10.91 18.91h22.11c-3.31-5.79-6.31-11.08-9.35-16.35-.39-.68-.92-1.28-1.85-2.56Zm68.86 67.95a8 8 0 0 0-8-7.84 7.64 7.64 0 0 0-7.7 7.47 8.06 8.06 0 0 0 7.58 8.27 8.49 8.49 0 0 0 8.12-7.9Zm-60.81-19.64a7.89 7.89 0 0 0-15.77-.49 7.89 7.89 0 1 0 15.77.49Zm-60.86 19.69a7.68 7.68 0 0 0-7.82-7.9 8.09 8.09 0 0 0-7.89 7.46 8.34 8.34 0 0 0 8.23 8.29 8 8 0 0 0 7.48-7.85Zm102.88-11a7.88 7.88 0 1 0-7.86 8 8 8 0 0 0 7.86-8.02Zm-84.07.22a7.86 7.86 0 1 0-8.07 7.75 8.07 8.07 0 0 0 8.07-7.77Zm118.84 25.38a7.81 7.81 0 0 0-7.27-7.95 7.73 7.73 0 1 0-.95 15.43 7.78 7.78 0 0 0 8.22-7.5Zm-153.68-.18a7.79 7.79 0 0 0-7.86-7.84 7.94 7.94 0 0 0-7.81 7.45 7.84 7.84 0 0 0 7.68 8.06 7.7 7.7 0 0 0 7.99-7.69Zm171.79 50.5c-4.76 0-7.53 2.83-7.58 7.86-.05 4.4 3 7.45 7.47 7.51 4.22.06 7.64-2.93 7.77-6.78.16-4.79-3.22-8.57-7.66-8.61Zm-81.06-90.12a7.674 7.674 0 1 0-.48 15.34 7.44 7.44 0 0 0 7.94-7.69 7.32 7.32 0 0 0-7.46-7.67Zm75.47 56.87a7.5 7.5 0 0 0-7.44-7.62 7.61 7.61 0 0 0-8 7.63 7.72 7.72 0 1 0 15.42 0Zm-188 20.23a7.87 7.87 0 0 0-7.91-8.2c-4.17.13-7.06 3.39-7.08 8a7.46 7.46 0 0 0 7.37 7.71 7.71 7.71 0 0 0 7.62-7.53Zm-19.46 21c.08 4.63 2.94 7.45 7.51 7.41s7.65-3.11 7.56-7.39c-.12-5.16-2.74-7.83-7.58-7.71-5.29.08-7.58 2.43-7.49 7.64Zm201.08-21.16c-.11 4.4 2.85 7.44 7.32 7.51a7.71 7.71 0 1 0 .2-15.41c-4.66-.05-7.4 2.82-7.52 7.85Zm-180.68-12a8 8 0 0 0 8.09-7.7 7.7 7.7 0 0 0-15.38-.68 7.76 7.76 0 0 0 7.29 8.37Zm68.12-65a7.684 7.684 0 1 0 .5 15.36 7.684 7.684 0 1 0-.5-15.36Zm163.84 106.89.25.86h17.24v-10.91Zm-284.48 1 .36-.93-17.42-10v10.93ZM123.6 285.33c7.52-10.71 9.79-21.9 5.08-33.88-4.83-12.32-13.95-19.74-27.11-21.46-4.36-.57-6.61-2.21-8.06-6.34-2.95-8.44-6.44-16.69-9.88-25.48h215.7c-3.94 9.92-7.6 19.53-11.66 29-.55 1.27-3.05 2.14-4.77 2.41-17.74 2.72-28.92 13.9-30.89 31.47a31 31 0 0 0 5.45 21.33c1.71 2.49 1.35 4-.49 6-10.92 12-25 17.88-40.47 21-24.11 4.92-47.7 3.41-70.42-6.54a54.39 54.39 0 0 1-22.48-17.51Zm67.82 4.95h25.45c2.5 0 4.68-.09 4.4-3.66-.6-7.63-1.09-15.26-1.39-22.91-.14-3.41-1.54-4.53-4.92-4.5q-23.44.19-46.91 0c-3.67 0-5 1.43-5.11 4.94-.27 7.14-.64 14.29-1.28 21.41-.32 3.51.77 4.8 4.31 4.74 8.48-.13 16.98-.03 25.45-.02Zm11-49.72v-15.27c0-14.87 0-14.87-14.83-14.53-5.43.13-7.08 1.75-7.13 7.23v22.59c-3.89 0-7.34-.12-10.78 0-3.85.17-5.73 2.62-5.76 6.22 0 3.88 2.74 4.25 5.9 4.23q21.48-.12 43 0c3 0 6.05.11 6.13-3.92.08-3.8-1.76-6.41-5.92-6.55-3.31-.07-6.62 0-10.59 0Zm69.25-35.22-.73-1.34c-15.73.59-31.47 1-47.18 1.88-5.63.34-9.08 4.45-9.9 10.26a61 61 0 0 0-.41 9c.06 7.1 4.44 11.57 11.48 11.65 4.16 0 8.32-.45 12.47-.38a20.44 20.44 0 0 0 16.71-7.58c6.22-7.56 11.76-15.64 17.58-23.49Zm-159.72-1.35-.9 1.39c6.21 8.15 12.15 16.52 18.72 24.37 4.39 5.24 10.81 6.89 17.54 7q5 .1 10 0c6.68-.11 11.27-3.78 12.06-9.59 1.52-11.07-1.83-19.27-8.67-21.16a6.21 6.21 0 0 0-1.48-.26q-23.6-.86-47.27-1.75ZM19.62 241.95c-3.77-10.37-7.53-20.74-11.6-32h15.43c.29-2.95.51-5.2.75-7.73h11l.65 7.39h15.68c-4.13 11.43-8 22-11.76 32.5l.79.67c4.07-4 8-8 12.24-11.84 1.35-1.24 3.28-1.83 4.94-2.72.61 1.82 1.66 3.62 1.75 5.46.56 11.8-1.94 22.87-9 32.49a29.77 29.77 0 0 1-7.83 7.56c-3.93 2.45-7.85 4.3-8.78 9.6-.25 1.37-2.87 3.32-4.29 3.23a5.68 5.68 0 0 1-4-3.67c-.77-4.81-4.23-6.38-7.79-8.63-11-6.92-15.48-17.89-17.22-30.16a53.56 53.56 0 0 1-.2-12.4c.4-4.29 2.13-4.81 5.39-1.88 2.72 2.44 5.15 5.2 7.78 7.75 1.73 1.69 3.58 3.26 5.37 4.88ZM325.39 226.71l17 16 .82-.51q-2.84-7.81-5.68-15.61c-1.9-5.27-3.78-10.55-5.95-16.59h15.37c.25-2.77.44-5 .68-7.64h11l.85 7.33h15.47c-4.05 11.24-7.83 21.71-11.6 32.18l.94.68c3.71-3.65 7.31-7.42 11.18-10.9 1.61-1.45 3.78-2.3 5.69-3.42.66 2.15 1.93 4.32 1.88 6.46-.43 17.62-4.58 33.37-22.15 42.08-1.16.58-1.55 2.6-2.46 3.82-1.6 2.15-3.32 4.2-5 6.29-1.78-1.94-4.23-3.61-5.15-5.9a9.46 9.46 0 0 0-5-5.43c-11.4-6-16.55-16.41-18.92-28.45-1.2-6.28-2.19-12.69 1.03-20.39Z\" \/>\n                <path fill=\"#4778FF\" d=\"M257.34 264.06c-.06-16.07 12.39-29.05 27.95-29.13 16.72-.08 29.85 12.62 29.87 28.89 0 15.64-13.32 28.83-29.13 28.8a29 29 0 0 1-28.69-28.56Zm16.07-.55a12.74 12.74 0 1 0 25.48.1 12.74 12.74 0 0 0-25.48-.1ZM97.11 234.95a28.8 28.8 0 1 1-.74 57.59c-15.56-.15-28.69-13.31-28.67-28.72a29 29 0 0 1 29.41-28.87Zm-.3 16a12.8 12.8 0 0 0-12.86 12.54 13.13 13.13 0 0 0 13 13.1 12.88 12.88 0 0 0 12.54-13 12.6 12.6 0 0 0-12.68-12.64ZM293.09 229.6c3.93-9.94 7.74-19.46 11.44-29 1.82-4.68 5.52-2 9.39-2.91-3 12.69-5.81 24.65-8.71 36.91ZM77.74 234.64c-2.93-12.31-5.76-24.19-8.6-36.09 7.74-1.49 7.72-1.48 10.41 5.29 3.36 8.45 6.75 16.89 10.26 25.67ZM191.72 267.13c4 0 8-.25 12 .13 1.6.15 3.06 1.68 4.59 2.58-1.45 1-2.87 2.8-4.35 2.84q-12.45.42-24.92 0c-1.47 0-2.88-1.84-4.32-2.83 1.53-.91 3-2.45 4.59-2.6 4.12-.37 8.3-.12 12.46-.12ZM242.46 220a11.43 11.43 0 0 1-11.88 11 11.402 11.402 0 0 1 .78-22.79 11.64 11.64 0 0 1 11.1 11.79ZM140.44 219.7a11.66 11.66 0 0 1 11.42-11.52 11.84 11.84 0 0 1 11.42 11.1 11.69 11.69 0 0 1-11.25 11.71 11.51 11.51 0 0 1-11.59-11.29Z\" \/>\n                <path fill=\"#4778FF\" d=\"M296.48 263.43A10.29 10.29 0 0 1 286.19 274a10.33 10.33 0 1 1-.05-20.66 10.42 10.42 0 0 1 10.34 10.09ZM107.17 263.68a10.65 10.65 0 0 1-10.67 10.35 10.34 10.34 0 1 1 10.67-10.35Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Lambayeque<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Lambayeque -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-piura\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 156.35 121.82\">\n                <path fill=\"#4778FF\" d=\"M339.31 490.93h4.9l.89-1.41.57-1.78.38-1.47v-1.29l-.12-1.72Zm-6.37.78 4.39.12-2.52 3.17-2.72-1.49Zm2.44 3.81 2.89 2.57 1.27-.73 1-1.07 1.32-1.64.92-1.08.94-1.7-5.31-.16Zm-3.58-.87 1.78 1.49-4.36 5.13Zm-2.31 8 1.06-.05h7.76l.62-1.74h-1.42l-1.67-.06-2-.35 2.23-.91 1.39-.72-2.71-2.43Zm14.53.15-2-2.18-1.67.13-1 1.91 2.26.05Zm10.27.67-7.38-5.28-1.89 1-2.12 1 3.18 2.74c2.33.11 4.68.26 7 .46Zm2.48.26c3.35.37 6.94.83 9 1.1 0 0 1.1-6.94 1.38-10.44.34-4.29.68-10.21.69-15.32 0-5.34-.11-11.19-.64-16.75-.58-6-1.7-13.7-2.81-19.21a139.7 139.7 0 0 0-3.84-13.84 59.58 59.58 0 0 0-2.66-6.31s-.12 3.2-.22 4.79-.25 3.78-.41 5.37c-.13 1.4-.51 2.77-.52 4.18 0 1.92.28 5.56.42 7.38a13.26 13.26 0 0 1-2.5-2.13 15.81 15.81 0 0 1-2.55-4.72 25 25 0 0 1-.69-7.17 14.33 14.33 0 0 1 1.67-4.72 38 38 0 0 1 2.62-4.38 11.27 11.27 0 0 0-2.42 1.51 59.59 59.59 0 0 0-5.93 7.09 27.38 27.38 0 0 0-2.6 6.15c-.83 2.52-1.89 6.81-2.42 9A17.2 17.2 0 0 1 340 441a33.7 33.7 0 0 1-.73-9.15 13.52 13.52 0 0 1 2.6-6.54c1.46-1.88 4.57-3.8 6.13-4.76 0 0-4.29.7-6.06 1.24a19.81 19.81 0 0 0-4.58 2 17.64 17.64 0 0 0-3.11 2.83 24.11 24.11 0 0 1 1.59 2.38c.53 1 1.24 2.87 1.6 3.79l-4.37-2.14c-1.51-.74-3-1.88-4.64-2.3a44.63 44.63 0 0 0-7.17-.65 7.47 7.47 0 0 0-1.86.25 10.84 10.84 0 0 1 3.05 1 24 24 0 0 1 4.23 3.94 14.75 14.75 0 0 1 2.78 4.49 15 15 0 0 1 .53 5.19 47.5 47.5 0 0 1-.86 6.18s-2.07-3.56-2.77-5.09c-.6-1.33-1.07-3.27-1.41-4.14a3.23 3.23 0 0 0-.63-1.08c-.57-.57-2-1.57-2.8-2.32s-1.25-1.61-2.05-2.22c-1.32-1-4.39-2.95-5.92-3.91 0 0 1.53 1.95 2.18 3a22.93 22.93 0 0 1 2.56 4.74 17.5 17.5 0 0 1 .59 5.37 14.69 14.69 0 0 1-.87 4.34 24.71 24.71 0 0 1-2.06 4s-1.17-4.05-1.41-5.46c-.16-1 .08-2 0-3a28.22 28.22 0 0 0-.5-3.31 29.08 29.08 0 0 0-.82-3.31c-.44-1.35-1.37-3.65-1.83-4.8l-.59-.73s-.33 2.59-.48 3.88c-.26 2.06-.9 5.66-1 8.51-.19 4.17-.24 11.57-.12 16.52.1 4.39.3 8.79.82 13.16a109.57 109.57 0 0 0 2.33 13.24c1.25 5.05 5.19 17.05 5.19 17.05l9.59-.4 4.57-10.93h-2.41l-.05-.61 2.74-.13 7.57-19.62-.55-.55-1.3-.68-1.5-1.39-.69-.84-.85-1.43-.54 1.2-1 .3-1.09.18-1-.46-.87-.9-.91-.8-.61-1-.45-.58-.54.63-.46.31-.77.25h-.68l-.45-.36 1.45-2.56 16.36-1 1.36-2.27.53-.1.22.29v.37l-.94 1.93 11.53 12.58-.72 2.58-1.23-1-.41-1.54-.72.69-1.55.16-1.51-.1-1.61-.94-.35-1-.38-1.2-.31-.6-2.33.35h-.92l-1.67-.09-1.17-.32-7.85 19.58 4.91-.06 7.66-8.92 10.66-.13-2.3 4.72-2.42 5.08-3.34 4.6-.86 1 2.2 1.55Zm-81.12 12.47 119.9.19a57.17 57.17 0 0 0-6.07-4.06c-2.54-1.29-6.48-2.65-9.16-3.66-2.27-.85-5.35-1.87-6.89-2.38 0 0 .15-4 .41-6a81.6 81.6 0 0 1 1.66-10.17 59.29 59.29 0 0 1 3.83-10.53 60.87 60.87 0 0 1 6.23-10 31.41 31.41 0 0 1 6.16-5.72 46.55 46.55 0 0 1 6.93-3.81 2.43 2.43 0 0 1 .29.89 53.41 53.41 0 0 1-.74 5.47 59.84 59.84 0 0 1-1.83 7 48.09 48.09 0 0 1-2.59 5.59 15 15 0 0 0 3.91-1.65 12 12 0 0 0 3.36-4 60.32 60.32 0 0 0 2.54-8.77 16.3 16.3 0 0 1 1.65 2.57c.65 1.54 1.64 4.81 2.24 6.71.49 1.55 1 3.12 1.35 4.7.46 1.88 1.1 5 1.42 6.59 0 0 2.18-3.09 2.54-4.89a37.9 37.9 0 0 0 .54-10.32c-.37-2.7-2.09-6-2.95-7.62 0 0 2.09 1.25 2.93 1.59a9.77 9.77 0 0 0 2.11.43c.45.06 1 0 1.36 0s.55-.05.75.1c.5.38 1.66 1.59 2.24 2.19a8.63 8.63 0 0 0-.22-2.71 17.38 17.38 0 0 0-2.41-3.82 12.83 12.83 0 0 0-2.75-2.26 12.08 12.08 0 0 0-2.29-.93c-.86-.32-2.21-.78-2.89-1 0 0 1.15-.95 1.77-1.35a18.8 18.8 0 0 1 2.26-1.23 9.7 9.7 0 0 1 1.58-.48 23.44 23.44 0 0 0-2.55-1 6.68 6.68 0 0 0-2.07-.16 5.18 5.18 0 0 0-1.72.47 20.11 20.11 0 0 0-2.17 1.32s-.39-3.51-.54-4.88a26.58 26.58 0 0 0-.41-3.33 8.25 8.25 0 0 0-1.06-2.28 11.11 11.11 0 0 0-1.42-1.63s.08 1.43 0 2.14a31.19 31.19 0 0 1-.36 3.85 24.45 24.45 0 0 1-1 3.37s-1.74-2.2-2.58-3.2a18.17 18.17 0 0 0-2.49-2.76 8.44 8.44 0 0 0-3.35-1.77 43.3 43.3 0 0 0-6.83-.24s3.37 2.75 4.42 3.67a16.42 16.42 0 0 1 1.9 1.82 12.14 12.14 0 0 1 1.4 2.07c.45.81 1 2.13 1.3 2.79a13.7 13.7 0 0 0-1.71-1 6.3 6.3 0 0 0-2.05-.58 4.71 4.71 0 0 0-1.94.45c-.88.38-2.53 1.35-3.35 1.84a24.57 24.57 0 0 1 3.68.66 13.2 13.2 0 0 1 2.92 1.61 4.38 4.38 0 0 1 .93 1.12 20.57 20.57 0 0 0-4.79-.69c-1.71.13-4 .36-5.47 1.49-2.19 1.64-5.82 6.09-7.63 8.32 0 0 1.61-1.2 2.46-1.74a53.8 53.8 0 0 1 4.9-2.92 23.37 23.37 0 0 1 4.82-1.79 35.45 35.45 0 0 1 5-.53c1-.08 2.24-.13 2.88-.16a44.64 44.64 0 0 0-6 3.78c-2.61 2.26-7.16 6.26-9.66 9.75s-4.16 8.56-5.34 11.18c-.67 1.48-1.37 3.53-1.72 4.55 0 0-.29-9.54-.67-14.3-.44-5.59-.95-13-2-19.2a163.62 163.62 0 0 0-4.2-18c-1.51-5.26-4.14-12.09-5.46-15.5 0 0 5.13 3.53 7.43 5.61 2.61 2.35 5.93 6.1 8.22 8.5 1.86 1.95 4.3 4.59 5.53 5.9 0 0-.61-7.17-1.9-10.41a30.85 30.85 0 0 0-5.87-9c-1.61-1.61-4.24-2.38-6.11-3a24.27 24.27 0 0 0-5.12-.9 16.88 16.88 0 0 1 4.05-1.81 55.47 55.47 0 0 1 9.74-.52c3.9.14 10.38 1 13.62 1.41 0 0-1.84-3.79-3.53-4.87a40 40 0 0 0-9.88-3.71 13.77 13.77 0 0 0-6.6 0c-2.6.71-6.88 3.12-9 4.33a35.59 35.59 0 0 1 3.24-4.87 48.24 48.24 0 0 1 5.46-4.6c1.26-1 3-2.13 3.94-2.71a15.54 15.54 0 0 0-2.65-.44 14.35 14.35 0 0 0-4.54.44 22.3 22.3 0 0 0-5.23 3.06 21.89 21.89 0 0 0-3.25 3.43 11.05 11.05 0 0 0 .6-2.3 18.23 18.23 0 0 0-.29-4.13c-.27-1.25-1.11-2.55-1.38-3.59a11.51 11.51 0 0 1-.25-2.65 42 42 0 0 0-2.18 4.7 21.45 21.45 0 0 0-1.1 5.17 38.46 38.46 0 0 0 .25 5.89s-1.7-1.26-2.59-1.76a11.51 11.51 0 0 0-2.71-1.26 12.86 12.86 0 0 0-4-.6 32.54 32.54 0 0 0-5.42 1.16s2.44.82 3.62 1.33a21.36 21.36 0 0 1 3.88 1.89 28.1 28.1 0 0 1 3.59 3.28s-4.13-.87-6.17-.54a17.06 17.06 0 0 0-7 2.71c-2.23 1.64-4.95 5.3-6.31 7.13a23.22 23.22 0 0 0-5.09-2.13 17.13 17.13 0 0 0-5.77.26 10.77 10.77 0 0 0-3.29 1.69 10.87 10.87 0 0 1 1.08-2.59 17.39 17.39 0 0 1 2.92-2.89c1.18-1 3.17-2.24 4.16-2.88a13.68 13.68 0 0 0-4.08-.3 17.28 17.28 0 0 0-5 2.29 16.34 16.34 0 0 0-3.05 3.1 51 51 0 0 0-.92-5.51 24.06 24.06 0 0 0-2-5.11 17.24 17.24 0 0 0-2.64-3.18s-.07 4.32.09 6.11a41.9 41.9 0 0 0 .88 4.64 1.57 1.57 0 0 0 .22.41 27.63 27.63 0 0 0-5-3.35 14.41 14.41 0 0 0-5.51-.78 15.94 15.94 0 0 0-4.42 1.1s3.56 1.5 5.11 2.3a24.85 24.85 0 0 1 4.23 2.49 34.34 34.34 0 0 1 3.81 3.91s-3.54-1.79-5.45-1.8c-2.89 0-8.71.43-11.89 1.74-2.91 1.2-5.74 4.51-7.19 6.11a8.86 8.86 0 0 0-1.48 3.53 33.86 33.86 0 0 1 6.24-3.37 60.87 60.87 0 0 1 10.47-1.7 65.72 65.72 0 0 1 8.29.06s-6.28 2.39-8.32 4.87c-2.2 2.68-4.08 8-4.85 11.2-.63 2.6-.06 6.21.22 8 0 0 3-3.6 4.27-5.53s2.75-4.69 3.86-6.46a43.49 43.49 0 0 1 2.8-4.18c1.27-1.57 3.63-4 4.81-5.24 0 0-.72 3.06-.92 4.62-.48 3.66-1.71 11.53-1.92 17.34a175.48 175.48 0 0 0 .53 20.45c.54 6.16 2.09 14.27 2.86 18.33 0 0-3.46-6.11-5.86-8.62a75.43 75.43 0 0 0-11.28-9.31 34.88 34.88 0 0 0-8.38-3.3 13.23 13.23 0 0 1 2.67-.79 39.47 39.47 0 0 1 5.71.09 18.13 18.13 0 0 1 4.46.84 74.07 74.07 0 0 1 6.82 3.23 21.65 21.65 0 0 0-3.29-3.81c-1.55-1.15-3.8-2.7-6-3.07-2.47-.4-6.7.3-8.82.65a15.7 15.7 0 0 1 2.57-2.27 31.72 31.72 0 0 1 4.61-1.8s-3-1.19-4.51-1a14.3 14.3 0 0 0-4.67 2.12 31.68 31.68 0 0 1 1.64-3.54 28.49 28.49 0 0 1 2.81-3.59c1-1.15 2.59-2.59 3.37-3.31 0 0-2.75-.51-4-.06a18 18 0 0 0-6 3.65c-1.51 1.59-2.54 4.44-3.06 5.87a21 21 0 0 1-1.39-2.52c-.54-1.39-1.42-4.33-1.86-5.8a16.55 16.55 0 0 0-1.23 4.13 48.64 48.64 0 0 0 .82 7.21 9.33 9.33 0 0 0-1.92-.78 6.13 6.13 0 0 0-3-.1 14.71 14.71 0 0 0-3.41 2.4 11.91 11.91 0 0 1 2.82 0 17.53 17.53 0 0 1 3.29 1.46 40.79 40.79 0 0 0-4.82 2.68 9.11 9.11 0 0 0-2.4 2.94 16.81 16.81 0 0 0-1.16 3.88 13 13 0 0 0-.15 2.37s1.16-1.58 1.67-2.12a5 5 0 0 1 1.36-1.1c.52-.26 1.24-.08 1.74-.41a28.58 28.58 0 0 0 3.05-2.75s-.42 2-.52 3a42.58 42.58 0 0 0-.35 5.37c.06 1.85-.09 4 .71 5.77.9 2 3.42 4.73 4.68 6.11a34.72 34.72 0 0 1-.23-4.29c.09-1.68.62-4.1.8-5.77.15-1.42.09-2.86.27-4.28.2-1.6.69-4.08.94-5.33a28.94 28.94 0 0 0 2 4.91 18.22 18.22 0 0 0 4.06 4.76 19.75 19.75 0 0 0 5.5 2.4 23.61 23.61 0 0 1-2.54-3.38c-.66-1.26-.79-2.85-1.39-4.21-.67-1.52-1.91-3.57-2.62-4.94-.57-1.09-1.36-2.7-1.64-3.3a.88.88 0 0 1 0-.31 5.24 5.24 0 0 1 1.94-.06 40 40 0 0 1 7.14 3.15 45.49 45.49 0 0 1 8.35 6.48A48.9 48.9 0 0 1 305 490a100.53 100.53 0 0 1 4.74 10.62 30.21 30.21 0 0 1 1 3.2l-7.9 1.24-11.67 3.15-9.64 4Z\" style=\"fill-rule:evenodd\" transform=\"translate(-263.44 -394.6)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Piura<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Ancash -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-ancash\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 118.41 129.82\">\n                <path fill=\"#4778FF\" d=\"M76.72 129.38H64.15c-1.61 0-3.22-.32-4.84-.39-1 0-1.95.17-2.92.19-5.52.14-11 .46-16.54.34-6.24-.14-12.47-.64-18.71-1a8.48 8.48 0 0 1-5.42-2.39c-4.07-3.83-6.56-8.63-8.93-13.6-2.66-5.6-3.82-11.51-5.08-17.51C.32 88.39.4 81.73.18 75.02.02 70.15.07 65.28 0 60.41a14.46 14.46 0 0 1 1.71-6.48 41.07 41.07 0 0 0 1.63-4.88c4-12.74 10.94-23.39 22.53-30.58a45.81 45.81 0 0 1 13.35-5.5 10.4 10.4 0 0 0 7.4-5.72c3.16-6 8.84-7.5 15.2-7.24 4.3.17 7.58 2 9 6.19 1.24 3.68 3.44 5.45 7.3 6.32 12.18 2.73 21.54 9.84 28.77 19.84a56.68 56.68 0 0 1 7.65 16.23c1.11 3.47 2.36 6.9 3.24 10.42.4 1.61 0 3.41 0 5.12 0 1.27.12 2.54.25 3.81a64.11 64.11 0 0 1-.28 15.9c-.75 5.11-.88 10.32-1.9 15.37-1.91 9.49-5.14 18.49-11.69 26a9.58 9.58 0 0 1-7.09 3.68c-6.79.27-13.57.63-20.35 1ZM19.67 63.6a17.92 17.92 0 0 0 2.63 1.37 8.2 8.2 0 0 0 5.45.18 9.37 9.37 0 0 0 4.67-3.34c.29-.37.25-1 .48-1.41s1-1 1-1.59a21.11 21.11 0 0 0 .29-4.82c-.42-4.88-5.4-9.8-10.93-8.62-4.21.89-7.28 4.46-7.84 9.22-.36 3.38 1.46 8.26 4.25 9.01Zm34.69 4.17-.14.38c-.17-.05-.38 0-.49-.14a6.65 6.65 0 0 0-5.25-1.47c-8.17.67-10.61 9.3-9.27 14.58a7.87 7.87 0 0 0 1.44 2.2 11.27 11.27 0 0 0 1.71-1.82c1.19-2 2.68-3.27 5.15-3a9.49 9.49 0 0 1 6 3.49 7.83 7.83 0 0 0 10.77.57q3.21-3.06 6.25-6.29a6.62 6.62 0 0 0 1.37-7.52c-.82-2-2.12-2.73-4.21-2.22a11.23 11.23 0 0 0-3 1.18c-1.46.86-2.81 1.89-4.2 2.84 0-2.54-.06-5.12 0-7.7.12-3.93.42-7.87.46-11.8a16.89 16.89 0 0 0-.76-4.48c-.25-.93-.89-1.57-2-.63a3.84 3.84 0 0 1-1.45.7c-3.86 1.18-7.71 2.38-11.59 3.48-2.28.65-2.63.95-2.85 3.26-.06.73-.18 1.46-.3 2.19-.77 4.84-6.06 9.58-10.9 9.81a6.46 6.46 0 0 0-2.4.48c-3.26 1.55-8.29.17-10.45-2.3-2.9-3.31-3.44-3.26-6.8-.31a13.58 13.58 0 0 1-7.62 3.56c-1.68.18-2.5 1.21-2.62 3-.08 1.23-.17 2.46-.2 3.69v4.68h.41c.9-2.5 2.25-4.6 4.75-5.75a14.67 14.67 0 0 0-3.67 6.94 35.49 35.49 0 0 0-.29 13.35c1.12 6.56 2.55 13.05 5.37 19.14 2.17 4.68 4.63 9.16 8.7 12.5a6.09 6.09 0 0 0 2.71 1.35 27.56 27.56 0 0 0 5.59.3c10.82-.57 21.63-1.33 32.45-1.79 3-.13 4.46-1.67 5.46-4.08a10.93 10.93 0 0 0 .87-3.26c.13-2.07 0-4.16 0-6.37 4.25-.56 8.63-1.16 13-1.7a8.25 8.25 0 0 1 5.93 1.29 4.47 4.47 0 0 0 1 .42c-1.55-3.06-3.94-4.16-7-3.52-5.27 1.11-10.48 2.35-16 2.09-5.92-.29-11.81-.52-17.51-2.26-2.81-.86-4.86-.17-6.86 1.92a83.49 83.49 0 0 1-8.12 7.5 21.11 21.11 0 0 1-9.84 4.81 2.9 2.9 0 0 1-2.34-.69c-.35-.44-.07-1.59.23-2.3a21.71 21.71 0 0 1 1.77-2.89 36.12 36.12 0 0 1-3.71 1.6c-2 .6-2.95-.36-2.25-2.3a21.24 21.24 0 0 1 2-3.76c.38-.63.5-1.09-.09-1.67-2.45-2.38-3.92-5.4-5.43-8.39-2.56-5.09-4.22-10.38-3.84-16.17a12.61 12.61 0 0 1 16.17-11.55c6.91 1.91 11.16 6.77 14 13a8.67 8.67 0 0 0 3.6 4.35 32.37 32.37 0 0 0 6.46 2.8 56.85 56.85 0 0 0 16.7 1.62 20.31 20.31 0 0 0 12.67-4.22 23.23 23.23 0 0 0 1.82-1.76 1.27 1.27 0 0 0-1-.17 43.64 43.64 0 0 1-18.27 1.3c-4.39-.56-8.65-2.21-13-3.39a6.74 6.74 0 0 1-1.51-.58c-3-1.65-5.1-4-5.26-7.62-.23-5.28 4.67-11.67 9.83-12.77 3.07-.53 5.57.56 7.85 2.27ZM27.97 31.4a31.41 31.41 0 0 0-5.51-.52c-5.66.44-10 3.32-13.27 7.86-2.91 4.08-4.22 8.86-5.49 13.62a2.61 2.61 0 0 0 .47 1.9 11.35 11.35 0 0 0 1.86 1.73 16.35 16.35 0 0 0 1.22-2.2c1-2.72 1.65-5.6 2.95-8.16 5.1-10 17.76-13.77 26.83-5.5a4.6 4.6 0 0 0 1.67.91 59 59 0 0 0 18.12 2.93c3.29.06 6.59-.12 9.89-.19a32.59 32.59 0 0 0 13-2.79 10 10 0 0 0 5.36-11.83 14.87 14.87 0 0 0-4.53-7 37.27 37.27 0 0 0-15.73-7.79l-1.67-.4.1-.38c3 .29 6.07.47 9.08.91a52.2 52.2 0 0 1 20 7.09 49.54 49.54 0 0 1 11.74 10.49 20.94 20.94 0 0 0 1.89 1.75 45.31 45.31 0 0 0-24-18.5 67.65 67.65 0 0 0-16.2-3.16c-.54 0-1.08-.14-1.72-.22.18-.33.21-.45.28-.49 2.31-1.53 2.86-3.63 2-6.18a5.59 5.59 0 0 0-5.01-4.21 19.5 19.5 0 0 0-3.82 0c-4.52.52-7.69 3.12-9.94 6.88-1 1.66-.19 3 1.75 3.26 1 .14 2.06.13 3.09.24a9.09 9.09 0 0 1 1.37.32v.39c-16.87 1-31.16 6.87-41.17 21.13 4.78-3.6 9.9-4.39 15.39-1.89Zm82.06 48.57a6.11 6.11 0 0 0-.26-.64 10.33 10.33 0 0 0-12.8-4.68 19.91 19.91 0 0 0-11.6 12.13c-1.46 4-4.3 5.89-8.06 7a54 54 0 0 1-14.25 2.27c-7 .21-14 0-20.81-1.84-4.75-1.27-8.27-3.6-10-8.62-1.62-4.78-5.19-8.17-9.75-10.43-5.28-2.61-10.52-1.19-13.84 3.69-2.18 3.21-2.35 6.8-2.16 10.5a22.57 22.57 0 0 0 6.69 15.17 9.62 9.62 0 0 0 2.24 1.67c.38.21 1.22.24 1.44 0a31.32 31.32 0 0 0 2.13-2.93 34.32 34.32 0 0 1-3.54-2.49c-4.17-3.85-4.41-12-2.61-15.76 1.07-2.25 2.73-3.69 5.41-3.64 3.9.06 6.34 2.3 6.88 6.3a13.18 13.18 0 0 0 2.64 6.93c4.83 5.87 11.33 8.89 18.46 10.69a55.88 55.88 0 0 0 23.46.42c3.31-.58 3.78-1.16 3.54-4.57a7.2 7.2 0 0 0-.11-1c-.27-1.39-.55-2.77-.85-4.24 1.61-.42 3.18-.81 4.73-1.24 4.25-1.15 7.54-3.31 9.22-7.71A22 22 0 0 1 93 77.76a11.74 11.74 0 0 1 11.32-2.45c2.54.79 4.06 2.76 5.71 4.66ZM3.13 53.82c-1.94 2.66-2.05 5.49-1.84 8.35s2.6 4.08 5.11 2.4a15.91 15.91 0 0 0 6.49-9.7 28.65 28.65 0 0 1 1.27-4.07 10.32 10.32 0 0 1 9-6.65c4.32-.34 8.08.94 10.57 4.82a11.61 11.61 0 0 1-.47 13.41c-.47.63-.9 1.28-1.34 1.92a9.68 9.68 0 0 0 7.74-6.27c2.33-6.13-.36-14.68-5.81-18.45a15 15 0 0 0-19.89 2.05c-3.79 4-5.55 8.85-6.41 14.16-.1.57-.5 1.51-.81 1.54a2.49 2.49 0 0 1-1.73-.81 21.6 21.6 0 0 1-1.88-2.66Zm102.67 2.2h.33c.05-.41.13-.81.15-1.22a18.65 18.65 0 0 0-2.78-10.56 12.9 12.9 0 0 0-8.05-6.07 14.82 14.82 0 0 0-10.33 1c-6.4 3.3-9 12-7.38 17.66a10.48 10.48 0 0 0 7.12 7.6 7.28 7.28 0 0 0 1.51.17l-3.29-5.39c-.13-.21-.27-.6-.39-.59-1.63.09-1.55-1.31-1.79-2.21-1.23-4.63 1.2-10.09 5.83-12.57 5.23-2.81 10.53-2.37 14.44 2.26 1.66 2 2.55 4.59 3.7 7a19.83 19.83 0 0 1 .93 2.96Zm10.91 13.22c-.35-1.94-.62-1.95-2.73-2.49a27.38 27.38 0 0 1-5.8-2.33 31.91 31.91 0 0 1-3.35-2.65 2.4 2.4 0 0 0-3.78.72c-2.11 3.19-7.4 4.81-11 3.65-2.31-.74-4.75-1.08-7.28-1.63.19.27.24.41.35.49.28.2.58.37.88.55a30.84 30.84 0 0 0 9.89 3.75c6.52 1.27 13 1.89 19.6.15a17 17 0 0 1 3.22-.17Zm-25.16-3.42.34-.41a3.51 3.51 0 0 1-.57-.21c-2.79-1.65-3.51-4.18-3.08-7.21.54-3.8 2.47-6.16 5.68-6.92A2.94 2.94 0 0 0 96 47.98a2.65 2.65 0 0 0-2.36-2.6 7.47 7.47 0 0 0-5.22 1.16c-5.51 3.82-7.05 9.73-2.87 15.59a8.81 8.81 0 0 0 6 3.73Zm9.64 53.3.33-.57a33.17 33.17 0 0 0-2.13-3.09c-3.64-4.19-7.37-8.31-11-12.52-.93-1.08-1.71-.91-2.64-.2a4.64 4.64 0 0 0-.25 6.73 35.2 35.2 0 0 0 12.8 9.11 14 14 0 0 0 2.89.58Zm-72.65-19.08c-.1-1.51-.47-2.56-1.71-3a2.76 2.76 0 0 0-3.35 1.18c-3.2 4.48-6.41 8.95-9.57 13.45a12.67 12.67 0 0 0-1.29 2.64 1.44 1.44 0 0 0 .2 1.19c.13.17.75.13 1.06 0a14.82 14.82 0 0 0 2.42-1.33c4.75-3.39 8.29-7.93 11.66-12.6a5 5 0 0 0 .58-1.49Zm60.83-.75a15.74 15.74 0 0 0 1.26 2.72c1.49 2 3 4 4.67 5.9 2.51 2.85 5.15 5.58 8.57 7.38a4.33 4.33 0 0 0 1.51.16 5.07 5.07 0 0 0 0-1.5 6.89 6.89 0 0 0-.9-1.85c-1.64-2.45-3.29-4.9-5-7.31s-3.38-4.6-5.13-6.85a2.32 2.32 0 0 0-3-.87 9.8 9.8 0 0 0-1.98 2.26Zm-55.81 6.41a3.66 3.66 0 0 0-2.12-3.53c-1.21-.55-1.59.69-2.16 1.32-2.42 2.65-4.81 5.32-7.14 8.05-1.72 2-3.36 4.11-5 6.19-.2.27-.16.72-.23 1.09A3.07 3.07 0 0 0 18 119a10.74 10.74 0 0 0 2.36-.79c5-2.52 8.91-6.41 12.39-10.72a6.48 6.48 0 0 0 .81-1.75Zm80.52-53.31c-1-4.73-2.25-9.52-5.11-13.5-4-5.56-9.44-8.54-16.52-7.61a36.88 36.88 0 0 0-4.2 1.06l.14.52c.35-.05.71-.08 1.06-.15 1.06-.2 2.11-.51 3.17-.61 7.84-.76 15.78 5.88 18.34 11.72 1.21 2.82 2.09 5.75 3.12 8.61Zm-15.82 0c2.28 2.75 2.67 5.79.9 8.76-1.93 3.25-5.12 2.6-8.25 1.76.94 1.62 2.72 2.25 5 1.9a6.06 6.06 0 0 0 5.16-5.32c.49-2.74-.68-5.91-2.77-7.06Zm-33 5.56a53.13 53.13 0 0 1 7 .43c2.42.46 3.87 2.52 5.27 4.46-1.3-4.42-8.78-7.24-12.31-4.87Z\" \/>\n                <path fill=\"#4778FF\" d=\"M50.88 56.97c-3.58-.47-5.67-.09-9.28 3.83-.12-1.53 1.16-3.38 3.1-4.3a5.69 5.69 0 0 1 6.18.47ZM79.39 34.97c-8.18 6-31.79 6.86-37.71 1.18a57 57 0 0 0 37.71-1.18ZM10.51 89.75c.06-3 .49-6.25 3.52-8.41a6.16 6.16 0 0 1 6.26-.45c-2.6-.06-5.51-.5-7.08 2-1.32 2.16-1.91 4.75-2.7 6.86ZM19.67 63.6c-.46-1.08-.93-2.16-1.37-3.25a7.1 7.1 0 0 1 0-5.45 5.58 5.58 0 0 1 5.83-3.79 6.05 6.05 0 0 1 5 5.34c.27 2.24.12 4.32-1.52 6-1.79 1.87-3.63 2.16-6 1.14a5.53 5.53 0 0 0-2-.08Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Ancash<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Madre de Dios -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-madre-de-dios\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" data-name=\"Capa 1\" viewBox=\"0 0 270.84 197.4\">\n                <path fill=\"#4778FF\" d=\"M0 197.01c.74-1.91 1.5-3.82 2.22-5.74s1.43-4 2.21-6 1.66-3.78 2.42-5.7 1.38-3.74 2.07-5.61l-.65-.23-6.18 8.52a1.56 1.56 0 0 1-.23-1.5c1.92-4 3.83-8 5.83-12 4.13-8.21 8.36-16.38 12.47-24.6 1.66-3.33 3.19-6.74 4.67-10.16a9 9 0 0 0 .31-2.57c-2.91 2.14-3.7 5.69-6.86 7.24 1.08-3.44 2.33-6.77 3.67-10.07q4-9.91 8.12-19.79c.62-1.49 1.33-2.87-.66-3.87.45-1.22.77-2.39 1.29-3.46 5.74-12 11.2-24.09 18.42-35.26q6.62-10.22 14.05-19.9A93.26 93.26 0 0 1 83 27.22a179.87 179.87 0 0 1 20.27-12.8c5.91-3.13 12.36-5.26 18.67-7.55a115 115 0 0 1 23.3-5.66c2-.29 4-.8 6-1.2h32.5l2 2.19c-.87 0-1.64.1-2.41.12-9.28.18-18.59 0-27.84.62a118.66 118.66 0 0 0-33.29 6.74 169.83 169.83 0 0 0-20.13 8.83c-5.82 3-11.25 6.83-16.78 10.42a32 32 0 0 0-4 3.6l.38.52c2.32-1.39 4.66-2.76 7-4.16 5.72-3.46 5.86-3.52 7.22-2.89l-5.61 5a14 14 0 0 0 3.05-1c1.93-.53 4-.65 5.88-1.31 4.08-1.45 8-3.43 12.12-4.65 7-2.06 14-3.72 21.06-5.52 2.78-.71 5.58-1.33 9-2.13l-4.51-1.15.05-.6c8.11-1.38 16.26-2.56 24.53-2.4s16.39.63 24.3 1l-7-3.16.08-.55c1.83.32 3.65.75 5.49.93a104.36 104.36 0 0 1 24.24 5.12c5.72 2 11.22 4.56 16.86 6.76a34.13 34.13 0 0 0 4.86 1.19l.44-1-5.73-4.38c-5.3-4-11.48-6.35-17.53-8.92-3.29-1.39-6.66-2.6-10-3.9l.09-.52c.94.11 1.89.15 2.81.35 1.28.28 2.54.67 3.81 1a61 61 0 0 1 7.63 2.26c5.13 2.23 10.22 4.57 15.14 7.22a36.6 36.6 0 0 1 12.64 10.58c1.61 2.23 3.29 4.68 1.3 7.71-.26.39.17 1.42.54 2a12.24 12.24 0 0 0 1.92 2c1.88 1.75 3.48 3.58 4 6.28a14.2 14.2 0 0 0 3.63 6.78 74.32 74.32 0 0 1 13.23 22 91.45 91.45 0 0 1 5.54 21.06 11.39 11.39 0 0 0 1.14 2.63v25.28a31.35 31.35 0 0 0-1.59 3.86c-1.31 4.82-2.08 9.83-3.85 14.46a103.86 103.86 0 0 1-10.46 20.42 100 100 0 0 1-24.23 25.83c-3.41 2.49-6.82 5.26-11.19 5.88-1.31.19-3.3-.07-4-.92s-.36-2.82.15-4c2.15-5.08 5-9.91 6.71-15.14 1.83-5.73 2.67-11.8 3.83-17.74.53-2.75-.23-3.29-2.81-2.21a80.77 80.77 0 0 1-27.15 6.39c-9.92.53-19.75.11-29.25-3.32a2.9 2.9 0 0 0-2.44.41 2.5 2.5 0 0 0-.55 3.54c3.65 5.54 5.6 11.82 7 18.18s2.08 12.91 3.08 19.37c-13.66 1.31-20.24-1-34.58-2.85-.84-.93-4.14-.87-5-1.79-3.4-3.69-10.44-5.6-9.55-11.17.25-1.52-.7-1.77-2-1.76-6.19 0-9.3-2.86-9.51-9-.1-2.93.16-5.87.18-8.81a5.13 5.13 0 0 0-.54-1.55 13.6 13.6 0 0 0-1.14.86c-.49.46-.94 1-1.4 1.45a8.2 8.2 0 0 1-1.69-1.75c-2.06-4.08-2.27-8.45-1.91-12.91.06-.65-.23-1.88-.46-1.9a4 4 0 0 0-2.36.48c-1.62 1-3.09 2.29-4.68 3.38s-2.78.64-3.76-.85a9.23 9.23 0 0 1-1.12-7.14 40.14 40.14 0 0 1 6.88-16c1.9-2.64 3.49-5.52 5.12-8.34.27-.46 0-1.21 0-1.82a7 7 0 0 0-1.67.3c-1.33.6-2.59 1.35-3.93 1.94a5.64 5.64 0 0 1-1.66.18c7.24-6.48 14-13 18.47-22.15-3.31.14-5.06 3.2-8.24 2.82 3-2.84 5.74-5.35 8.36-8a10.29 10.29 0 0 0 1.38-2.61c-.94-.1-1.89-.27-2.83-.3-1.81-.05-3.61 0-5.42 0 .19-.66.41-.93.69-1 3.84-.82 6.91-3.08 9.92-5.4a3.41 3.41 0 0 0 1.13-2.11c0-.3-1-.89-1.66-1.1a19.79 19.79 0 0 0-10.24-.72l-.21-.46 4.53-3.08a24 24 0 0 0-3.1-.84 15.81 15.81 0 0 0-4-.17q-5.72.7-11.41 1.7c-1.65.29-3.24.66-4.88-.08 2.91-1.21 5.89-2 8.8-3a34.9 34.9 0 0 1 16.25-1.13c5.79.8 11.5 2.26 17.22 3.53.65.14 1.12 1 1.74 1.44a4.51 4.51 0 0 0 1.92 1c2.26.21 4.55.21 6.82.35.37 0 .7.45 1.06.48 2.38.19 4.75.44 7.13.4a6.3 6.3 0 0 0 2.53-1.15c1.15-.63 2.24-1.33 3.17.37.14.26.85.39 1.25.31a33.77 33.77 0 0 0 4.46-1.1c1.45-.51 2.8-1.35 4.3-.09.21.17.88 0 1.25-.24 2.64-1.39 5.26-2.83 7.89-4.25.45-.24 1-.71 1.39-.59 2.83 1 4.76-.71 6.67-2.25 2.46-2 4.79-4.13 7.19-6.2a12.43 12.43 0 0 1 2.48-1.89 2.08 2.08 0 0 1 1.77.39c.27.24.22 1.1.05 1.59-.61 1.76-1.52 3.44-2 5.24-.93 3.67-1.61 7.4-2.45 11.1a12.09 12.09 0 0 1-.95 2.12l-.81-.14c-.14-1.82-.25-3.64-.44-5.45a8.25 8.25 0 0 0-.52-1.62 12.54 12.54 0 0 0-1.45.77c-.86.57-1.85 1.83-2.5 1.67-1.7-.43-2.23.71-3.15 1.52-2.23 2-4.49 3.93-6.81 5.82a1.68 1.68 0 0 1-1.55.17c-1.28-1.16-2.36-.45-3.44.2s-2.12 1.41-3.21 2.05a.81.81 0 0 1-1.24-1c.26-.86.63-1.69 1.13-3a17.67 17.67 0 0 0-2.25.52c-1.75.64-3.45 1.41-5.22 2-.61.2-1.69.24-2-.12-1.36-1.61-2.55-1-4.06-.24a3.78 3.78 0 0 1-3.2.17c-1.07-.76-1.64-1-2.75-.19-.57.39-2.14.46-2.28.18-1.11-2.19-2.5-1-3.88-.55-.79.23-2 .61-2.4.25-1.43-1.18-2.55-.44-3.88 0-.84.3-2.21.5-2.72 0-1.08-1-2.13-1.06-3-.31a7 7 0 0 0-1.83 2.78 27.33 27.33 0 0 0-.68 3.31c-1.31 5.23-2.75 10.44-3.94 15.7a8.84 8.84 0 0 0 .36 4.06c.49 1.76 1.35 3.41 1.94 5.14.51 1.51.8 3.1 1.31 4.62.39 1.15.9 2.21 2.48 2.21.37 0 .88.71 1.09 1.2 1.22 2.88 2.2 5.88 3.58 8.67a37.71 37.71 0 0 0 11.76 14.17 146.92 146.92 0 0 0 12.5 7.74 28.71 28.71 0 0 0 5 1.79 23.94 23.94 0 0 0-2.9-3.19c-2.18-2.32-4-4.83-4.13-8.21-.21-6.84 2.18-13.16 4.25-19.46a177.07 177.07 0 0 1 7.2-17.77c2.63-5.76 5.78-11.26 10.3-15.84a9.85 9.85 0 0 1 12.46-1.43c1.1.71 2.33 1.2 3.95 2-.07-1.43-.1-2.14-.15-2.86-.23-3.52.1-6.94 2.05-10 1.72-2.7 3.39-5.43 5.25-8 3.78-5.3 8.09-10.05 14-13.15 3.45-1.81 6.82-3.81 10.09-6 2.54-1.65 4.86-3.66 7.31-5.46a5.85 5.85 0 0 1 1.52-.59c-6.14 8.46-15.36 12.59-23.54 18.22a1.9 1.9 0 0 0 1.7.07c3.5-2 7-3.95 10.45-6a48.4 48.4 0 0 0 14.1-12.21 4.45 4.45 0 0 1 5.08-1.29l1.79.59a3.09 3.09 0 0 0 .2-.86 1.82 1.82 0 0 0-.26-.75 22.51 22.51 0 0 0-11.61-9.37 24.5 24.5 0 0 0-18.85 1.34c-6.26 2.94-10.08 7.85-12.51 14.1-.55 1.41-1.19 2.77-1.79 4.16-2.06-2.88-3.3-5.65-2.23-8.73s2.44-5.87 3.64-8.81c.93-2.29 1.42-4.67.18-7-.34-.61-1.37-.85-2.09-1.27-.21.62-.74 1.34-.59 1.85 1.35 4.59-.4 8.47-2.45 12.39-1.57 3-1.26 6.21-.36 9.36.21.74.81 1.37 1.09 2.11a.77.77 0 0 1-1.28.84 18.06 18.06 0 0 1-1.95-2.5c-2.74-4.34-1.15-8.52.74-12.56a20 20 0 0 0 2.22-8.84c0-3.16-2.47-4.58-5.18-4.6-1.32 0-1.63.9-.82 1.91 3.29 4.05 2.48 8.26.72 12.63-1.22 3-2.5 6.15-1.14 9.49.85 2.09 1.89 4.11 2.84 6.16a4.55 4.55 0 0 1-2.42-1c-1-.71-1.89-1.91-3-2.16a5.58 5.58 0 0 1-3.78-2.78c-2.2-3.5-2.32-7.33-1.95-11.21.33-3.51.45-7-1-10.24-1.29-2.85-3.16-5.33-6.52-6-2.75-.51-5.53-.92-8.32-1.2-4.78-.5-9.58-1.12-14.38-1.22-4.23-.08-8.64-.14-12.69.89-4.26 1.08-8.31 3.23-12.22 5.35q-7.8 4.24-15.21 9.17c-9.34 6.22-17.67 13.56-23.9 23-1.46 2.22-2.72 4.57-4.19 6.78-2.87 4.31-7.34 6.47-11.8 8.62-6.24 3-12.13 6.48-16.69 11.85-1 1.22-2.07 2.36.42 3.3l-10.36 11.48.27.58a6.94 6.94 0 0 0 2 0c.67-.22 1.21-.85 1.88-1.11a4.64 4.64 0 0 1 1.63-.05c-.18.45-.36.9-.51 1.37-.26.78-.49 1.58-.79 2.54l3.93-1.25.33.49a10.16 10.16 0 0 1-.66 1.32c-2.08 2.93-4.21 5.83-6.24 8.79a9.49 9.49 0 0 0-.83 2.24l2.26-.1c.18 0 .37 0 .81.08a4.63 4.63 0 0 1-.43 1.48c-2.14 3-4.48 5.82-6.45 8.9a19.31 19.31 0 0 0-2.61 6.13c-.42 1.87.75 2.55 2.56 1.89a6.43 6.43 0 0 0 2.32-1.12c3.9-3.91 7.71-7.9 11.57-11.85.66-.67 1.4-1.25 2.51-2.22a8.51 8.51 0 0 1 0 2.53 68.59 68.59 0 0 1-3.3 7.49c-3.61 6.51-8.52 12.06-13.43 17.6a43 43 0 0 0-3.56 4.32 2.83 2.83 0 0 0-.06 2.32c.14.32 1.37.42 2 .23a11.26 11.26 0 0 0 3.25-1.48c3.63-2.57 7.19-5.25 10.79-7.87a5 5 0 0 1 1.19-.45 5.33 5.33 0 0 1 .29 1.26 2.83 2.83 0 0 1-.34 1.15 65.42 65.42 0 0 1-18.26 22.68 7.56 7.56 0 0 0-1.33 2.41c.94.28 1.88.62 2.84.82a1.74 1.74 0 0 0 1.16-.27 76.6 76.6 0 0 0 8-5.12c3.21-2.57 6.08-5.56 9.36-8.61a7.74 7.74 0 0 1 .37 2.67c-.78 3.85-1.76 7.66-2.6 11.5-.22 1-.58 2.59-.13 2.93a3.78 3.78 0 0 0 3.12.29 80.2 80.2 0 0 0 9.33-4c2.75-1.44 5.27-3.34 7.91-5 .29-.18.82-.33 1-.18a1.13 1.13 0 0 1 .32 1c-.22.75-.66 1.44-.93 2.19-.66 1.8-1.71 3.71-.42 5.53s3 .83 4.64.57a2.39 2.39 0 0 1 1.18 0c.53.21 1.3.52 1.42.94.7 2.6 2.92 3.22 5 3.8 4.69 1.32 9.44 2.4 14.17 3.59.53.14 1.05.32 1.58.48v.53a12.31 12.31 0 0 1-2.22.34c-2.48 0-5-.12-7.42-.29-12.85-.91-25.5-.28-37.53 5-5 2.2-9.34 2.45-13.63 5.93-1.6 0-3.79 2.14-5.4 2.14a61.05 61.05 0 0 1 16.1-9.9c2.77-1.16 5.53-2.39 8.29-3.59a1.7 1.7 0 0 0-1.3-.4 62.41 62.41 0 0 0-25.87 7.78c-3.1 1.77-4.38 1.38-7.32 3.44-2.41 0-6.35 2.67-8.76 2.67l5.83-3.77c2.63-4.79 1.24-8.46-4.38-5m193.56-73.05q-1.21-2.37-2.45-4.72a4.08 4.08 0 0 0 2.51 4.66 40.73 40.73 0 0 0 2.53 4.53 33.61 33.61 0 0 0 3.32 3.44l.51-.49c-.65-.86-1.25-1.76-2-2.57-1.44-1.78-2.95-3.36-4.44-4.98Zm-11.17-9.72c0 1.23-.25 2.56 1.31 3.48.16-1.57.28-2.86-1.37-3.43-.94-4.71-8.86-13.64-12.27-13.69a50.32 50.32 0 0 1 10.89 12.47c.29.38.93.65 1.42 1.04Zm7.9 21.42-2.24-10c-.58.69-.82.86-.8 1 .73 2.82 1.47 5.64 2.26 8.44.06.23.55.33.83.49a24.48 24.48 0 0 1 .7 2.87 20.69 20.69 0 0 1 0 3.15 6.49 6.49 0 0 1-.33 1.34c2.92-1 3-1.12 6.1.57s6.45 1.29 9.76.49a12.21 12.21 0 0 0-4-.68c-5.17.11-8.52-2.58-11-6.83-.21-.51-.85-.69-1.3-.97Zm52.57-41.21a5.77 5.77 0 0 0 .33-1.73 87.73 87.73 0 0 0-2-9.12 54 54 0 0 0-7.65-16c-2.48-3.36-5.29-6.48-8.08-9.59-.52-.58-1.64-.62-2.48-.91-.18.92-.43 1.84-.52 2.78a2.61 2.61 0 0 0 .38 1.33c1.25 2.43 2.54 4.83 3.81 7.25 2.4 4.6 4.77 9.23 7.25 13.79a3.15 3.15 0 0 0 1.89 1.5c2.46.4 3.62 2 4.44 4.1s1.63 4.12 2.63 6.6ZM186.1 49.03h.88c.12-.69.23-1.37.36-2.06a48.75 48.75 0 0 1 1.26-6.41c1.55-4.61 2.08-9.18.41-13.85-.13-.35-.32-.84-.61-1-1.94-.79-3.9-1.55-5.9-2.2-.37-.12-.92.31-1.4.49a5.87 5.87 0 0 0 .71 1.25c3.32 3.57 5 7.64 4.12 12.6a29.19 29.19 0 0 0-.65 5.57 41.18 41.18 0 0 0 .82 5.59Zm38.85 34.36-.55.24 8.91 18.16c1.1-3.16-3.93-14.1-8.36-18.42Zm11.3 64.33c-2.09 3.83-2.94 13.33-1.14 15.39.05-.85.12-1.49.13-2.12a17.92 17.92 0 0 1 2-8.68c1.49-2.6 1.45-2.83-.99-4.61Zm-20-81.53c3.12 2 5.22 1.09 8.95-3.82Zm22-12.81-.51-.67-5 4 .48.63Zm25.61 33.28-1 .07.38 3.21.8-.08c-.06-1.07-.12-2.15-.19-3.22Z\" \/>\n                <path fill=\"#4778FF\" d=\"M211.87 114.69a4.06 4.06 0 0 1-2.5-4.66q1.22 2.37 2.45 4.72ZM200.62 105.08c1.64.58 1.52 1.86 1.36 3.44-1.56-.93-1.32-2.25-1.31-3.49ZM83.83 66.86c2.79-1.71 5.51-3.55 8.38-5.11a47.36 47.36 0 0 1 18-5.42 36.72 36.72 0 0 1 16 1.68c5.71 2 11.24 4.49 17 6.44a22.11 22.11 0 0 0 14.37-.14c4.23-1.41 8.4-3 12.62-4.44a1.61 1.61 0 0 1 1.46.42c.92 2 2.37 1.41 3.92 1.13a25.28 25.28 0 0 1 3.37 0 24.37 24.37 0 0 0 3.82-.39c1.29-.26 2.52-.83 3.82-1.09a1.48 1.48 0 0 1 1.29.65c.16.29-.12 1-.44 1.31-3.06 2.68-6.43 4.67-10.68 4.71a7.08 7.08 0 0 0-2.24.62c-.93.33-1.81.78-2.74 1.12-1.25.45-1.75-.1-1.67-1.35.11-1.64-.4-1.82-1.86-1.05-6.42 3.4-13.28 5.72-20.57 5-4.37-.42-8.64-2.1-12.89-3.45-4.89-1.55-9.6-3.73-14.55-5a39.61 39.61 0 0 0-20.81.25c-4.59 1.32-9 3.16-13.54 4.74a9 9 0 0 1-1.65.25ZM164.52 36.56c.81-2.21 1.24-2.43 2.61-.79a21.67 21.67 0 0 1 2.84 5.07c.21.47-.35 1.29-.56 2-.42-.49-.85-1-1.26-1.47a7.08 7.08 0 0 1-.38-.66l-.56.11a15.86 15.86 0 0 0 .61 2.51c.55 1.28 1.31 2.46 1.86 3.74a1.57 1.57 0 0 1-.09 1.42 1.44 1.44 0 0 1-1.41 0c-1-1.34-2.33-2.67-2.77-4.22-1.41-4.94-3.61-9.34-7.92-12.3-2.19-1.5-4.59-3.14-7.87-1.62a5.24 5.24 0 0 0 1.22.6c4.27.52 7.16 3.15 9.15 6.6 2.27 3.93 4 8.15 6.08 12.35-.47.23-.82.53-1.16.53a15.53 15.53 0 0 0-7.67 1.93c-1 .53-2.46.24-2.49 2a4.05 4.05 0 0 1-2.13.43 31.08 31.08 0 0 1-6.35-.79c-4.1-1.19-7.94-3-10.41-6.73a10.46 10.46 0 0 1 3.09-14.31 31.24 31.24 0 0 1 5.48-2.16c1.77-.67 3.57-1.3 5.34-2a7.59 7.59 0 0 1 6.09.32c3.12 1.24 5.09 3.73 7.59 5.62.45.35.64 1.05 1.07 1.82Zm-5.57 5.92c.27-6-5.12-10.45-10.81-10.4-6.53.06-10.33 4.9-10.23 10 .12 6.45 5 10 11.2 9.8 5.93-.25 10.09-3.19 9.84-9.4ZM98.41 51.79c3.73-3.4 8.15-5 12.71-6.26a34.34 34.34 0 0 0 18.86-12.74c2.19-2.84 5.35-5 8.17-7.28.58-.48 1.58-.44 2.39-.65l.2.6a18.57 18.57 0 0 0-2.63 2.18c-2.66 3.11-5.71 6-7.73 9.53-3.83 6.63-9.43 9.93-16.78 11.14-4.43.74-8.74 2.17-13.12 3.26a14.09 14.09 0 0 1-2.07.22ZM218.86 36.94c4.35 0 5.58 1.68 4.29 4.69a15.67 15.67 0 0 1-9.13 8.9c-.74.28-1.41.75-2.15 1-2.25.89-4-.46-3.57-2.83.65-4 3-6.93 6.07-9.3a27.92 27.92 0 0 1 4.49-2.46ZM187.29 56.79a9.43 9.43 0 0 1-2.41-.43c-6.88-3.19-10.25-8.82-11-16.18-.44-4.27-1.17-8.44-3.46-12.18-.19-.31 0-.84 0-1.27.4.09.92 0 1.2.29 3.38 2.85 5.64 6.23 5.73 10.91.1 5.54 1.63 10.65 5.75 14.66 1.35 1.31 2.84 2.48 4.26 3.72ZM123.91 47.96c2.49-1 4.61.2 6.37 1.37a56.84 56.84 0 0 1 8.56 7.28 7.15 7.15 0 0 1-2.59-.45c-1.79-1.08-3.42-2.45-5.17-3.61-2.3-1.53-4.64-2.98-7.17-4.59ZM164.1 54.49c3.58-1.65 11.38-1.46 13.2.57h-13.17ZM145.35 141.12c4.78-.36 5.48 4.16 7.81 6.75-3.05-1.69-5.43-4.22-7.81-6.75ZM143.62 139.79c-2.7-.66-5.79-4.82-5-7.66l5.41 7.25ZM149.87 55.53c-2.88 1.45-6.42 1-9.71-.78v-.6c1 0 2.35-.4 2.82.08 1.35 1.39 2.89 1.08 4.45 1.13.8.02 1.62.11 2.44.17ZM140.62 28.67h3.73v.6h-3.73Z\" \/>\n                <path fill=\"#4778FF\" d=\"M147.55 48.94c-4.19 0-6.69-2.67-6.67-7.06a7.09 7.09 0 0 1 7.36-7.07c2.81 0 6.8 3 6.72 6.7-.09 4.47-3 7.44-7.41 7.43Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Madre de Dios<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Ayacucho -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-ayacucho\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 139.56 155.84\">\n                <path fill=\"#4778FF\" d=\"m345.38 449.4 6.81-27.4.21.08 2.35.89 2.12.8 2.28.59 2.22.09 2.79-.4 2.29-.66 1.33-.43-6.87 27.58-2 .6-2.47.64-2.46.1-2.43-.36-2.24-.51-2.06-.76Zm-29.3-10.18 7-27.8a45.86 45.86 0 0 1 4.91-1.05 14.2 14.2 0 0 1 3.51.32 21 21 0 0 1 2.6.72c.57.18 1.15.41 1.69.63s1.64.11 1.55.66c-.77 4.74-4.37 20.08-6.17 27.76l-3.45-1.53-3.55-.86-2.13-.26-2.78.33-1.15.3Zm-28.33 47h3.37c.14-5.44-.41-8.63-1.66-8.55-1.67.15-1.92 4.27-1.71 8.58Zm-4.13 0H287c.14-5.44-.41-8.63-1.66-8.55-1.68.15-1.93 4.27-1.72 8.58Zm5.8-12a1.56 1.56 0 1 0 1.55 1.55 1.56 1.56 0 0 0-1.55-1.48Zm-8.26 0a1.56 1.56 0 1 0 1.55 1.55 1.56 1.56 0 0 0-1.55-1.48Zm4.13 0a1.56 1.56 0 1 0 1.55 1.55 1.56 1.56 0 0 0-1.55-1.48Zm-5.8 12h3.37c.14-5.44-.41-8.63-1.66-8.55-1.67.15-1.92 4.27-1.71 8.58Zm12.39 0h3.37c.14-5.44-.41-8.63-1.66-8.55-1.66.15-1.92 4.27-1.71 8.58Zm-14.85-12a1.56 1.56 0 1 0 1.55 1.55 1.56 1.56 0 0 0-1.58-1.48Zm16.52 0a1.56 1.56 0 1 0 1.55 1.55 1.55 1.55 0 0 0-1.55-1.48Zm-7.24-11.65a3.61 3.61 0 1 0 3.61 3.61 3.62 3.62 0 0 0-3.61-3.54Zm-10.95 23.61h3.37c.14-5.44-.41-8.63-1.66-8.55-1.67.19-1.92 4.31-1.71 8.62Zm28.32-1.18 8.83.24 3.36 13.16-87.65-.14 1.63-4.75 7.24.39 1.62-9.51h10.09l4.34-20.41 3.37-.15 1.86-13.23 3.82-.22 3.12-33.8L268 416l5.33-72 3.4-1.38 2.89 58.7 1.92-.08 2.76 27.47-5.44.19-.27 11.48-7.18.26v8H266l-.13 2.64h7.9l-.12-7.88 7.66-.37.18-11.54 6.06-.1 2.58 26-19.59.12-2.94 27.08 3 .28 2.56-24.87 23.06-.22 5.06 23.36 17.66-74.68 2.81.81Z\" style=\"fill-rule:evenodd\" transform=\"translate(-228.22 -342.58)\" \/>\n                <path fill=\"#4778FF\" d=\"m103.26 98.08 2.54 1.42 2.53 1.68 2.39 1.66 2.42 1.55 3.49 2.21 6.81-27.33-1.72-1.01-3.49-2.1-3.6-2.48-3.86-2.48-1.01-.63-6.5 27.51z\" style=\"fill:none;stroke:#000;stroke-linecap:round;stroke-linejoin:round;stroke-width:.5px\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Ayacucho<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en San Martin -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-san-martin\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 152.54 145.92\">\n                <path fill=\"#4778FF\" d=\"M235.31 196.14c-.78.48-1.22 1-1.63.94s-.72-.59-1.08-.91c.39-.34.74-.88 1.15-.93s.81.44 1.56.9Zm-9 6.73c-.56-.73-1.21-1.24-1.13-1.53.16-.52.74-1.21 1.18-1.24a1.64 1.64 0 0 1 1.26 1.08c-.02.45-.71.93-1.35 1.69ZM205.84 177c.61 1.07 1.19 1.69 1.08 2.2a1.74 1.74 0 0 1-1.35 1 1.61 1.61 0 0 1-1.18-1.17c.02-.37.75-1.03 1.45-2.03Zm29.85-42.31 1.48-1.53a6.75 6.75 0 0 1 1.32 1.9c.09.33-.67.91-1.07 1.39Zm-3.33 54.69c.64 1 1.35 1.58 1.32 2.15a1.87 1.87 0 0 1-1.4 1.22c-.58-.07-1.47-.82-1.5-1.31s.79-1.1 1.58-2.05Zm-12.27 13.86-1.46-1.86c.61-.46 1.17-1.17 1.84-1.3.37-.08 1.39 1 1.31 1.26-.19.66-.88 1.08-1.69 1.91Zm-18.71-16.8 4.13.41c-.24 1.35-.83 2-2 2-1.42-.02-1.9-.93-2.13-2.4Zm24 .63-1.81-2.2c.67-.54 1.3-1.42 2-1.49.54 0 1.18.94 1.78 1.47Zm-1-73.86c1.62.1 3.54 1.85 3.32 2.9a1.6 1.6 0 0 1-1.24.9 3.09 3.09 0 0 1-2.71-3c.06-.35.48-.62.61-.79ZM207.07 160c-.46 1.65-2.63 3.43-4 3.3-.31 0-.81-.29-.85-.52a1.53 1.53 0 0 1 .31-1.17 5.15 5.15 0 0 1 4.54-1.61ZM228 199.07c-.86-1.15-1.86-2-1.71-2.38a2.92 2.92 0 0 1 1.94-1.62 2.28 2.28 0 0 1 1.71 1.55c-.07.67-1.02 1.31-1.94 2.45Zm-2.07-5.35-2.09-2.47c.69-.57 1.33-1.5 2.06-1.58a2.32 2.32 0 0 1 1.8 1.47c-.04.69-.95 1.4-1.82 2.58Zm8.81-68.51a4.51 4.51 0 0 1 1.26 4.39 1.67 1.67 0 0 1-1.08 1c-.25.07-.88-.43-1-.79a4 4 0 0 1 .77-4.6Zm-15 62-2.15-2.15c.75-.62 1.41-1.58 2.24-1.73.53-.1 1.79 1 1.79 1.56s-1.03 1.32-1.89 2.33Zm9.6-69.63 4.43 4.3a.85.85 0 0 1 0 .79 2.11 2.11 0 0 1-1.18.31c-2.12-.18-3.72-2.45-3.26-5.39Zm-4.74-8.88a13.81 13.81 0 0 1 6.14 4.63c-2.57 1.08-6.28-1.73-6.15-4.62Zm-7.45 72.51c-.6-.78-1.6-1.51-1.71-2.36v-.22a1.74 1.74 0 0 1 1.73-1.73 2 2 0 0 1 .43.05c.83.18 2 1.18 2 1.88s-1 1.58-1.61 2.37Zm15.8-18.09 5.8 6.77a4.32 4.32 0 0 1-4.55-1.71 6.55 6.55 0 0 1-1.26-5.05Zm-13.88 26c.62.75 1.68 1.46 1.76 2.28.15 1.38-1.07 2-2.36 2s-2.46-.53-2.36-2 1.18-1.98 2.95-2.32Zm-7.64-7.26c-1-1.34-1.95-2.08-2.06-2.94-.16-1.38 1-2.15 2.31-2.06s2.26.93 2 2.15c-.16.83-1.17 1.51-2.26 2.81Zm9.28-42.13 5 7.12c-3.17 1.22-6.13-3.85-5.01-7.16Zm10.15 18.05c-2.15-2.42-6.72-2.3-7-7.28 2.31 2.86 6.82 2.86 6.99 7.24Zm-10.17 41.35c-.42-.58-1.4-1.33-1.48-2.15-.12-1.36 1.07-2.06 2.36-2.08s2.44.55 2.37 2-1.31 1.94-3.26 2.19Zm1.54-76.79c2.69.86 4.59 4.86 3.47 7-2.22-.91-3.89-4.22-3.48-7.04Zm-6.7-17.67a10.77 10.77 0 0 1 6.4 3.81 1.21 1.21 0 0 1 .14 1 1.91 1.91 0 0 1-1.33.37 7.32 7.32 0 0 1-5.22-5.22Zm-22.38 11c-.16-.38-.76-1.27-.57-1.47a15.55 15.55 0 0 1 3.59-3.28c1.07-.6 1.71.29 1.49 1.5-.27 1.4-2.47 3.19-4.52 3.18Zm-12.36 68.69a34.51 34.51 0 0 1-3.67-2.15c-1.08-.81-.56-1.5.55-1.83 1.36-.41 4.3.6 5.05 1.8.2.33.34 1.08.19 1.15a11.86 11.86 0 0 1-2.13.96Zm39.49-79.78c-2.22.46-5.81-1.18-6.6-3.11a1.34 1.34 0 0 1 .47-1.2c2.04-.67 5.67 1.96 6.12 4.24Zm6.13 29a6.3 6.3 0 0 1 .76 6.06 1.28 1.28 0 0 1-2.36.1c-1.11-1.74-.22-5.17 1.59-6.22Zm-26.57-21.17a20.78 20.78 0 0 1 1.86-3.44c.76-.93 1.68-.64 2.15.52a5.49 5.49 0 0 1-1.67 5c-.32.21-1.08.35-1.16.21a16 16 0 0 1-1.19-2.35Zm-.76 9.19c1.84 0 4.53 3.11 4.13 4.54a1.89 1.89 0 0 1-1.47 1c-1.82 0-3.82-2.89-3.31-4.66.09-.48.5-.76.64-.94Zm11-10.38c-.35.12-.89.48-1.34.41-1.58-.27-3.93-2.9-4.15-4.5-.16-1.16.28-1.69 1.49-1.36 1.39.34 3.92 3.51 4 5.39ZM168 148.84c-.29-.24-1.3-.68-1.53-1.39-.38-1.15 2-3 3.72-2.91 1.07 0 2.23.15 2.27 1.62.06 1.29-1.9 2.63-4.46 2.68Zm17.3-41c-.19 2.22-2.5 4.38-4.17 4.3-1.14 0-1.75-.58-1.57-1.8.27-1.73 2.62-3.74 4.3-3.5.64.16 1.14.75 1.47.98Zm9.37 21.48c-.82.13-2.15.4-3.5.56a5.24 5.24 0 0 1-1.56-.33 4.22 4.22 0 0 1 7-2.52 6.29 6.29 0 0 1 1.22 1.68c-.64.26-1.27.54-1.91.76a5.4 5.4 0 0 1-1.22-.17Zm-7.63-5.13c0-3.44 2.63-6.17 5.28-6a5.37 5.37 0 0 1 1.49.56A10 10 0 0 1 193 120c-1.25 1.44-2.53 2.86-3.81 4.3-.38.42-.81.78-1.22 1.18Zm3.5 46.32c-1-.49-1.77-.63-1.95-1.07a2.13 2.13 0 0 1 .39-1.64 5.2 5.2 0 0 1 5.32-2.3c1.39.31 1.84 1.37.76 2.24a36 36 0 0 1-4.49 2.75Zm-8.16-65.36c-.12-.07-1.08-.24-1.18-.67a2.42 2.42 0 0 1 .51-1.94 5.66 5.66 0 0 1 5.65-2.09c1.2.25 1.43 1 .76 1.89a6.35 6.35 0 0 1-5.71 2.79Zm-4.94-11.54a7 7 0 0 1-2 1.21 44.74 44.74 0 0 1-6.11.76c-.6 0-1.24-.62-1.85-1 .43-.53.74-1.35 1.29-1.57a12 12 0 0 1 8.55-.21Zm9 49.85c1.9 2.23 3.86 4.41 5.66 6.71.72.93 0 1.74-1 1.43a9.07 9.07 0 0 1-3.62-1.93 6.4 6.4 0 0 1-1.79-5.79Zm-12.24 14.87 1.5.64a8.11 8.11 0 0 1-.91 1.93 6.46 6.46 0 0 1-5.05 2.44c-1.56 0-2.15-1-1.31-2.3 1.27-1.87 3.01-2.77 5.82-2.73Zm20.84-1.6 9.68 1.29c-2.46 3.08-4.25 3.71-6.86 2.54-2.16-1-3.01-2.22-2.77-3.85Zm-1.89-52.52c.93.62 2.83 1.22 3 2.07.22 1.65-1.65 2.15-3 2.37a9.35 9.35 0 0 1-3.64-.43 2.07 2.07 0 0 1-1.3-1.37 2.16 2.16 0 0 1 1.15-1.48 30.74 30.74 0 0 1 3.84-1.18Zm25 17c-2.94-.11-6.08-3.51-6-5.88 0-1.31.76-1.72 1.85-1.16a8.43 8.43 0 0 1 4.66 5.72c.2.47-.3 1.03-.44 1.35Zm-18.36-16.87a6.75 6.75 0 0 1-5.19-3c-.82-1.24-.36-2.15 1.08-2.36a6.88 6.88 0 0 1 5.93 3.22c.79 1.4.26 2.17-1.75 2.17ZM180 168.58l-3-1.85c.64-.91 1.07-2.23 2-2.63a11.54 11.54 0 0 1 4.47-.77c.52 0 1.31.76 1.51 1.34a1.92 1.92 0 0 1-.69 1.69c-1.29.82-2.73 1.41-4.29 2.22Zm-25-16.13c.56 2.91-2.07 8.31-4.66 9.8-2.27-3.25 0-8.07 4.66-9.8ZM183.73 177a11 11 0 0 1-2.76-.66 3.21 3.21 0 0 1-1.64-1.74c-.07-.48.81-1.39 1.45-1.68a6 6 0 0 1 6.22.45c1.29.9 1.27 1.83-.12 2.56a20.5 20.5 0 0 1-3.15 1.07Zm0-50a38.85 38.85 0 0 1-1.84 4.37 2.27 2.27 0 0 1-1.86.79c-.46-.06-1-.82-1.2-1.38a6 6 0 0 1 1-5.64 3.11 3.11 0 0 1 2.15-1.29c.43 0 .93 1.2 1.31 1.91a3 3 0 0 1 .11 1.08Zm31.85-.66c.46-1.07.57-1.86 1-2a2.19 2.19 0 0 1 1.64.46 8.27 8.27 0 0 1 3.44 5.38 6.52 6.52 0 0 1-.64 2.53c-.88-.26-2.15-.26-2.57-.86a49.82 49.82 0 0 1-2.88-5.48Zm-37.86-4.8h-.18a1.46 1.46 0 0 1-1.45-1.45 1.24 1.24 0 0 1 0-.27c.06-2.29 3.46-5.54 5.75-5.28a2.15 2.15 0 0 1 1.4 1.47c.03 2.2-3.3 5.48-5.53 5.56Zm-32.64 36.09c2.34 2 3.59 7.81 2.15 10.28a1.77 1.77 0 0 1-1.55.23 14.63 14.63 0 0 1-2-3.9 7.85 7.85 0 0 1 1.39-6.58Zm39-63.87a39.82 39.82 0 0 1 4 1.38c1.18.55 1.08 1.4.18 2.22-1.78 1.65-5.86 1.94-7.92.6-1.22-.81-1.28-1.74-.09-2.47a29.57 29.57 0 0 1 3.84-1.7Zm-18.74 33.88c-1.34.11-1.84-.58-1.52-1.94.54-2.33 4.08-5 6.45-5 1.08 0 1.64.43 1.44 1.61a7.3 7.3 0 0 1-6.36 5.36Zm-.25 23.7c1.88.27 3.79.22 4 2.15s-1.52 2.58-3 3a5.79 5.79 0 0 1-3.09.07c-.95-.31-2.3-1.15-2.38-1.89s1-1.88 1.81-2.46a8.36 8.36 0 0 1 2.67-.84Zm-32.45-16.51c.46 3.77.13 7.41-2.15 10.64-.33.46-1.07 1-1.46.92a1.75 1.75 0 0 1-1-1.37 17.76 17.76 0 0 1 .69-5.43 29.38 29.38 0 0 1 3.23-5.09Zm25.53 3c-1.71 0-2.47-.9-1.79-2.35a7.62 7.62 0 0 1 5.71-4.68c1.84-.34 2.57.52 2.1 2.37a7.1 7.1 0 0 1-6.01 4.73Zm2.15 22.69c2.65 0 3.38 1 2.63 3a6.57 6.57 0 0 1-5.81 3.78c-2-.11-2.8-1.45-1.89-3.22a6.28 6.28 0 0 1 5.08-3.49Zm7.89 14.7a30.07 30.07 0 0 1-4.09-2.15c-1.07-.8-.93-1.94.16-2.82 2.21-1.79 6.61-1.07 8.2 1.29.65 1 .5 1.85-.5 2.33a36 36 0 0 1-3.76 1.42Zm8.69-25.37c.53-1.53.14-3.28 2-3.72s2.66 1.07 3.16 2.32a13 13 0 0 1 .83 4.66c0 .8-.83 2.15-1.44 2.23a3.23 3.23 0 0 1-2.6-1.19 24.41 24.41 0 0 1-1.94-4.23Zm-.35-15.6c-.31 3-2.23 5.85-4.68 6.75-2 .74-2.85.11-2.6-2a8.15 8.15 0 0 1 3.65-6.22 3.41 3.41 0 0 1 2.5-.58c.58.22.77 1.39 1.14 2.12ZM168 188a8.14 8.14 0 0 1-5.51-2.23c-.94-.87-.82-1.71.14-2.51 2.48-2.07 7.69-1.57 9.75.92.94 1.08.78 2.15-.5 2.72A27.26 27.26 0 0 1 168 188Zm-4.2-47.9c.13 4-4.46 9.07-7.71 9.26-1.07 0-1.49-.36-1.41-1.44.25-3.3 4.3-8 7.53-8.6.54-.06 1.22.6 1.59.78Zm-10.05 32.07c2.85.39 5.24 2 5.22 3.88s-2.15 3.34-4.78 3.32a8.75 8.75 0 0 1-4.06-1.07c-1.93-1.08-2.06-2.89-.3-4.3a18.91 18.91 0 0 1 3.92-1.83Zm-27.95-21c2.73 3.22 3 10.62.64 13.9-.72 1-1.37 1.16-2.15.09-2.54-3.16-1.75-11.03 1.51-13.95Zm-.86-22.47a172.24 172.24 0 0 0-16.66 36.3c1.48-14 7.81-25.68 16.66-36.26Zm-3.88 43.68 1.08-3.23a17 17 0 0 1 2.54 2 14.7 14.7 0 0 1 3.66 12c-.28 2-1.07 2.23-2.53.87-3.46-3.02-4.28-7.17-4.75-11.6Zm84.32 23 1.3-1.8a26.43 26.43 0 0 0-3.33 0c-1.49.19-3 .66-4.46.83-2 .23-4 .28-6.13.41v-3.51c2.67-.22 5.31-.39 8-.65a15.35 15.35 0 0 0 3.22-.59c2-.67 3.23-.1 4.67 2.71.31-.61.5-1.07.77-1.53a2.39 2.39 0 0 1 3.23-1.07c1.37.57 1.49 1.32.43 2.35a13 13 0 0 1-7.7 2.87Zm-83.94-9.49c5.18 2 11.21 12.47 9.91 17.26-4.87-.15-11.68-12.06-9.91-17.24Zm74.06-1.32c1.32.38 2.88.46 3.9 1.24s1.4 2.23 2.35 3.88h-8.39c-1.31-3.15-2.62-6.33-3.89-9.39 1 .27 2.3.59 3.6 1a3.58 3.58 0 0 0 4.54-1.65c1.69-2.83 3.22-5.75 4.78-8.68 1.73-3.36 3.51-6.65 6.65-8.95a1.53 1.53 0 0 1 .8-.29c-4.48 7-6.64 14.85-8.82 22.81 1.61-.95 2.87-.81 3.86.6 2.2-2.3 2.52-2.3 6.32.18.18-.39.3-1.07.72-1.37a3 3 0 0 1 2.15-.43c.68.26 1.07 1.16 1.63 1.77-.65.42-1.34 1.24-1.95 1.2-4.12-.3-8.22-.73-12.31-1.25-2-.24-3.88-.76-5.83-1.15Zm-16.74-82.84c-3.22 3.1-4.59 7.12-6.45 11-2.67 5.58-7.8 8.92-12.66 12.39l-.37-.33c.43-.44.84-.89 1.29-1.32 1-1 2-1.86 3-2.84 2.88-2.88 3.34-5.22 1.27-8.76a48.08 48.08 0 0 0-4.3-5.65c-.75-.94-1.6-1.81-2.41-2.72l.3-.35 3.29 2.22c-2.54-3.91-6.52-6.12-10.09-9 .57.21 1.15.39 1.71.61 3.73 1.44 7.46 2.9 11.19 4.3 4.64 1.72 9.32 2.43 14.23.47Zm24.63 38.65c.7-1.07 1.49-1.85 1.36-2.31a2.67 2.67 0 0 0-1.68-1.42c-.3-.07-1.31.94-1.26 1.34.1.68.81 1.28 1.58 2.45Zm8.93 6.17-2.54-3.85c-1 2.36-.32 3.31 2.51 3.85Zm-6.06-5.9c-3.69 3-5.13 2.76-8-.9-.31-.4-1.22-.34-1.84-.49-.14.63-.55 1.38-.35 1.86 1 2.41 4.3 4.45 6.85 4a8.69 8.69 0 0 0 3.74-2.15c.78-.65.64-1.68-.4-2.3Zm2.28-24.31c1.28 2.5 2.52 4.8 3.66 7.14a8.44 8.44 0 0 1 .56 6.2 13.33 13.33 0 0 0 1 9.51 93.73 93.73 0 0 0 4.31 8.33c2.71 4.76 5.59 9.44 8.41 14.19l1.37-3.29c1.52 1.45 2.35 2.67 1.68 4.63a3.46 3.46 0 0 0 .51 2.53c1 1.62 1.08 1.76-.17 3.69-1.4-1.35-2.75-2.68-4.14-4-5.16-4.86-6.45-4.89-11.83-.33a5.08 5.08 0 0 1-1.9 1.15c.35-.7.73-1.38 1.08-2.09a9.65 9.65 0 0 0 .19-7.67c-.73-1.86-1.74-3.61-2.58-5.38a6 6 0 0 0-6.12-3.92 14 14 0 0 1-9.67-4.3c-1.27-1.22-2.46-2.51-3.75-3.69-1-.91-1.08-.86-2.6.06a27.4 27.4 0 0 0 11.45 9.63l-.14.5a30.11 30.11 0 0 1-3.54-.36c-3.84-.88-6.64-3.39-9.23-6.16-2-2.15-2.44-2.25-5.2-1.07l-4.6 1.9-.46-.62c2.43-2.29 4.71-4.77 7.31-6.83a10.06 10.06 0 0 1 7.9-2.15 19.92 19.92 0 0 0 5.23-.28 32 32 0 0 1 13 .59 13.57 13.57 0 0 0-.74-1.54c-.69-1.07-1.45-2-2.15-3.1-2.78-4.73-2.45-8.85 1.16-13.25Zm33.33 86c-1.49 1.5-3.13 2.5-3.74 3.94s-.13 3.33-.13 5.47c-5.15-3.45-10.15-2.93-15.05-1.07l.74-4.43-4.17-.32c.45 2 .87 3.4 1.07 4.87s.76 1.37 1.93 1.15a41 41 0 0 1 8.6-1.27c2.32 0 4.63 1.15 7.17 1.85 1.36-2.99 4.59-5.47 3.58-10.19Zm4.16-56.9-.56.1c.07 2-1.75 4.24 1.69 6Zm9.86 41.24a6.8 6.8 0 0 1-.07 2.25c-.14.38-1 .49-1.49.73l-.39-.47 1.14-2.58Zm-10 15.62c7.22-2.46 13.64-15.62 10.37-21.86-.77 1.48-1.53 2.75-2.1 4.1a9.14 9.14 0 0 1-4.61 5.21c-4 1.7-5.82 7.62-3.71 12.56Zm-2-70.22c.08-.11 0 0-.15.17-1.85 1.65-1.66 2.94.57 3.8.76.29 1.51.59 2.28.87 1 .35 1.57.05 1.26-1-1.3-4.64-4-8.49-7-12.18.91 2.66 1.89 5.34 3 8.34Zm-.53 7.35s-.28.2-.39.3a1.83 1.83 0 0 0-.27.3.45.45 0 0 0 0 .28 1.08 1.08 0 0 0 .18.33c.08.13.21.29.31.43s.3.39.36.49 0 .14.05.11.17-.26.24-.37a2 2 0 0 1 .22-.27 2.35 2.35 0 0 0 .26-.29.9.9 0 0 0 .1-.38.5.5 0 0 0-.1-.24 1.64 1.64 0 0 0-.2-.26 2.15 2.15 0 0 0-.24-.18l-.32-.16Zm-1.34 3.22v.37a.5.5 0 0 0 .07.27 1.91 1.91 0 0 0 .49.34 3.88 3.88 0 0 0 .85.24 4.17 4.17 0 0 0 .85 0 2 2 0 0 0 .49-.15 1.41 1.41 0 0 0 .52-.36 8.87 8.87 0 0 0 .58-.84 1.24 1.24 0 0 0 .13-.5c0-.1-.12-.19-.18-.26a.9.9 0 0 0-.19-.16.32.32 0 0 0-.17 0s0 0 0 .06l-.07.1a.49.49 0 0 0 0 .11l-.1.2a1.43 1.43 0 0 1-.08.22.8.8 0 0 1-.18.19 1.52 1.52 0 0 1-.22.22 2.17 2.17 0 0 1-.33.19.75.75 0 0 1-.29.09 2.4 2.4 0 0 1-.57-.09 3.36 3.36 0 0 1-.46-.19l-.26-.1-.19-.1a.2.2 0 0 0-.11 0h-.18l-.17.07c-.02.06-.11.05-.14.08Zm-81.22 81.82c-10.73-2.69-23.49-6.58-28.67-11-10.8-9.14-22.32-23.53-20.68-40.29 1.46-14.75 7.27-27.83 15-40.18 1.34-2.15 2.69-4.23 4.12-6.28 2-2.83 2-4.76.08-7.53a11.84 11.84 0 0 0-.95-1.17c-4.57-4.93-5-10.56-2.7-16.59a26.15 26.15 0 0 1 6.32-9.43c4.3-4.19 9.36-5 14.9-2.87 2 .76 3.82 1.88 5.81 2.61a4.88 4.88 0 0 0 3.22.23c14.85-6 29.81-5.38 44.87-.95a81.33 81.33 0 0 1 19 8.26 5.09 5.09 0 0 0 5.24.3 29.56 29.56 0 0 1 23-.91c.51.18 1 .42 1.39.58-3.38 5.53-6.68 11-10.09 16.42-.67 1.08-.32 1.63.22 2.48 2.94 4.56 5.91 9.11 8.68 13.77a7.71 7.71 0 0 1-.35 8.84 4.35 4.35 0 0 0-.39 3.92 24.92 24.92 0 0 1 1 6.19 7 7 0 0 0 1.4 4.52 58.68 58.68 0 0 1 8.19 14.27c1.23 3.14 2 6.3.73 9.68a7 7 0 0 0-.18 3c.69 8.38-2.63 15-9 20.19a35.49 35.49 0 0 1-4.52 3c-2.47 1.48-3.45 4-4.76 6.37-.13.24.06.72.2 1.07 2.77 6.34.83 12-5.14 15.22a60.57 60.57 0 0 0-5.53 3.43 7.07 7.07 0 0 1-7.13.55 10.43 10.43 0 0 0-8-.18c-1.57.54-3.17 1-4.92 1.56-.17-1.14-.27-1.82-.38-2.49a7.76 7.76 0 0 0-5-6.54 17.46 17.46 0 0 1-7.73-5.73 8.17 8.17 0 0 0-2.06-1.59c-3.6-2.37-7.25-4.63-10.75-7.1a1.66 1.66 0 0 0-2.29.16c-4.21 3.17-5.67 7.61-4.3 13 .2.76.41 1.51.57 2.09l-22.62-20.49a5.55 5.55 0 0 0 .48.94c4.55 6.58 8.79 9.69 14.47 15.26 3.76 3.68 8.26 3.88 6.69 5.06-1.35 1-24.7-3.56-30.72-8.56-8.07-6.69-14.55-17.2-16.44-27.32 6.45 12.2 16.32 20.86 28.29 27.41-1.27-1.34-2.52-2.69-3.82-4a113 113 0 0 1-17.2-21.29c-9.67-16.18-11-33.06-4.12-50.53 1.53-3.91 4-7.7.11-11.4.28-.4.32-.57.41-.6 5.38-1.34 5.17-4.37 4.49-9.26a16.81 16.81 0 0 0-4.16-8.47 13.29 13.29 0 0 1-2.5-4.3c-.71-2.22.28-4.12 1.94-5.71s3.48-3.35 5.09-5.09c1.17-1.3 2.48-2 4.15-1.41 5.54 1.89 10.21 5 13.31 10.09a12 12 0 0 1 .61 1.54l-6.68-2.56-.14.32 4.44 4.07-.33.42-4.7-.59-.12.34 4.14 2.4-7 1.34v.23l8.36 1.59.09.8c-5.09.86-9.07 3.11-10.75 8.29 3-3 6.29-5.38 11-5l-2.86 3.62 6.11-2c0 .63.06.82 0 .85a18.6 18.6 0 0 0-6.45 7.53c-.9 1.79-3.22 2.88-5.05 4.2-.52.4-1.23.54-1.8 1.21h4.77l.29.36a39 39 0 0 1-3.95 2.95 43.38 43.38 0 0 1-4.75 2.06c2.58 1.47 5 1 7.71.58-.86.58-1.7 1.21-2.59 1.72s-2.15 1-3.15 1.68a22.29 22.29 0 0 0-2.41 2.25l-5.28-6.29-3.22 10.29 4.49-1.66c-2.31 3.78-4.41 7.06-5 11.26l2.86-1.47c-1.7 3.51-3.23 6.95-3 11.4l2.65-3.38.86.42c-1.74 5.58-.58 10.95.79 16.51l3.41-5.82.5.17c-1 4.13-1.41 8.26-.14 12.35 1.62-1.67 3.13-3.29 4.71-4.83.26-.26.8-.22 1.16-.3-1.16 3-2.29 5.92-3.43 8.85l.65.35c1.74-3.5 3.86-6.54 8.48-7.53-4.72 5.24-5.27 10.75-2.73 16.64-.25-2.81-.39-5.63 1-8.25s4.3-4.56 6.8-4.3c-1.07 1.76-2.22 3.53-3.32 5.37-.11.19 0 .49 0 1 2.39-3 5.07-5.05 9.43-5.15-3.57 2.58-5.84 5.49-6.29 10.14 3.34-4.67 7.35-7.21 13.16-6.83l-5.68 3.4c6.11-1.8 11.78-1.66 17 2.55l-8.72 3.62.16.39c2.54-.77 5.09-1.51 7.6-2.31a2.25 2.25 0 0 1 2.91 1c2.84 4.63 7.36 7.25 11.83 9.82a20 20 0 0 1 6.45 5 8.62 8.62 0 0 0 3.47 2.46c3.93 1.67 7.16 3.87 7.84 8.6l.66.37 2.15-3.34.56.46.43 2.3 4.6-3.58-.21 3.09c3.14-.24 4.66-2.51 6.27-5.07.95 2.56 0 4.41-1.3 6.45 3.79-.55 5.23-3 6.31-6.45.55 1.07.9 1.67 1.34 2.47 3.34-1.61 5.74-3.86 6.26-7.63.36-2.53-.53-3.23-3-3a29.68 29.68 0 0 1-4.41-.54 10.44 10.44 0 0 0-3.78 0 23.61 23.61 0 0 1-12.59.42 20.72 20.72 0 0 0-5.38-.56c-6.19.32-11.62-1.25-15.48-6.3a31.09 31.09 0 0 1-3.22-6.45c-.58-1.33.07-2.1 1.48-2.31a25.18 25.18 0 0 0 5.28-1.24l-6.64.42c-.56-2.15-.35-2.67 1.69-2.94 2.67-.36 5.38-.61 8-.78 2-.14 2.08 0 2.22 2 2.47-.34 4.71-3.43 7.52-.93a12 12 0 0 1 3.34-1.08 2.61 2.61 0 0 1 2 1.5 2.92 2.92 0 0 1-1.08 2.26c-.71.61-1.62.85-1.45 2.1 0 .25-.66.87-1 .84a2.59 2.59 0 0 1-1.52-.81c-.27-.3-.21-.91-.27-1.31h-3v-.27l1.53-.55c-1.63.36-3.43-1.39-4.94.4-.22.28-.83.22-1.23.38l-9.91 4.08.22.52 10.75-4.06 4.88 3-6.11 5.38.33.4c1.07-.88 2.15-1.72 3.11-2.65a8.62 8.62 0 0 1 8.45-2.15 26.88 26.88 0 0 0 22.73-4.9 14.21 14.21 0 0 0 2.15-1.87c3.7-3.95 4-7.12.56-11.3a18.36 18.36 0 0 0-5.6-4.85c-4.3-2.15-5.69-5.66-5.75-10.41 1.07 1 1.9 1.86 2.83 2.62 3.22 2.71 5.7 2.82 9.11.33a2.61 2.61 0 0 1 2.95-.23 45.38 45.38 0 0 0 4.55 1.74 8.84 8.84 0 0 0 6.56-.58c1.27-.57 1.76-1.37 1.08-2.65-2.53-4.72-4.91-9.53-7.69-14.12a72.11 72.11 0 0 0-6.21-8.23c-3.06-3.73-2.9-8.09-2.7-12.49a4.32 4.32 0 0 1 .16-.93c.59-2.33 1.3-4.63-1.56-6.17-.54-.28-.85-1.25-1-2a14.77 14.77 0 0 0-4.93-9.06l.28-.36 5 1.62a54.91 54.91 0 0 0-14.79-15.17c5.23-2 10-3.39 15.2-2.94h.07a1.86 1.86 0 0 1 1.88 1.86 1.92 1.92 0 0 1-.2.84c-1 2.54-2.15 5-3.29 7.52a6.32 6.32 0 0 0-.22 1.56c.51-.2 1.19-.26 1.49-.61a20.56 20.56 0 0 0 2.15-3.09c1.69-3.11 3.32-6.24 5.09-9.58a20.91 20.91 0 0 0-9.46-.78 53.89 53.89 0 0 0-9.33 2.63 7.35 7.35 0 0 1-6.93-.39 88.34 88.34 0 0 0-27.57-10.46 1.34 1.34 0 0 0-1 .14 3.9 3.9 0 0 0 .81.53c3.73 1.15 7.11 3.23 11.12 3.75 2.5.31 4.24 2 5.56 4.3a21.24 21.24 0 0 0 4.07 4.84c6.35 5.9 12.37 12 16.55 19.77a51.14 51.14 0 0 1 5.57 18.37c-.78-1.58-1.59-3.16-2.35-4.75-3.12-6.45-5.75-13.19-10.38-18.84-10.34-12.39-22.26-22.4-38.07-26.9a38.64 38.64 0 0 0-24 1 3.56 3.56 0 0 0-1.36.87c3.16 1 5.78 3.66 9.61 2.44a8.11 8.11 0 0 1 6.18.6 6.4 6.4 0 0 1-7.73 2.37c-6.13-2.32-12.16-4.88-18.28-7.32a23.45 23.45 0 0 0-4.74-1.68A9.58 9.58 0 0 0 135.6 94a21.12 21.12 0 0 0-6.77 13.23 10.26 10.26 0 0 0 2.71 8.11c4.3 5 4.59 8.45 1.07 14-7.07 11.21-12.27 23.17-14.37 36.36-3.34 20.8 4.29 39.3 22.12 50.3 5.31 3.3 12.97 6.25 20.44 8.47Zm0 0c11.66 2.92 20.93 4.42 15.47 3.58a120 120 0 0 1-15.47-3.58Zm25.5-68.58c1.86 1.46 3.71 2.9 5.51 4.4a1.49 1.49 0 0 1 .49 1.27c-.13.32-.76.57-1.21.63a3.65 3.65 0 0 1-.74.08 3.68 3.68 0 0 1-3.61-3 24.19 24.19 0 0 1-.44-3.38Zm0 0-.28-.22.25-.69c0 .3.02.61.03.91Z\" style=\"fill-rule:evenodd\" transform=\"translate(-108.28 -87.56)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>San Martin<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Amazonas -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-amazonas\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 189.33 251.75\">\n                <path fill=\"#4778FF\" d=\"M163.02 251.05h-4.35c-.1-22.89.59-45.66 5-68.6-6.29 6.77-14.12 10.74-20.77 16.25a53.34 53.34 0 0 0-11.56 12.71c-.81 1.29-.81 3.12-1.06 4.73q-2.81 17.42-5.57 34.84c0 .21-.09.41-.17.77l-2.06-.43 5.79-36.6c-12.3 6.25-24.58 12.71-37.07 18.72a69.08 69.08 0 0 1-22.4 6.64c-3.52.38-7.09.43-10.85.64q-.88 4.92-1.87 10.41l-4.24-.7c.56-3.37 1.1-6.63 1.65-9.92h-5c-7.2-.21-14.13-1.58-20.49-5.14-5.39-3-10.78-6-16.14-9.13-4.28-2.46-6.91-6.3-8.63-10.82-3.36-8.85-4.46-17.94-1.39-27 1.52-4.49 4.14-8.67 6.65-12.75 8.12-13.2 16.09-26.49 22.23-40.74 3.32-7.72 6.12-15.67 9-23.59a23.49 23.49 0 0 0 .95-11 13.55 13.55 0 0 0-4.36-8.44c-3.56-3.22-3.33-6.76-.66-9.95 1.62-1.92 3.3-3.8 5-5.73-1.11-1.49-2.29-2.92-3.29-4.47-.77-1.19-1.25-2.55-1.94-3.79-.44-.81-1-1.55-1.53-2.34a3.69 3.69 0 0 1-.75-1.42c-.24-2.52-.31-5 1.2-7.29q7.77-11.69 15.51-23.41c3.09-4.65 6.19-9.29 9.2-14a15.81 15.81 0 0 0 2.1-4.41c1.31-4.93 4.56-7.73 9.21-9.4a90.62 90.62 0 0 1 20.1-4.55 179.22 179.22 0 0 1 33.48-.65c9.57.65 19.07 1.87 28.19 5 4.09 1.4 8.21 3 10.84 6.73a22.35 22.35 0 0 1 2.44 4.61q8.82 23.13 17.52 46.31a19 19 0 0 1 .5 12.68 4.55 4.55 0 0 0 1.41 4.5c3.09 3.37 2.91 7.09 1.63 11.05a3.24 3.24 0 0 0 0 2.15c4 8.51 3.21 17.39 2 26.27-1.73 13-5.63 25.37-10.11 37.6a57.8 57.8 0 0 1-8.06 14.05c-.92 1.24-1.06 3.14-1.29 4.78-1.5 10.29-3.05 20.57-4.31 30.88-.65 5.38-.87 10.82-1 16.24-.26 8.65-.31 17.31-.45 26-.16.49-.2 1.02-.23 1.71Zm-74.35-88.49c.3-2.17.68-4.06.81-6q.76-10.74 1.37-21.47c.28-4.92.43-9.85.71-14.77.11-1.87 1.06-2.74 2.5-2.59s2 1.24 1.87 3.1c-.21 2.83-.41 5.68-.5 8.52-.33 10.89-.44 21.8-2.28 32.59a5.44 5.44 0 0 1-2.52 4.19c-3.73 2.29-7.24 4.93-11 7.23-2.59 1.61-5.36 2.92-8.08 4.3-1.8.91-3.4.36-5.05-.69a142.84 142.84 0 0 1-18.19-13.76 6.65 6.65 0 0 1-2.5-6c.86-12.62 1.52-25.26 2.4-37.88a66.61 66.61 0 0 0-2.36-21.92c-.81-3-2.15-5.9-3.29-8.93-.05.05 0-.06.09-.11a118.32 118.32 0 0 1 47.08-14.2 152.73 152.73 0 0 1 34.91 1 222.08 222.08 0 0 1 40.12 9.65c5.64 1.9 11.21 4 16.81 6 1.79-2.77 1.67-5.16-.19-7.65-.8-1.09-1.32-2.38-2.06-3.52a3.42 3.42 0 0 0-1.38-1.39c-21.33-7.91-43.18-13.5-66-14.77a145.74 145.74 0 0 0-43.27 3.77 121.15 121.15 0 0 0-24.12 8.67c.69 1.52 0 2.59-1 3.65q-2.37 2.5-4.55 5.19c-1.5 1.85-1.2 2 .2 3.87a32.07 32.07 0 0 1 4.92 7.83 23.15 23.15 0 0 1-.17 15.81c-2.93 8.52-6 17-9.59 25.28-6 13.83-13.73 26.74-21.59 39.58-2.59 4.22-5.38 8.52-6.9 13.17-2.52 7.71-1.52 15.57 1.31 23.16 1.43 3.84 3.58 7.13 7.25 9.23 4.6 2.63 9.17 5.35 13.82 7.89a48.06 48.06 0 0 0 7.3 3.34c8.08 2.77 16.32 2.64 24.63 1a61.14 61.14 0 0 0 32.48-17c3.64-3.64 7.56-7 11.33-10.5a5.54 5.54 0 0 0 1-1.45c1.88-3.39 3.65-6.85 5.62-10.19a34.89 34.89 0 0 1 11.48-11.32 132.1 132.1 0 0 0 12.06-8.5c4.75-3.92 7.7-9.35 11-14.48 6.23-9.82 11.17-20.31 15.84-30.93 2.2-5 4.43-10 6.33-15.1 1.24-3.36 1.11-6.77-1.54-9.68-1.07-1.17-3.34-2.4-4.21-1.9a11.4 11.4 0 0 1-6.17 1.21c-2 0-4.59 2.67-4.24 4.59a15.51 15.51 0 0 1-2 10.52 2.58 2.58 0 0 1-.22.44 8.88 8.88 0 0 1-1.76 2c-9.58 5.9-19.77 5.93-30.21 3a21 21 0 0 1-8.66-5.14 55.17 55.17 0 0 1-5.14-5.89 101.71 101.71 0 0 1-10.29-16.56 54.73 54.73 0 0 0-6.1-8.89c-2.67-3.28-6.16-5.66-9.92-7.91a9.08 9.08 0 0 0 0 1.5c1.77 8.5.88 17-.9 25.27-2.7 12.67-5.65 25.29-7.24 38.17-.46 3.68-1 7.34-1.46 11.16a63.33 63.33 0 0 1 21.41 5.21ZM36.9 61.79c49.09-17.36 96.49-14.69 142.84 8.48a22.63 22.63 0 0 0-1-5.56c-5.79-15.51-11.67-31-17.5-46.48a11 11 0 0 0-5.67-6.51 50.32 50.32 0 0 0-5-2.08c-9.09-3.11-18.54-4.23-28.05-4.86a171.81 171.81 0 0 0-31 .63 87.73 87.73 0 0 0-19.64 4.31c-3.41 1.22-5.83 3.19-6.77 6.89a18.5 18.5 0 0 1-2.34 5c-2.34 3.76-4.83 7.44-7.28 11.13q-8.62 13-17.25 26a22.1 22.1 0 0 0-1.34 3.05Zm146.23 36a10.56 10.56 0 0 1-1.64 2.23c-4.57 3.67-6.11 9.3-9.15 13.95a3.57 3.57 0 0 0-.3.94c-.4 1.25-.68 2.54-1.2 3.74-2.64 6.06-5.42 12.05-8 18.14a207 207 0 0 1-18.36 33.65 43.15 43.15 0 0 1-13 13.08c-2.92 1.83-5.74 3.82-8.64 5.69-4.78 3.07-8.05 7.4-10.69 12.52a3.06 3.06 0 0 0 .61-.15c13.46-8.31 27.5-15.58 41.57-22.79a36.38 36.38 0 0 0 10.41-7.9 54.49 54.49 0 0 0 11.38-20.48c3.85-11.93 7.54-23.9 8.49-36.48.44-5.49 1.11-11.07-1.48-16.15ZM62.76 156.91c.25-1.86.48-3.75.77-5.64 1.17-7.84 2.17-15.71 3.59-23.5 1.5-8.27 3.67-16.42 5-24.71.81-5 .74-10.12.85-15.19a40.1 40.1 0 0 0-.82-6.14c-.46.34-.69.48-.88.66a70.91 70.91 0 0 0-16.74 23.69 15.92 15.92 0 0 0-1.47 5c-1 13.1-1.8 26.2-2.61 39.31-.16 2.64 0 5.29 0 7.79Zm65.55-59.43v.1c-2.47 0-4.94.06-7.4 0a7.11 7.11 0 0 0-6.23 3.34 15.3 15.3 0 0 0-2.72 12.31c.81 4 .41 4.56 5.5 5.69a46.8 46.8 0 0 0 22.74-.32 8.66 8.66 0 0 0 6.57-6.19c1.37-4.61-.19-8.62-3.07-12.18a4.94 4.94 0 0 0-2.76-1.95c-4.2-.45-8.42-.56-12.63-.8Z\" \/>\n                <path fill=\"#4778FF\" d=\"M58.34 192.43c4 .25 8 .47 11.95.74a9.3 9.3 0 0 1 2.38.55c2.8 1 3.72 2.83 2.88 5.65a2.22 2.22 0 0 1-2.65 1.65 163.1 163.1 0 0 0-31.94.32c-.6 0-1.21.07-1.81.07-2.32 0-3.15-.58-3.44-2.41-.37-2.3.45-4 2.48-4.51a58.46 58.46 0 0 1 18-2h2.14ZM130.12 113.27c-2.89-.14-5.8-.22-8.69-.44-2.62-.21-3.73-2-2.7-4.5 1.14-2.74 2.83-5 6.21-4.89 4.42.09 8.85.09 13.25.42a4 4 0 0 1 2.54 2.19c1.07 2.2.44 4.39-1 6.3a2 2 0 0 1-1.44.53h-8.2Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Amazonas<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Cajamarca -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-cajamarca\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"60px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:2\" viewBox=\"0 0 102 79\">\n                <path fill=\"#4778FF\" d=\"m0 11.798-.68-.447-7.927 11.708.748.491L0 11.798m121.135 4.45-.753-1.41c-2.891-.57-4.292 1.306-5.654 3.247l.726 1.279 5.681-3.116M137.089.107c-1.161 1.365-5.182 1.203-5.95 5.36 4.668.33 3.67-5.421 5.95-5.36m-24.237-46.714 1.06.681 6.325-10.046-.816-.521-6.569 9.886m-7.175 108.319c-1.269-4.829-4.234-6.966-7.678-6.205l7.678 6.205m45.805-73.364c5.776 2.679 4.504 2.87 5.611 8.563 3.11-1.183 3.692-3.297 1.954-7.09-1.524-3.323-3.476-3.703-7.565-1.473m-78.253.306.924-.307-.938-8.679c-2.013 1.718-3.415 3.162-5.049 4.26-3.479 2.339-2.758 5.119-1.146 8.508.238-1.501.328-2.621.609-3.69.309-1.172.794-2.298 1.365-3.901l1.465 2.258.956-1.548 1.814 3.099m217.22-97.35 3.203.898c-1.808-3.948-3.361-4.79-6.663-3.896-3.227.873-4.554 3.17-4.022 7.099 3.003-.352 6.598.584 7.482-4.101M48.332 22.054c-.091 5.65 19.31 20.45 29.757 22.969-12.264-4.582-21.122-13.63-29.757-22.969m16.96 13.777c-.157.344-.315.689-.474 1.033 8.863 4.424 17.717 8.862 26.608 13.228.444.218 1.199-.194 1.81-.314-.159-.719-.081-1.711-.527-2.099-.835-.724-1.94-1.182-2.992-1.603-6.55-2.621-13.13-5.168-19.669-7.816-1.643-.666-3.173-1.612-4.756-2.429m97.774-59.484c4.357-1.498 6.787-4.341 8.179-8.451.183-.54.747-1.036 1.256-1.368 2.638-1.722 5.314-3.384 7.978-5.067-1.054-.859-2.284-1.316-3.133-.933-7.082 3.195-10.51 9.673-14.28 15.819m-.891 3.514c4.191.622 6.387 2.495 6.626 6.845 2.47-1.981 4.443-3.654 6.511-5.2 2.811-2.1 4.412-4.081 1.57-7.618-1.905-2.372-3.56-3.299-6.075-1.355-2.782 2.15-5.374 4.543-8.632 7.328m-3.108 18.766-.735-.919c-4.218 3.56-8.499 7.05-12.586 10.754-.642.581-.669 2.165-.527 3.225.317 2.369.646 4.802 1.474 7.021 1.072 2.874 2.634 5.566 3.985 8.336l1.801-.185 6.588-28.232M72.755-71.929c-10.303-6.432-19.4-12.133-28.519-17.798-5.1-3.168-15.03-2.781-19.642 1.057-3.246 2.701-6.197 5.754-9.315 8.61a79.442 79.442 0 0 1-2.04 1.811C7.994-73.763 4.34-68.126 1.154-62.157c-.866 1.624-1.703 3.835-1.298 5.465 1.443 5.811 4.757 10.71 9.034 15.101-.692-3.433-2.016-6.639-3.089-9.927-.377-1.156-.138-2.512-.18-3.777 1.11.025 2.245-.088 3.325.105 1.925.343 3.851 1.351 5.716 1.219 3.677-.26 4.125 1.984 4.44 4.646.359 3.041-1.993 2.543-3.645 2.66-1.841.13-2.915.734-2.467 2.712.905 3.992.736 4.291-3.579 4.882l14.103 19.862 49.241-52.72M139.649.98c-.507.794-1.016 1.587-1.562 2.439l-1.74-1.16-.628 2.352 3.468 1.854-.105.699h-4.953c.365 2.209.13 4.467 1.099 5.926 2.438 3.67 2.294 5.919-1.084 8.396l-2.126-7.98c.074-1.458.543-3.08.081-4.368-.286-.792-1.992-1.073-3.06-1.584 1.242-2.535.276-4.437-1.424-6.454-2.869-3.401-5.661-6.91-8.07-10.641-1.562-2.419-2.384-5.314-3.888-8.809l-3.55 5.182c-4.41-2.945-7.596 2.594-12.306 3.826 1.449-1.581 2.334-2.793 3.457-3.714 1.751-1.438 3.489-3.331 5.54-3.877 5.649-1.504 5.713-1.268 4.793-6.823l2.521 2.787.408-2.448.629-.011.852 4.822c3.898-5.324 3.952-7.326.437-12.16l-23.321 9.6-.392-.793 4.362-2.715-.133.119c5.946-3.141 13.286-3.204 18.592-8.322a9085.713 9085.713 0 0 1-2.803-5.371c-7.199 1.797-11.524 8.038-17.937 10.386l-.515-.936 17.69-11.447c-1.372-2.824-2.432-5.61-4.002-8.072-1.554-2.436-3.666-3.756-6.443-1.163-7.515 7.016-15.183 13.868-22.631 20.954-6.34 6.032-6.874 13.564-4.913 21.575.273 1.115.589 2.219.885 3.328l-.692.258-3.648-4.863-.683.347 3.297 10.218-.727.23-5.74-10.221-1.07 5.35-4.787-8.084c-1.145 1.061-2.12 2.011-3.144 2.906-2.182 1.905-3.188 3.832-1.594 6.847.952 1.801.841 4.162 1.19 6.174l-3.091-1.195.856-3.875c-1.442-.191-2.437-.322-3.636-.482-5.03 3.074.053 7.915-1.507 12.361l-2.002-6.59c-1.559 5.328 4.052 14.299 9.825 17.029 4.23 2.001 5.8 1.107 6.157-3.49.014-.18.221-.344.338-.516l.932.018c-.13 1.739.283 3.781-.489 5.161-2.647 4.735-1.84 8.498 2.909 10.505l2.688-.3-1.323-2.012c3.321 1.916 7.53 2.617 8.752 7.044.238.865 1.143 1.874 1.977 2.191 4.085 1.554 8.25 2.896 12.388 4.312l.505-.711c-7.737-3.577-10.11-11.394-14.499-17.621 1.5 1.477 2.647 3.247 4.03 4.806 3.323 3.746 6.701 7.446 10.192 11.034.704.723 2.006.866 3.032 1.277l.108-.477-5.633-5.15c3.104 1.114 5.687 2.783 8.372 4.265.667.368 1.666.133 2.512.175.007-.842.197-1.735-.016-2.517-.575-2.107-1.323-4.167-2.003-6.246l.45-.149 2.939 6.308c.278-.103.558-.204.837-.306l.722-13.502-.754-.141-2.311 3.278c-.582-4.178 1.487-6.631 3.945-8.758 2.153-1.862 4.522-3.477 6.827-5.158 3.634-2.649 6.772-2.727 9.573-.502l5.976-7.964v5.344c-.534.145-2.026.233-2.111.625-.53 2.464-.959 4.663-2.768 6.86-1.989 2.415-2.491 5.994-4.053 8.839-1.723 3.137-3.915 6.016-6.254 9.536-.313-.885-.997-1.878-.746-2.268 1.464-2.273 2.929-4.616 4.802-6.539 3.828-3.932 5.452-8.919 3.717-12.947-1.907 2.79-4.571 2.27-7.392 2.176-1.489-.05-3.031 1.499-4.549 2.326l1.323 2.376c-.837.951-2.219 1.799-2.436 2.881-1.697 8.438-2.877 16.92-.379 25.439 1.36 4.637 2.272 4.969 6.371 2.309 1.711-1.111 3.472-2.142 5.212-3.209l.601.967-5.549 3.582.29.557 4.976-2.096.364.739-4.754 2.949c5.201-2.617 9.394.706 13.713 2.161 3.627 1.221 7.041 3.074 9.836 4.328 1.26-1.411 2.446-2.26 2.975-3.412 2.719-5.906 5.536-11.792 7.739-17.895.823-2.28.425-5.198-.091-7.686-.295-1.426-1.941-2.572-2.979-3.843l.388-.684 4.025 1.432-1.075-5.171-1.961 2.986-3.54-14.414c-.497.131-.995.261-1.493.39l1.467 5.619-2.3 6.133-1.259-.088c1.102-5.082 1.596-10.062-1.896-14.507 3.106.406 2.843-1.317 2.359-3.098-.223-.819-.786-1.561-.925-2.383-.399-2.355-.658-4.732-.973-7.103l3.301 5.86.812.216c.15-1.547.821-3.309.298-4.58-.489-1.192-2.241-1.866-3.437-2.768l-.857 1.4m24.254-9.541c.583-.685 1.153-1.383 1.752-2.053 2.821-3.152 1.555-7.071-2.638-7.874-3.094-.593-4.798 1.604-6.237 2.816 1.473 2.412 2.617 4.362 3.843 6.261.538.834 1.239 1.562 1.866 2.337-2.139 4.212-1.715 6.955 1.489 10.52 4.217 4.694 9.733 6.061 16.199 7.027 0-3.348-.242-5.993.066-8.573.319-2.674.438-5.862 1.956-7.792 2.418-3.072 5.719-5.595 9.02-7.789 4.356-2.894 4.946-3.774 3.452-8.869-.512-1.745-.98-3.503-1.446-5.26-.515-1.937-1.349-3.378-3.764-3.014-.837.126-1.73-.11-2.597-.181l-.017-.309 3.887-.554c.163-2.526-1.04-3.068-3.145-3.063-5.59.015-10.828 1.053-15.293 5.465l9.672-1.277-.478 5.543h9.851l-.235 4.115-1.738.263.911 2.238c-10.87-1.736-10.855-1.718-19.764 5.259-2.137 1.674-4.405 3.18-6.612 4.764M96.411 64.668c-.031.22-.172.553-.077.646 2.808 2.758 5.572 5.567 8.525 8.16.515.451 1.838-.019 2.787-.063-.168-.804-.066-2.04-.549-2.343-3.521-2.212-7.159-4.237-10.761-6.321-.081-.767.109-2-.285-2.229-4.349-2.523-8.596-5.376-13.238-7.211-15.511-6.133-31.11-12.058-46.811-17.684-4.983-1.785-10.637-.839-14.831 1.935-6.722 4.446-12.975 9.767-16.714 17.325-.504 1.019-1.643 1.723-2.487 2.573L.9 58.81l2.781-9.447-.992-.317-8.156 22.691 1.332.712C1.079 61.818 8.476 53.118 18.072 45.502l.878 4.062c2.582-.481 4.924-1.025 7.297-1.343 11.476-1.535 22.945-1.352 33.902 2.545 11.19 3.979 22.08 8.801 33.12 13.209.984.394 2.097.463 3.142.693m94.695-101.733c3.515.314 11.401-3.644 12.249-6.799.388-1.441-.871-3.615-1.944-5.033-.51-.675-2.732-.929-3.495-.395-4.717 3.302-9.238 6.883-13.951 10.467 2.715.705 4.993 1.295 7.271 1.888-9.287-.727-10.652-.531-12.535 2.424 7.59-2.268 14.32-2.994 15.495 8.28 1.055-4.614.122-7.202-3.09-10.832M147.934-3.214l2.677 5.391c4.267-2.33 5.107-3.802 4.672-8.06-.214-2.095-.804-3.904-3.174-4.197-3.382-.417-5.877 1.238-7.968 3.392l3.903 3.577c-1.35-.545-2.704-1.073-4.046-1.637-2.272-.954-3.882-.457-4.724 2.029 5.625.961 6.678 2.109 7.464 8.126 2.495-1.005 2.505-2.957 2.06-5.072-.251-1.191-.573-2.367-.864-3.549m36.56 60.309c-1.403 6.647-3.661 12.942-7.652 18.519-.532.745-1.009 1.552-1.649 2.195-4.191 4.219-4.677 9.152-3.665 14.811 1.761 9.834 3.006 19.761 3.835 29.886-1.181-4.428-2.817-8.793-3.448-13.299-1.221-8.724-2.191-17.511-2.676-26.305-.47-8.567-2.883-16.327-7.255-23.645-2.097-3.509-3.59-7.374-5.571-10.959-1.167-2.112-2.752-3.992-4.328-6.23-3.284 7.474-6.257 14.232-9.223 20.994-.983 2.241-.235 4.119 1.963 4.67 6.607 1.654 9.564 7.612 14.178 11.595.382.329.51 1.236.401 1.806-1.343 7.056-2.617 14.129-4.209 21.13-.65 2.858-2.251 5.492-3.013 8.336-.96 3.583-1.51 7.276-2.225 10.923-.208 1.056-.376 2.119-.701 3.972-1.751-5.321-1.93-9.388.776-13.739 3.285-5.283 4.633-11.329 4.756-17.683.054-2.772.865-5.73 2.088-8.235 2.349-4.814-.412-7.553-3.375-10.465-7.136-7.014-16.202-10.357-25.479-13.097-3.746-1.106-7.8-1.453-11.731-1.562-3.378-.095-4.223 3.072-5.153 5.611-.122.334 1.29 1.745 2.038 1.786 2.152.115 4.347-.086 6.491-.402 3.157-.465 5.773.151 8.124 2.522 1.747 1.762 3.922 3.116 5.982 4.54.621.429 1.498.485 2.257.712l-1.307 1.631c-1.106-.52-2.191-1.088-3.32-1.549-3.776-1.539-7.448-3.678-11.38-4.412-6.578-1.229-10.869 2.229-12.227 8.792-2.015 9.737-3.863 19.513-6.123 29.193-.964 4.129-2.62 8.054-1.112 12.388.151.435-.592 1.18-.92 1.781-.496-.466-1.216-.839-1.452-1.412-1.106-2.695-1.39-5.193-.081-8.199a56.642 56.642 0 0 0 3.954-13.423c1.05-6.466-.856-12.644-3.225-18.658-.5-1.268-.653-2.73-.691-4.11-.088-3.315-1.438-5.622-4.793-6.732l-.841 1.816c-.276-.093-.575-.098-.671-.24-3.576-5.32-9.67-6.731-14.912-9.296-6.97-3.409-14.071-6.81-21.472-9.013-9.395-2.796-19.209-4.475-29.036-2.358-2.966.639-5.588 2.926-8.338 4.509C9.291 61.25 7.527 70.576 4.25 78.994 2.021 84.719-.405 90.37-2.543 96.128c-1.184 3.183-2.226 6.469-2.836 9.8-.559 3.053.817 5.652 2.789 7.363 3.744-8.067 7.383-16.09 11.188-24.035 2.079-4.341 5.964-5.61 10.502-5.621 11.255-.027 22.348 1.334 33.379 3.504 5.49 1.08 9.407 4.368 13.175 8.141 2.575 2.578 5.497 4.806 8.088 7.369 2.222 2.197 4.239 4.608 6.262 6.998 1.977 2.334 3.846 4.76 6.403 7.943-2.049-.716-3.206-1.074-4.328-1.521-10.725-4.273-21.347-8.826-32.186-12.784-15.807-5.77-30.564-1.519-44.867 5.588-.815.404-1.899.808-2.251 1.514-2.255 4.53-6.092 5.578-11.214 4.684l.716 5.31-4.187 1.209c-.101-.371-.458-1.064-.454-1.756.021-4.139-.826-7.967-2.177-11.966-1.055-3.125-.042-7.204.813-10.672 2.763-11.203 5.587-22.407 8.936-33.445 3.474-11.449 9.683-21.18 20.067-27.763.674-.427 1.312-.915 1.94-1.41.161-.127.219-.387.592-1.092-4.639-.547-9.109-.894-13.51-1.647-3.888-.666-7.737-1.65-11.53-2.748-3.355-.97-3.904-3.608-2.33-6.247 2.861-4.798 5.792-9.627 9.294-13.955C6.718.257 14.111-8.044 21.334-16.484c.44-.515.856-1.051 1.365-1.677C17.202-26.11 11.64-33.932 6.332-41.923c-2.523-3.798-4.566-7.914-6.821-11.89-1.577-2.782-1.122-5.567.216-8.226 6.24-12.399 16.051-21.685 27.071-29.612 4.362-3.138 9.861-4.234 15.174-.886 9.482 5.974 19.085 11.759 28.482 17.861 2.38 1.546 3.645 1.46 5.709-.516a1595.893 1595.893 0 0 1 30.133-28.089c2.235-2.031 4.984-3.603 7.704-4.976 7.133-3.6 14.988.295 14.622 9.283-.199 4.897.57 9.827.531 14.739-.057 7.078-1.067 14.015-4.554 20.367.088-.851-.026-1.797.306-2.546 4.508-10.17 2.88-20.683 1.499-31.089-.293-2.208-2.514-5.901-3.847-5.901-3.939-.001-8.284.738-11.739 2.568-9.629 5.099-16.63 13.48-24.288 21.001-.635.624-1.363 1.151-2.049 1.723-.196-.848-.036-1.279.264-1.561 6.922-6.5 13.6-13.296 20.879-19.369 5.342-4.457 11.245-8.631 19.2-6.675-.619-.74-1.199-1.251-1.874-1.462-4.74-1.486-9.276-.685-12.895 2.519-10.44 9.244-21.173 18.242-30.843 28.252C59.266-55.757 39.88-34.561 20.381-13.481 14.256-6.858 8.507.113 2.415 7.121l2.043.99C1.319 12.722-1.75 17.11-4.687 21.588c-1.893 2.886-.917 6.756 2.042 7.361 10.631 2.175 21.388 4.737 31.961.06 7.242-3.203 10.578-5.559 9.926-12.915-.189-2.132 1.319-4.821 2.816-6.615C45.784 5.012 49.874.838 53.96-3.314a1420.616 1420.616 0 0 1 20.162-20.103c9.409-9.185 18.651-18.567 28.473-27.292 5.749-5.107 12.487-9.1 18.908-13.685l.422 3.043 2.779-2.602c-3.031 6.27-5.964 12.591-9.146 18.783-1.125 2.188-.946 3.847.013 6.079 2.142 4.982 6.457 9.053 6.5 14.894.014 1.723-.471 3.449-.835 5.889l1.01 1.087-2.55 1.583c3.511 6.105 4.543 13.462 11.478 17.917 1.873-1.606 4.052-3.488 6.248-5.351 1.735-1.472 3.608-2.805 5.196-4.42.978-.994 1.343-2.591 2.324-3.578 1.432-1.44 3.044-3.406 4.802-3.671 3.917-.591 6.913-2.606 9.883-4.807.835-.619 1.494-1.749 1.796-2.773 2.454-8.35 8.161-13.881 15.482-17.993.74-.415 2.151-.581 2.733-.156 2.035 1.488 3.547.733 5.232-.542A1411.102 1411.102 0 0 1 201.908-53.7c.965-.708 2.14-1.129 3.203-1.671l-3.869 3.205 4.854 6.907c3.397-3.14 6.692-6.115 9.898-9.185 1.153-1.105 3.021-2.061 1.727-4.227-1.265-2.117-2.937-3.162-5.426-2.072l3.907-3.181 3.271 6.984c6.116-4.74 11.702-8.997 17.159-13.413.531-.43.643-2.004.308-2.764-1.213-2.751-3.18-2.35-5.221-.864l13.224-9.918-7.862 6.704 2.486 4.989c1.37-.779 2.553-1.265 3.513-2.03 3.11-2.478 5.894-5.473 9.271-7.483 3.243-1.93 4.141-3.714 1.823-6.771l3.056 3.214c2.799-1.398 5.592-2.957 8.52-4.199 2.062-.875 2.047-1.929 1.237-3.724-.826-1.835-1.951-2.039-3.552-1.296-1.236.572-2.454 1.18-3.857 1.432 3.461-2.74 7.091-5.159 11.605-5.923l-4.284 3.324 1.877 4.724c2.266-1.111 4.2-2.303 6.294-3.031 3.375-1.173 4.139-3.122 2.424-6.158.909 1.095 1.813 2.177 3.01 3.612.718-1.372 1.447-2.465 1.823-3.667.119-.379-.871-1.573-1.078-1.509-1.29.402-2.504 1.054-3.742 1.623l-6.412 1.155c2.477-1.306 4.843-2.944 7.465-3.821 2.409-.806 3.339-2.262 3.407-4.48.106-3.5 2.22-5.084 5.268-5.809 2.83-.673 6.494.969 7.844 3.695 1.361 2.747 1.196 5.603-.577 8.133-.523.745-1.667 1.126-2.596 1.503-3.987 1.618-8.104 2.952-11.984 4.792-10.526 4.991-20.946 10.208-30.239 17.362-4.667 3.592-9.297 7.234-13.972 10.815-10.121 7.751-20.339 15.379-30.349 23.271-3.395 2.675-6.292 5.985-9.396 9.025-.314.307-.717.756-.704 1.126.13 3.758-.14 7.616.64 11.244 1.02 4.746.675 6.251-3.251 8.945-3.185 2.186-6.735 4.293-8.95 7.3-1.788 2.428-1.984 6.121-2.486 9.316-.086.552 1.751 1.564 2.828 2.111 3.245 1.651 6.507 3.285 9.851 4.72 3.008 1.292 3.055 3.533 2.571 6.219-1.656 9.188-3.341 18.347-7.004 27.033-1.372 3.252-2.096 6.772-3.244 10.126-.421 1.23-1.213 2.333-1.839 3.498.275-1.434.43-2.91.851-4.304 3.466-11.439 8.322-22.457 9.865-34.477.706-5.505-1.09-8.505-6.883-9.536 1.646 2.673 6.229 3.13 5.637 6.978l-3.426 1.438c-2.164-1.346-4.206-3.05-6.556-3.96-2.625-1.016-5.569-1.166-8.301-1.951-5.803-1.667-11.188-4.08-14.76-9.33-.143-.209-.593-.209-1.203-.404-.661 2.737-1.74 5.362-1.844 8.026-.249 6.328-2.196 12.17-4.592 17.863-2.384 5.663-1.537 12.337 1.828 15.875l8.105 1.312c-1.078 4.882 1.815 7.974 3.937 10.905 2.079 2.873 5.486 4.784 8.286 7.096l-3.922 6.452c-.546-.792-1.264-1.613-1.739-2.557-2.568-5.107-4.954-10.31-7.661-15.341-1.119-2.081-2.879-3.817-4.348-5.711l-.929.599c1.56 3.362 2.924 6.833 4.723 10.062 3.664 6.58 7.617 12.999 8.322 20.766.071.791.726 1.529 1.11 2.291.859-.436 2.101-.646 2.516-1.345 2.836-4.78 5.549-9.636 8.195-14.525 1.103-2.039 1.944-4.221 2.905-6.338\" transform=\"matrix(.32425 0 0 .32425 5.175 37.004)\" \/>\n                <path fill=\"#4778FF\" d=\"M0-41.056c1.722 1.412 3.47 2.794 5.162 4.241 7.178 6.134 14.37 12.253 21.474 18.471 1.079.944 1.729 2.38 2.564 3.598 1.6 2.333 2.819 5.071 6.156 5.488.381.048.798.476 1.044.834C38.098-5.951 39.754-3.451 42.065 0c-4.552-1.337-8.795-1.734-12.093-3.71-9.879-5.92-19.453-12.364-28.97-18.862-1.317-.9-2.185-3.214-2.317-4.946-.327-4.297-.107-8.635-.107-12.956L0-41.056\" transform=\"matrix(.32425 0 0 .32425 23.905 70.883)\" \/>\n                <path fill=\"#4778FF\" d=\"M0-15.798-7.358.513-8.394.224l-1.082-2.94-6.2 3.432-.696-.997c5.113-5.521 8.936-12.301 15.679-16.233l.693.716\" transform=\"matrix(.32425 0 0 .32425 50.157 77.559)\" \/>\n                <path fill=\"#4778FF\" d=\"M0-17.435C11.066-14.605 21.304-10.385 27.577 0 19.804-8.033 10.076-12.96 0-17.435\" transform=\"matrix(.32425 0 0 .32425 46.918 63.911)\" \/>\n                <path fill=\"#4778FF\" d=\"M3.643-1.298c-.321 3.943-.641 7.886-.964 11.83l.964.097L4.898-1.176l-1.255-.122Z\" transform=\"matrix(.2546 .2008 .2008 -.2546 41.1 20.83)\" \/>\n                <path fill=\"#4778FF\" d=\"m-4.29-12.757-.893 14.11.893.064.812-14.116-.812-.058\" transform=\"matrix(-.25762 -.1969 -.1969 .25762 1.558 43.272)\" \/>\n                <path fill=\"#4778FF\" d=\"M0 29.549c-2.432-4.852-5.071-9.615-7.219-14.589-1.31-3.034-2.684-5.175-6.412-4.415-.596.121-1.287-.231-1.276-.229 0-1.766.085-3.151-.02-4.522C-15.079 3.81-16.439 1.5-12.853 0c-1.22 6.841 5.785 8.664 7.085 14.105 1.249 5.231 4.466 9.991 6.818 14.959L0 29.549\" transform=\"matrix(.32425 0 0 .32425 29.759 38.337)\" \/>\n                <path fill=\"#4778FF\" d=\"M0 3.606-1.793.505c-1.564 5.001-5.146 4.286-9.293 4.009C-8.197 2.221-5.858.198-3.315-1.523c.555-.377 2.31.01 2.689.587C.179.291.442 1.873.928 3.31L0 3.606\" transform=\"matrix(.32425 0 0 .32425 41.078 33.997)\" \/>\n                <path fill=\"#4778FF\" d=\"m0 8.428-4.056-1.959L1.841 0C3.153 1.671 2.271 6.031 0 8.428\" transform=\"matrix(.32425 0 0 .32425 39.991 36.196)\" \/>\n                <path fill=\"#4778FF\" d=\"m0 11.284-1.83-.18-.246-.721L15.319-.12l.437.748-15.89 10.776.134-.12\" transform=\"matrix(.32425 0 0 .32425 37.304 25.345)\" \/>\n                <path fill=\"#4778FF\" d=\"M0-7.825C3.156-3.691 10.364-5.992 12.351 0 9.396-4.454 2.582-2.778 0-7.825\" transform=\"matrix(.32425 0 0 .32425 30.504 42.45)\" \/>\n                <path fill=\"#4778FF\" d=\"M1.987-.468.295 7.689l1.692.353L3.379-.112 1.987-.468\" transform=\"matrix(.288 .14897 .14897 -.288 34.792 34.077)\" \/>\n                <path fill=\"#4778FF\" d=\"M0 5.556-3.598 6.58v-7.604L0 5.556\" transform=\"matrix(.32425 0 0 .32425 42.86 39.257)\" \/>\n                <path fill=\"#4778FF\" d=\"M0-19.367 13.766-.495l-.19.495c-1.602-1.21-3.468-2.193-4.753-3.677-3.015-3.482-5.9-7.103-8.519-10.887-.845-1.22-.696-3.129-1.001-4.722L0-19.367\" transform=\"matrix(.32425 0 0 .32425 56.518 54.537)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Cajamarca<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Iquitos -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-iquitos\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"45px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 532.89 453.78\">\n                <path fill=\"#4778FF\" d=\"M532.89 453.7c-1.68-.05-3.5.31-5-.21a260 260 0 0 1-96-57.59c-8.18-7.63-16.34-15.26-24.6-22.79a41.13 41.13 0 0 0-12.09-7.48 17.71 17.71 0 0 1-10.26-10.65c-2.13-5.8-5.95-10.5-10.13-14.94-2.6-2.75-5.3-5.42-7.9-8.18a4.48 4.48 0 0 0-4.55-1.45 28.73 28.73 0 0 1-8 .34 32.43 32.43 0 0 1-12.45-4c-4.28-2.37-5.44-5.67-3.83-10.29 1.44-4.15.85-6.42-2.67-9.1a255.1 255.1 0 0 0-28.89-19.61 8.46 8.46 0 0 0-9.24-.06 8.72 8.72 0 0 1-5.06.82 22.11 22.11 0 0 1-14.25-7.53 8.81 8.81 0 0 1-1.62-2.72 8.16 8.16 0 0 0-6.59-5.48c-8.82-1.58-17.63-3.22-26.47-4.68a116.16 116.16 0 0 0-20.58-1.29 27.13 27.13 0 0 0-11.38 2.47 118.29 118.29 0 0 1-38.88 10.51c-5.26.51-9.82 2.85-14 5.92a46.86 46.86 0 0 0-16.43 20.77c-1.67 4.26-1.73 8.76-2.09 13.22a86.83 86.83 0 0 0-.47 9.39c.09 3.64.49 7.27.88 10.89a8.69 8.69 0 0 1-.9 5.34c-1.68-2.22-3.36-4.15-4.72-6.3-3.55-5.6-5-11.87-5.5-18.4-.06-.82.09-1.66.11-2.49a2.34 2.34 0 0 0-1.25-2.42c-1-.51-1.8 0-2.5.64a36.44 36.44 0 0 1-16.92 8.13 39.74 39.74 0 0 1-14.74.5 27.63 27.63 0 0 0-19.91 4c-4.6 2.92-9 6.1-13.51 9.22-.87.6-1.66 1.27-2.74.7s-1-1.79-.82-2.83c.75-4.84 3.26-8.78 6.46-12.35 1.1-1.24 2.24-2.44 3.57-3.89-.76-.08-1.32-.18-1.87-.19a28 28 0 0 0-15.4 4.33c-7.58 4.7-15.08 9.53-22.69 14.19a43.94 43.94 0 0 1-17.2 6.62 68.65 68.65 0 0 1-7.18.42 2.33 2.33 0 0 1-2.49-1.62 2.21 2.21 0 0 1 1.15-2.57c5.79-4.13 11.59-8.25 17.33-12.46s11.58-8.75 17.46-13a39.73 39.73 0 0 1 17.35-7.28 40.89 40.89 0 0 1 20.55 2.38 76.5 76.5 0 0 0 20.31 4.75 30.26 30.26 0 0 0 20.29-5.65c7.84-5.56 14.32-12.5 20.16-20.08a5.15 5.15 0 0 0 .32-.66c-2.58-.47-5.05-.95-7.53-1.37a102.61 102.61 0 0 0-19.15-1.77c-3.73.08-7.45.56-11.18.83-7 .5-13.89-.3-20.26-3.4-5.62-2.74-10.77-2.11-16.1.81a166.64 166.64 0 0 1-17.61 8.74c-9.7 3.89-19.7 3.51-29.64.54-.17 0-.33-.13-.62-.25a2.2 2.2 0 0 1 .5-.34c9.16-2.72 17.74-6.89 26.46-10.69a127.25 127.25 0 0 1 19-6.85 4.85 4.85 0 0 0 .71-.29 49.68 49.68 0 0 0-9.83-8.83c-6.12-4.24-12.38-8.26-18.48-12.51a48.24 48.24 0 0 1-11.85-11.57c-.18-.25-.33-.52-.5-.79l.21-.41a45.86 45.86 0 0 1 5.44 2.14c6.77 3.7 13.47 7.53 20.2 11.31a24.77 24.77 0 0 0 2.46 1.26c1.59.66 2.77.15 3.16-1.57a47.94 47.94 0 0 0 .82-5.75 20.11 20.11 0 0 1 2.16-8.13 7.81 7.81 0 0 1 2.86 4.3 39.07 39.07 0 0 1 1 7.37c.27 9.21 4.95 15.45 12.93 19.46a51.15 51.15 0 0 0 27.35 5.65 5.76 5.76 0 0 0 1.49-.27c1.48-.5 2-1.88 1.08-3.06-3.13-3.81-6.07-7.83-10.6-10.21a14.24 14.24 0 0 1-6.89-8.52c-.78-2.37-1.4-4.79-2-7.2-.25-1-.5-2.14.57-2.78a2.78 2.78 0 0 1 3.34.47c3.58 3.14 7.18 6.25 10.66 9.49 4.62 4.32 8.95 9 14.37 12.35 11.95 7.43 24.6 8.37 37.61 3.48 4.64-1.74 9-4.3 13.39-6.65a185.62 185.62 0 0 1 56.95-19.84c2.32-.39 4.67-.65 7-1.08a24 24 0 0 0 3.1-1 9.6 9.6 0 0 0-3.34-4 27.72 27.72 0 0 1-4.46-3.71 17.89 17.89 0 0 1-3-5.38 5.28 5.28 0 0 1 1.61-6.05c2.08-1.75 4.49-2.62 7-1.39a14 14 0 0 1 4.3 3.16 35.65 35.65 0 0 0 17.57 10.58 45.28 45.28 0 0 1 14.57 6.89c4.27 3.08 9.24 4.82 14.17 6.56a14.41 14.41 0 0 1 1.43.53 8.57 8.57 0 0 0 7.81 0 20 20 0 0 1 7.25-1.56 115.15 115.15 0 0 1 12.6.13 12.36 12.36 0 0 1 9.65 5.53c2.57 3.62 6.35 4.73 10.54 4.75a4.76 4.76 0 0 0 2.34-.75c2.39-1.47 2.46-3.91.3-5.68-5.67-4.66-11.39-9.27-17-14.06-12.69-10.9-24.4-22.73-34-36.49a133.94 133.94 0 0 1-18-35.95 111.19 111.19 0 0 0-4.56-10.7 36.45 36.45 0 0 1-2.73-18.59c.94-9.6 2.36-19.15 3.48-28.73a98.47 98.47 0 0 0 .72-20.73c-.32-3.47-2.6-5-6.09-4.63-8.5.79-17 1.63-25.52 2.16-8.89.55-17.82.57-26.7 1.16-12.66.84-25.34 1.63-37.94 3.07a213.71 213.71 0 0 0-58 14.58 216.17 216.17 0 0 0-37.77 20.5c-5 3.38-8 8.23-9.65 14-.16.53-.3 1.06-.52 1.88-.31-.48-.52-.78-.69-1.1-3.69-6.94-3.8-14.15-2.14-21.69 3.82-17.23 12.07-32.09 23.75-45.12a192.79 192.79 0 0 1 54.78-42.32c19.22-10 39.58-16.86 60.75-21.37a189.67 189.67 0 0 1 30-4 183.24 183.24 0 0 1 39.08 2.15 16.34 16.34 0 0 0 9.47-1A56 56 0 0 1 285.38.26a1.7 1.7 0 0 0 .47-.23h10a10.05 10.05 0 0 0 1.05.26 52.35 52.35 0 0 1 17.8 5.48 78.78 78.78 0 0 1 36.36 38.59c6.3 13.92 9.36 28.7 11.3 43.72.61 4.7 2.67 7.79 7 9.57q4.68 1.94 9.22 4.17a140.15 140.15 0 0 1 40.5 30.1 157.75 157.75 0 0 1 22.82 31.45c4.74 8.57 9.09 17.36 13.92 25.88s9.92 16.67 14.9 25c2.49 4.16 4.08 8.55 3 13.46a7.48 7.48 0 0 0 .73 4.93c2.41 5.29 5 10.53 7.07 15.95 4.53 11.72 7.32 23.93 9.73 36.23.37 1.9.75 3.81 1 5.73a3.92 3.92 0 0 1-2 4.09 4 4 0 0 1-4.21-.27c-.6-.34-1.18-.73-1.76-1.11l-5.78-3.8a1.77 1.77 0 0 0 0 .37c.45 1 .89 1.93 1.36 2.88a320.08 320.08 0 0 0 17.61 30.32q12.27 19.23 24.5 38.47c5.92 9.28 8.44 19.32 6.82 30.26a34.7 34.7 0 0 1-1.75 7c-.94 2.53-2.87 3.36-5.36 2.47a26 26 0 0 1-4.25-2.27c-.66-.39-1.13-.46-1.42.32-1.12 3-4.29 2.82-6.28 1-1-.86-1.82-1.84-2.76-2.72-1.39-1.31-1.76-1.32-3.29-.18-2.54 1.88-4.47 1.92-6.78 0a52.42 52.42 0 0 1-10.35-11.49c-4.77-7.31-8-15.39-11.86-23.18-6.39-13-12.69-26.09-19.22-39-4.93-9.79-10.88-18.88-19-26.45a89 89 0 0 0-20.14-14.13c-2.22-1.15-3.16-.78-4.37 1.4-.79 1.41-1.55 2.85-2.45 4.18-1.84 2.73-4.29 4.73-7.67 4.89a53.18 53.18 0 0 1-6.86-.57 7.68 7.68 0 0 0-2.33-.1 12 12 0 0 0-7.81 6c-1.12 2-.63 2.87 1.63 3.33 6.81 1.37 10.17 5.51 9.64 12.19a8.12 8.12 0 0 0 2.36 6.66c8.15 8.51 16.22 17.1 24.48 25.5 5.41 5.5 11 10.8 16.65 16.09a304 304 0 0 0 33.84 27.74c5.93 4.15 11.64 8.56 16.33 14.09 3.19 3.76 6.07 7.8 9 11.78 6.9 9.43 15.54 17.17 24 25.13 3.69 3.49 8 6.42 10.22 11.29ZM275.67 9.48h-2.63c-4.46.31-6.33 2.1-6.8 6.49a4.59 4.59 0 0 0 0 1.11c.58 4.25 1 8.53 1.8 12.73 1.25 6.58 3.2 13 4.07 19.66 1.54 11.75-1.69 22-11.28 29.62a4.59 4.59 0 0 0-1.83 3.86c.05 1.48.18 2.95.24 4.43a150.7 150.7 0 0 1-2.33 33.52 76.39 76.39 0 0 0-.67 26.59c1 6 3.39 11.42 8.36 15.18a40.48 40.48 0 0 0 25.4 8.15c4.62-.05 8.15-2.39 10.31-6.62a24.41 24.41 0 0 0 2.25-8.52c.43-3.69 1.57-7 4.54-9.49a26.73 26.73 0 0 0 8.17-13c.9-2.95 1.63-6 2.25-9 1-4.72 2.59-9 6.29-12.36a16.21 16.21 0 0 0 4.57-8.87c1-4.82.64-9.65-.1-14.46a22.19 22.19 0 0 1 .64-10.67 20.58 20.58 0 0 0 .65-9.74 31.75 31.75 0 0 0-5-12.22c-5.35-8.43-10.77-16.81-16.07-25.28-2.51-4-5-8-8.39-11.33a33.78 33.78 0 0 0-24.44-9.78ZM107.1 49.86l.26.42c34-18.31 70.13-28.93 108.88-31.07a5.63 5.63 0 0 1-3.4 3.49c-1.86.79-3.74 1.57-5.54 2.51-8.35 4.38-15.41 10.18-20.05 18.56a15.31 15.31 0 0 0-1.77 4.76c-.6 3.62 1.75 5.78 5.34 5.16a248.56 248.56 0 0 1 32.79-3c6-.25 12-.21 18-.12 4.42.07 8.85.42 13.27.68 3 .18 6 .49 9 .58 1.87.06 2.51-.91 1.89-2.68a30.9 30.9 0 0 0-1.41-3.17c-4.64-9.64-5.92-19.64-3.12-30.06 1.3-4.86.29-6.49-4.75-7s-10.38-1.17-15.59-1.25c-8.35-.11-16.72-.1-25 .39a185.56 185.56 0 0 0-54.64 11.83 211.41 211.41 0 0 0-42.51 21.72c-4 2.6-7.79 5.49-11.65 8.25Zm222 219.88c5 3 9.94 6 14.79 9.09 7.11 4.57 14.13 9.3 21.22 13.9a3.74 3.74 0 0 0 2.54.69 25.35 25.35 0 0 0 12.71-7.72 2.43 2.43 0 0 0 .31-2.94c-3-6.28-8.2-8.28-14.67-5.59-1.62.67-3.26 1.3-4.93 1.85-5.38 1.76-10.56 1.51-15.4-1.69-3.81-2.53-7.63-5-11.43-7.6a4.16 4.16 0 0 0-5.17.01Zm38.81 29.54c-1.86 1.11-3.54 2.06-5.16 3.1a31.85 31.85 0 0 0-3.36 2.43 1.82 1.82 0 0 0-.33 2.61 2.15 2.15 0 0 0 2.61 1.05 10.31 10.31 0 0 0 1.52-.67 20.08 20.08 0 0 1 19.53.24c2.2 1.16 4.2 2.67 6.31 4 .78.5 1.62.8 2.4 0a2.39 2.39 0 0 0 .71-2.77 4.44 4.44 0 0 0-1.27-1.61 11.1 11.1 0 0 0-5.64-2.46 19.7 19.7 0 0 1-2.87-.45c-1.92-.51-2.76-1.78-2.13-3.65a23.76 23.76 0 0 1 2.51-5.2c1.17-1.82 2.68-3.41 4-5.11.59-.75 1.1-1.54.28-2.47a2.07 2.07 0 0 0-2.84-.56 10.68 10.68 0 0 0-1.36.95c-2.92 2.27-5.82 4.56-8.74 6.83-2.43 1.9-5 2.55-8 1.2a10.12 10.12 0 0 0-8.87.3c-2.91 1.47-5.64 3.32-8.42 5a2.83 2.83 0 0 0-.91 1c-.55 1 0 1.76.77 2.37s1.3.08 1.89-.45a60.86 60.86 0 0 1 5.76-4.92c3.56-2.34 7.41-2.45 11.61-.76Zm-69-45.75-5.7 2.82a22.28 22.28 0 0 0-7.22 5.48 1.89 1.89 0 0 0-.28 2.53 2.07 2.07 0 0 0 2.59.74 11 11 0 0 0 2.11-1c2.56-1.65 5.19-3.23 7.6-5.08a15.75 15.75 0 0 1 7.82-3.2 39.58 39.58 0 0 0 4.39-1.13c-7.27-5.71-22.23-3.4-27.7 1.46.65-.17 1.2-.25 1.71-.44 2.24-.84 4.46-1.75 6.72-2.55a10 10 0 0 1 7.95.37Z\"\/>\n                <path fill=\"#4778FF\" d=\"M282.19 18.18c5.76.05 11.06 5.28 11 10.85s-5.32 10.78-10.81 10.77c-5.65 0-10.75-5.25-10.67-11s5.1-10.66 10.48-10.62Z\"\/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en<br>Iquitos<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours en Cruceros -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-cruceros\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"45px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 383.78 287.6\">\n                <path fill=\"#4778FF\" d=\"M369.42 95.95c1.67 0 3.34-.05 5 0 6 .21 9.7 3.89 9.33 10-2.81 45.57-17.09 86.93-45.33 123.2a48.63 48.63 0 0 0-7.59 13.73c-2.24 6.53.07 12.42 5.23 17.1a35.16 35.16 0 0 1 11.32 21.16c.7 4.38-1.25 6.75-5.7 6.43-25.41-1.84-50.82-3.8-76.24-5.62-25.92-1.84-51.85-3.51-77.78-5.36-23.76-1.69-47.51-3.54-71.27-5.27q-32.15-2.34-64.3-4.56c-11-.76-21.95-1.35-32.91-2.22-5.64-.45-10.27-2.89-12.65-8.37-5.9-13.62-8.43-27.69-5-42.37 1.81-7.66 4.33-9.43 12.21-9.82 18-.88 34.51-7.14 50.53-14.6 29.43-13.71 58.45-28.29 87.95-41.84 40.2-18.47 81.91-32.54 125.4-41.22a577.54 577.54 0 0 1 91.8-10.37ZM239.9 166.16c1 8.42 3.4 15.71 9.58 21.27 7.37 6.64 16.73 5.4 22.4-2.73 7.06-10.12 5-27.54-4.28-35.74-8-7.09-18.6-5.43-23.48 4.11-2.06 4.03-2.85 8.7-4.22 13.09Zm-42.92 24.95c.18-6.1-1.6-11.54-6-15.81-6.43-6.18-15.07-4.47-18.92 3.61a21.55 21.55 0 0 0-.41 17.9c2.71 6.88 8.6 11.56 14 10.88 6-.76 10.82-6.92 11.39-14.58-.02-.67-.06-1.28-.06-2Zm-71.21 17.6c-1-2.73-1.38-6.43-3.4-8.65s-5.93-4.53-8.63-4.15-6 3.62-7.09 6.37c-2.32 5.7-1.12 11.5 3.28 16.12s10.86 3.63 13.7-1.92c1.09-2.14 1.33-4.71 2.14-7.77Zm-63.86 17.7c0-5.66-3.31-10-7.55-10-4 0-6.73 3.63-6.68 8.85s3.77 10 7.86 9.85c3.64-.11 6.38-3.85 6.37-8.7Z\" \/>\n                <path fill=\"#4778FF\" d=\"M309.09 66.15c-1.13-4.47-1.83-8.92-3.48-13-.74-1.84-3.17-3.35-5.16-4.28-12.19-5.72-25.37-6.42-38.52-7.24-29.63-1.85-56.58 6.12-81.67 21.64-34.4 21.29-69 42.24-103.49 63.42-5.1 3.14-9.88 6.8-14.84 10.16a16.47 16.47 0 0 0-7.1 11.53c-1.57 9.18-3.49 18.31-5 27.49-.5 3-1.82 4.7-4.75 5.58-4.76 1.43-9.43 3.15-15.06 5.07 2.22-12 4.26-23.2 6.35-34.37a112 112 0 0 1 2.46-11.7c2.42-7.93 7.42-14 14.21-18.73 34-23.88 69.35-45.45 105.43-65.95 16.51-9.37 32.6-19.49 50.89-25.26 18.52-5.84 37.49-7.43 56.77-6.19 13 .84 25.9 2.17 38.14 7.05a53.13 53.13 0 0 1 7.65 3.65c5.56 3.35 9.78 7.52 11.24 14.45 2.37 11.2 5.55 22.22 8.71 34.56-8.09 0-15.61 1.08-22.72-.2-26.23-4.72-52.39-7.67-78.88-2.16-15.17 3.16-29 9.62-42.69 16.55q-46.19 23.36-92.37 46.61c-.86.43-1.79.7-3 1.18.08-6.64 1-11.51 7.71-15.23 32.19-17.83 63.9-36.53 96-54.57 25.16-14.15 52.54-17.46 80.81-14.74 10.51.99 20.99 3 32.36 4.68ZM167.67 33.23 96.05 75.06c0-18.11-.23-35.7.12-53.27.12-6.11 4.46-10.38 9.44-13.36a57.71 57.71 0 0 1 41.73-7.27 13.73 13.73 0 0 1 8.43 6.11c4.47 8.3 7.95 17.13 11.9 25.96Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours en <br>Cruceros<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours Privados -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-privados\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"40px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" data-name=\"Capa 1\" viewBox=\"0 0 254.85 255.2\">\n                <path fill=\"#4778FF\" d=\"M0 127.15C0 56.73 57.85-.49 127.89 0c70.7.49 127 57.28 127 128.7 0 68.51-58 126.26-125.8 126.5C56.48 255.45-.27 197.21 0 127.15ZM127.33 245.5c63.45.75 115.58-51.3 117.93-112.94C247.9 63.69 192.8 9.73 128.42 9.33 62.83 8.87 9.01 62.21 9.31 127.52c.31 68.89 57.03 118.89 118.02 117.98Z\" \/>\n                <path fill=\"#4778FF\" d=\"M17.85 127.47C18.18 66.2 67.18 17.33 127.97 17.62s109.42 49.95 109 111.62c-.39 59.76-50.21 108.49-110.49 108.09s-109-49.71-108.63-109.86Zm217.81.47c.54-58.43-47.9-108.19-105.86-108.76-61-.59-110.13 47-110.75 107.36-.63 59.79 48.43 109.38 108.34 109.54 59.09.16 107.72-48.43 108.27-108.14Z\" \/>\n                <path fill=\"#4778FF\" d=\"m87.78 49.93 20.7 22 18.91-34.08c6.39 11.57 12.47 22.58 18.83 34.08l20.94-22.15.77.36q-3.22 13.34-6.44 26.66c-1.52 6.29-3.17 12.55-4.52 18.87-.56 2.68-1.49 4-4.51 4-16.82-.11-33.64 0-50.45-.18a5 5 0 0 1-3.76-2.75c-3.94-15.4-7.62-30.86-11.36-46.3ZM161.75 174.22v33.2h-13.12c-.1-1.83-.24-3.3-.24-4.77 0-23.29.06-46.57-.08-69.86 0-3.78.82-5.44 5-5.14 6.79.49 13.65.12 20.4.81 9.3 1 15.16 7.85 15.33 17.17q.11 5.49 0 11c-.18 9.93-7.26 17.16-17.26 17.59-3.16.11-6.3 0-10.03 0Zm.32-35v24.07c4.92.06 11 1.64 12.55-3.72a31.08 31.08 0 0 0-.35-17.26c-1.63-4.98-7.58-3.17-12.2-3.13ZM111.54 127.73c-1.69 9.47-3.21 18.26-4.82 27-2.89 15.85-5.93 31.67-8.68 47.54-.66 3.83-1.69 5.67-6.19 5.57-12.06-.28-11.83-.06-14-12.33-3.58-20.61-7.51-41.16-11.27-61.74-.32-1.76-.52-3.55-.83-5.73h13c3.1 19.24 6.23 38.64 9.36 58.05l1 .19c.66-3.51 1.4-7 2-10.53 2.35-14.76 4.7-29.52 6.92-44.3.39-2.59 1.25-3.93 4.06-3.78s5.87.06 9.45.06ZM133.71 207.44h-12.23v-79.35h12.28ZM101.34 113.91l-1.49-6.26h54.47c-.19 2-.39 4-.6 6.26Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours <br>Privados<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Guiados Turisticos -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/guiados-turisticos-cusco-machupicchu\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 98.42 88.38\">\n                <path fill=\"#89370B\" d=\"M98.42 81.57H64.74v-4.46c0-2-.87-2.83-2.83-2.84h-4.4a9.43 9.43 0 0 1 .63-1 90.32 90.32 0 0 0 9.82-13.21c1.12-1.95 2-4.05 3-6.16l7.17 3.32c3.58 1.66 7.12 3.38 10.73 5a10.71 10.71 0 0 1 6.51 7.7c.87 3.64 1.91 7.24 2.88 10.86.07.22.11.47.17.79ZM54.39 18a57.24 57.24 0 0 1-13.44-1.31c-1.67-.38-1.89-.67-1.38-2.26.95-2.93 1.95-5.85 3-8.75a7.47 7.47 0 0 1 5.91-5 26.48 26.48 0 0 1 12.91.25 6.83 6.83 0 0 1 4.62 3.87 57.5 57.5 0 0 1 3.55 10.35c.21.79-.17 1.17-.89 1.36a52.56 52.56 0 0 1-10.94 1.48c-1.13.05-2.24.01-3.34.01ZM61 1.51a33 33 0 0 1-13.14 0c1.77 1.73 11.68 1.72 13.14 0Z\" \/>\n                <path fill=\"#89370B\" d=\"M38.68 13.32c-.13.51-.22.94-.33 1.37a2.15 2.15 0 0 0 1.7 3 50.53 50.53 0 0 0 11.15 1.43 70 70 0 0 0 12.86-.55c1.68-.25 3.35-.6 5-1a2.09 2.09 0 0 0 1.61-2.65c-.12-.52-.25-1-.42-1.75a23.91 23.91 0 0 1 2.51.47c2.17.64 4.35 1.28 6.47 2a6.73 6.73 0 0 1 2.13 1.38 1.91 1.91 0 0 1 0 3.18 11.65 11.65 0 0 1-2.8 1.72 36.55 36.55 0 0 1-9.76 2.47 97.9 97.9 0 0 1-17.11.95c-6.31-.2-12.6-.68-18.7-2.48a33 33 0 0 1-4.11-1.66 5.12 5.12 0 0 1-1.36-1 1.88 1.88 0 0 1 0-3.05 8.94 8.94 0 0 1 2.86-1.79c2.5-.83 5.08-1.44 7.62-2.14a4 4 0 0 1 .68.1ZM51.62 74.32H47.2c-2 0-2.79.82-2.8 2.83v4.27c0 .05-.06.11-.09.16a1.9 1.9 0 0 1-2.33-1c-4.74-7.23-9.54-14.42-14.41-21.76L38.2 53.9c2.12 6.5 6.32 11.6 10.43 16.76.88 1.15 1.85 2.25 2.99 3.66ZM66.2 51.01c.63.53 1.22 1 1.74 1.5a1 1 0 0 1 .29.8A36.41 36.41 0 0 1 66.29 58 82.29 82.29 0 0 1 56 71.91a1.38 1.38 0 0 1-.79.27c-.21 0-.46-.11-.65 0-1.15.44-1.68-.32-2.3-1.06-3.73-4.46-7.42-8.95-10.11-14.15a25.24 25.24 0 0 1-1.36-3.51 1.14 1.14 0 0 1 .36-.87c.55-.52 1.18-1 1.77-1.44a9.71 9.71 0 0 1 .15 1.56c-.07 2.23 1.19 3.73 2.73 5.06 4.67 4 13.15 4 17.78-.14 1.64-1.46 2.82-3.14 2.57-5.5a6.53 6.53 0 0 1 .05-1.12Z\" \/>\n                <path fill=\"#89370B\" d=\"m38.64 26.21 5.8.75a26 26 0 0 1-1.82 2 2.14 2.14 0 0 0-.88 2.44c.81 2.94 1.21 6 2.34 8.82 1 2.48 2.89 4.58 4.16 7a5.4 5.4 0 0 0 6.07 3.09 19.52 19.52 0 0 1 2.65 0 2.8 2.8 0 0 0 2.49-1.14c2-3.09 4.32-6.07 5.77-9.41 1.3-3 1.68-6.44 2.33-9.7a16 16 0 0 0-.07-3.37l3.12-.46c-.73 5.18-1.19 10.32-3.26 15.07a49.51 49.51 0 0 1-3.6 6c-.64 1-1.32 2-2 3a5.33 5.33 0 0 1-4.18 2.46c-2 .1-4 .09-6 0a5 5 0 0 1-4-2.23 71.17 71.17 0 0 1-5.15-7.93 31.2 31.2 0 0 1-2.38-7.24c-.67-2.88-1-5.83-1.46-8.75a.83.83 0 0 1 .07-.4ZM22.84 56.19a6.29 6.29 0 0 1 1.29 1.18c2.45 3.6 4.85 7.24 7.26 10.87q4.71 7.09 9.43 14.19c.89 1.35.44 2.75-1 3a1.84 1.84 0 0 1-2-1c-2.33-3.53-4.68-7.05-7-10.57l-9.17-13.79c-.28-.42-.57-.84-.81-1.28-.64-1.13.27-2.6 2-2.6ZM2.75 72.7l7 2.45a11.28 11.28 0 0 0 1.16.39c1 .24 1.25.81 1.16 1.81-.24 2.77-.37 5.55-.57 8.58L20.45 80l8.9-5.93 1 1.41c-1.06.72-2.09 1.43-3.14 2.12q-7.87 5.25-15.78 10.47a1.58 1.58 0 0 1-1.23.25 1.53 1.53 0 0 1-.44-1.2c.14-3 .32-5.93.54-8.89a1.13 1.13 0 0 0-.94-1.4c-2.84-.94-5.65-1.95-8.46-3-.36-.13-.84-.5-.87-.81a1.38 1.38 0 0 1 .63-1q9.36-6.29 18.76-12.49a1 1 0 0 1 .27-.1l.94 1.37ZM54.36 73.6c-1.13 1.63-1.24 2.18-.62 2.74s1.15.41 2.62-1a6.56 6.56 0 0 0 1.4.33h4.36c.89 0 1.26.39 1.26 1.25v8.73c0 1-.34 1.28-1.34 1.28h-15c-1 0-1.28-.34-1.28-1.33v-8.63c0-1 .24-1.28 1.28-1.29h4.55a.82.82 0 0 0 1-.67 1.8 1.8 0 0 1 1.77-1.41Zm7.3 11.58v-6.86H47.52v6.85Z\" \/>\n                <path fill=\"#89370B\" d=\"M70.2 52.37a15.14 15.14 0 0 1-2 5.95 75.3 75.3 0 0 1-8.69 12.28c-1.29 1.55-2.64 3.06-4 4.59-.12.14-.23.34-.39.4a6.44 6.44 0 0 1-1 .21c.05-.32 0-.74.16-1 1.19-1.43 2.46-2.8 3.66-4.23a80.24 80.24 0 0 0 9.05-12.6 13.92 13.92 0 0 0 2-5.56c0-.27.42-.5.64-.75ZM53.13 73.17l-.88.77c-1.06-1.25-2.14-2.48-3.17-3.74a69.89 69.89 0 0 1-8.17-11.6 46.93 46.93 0 0 1-2.07-5.25 2 2 0 0 1-.09-.65c0-.45-.05-1 .56-1 .22 0 .45.54.58.88a47.65 47.65 0 0 0 2.12 5.52c2.6 4.87 6.11 9.12 9.66 13.32ZM24.98 81.55l5.9-3.93 2.6 3.93Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\" style=\"color: #89370B\">Guiados<br>Turisticos<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours Especiales -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-especiales\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 232.77 227.83\">\n                <path fill=\"#4778FF\" d=\"M269.81 277.64a12.52 12.52 0 1 0 12.52 12.51 12.52 12.52 0 0 0-12.52-12.51Zm79.64 111.63a11.79 11.79 0 1 0 11.79 11.79 11.79 11.79 0 0 0-11.79-11.79Zm-145.28-4.51a18.08 18.08 0 0 1 7.31 8.6h121.13a18 18 0 0 1 5.4-7.26l-55.29-73.5h-27.1Zm157.72 79.6v-31.61h-9.49v38.92h21.91v-7.31Zm-25.79-6.88h-9.59l4.77-14.25Zm2.44 7.32 2.33 6.87h10l-14.09-38.92h-11l-14.08 38.92h9.92l2.38-6.87Zm-37.82 6.87h9.49v-38.92h-9.49Zm-41.08-19.51a20.77 20.77 0 0 0 2.49 10.25 17.86 17.86 0 0 0 7 7 20.24 20.24 0 0 0 10.08 2.59 19.49 19.49 0 0 0 11.87-3.63 17.39 17.39 0 0 0 6.59-9.95h-10.42a8.48 8.48 0 0 1-3.3 3.71 9.27 9.27 0 0 1-4.85 1.28 9.07 9.07 0 0 1-7.1-3.05 13.57 13.57 0 0 1 0-16.3 9 9 0 0 1 7.1-3.05 9.26 9.26 0 0 1 4.85 1.27 8.45 8.45 0 0 1 3.3 3.72h10.42a17.52 17.52 0 0 0-6.59-10 19.43 19.43 0 0 0-11.87-3.65 20.24 20.24 0 0 0-10.12 2.52 17.85 17.85 0 0 0-7 7 21 21 0 0 0-2.45 10.29Zm-16.14-11.81h14.36v-7.6H234v38.92h23.84v-7.59H243.5v-8.54h12.7v-7.32h-12.7ZM185 472.06a16.66 16.66 0 0 0 7.59-1.61 11.82 11.82 0 0 0 4.91-4.32 11.19 11.19 0 0 0 1.69-6 9.06 9.06 0 0 0-1.72-5.72 11.73 11.73 0 0 0-4.07-3.38 52.58 52.58 0 0 0-6.13-2.44 29.45 29.45 0 0 1-5.55-2.27 3.52 3.52 0 0 1-.72-5.57 4.11 4.11 0 0 1 2.78-.92 4.88 4.88 0 0 1 3.27 1.08 4 4 0 0 1 1.38 3h10.26a11 11 0 0 0-4.21-8.57q-3.94-3.07-10.37-3.08c-4.22 0-7.63 1-10.26 3.08a10.22 10.22 0 0 0-3.94 8.51 9.65 9.65 0 0 0 1.72 5.94 11.39 11.39 0 0 0 4.11 3.43 42.65 42.65 0 0 0 6.15 2.33 37.58 37.58 0 0 1 4 1.39 8 8 0 0 1 2.39 1.55 3.23 3.23 0 0 1 1 2.39 3.27 3.27 0 0 1-1.28 2.62 5.28 5.28 0 0 1-3.33 1 4.81 4.81 0 0 1-3.33-1.14 4.92 4.92 0 0 1-1.5-3.3h-10.09a11.24 11.24 0 0 0 2.14 6.54 12.56 12.56 0 0 0 5.4 4.11 20.15 20.15 0 0 0 7.71 1.35Zm31.88-21.9h-5.16v-9.76h5.16a5.67 5.67 0 0 1 4 1.28 5.54 5.54 0 0 1 0 7.2 5.67 5.67 0 0 1-4.05 1.28Zm15-4.88a12.94 12.94 0 0 0-1.61-6.49 11 11 0 0 0-4.83-4.43 17.33 17.33 0 0 0-7.87-1.61h-15.38v38.92h9.48v-14h5.88a16.71 16.71 0 0 0 8-1.72 11.3 11.3 0 0 0 4.77-4.52 12.45 12.45 0 0 0 1.54-6.15Zm-37.09-56a11.79 11.79 0 1 0 11.78 11.79 11.79 11.79 0 0 0-11.8-11.8Zm151.86-6.95a18.06 18.06 0 0 1 19.33 11h17.47a5.23 5.23 0 0 1 5.23 5.23v94.07a5.23 5.23 0 0 1-5.23 5.22H161.11a5.22 5.22 0 0 1-5.22-5.22v-94.04a5.23 5.23 0 0 1 5.22-5.23h17a18 18 0 0 1 16.66-11.23l49.73-69.75v-17.51a24.81 24.81 0 0 1 49.61-.62v18.23Z\" style=\"fill-rule:evenodd\" transform=\"translate(-155.89 -270.05)\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\">Tours <br>Especiales<\/p>\n        <\/a>\n    <\/div>\n\n    <!-- Tours con Descuentos -->\n    <div class=\"flex-none mr-2 w-28\">\n        <a href=\"https:\/\/www.machupicchuterra.com\/es\/tours-promociones\/\" class=\"py-4 rounded-md transition duration-150 ease-in-out flex flex-col justify-center items-center\">\n            <svg width=\"50px\" height=\"40px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 183.73 223.01\">\n                <path fill=\"#0433FD\" d=\"M46.23 76.46c-4.29-.84-8.74-1.2-12.82-2.62a37.19 37.19 0 0 1-18.48-14.08c-6.41-9.13-8-19.32-6-30a35.62 35.62 0 0 1 10.51-18.9 38.06 38.06 0 0 1 55.88 2.94 34.68 34.68 0 0 1 7.77 16.11c.33 1.89.71 3.77 1 5.66a2.4 2.4 0 0 0 2 2.23c3.1.81 6.17 1.72 9.29 2.48 5.68 1.39 11.41 2.62 17.08 4.07a16.6 16.6 0 0 1 11.11 8.54c2.38 4.46 5.09 8.74 7.62 13.11 2 3.4 3.86 6.85 5.82 10.25s3.94 6.67 5.88 10c1.41 2.43 2.75 4.9 4.16 7.32 2.62 4.51 5.3 9 7.92 13.51 1.91 3.3 3.75 6.65 5.65 10 2.6 4.53 5.24 9 7.84 13.56 2 3.51 3.95 7.06 6 10.55 1.89 3.26 3.78 6.51 5.78 9.7 3.63 5.79 4.83 11.88 2.1 18.32a17.56 17.56 0 0 1-7.29 8.21c-4.47 2.7-9 5.31-13.5 7.9s-9 5-13.5 7.62-8.69 5.16-13.06 7.7c-3.3 1.91-6.65 3.73-10 5.62s-6.69 3.89-10 5.83-6.89 4-10.37 6c-1.51.84-3.1 1.57-4.68 2.29-6.85 3.12-16 .44-20.35-5.73-1.91-2.75-3.46-5.76-5.17-8.65-1.87-3.14-3.75-6.27-5.59-9.43-2.57-4.42-5.09-8.87-7.65-13.29s-5.36-9.09-8-13.66c-1.94-3.36-3.79-6.76-5.72-10.12s-3.84-6.59-5.75-9.9c-1.51-2.63-3-5.29-4.48-7.91-2-3.34-4-6.64-5.91-10-1.84-3.16-3.64-6.33-5.45-9.5-2.07-3.61-4.21-7.18-6.14-10.86-1.58-3-2.73-6.24-1.81-9.74 1.17-4.46 2.49-8.88 3.72-13.32.8-2.92 1.57-5.86 2.37-8.78a7.77 7.77 0 0 1 .71-2.05 1.59 1.59 0 0 1 2.3-.59c2.55 1.12 5.18 2.08 7.82 3 4.49 1.55 9.16 1.55 13.84 1.66 1.37 0 2.77 1.26 4.05 2.1 5.87 3.83 12 4.5 18.47 1.71 7.37-3.18 10.87-9.22 11.22-16.85.27-5.74-2.21-10.73-6.67-14.54a17.76 17.76 0 0 0-12.9-4.56c-7.18.45-12.7 3.8-16 10.41a25.05 25.05 0 0 1-1.51 3.18 2.35 2.35 0 0 1-1.82 1c-3-.65-5.88-1.41-8.75-2.35a10 10 0 0 1-3.42-2.1 2.79 2.79 0 0 1-.79-2.29c.83-3.32 1.89-6.59 2.85-9.88.63-2.15 1.24-4.31 1.85-6.48.76-2.76 1.58-5.51 2.25-8.29 1-4.26 3.64-5.89 7.86-4.84 6.83 1.7 13.67 3.35 20.49 5.08 2.88.73 5.74 1.58 8.59 2.43 2.22.66 3.4-.29 2.92-2.51-1.53-7.18-4.68-13.47-10.35-18.31-6.47-5.51-13.86-8.39-22.48-7.93-9.44.5-17 4.61-23 11.78-6.8 8.15-8.41 17.65-6.09 27.64a30.09 30.09 0 0 0 12.51 18.05 31.26 31.26 0 0 0 24.95 5.11 30 30 0 0 0 13.7-7c.51-.44 1-.89 1.57-1.28 1.89-1.34 3.05-1.27 4.44.23 1.23 1.35 1.23 3-.3 4.49a33.29 33.29 0 0 1-10.77 7.18c-4.88 2-9.85 3.56-15.23 3.28Zm53.25 87h-.14v17.59c0 2.14-.1 4.29.11 6.41.24 2.42 3 4.93 5.4 5.39a7.45 7.45 0 0 0 8.83-7.37c-.11-1.85.06-3.72.13-5.58q.72-21.88 1.45-43.78.48-14.53 1-29.07c.1-2.67.16-5.31-1.1-7.77-2.13-4.12-8.14-4.34-10.55-2.24a9 9 0 0 0-3.24 7.08c-.08 8-.17 16-.45 24-.38 11.84-.95 23.57-1.44 35.38Zm40.46 7.84c11.7.45 21.57-9.72 21.38-21.56a21.501 21.501 0 0 0-43 .47c.1 11.21 9.77 21.65 21.62 21.13Zm-43.39-32.53c.34-10.41-8.4-20.88-20.42-21.43a21.5 21.5 0 1 0 20.42 21.43Z\" \/>\n                <path fill=\"#0433FD\" d=\"M.01 96.83c-.15-4 1.86-7.17 4.12-10.15q5.6-7.39 11.38-14.64a2.85 2.85 0 0 1 2.49-.87 2.42 2.42 0 0 1 1.38 3.08l-3 10.2q-2 6.72-3.91 13.44c-1.22 4.16-1.68 8.37.32 12.36 2.61 5.2 5.48 10.28 8.28 15.38q2.83 5.18 5.79 10.28c2 3.45 4 6.86 6 10.3 1.86 3.2 3.67 6.44 5.53 9.64 2.71 4.65 5.47 9.27 8.16 13.93 1.88 3.26 3.67 6.57 5.55 9.83 2.57 4.47 5.2 8.91 7.79 13.37 1.32 2.29 2.57 4.62 3.9 6.9 2.74 4.7 5.51 9.38 8.27 14.08a11.52 11.52 0 0 1 .72 1.34c.52 1.27.08 2.14-1.26 2.33-5.47.78-11 1.48-16.41 2.27-5.8.84-11.62 1.57-17.37 2.67-6.47 1.25-12.13-.09-16.8-4.7a14.09 14.09 0 0 1-4.33-8.21c-1.08-7.81-2.3-15.6-3.47-23.4s-2.32-15.49-3.46-23.24-2.21-15.5-3.38-23.24c-1.35-9-2.82-17.91-4.16-26.88-.75-5.35-1.41-10.72-2.13-16.07ZM139.91 143.44a6.8 6.8 0 0 1 6.82 6.69c0 3.28-3.49 6.76-6.8 6.74-2.74 0-6.77-2.51-6.68-6.88a6.46 6.46 0 0 1 6.66-6.55ZM75.18 145.47c-4.27.28-6.81-3.58-6.88-6.57-.09-3.59 3.33-6.82 7-6.8a6.77 6.77 0 0 1 6.54 6.61 6.49 6.49 0 0 1-6.66 6.76Z\" \/>\n            <\/svg>\n            <p class=\"text-center mt-2 mb-0\" style=\"color:#0433FD;\">Tours con<br>Descuentos<\/p>\n        <\/a>\n    <\/div>\n\n<\/div>\r\n<div class=\"container\">\r\n    <hr><br>\r\n    <h1 id=\"audios-cusco\" class=\"section-title-36 text-center m-b-20\">Paquetes tur\u00edsticos en promoci\u00f3n<\/h1>\r\n    <!-- <div class=\"text-center mb-6\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/logo-filtro-ofertas-machu-picchu.png\" class=\"lazy\" alt=\"Navidad Machupicchu Terra\" width=\"200\">\r\n    <\/div> -->\r\n    <p class=\"text-lg mb-8\"><strong>Descubre todos nuestros paquetes tur\u00edsticos en los principales tours por Machu Picchu, Cusco y el Per\u00fa<\/strong>. Disfruta del tour al Valle Sagrado de los Incas, el tour a la laguna Humantay, la Monta\u00f1a de los 7 Colores y Machu Picchu. Adem\u00e1s, vive la experiencia del tour a la isla de Uros, Amantan\u00ed y Taquile en Puno (lago Titicaca), el circuito m\u00e1gico del agua en Lima, Paracas y Huacachina en Ica, el nado con tortugas en la calurosa regi\u00f3n de Piura y m\u00e1s. Todos los tours est\u00e1n organizados para ofrecer la mejor de las experiencias al visitante. \u00a1Aprovecha los precios promocionales en todos nuestros tours!<\/p>\r\n    <!-- <div class=\"single-paragraph section\">\r\n        <div class=\"mtc-video-wrapper\">\r\n            [shortcodeelement id=\"o9Am3G\"]\r\n        <\/div>\r\n    <\/div> -->\r\n    <h2 class=\"section-title mb-6\">Paquete turisticos con Machu Picchu<\/h2>\r\n    <div class=\"wrapper-4\" style=\"min-height:175px;\">\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/tour3dias-card-tour.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">3 D\u00edas<\/span>\r\n                <\/div>\r\n                <div class=\"absolute top-3 right-2\">\r\n                    <span class=\"text-xs bg-opacity-75 px-2 py-1 border-1 rounded-md\" style=\"background: #e11d48;\">M\u00c1S POPULAR<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">650 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 618 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">City Tour + Valle Sagrado + Machu Picchu 3 d\u00edas<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/ciudad-cusco\/tour-machu-picchu-3-dias\/\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/tour-valle-sagrado-media-1.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">2 D\u00edas<\/span>\r\n                <\/div>\r\n                <div class=\"absolute top-3 right-2\">\r\n                    <span class=\"text-xs bg-opacity-75 px-2 py-1 border-1 rounded-md\" style=\"background: #e11d48;\">M\u00c1S POPULAR<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">430 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 410 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">Tour Valle Sagrado + Machupicchu<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/machu-picchu\/tour-valle-sagrado-machupicchu\/\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"wrapper-4\" style=\"min-height:175px;\">\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/paquete-4d-card1.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">3 D\u00edas<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">380 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 355 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">Tour Machu Picchu + Monta\u00f1a de Colores y Laguna Humantay<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/tour-machu-picchu-montana-colores-laguna-humantay\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/machupicchu-2d-card.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">2 D\u00edas<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">365 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 350 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">Tour Machu Picchu 2 d\u00edas<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/tour-machu-picchu-2d\/\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n    <\/div>\r\n    <br>\r\n    <h2 class=\"section-title mb-6\">Tours m\u00e1s populares en Per\u00fa<\/h2>\r\n    <div class=\"wrapper-4\" style=\"min-height:175px;\">\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/target-tour-taquile-media.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">2 D\u00edas<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">69 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 55 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">Tour Uros, Amantani y Taquile<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/puno\/tour-uros-amantani-taquile-2d\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/laguna-salinas-target-media.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">1 D\u00eda<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">45 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 35 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">Tour Laguna Salinas<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/arequipa\/tour-laguna-salinas\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/target-circuito-magico-agua-media.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">1\/2 D\u00eda<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">45 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 35 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">Tour Circuito M\u00e1gico del Agua<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/lima\/tour-circuito-magico-agua\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"wrapper-4\" style=\"min-height:175px;\">\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/nado-tortugas-mancora-1-card.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">1 D\u00eda<\/span>\r\n                <\/div>\r\n                <div class=\"absolute top-3 right-2\">\r\n                    <span class=\"text-xs bg-opacity-75 px-2 py-1 border-1 rounded-md\" style=\"background: #e11d48;\">M\u00c1S POPULAR<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">40 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 30 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">Tour nado con tortugas en Piura<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/piura\/tour-nado-tortugas-mancora\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/palcoyo-media-tarjeta.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">1 D\u00eda<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">55 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 45 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">Tour full day: Monta\u00f1a de colores Palcoyo<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/canchis\/tour-montana-colores-palcoyo-full-day\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n        <div class=\"relative rounded shadow-sm overflow-hidden mb-5 group\">\r\n            <div class=\"text-white rounded-md\">\r\n                <div class=\"card-img\">\r\n                    <img decoding=\"async\" class=\"lazy card-img loaded\" data-ll-status=\"loaded\" alt=\"Machupicchu\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/paracas-target.jpg\">\r\n                <\/div>\r\n                <div class=\"absolute bg-gradient-to-t from-black opacity-50 h-1\/2 w-full bottom-0\"><\/div>\r\n                <div class=\"absolute top-3 left-2 right-2\">\r\n                    <span class=\"text-xs bg-slate-900 bg-opacity-75 px-2 py-1 border-1 rounded-md\">1 D\u00eda<\/span>\r\n                <\/div>\r\n                <div class=\"absolute top-3 right-2\">\r\n                    <span class=\"text-xs bg-opacity-75 px-2 py-1 border-1 rounded-md\" style=\"background: #e11d48;\">M\u00c1S POPULAR<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:1.6rem;\">\r\n                    <h3 class=\"font-bold text-xs px-2\">Antes: <span class=\"\">88 USD<\/span><\/h3>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:0.25rem;\">\r\n                    <span class=\"font-bold text-xl rounded px-2\" style=\"background: #1e40af;\">Ahora: 75 USD<\/span>\r\n                <\/div>\r\n                <div class=\"absolute left-4 right-4\" style=\"bottom:2.8rem;\">\r\n                    <h3 class=\"font-bold text-base\">Tour Ica Full Day \u2013 Paracas y Huacachina<\/h3>\r\n                <\/div>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/ica\/tour-ica-paracas-huacachina\" target=\"_self\" class=\"card-link\" rel=\"noopener\"><\/a>\r\n        <\/div>\r\n    <\/div>\r\n    <br>\r\n    <h2 class=\"section-title mb-6\">Precios de los paquetes tur\u00edsticos en promoci\u00f3n<\/h2>\r\n    <p class=\"f-z-16\">Los tours promocionales de Machupicchu Terra  son servicios todo incluido que ofrecen: recojo, transporte completo, gu\u00eda profesional, entrada a todos los lugares a visitar y m\u00e1s. Los tours son 100% confiables y bien organizados.<\/p>\r\n    <div class=\"overflow-x-auto\">\r\n        <table class=\"min-w-[700px]\">\r\n            <thead>\r\n                <tr>\r\n                    <th class=\"bg-primary-500 text-white\">\r\n                        <div class=\"bg-primary-500 text-white__text text-center\" style=\"color:white;\">D\u00edas<\/div>\r\n                    <\/th>\r\n                    <th class=\"bg-primary-500 text-white\">\r\n                        <div class=\"bg-primary-500 text-white__text text-center\" style=\"color:white;\">Tours en Cusco<\/div>\r\n                    <\/th>\r\n                    <th class=\"bg-primary-500 text-white\">\r\n                        <div class=\"bg-primary-500 text-white__text text-center\" style=\"color:white;\">Precio habitual<\/div>\r\n                    <\/th>\r\n                    <th class=\"bg-primary-500 text-white\">\r\n                        <div class=\"bg-primary-500 text-white__text text-center\" style=\"color:white;\">PRECIO PROMOCIONAL<\/div>\r\n                    <\/th>\r\n                <\/tr>\r\n            <\/thead>\r\n            <tbody>\r\n                <tr>\r\n                    <td class=\"text-center\">1\/2 d\u00eda<\/td>\r\n                    <td class=\"text-center\"><a href=\"https:\/\/www.machupicchuterra.com\/es\/arequipa\/tour-laguna-salinas\/\">Tour Laguna Salinas en Arequipa Medio D\u00eda<\/a><\/td>\r\n                    <td class=\"text-center\">45 USD<\/td>\r\n                    <td class=\"text-center\">35 USD<\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center\">1\/2 d\u00eda<\/td>\r\n                    <td class=\"text-center\"><a href=\"https:\/\/www.machupicchuterra.com\/es\/lima\/tour-circuito-magico-agua\/\">Tour Circuito M\u00e1gico del Agua en Lima medio d\u00eda<\/a><\/td>\r\n                    <td class=\"text-center\">45 USD<\/td>\r\n                    <td class=\"text-center\">35 USD<\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center\">1\/2 d\u00eda<\/td>\r\n                    <td class=\"text-center\"><a href=\"https:\/\/www.machupicchuterra.com\/es\/piura\/tour-nado-tortugas-mancora\/\">Tour Nado con tortugas en M\u00e1ncora 1 d\u00eda <\/a><\/td>\r\n                    <td class=\"text-center\">40 USD<\/td>\r\n                    <td class=\"text-center\">30 USD<\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center\">1 D\u00eda<\/td>\r\n                    <td class=\"text-center\"><a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/canchis\/tour-montana-colores-palcoyo-full-day\/\">Tour Monta\u00f1a de Colores de Palcoyo en Cusco 1 d\u00eda <\/a><\/td>\r\n                    <td class=\"text-center\">55 USD<\/td>\r\n                    <td class=\"text-center\">45 USD<\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center\">1 D\u00eda<\/td>\r\n                    <td class=\"text-center\"><a href=\"https:\/\/www.machupicchuterra.com\/es\/ica\/tour-ica-paracas-huacachina\/\">Tour Ica, Paracas y Huacachina 1 d\u00eda desde Lima <\/a><\/td>\r\n                    <td class=\"text-center\">88 USD<\/td>\r\n                    <td class=\"text-center\">75 USD<\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center\">2 D\u00edas<\/td>\r\n                    <td class=\"text-center\"><a href=\"https:\/\/www.machupicchuterra.com\/es\/puno\/tour-uros-amantani-taquile-2d\/\">Tour Uros, Amantani y Taquile 2 d\u00edas 1 noche<\/a><\/td>\r\n                    <td class=\"text-center\">69 USD<\/td>\r\n                    <td class=\"text-center\">55 USD<\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center\"><b>2 D\u00edas<\/b><\/td>\r\n                    <td class=\"text-center\"><b><a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/urubamba\/machu-picchu\/tour-valle-sagrado-machupicchu\/\">Tour Valle Sagrado con Machu Picchu 2 d\u00edas + Hotel y Buffet<\/a><\/b><\/td>\r\n                    <td class=\"text-center\"><b>430 USD<\/b><\/td>\r\n                    <td class=\"text-center\"><b>405 USD<\/b><\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center\"><b>2 D\u00edas<\/b><\/td>\r\n                    <td class=\"text-center\"><b><a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/tour-machu-picchu-2d\/\">Tour Machu Picchu 2 d\u00edas Todo Incluido<\/a><\/b><\/td>\r\n                    <td class=\"text-center\"><b>360 USD<\/b><\/td>\r\n                    <td class=\"text-center\"><b>345 USD<\/b><\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center\"><b>3 D\u00edas<\/b><\/td>\r\n                    <td class=\"text-center\"><b><a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/tour-machu-picchu-montana-colores-laguna-humantay\/\">Tour Machupicchu + Monta\u00f1a 7 colores + Laguna Humantay 3 d\u00edas<\/a><\/b><\/td>\r\n                    <td class=\"text-center\"><b>380 USD<\/b><\/td>\r\n                    <td class=\"text-center\"><b>350 USD<\/b><\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center\"><b>4 D\u00edas<\/b><\/td>\r\n                    <td class=\"text-center\"><b><a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/ciudad-cusco\/tour-machu-picchu-3-dias\/\">City Tour + Valle Sagrado + Machu Picchu 4 D\u00edas VIP + Hotel<\/a><\/b><\/td>\r\n                    <td class=\"text-center\"><b>620 USD<\/b><\/td>\r\n                    <td class=\"text-center\"><b>595 USD<\/b><\/td>\r\n                <\/tr>\r\n            <\/tbody>\r\n        <\/table>\r\n    <\/div>\r\n    <br>\r\n    <br>\r\n    <h2 class=\"section-title m-b-20\">Las principales actividades para aprovechar las promociones<\/h2>\r\n    <p class=\"f-z-16\" style=\"margin-bottom: 30px;\">Las promociones con que cuenta Machupicchu Terra son una opci\u00f3n ideal para visitar Cusco y todos sus atractivos tur\u00edsticos, los cuales nos sumergen en aventuras y experiencias inolvidables. Descubre cu\u00e1les son las mejores opciones que tienes para tu viaje corto por la ciudad de los incas.<\/p>\r\n    <div class=\"overflow-x-auto\">\r\n        <table class=\"min-w-[700px]\">\r\n            <thead class=\"text-center\">\r\n                <tr>\r\n                    <th class=\"bg-primary-500 text-white\" colspan=\"2\">\r\n                        <div class=\"bg-primary-500 text-white__text\" style=\"color:white;\">Las principales actividades para aprovechar las promociones<\/div>\r\n                    <\/th>\r\n                <\/tr>\r\n                <tr>\r\n                    <th class=\"bg-primary-500 text-white\">\r\n                        <div class=\"bg-primary-500 text-white__text\" style=\"color:white;\">Actividad<\/div>\r\n                    <\/th>\r\n                    <th class=\"bg-primary-500 text-white\">\r\n                        <div class=\"bg-primary-500 text-white__text\" style=\"color:white;\">Descripci\u00f3n<\/div>\r\n                    <\/th>\r\n                <\/tr>\r\n            <\/thead>\r\n            <tbody>\r\n                <tr>\r\n                    <td class=\"text-center px-3\"><b>Machu Picchu Full Day<\/b><\/td>\r\n                    <td class=\"px-3\">Conoce una de las Maravillas del mundo, Machu Picchu, en un viaje inolvidable de un d\u00eda completo. Contar\u00e1s con todos los servicios incluidos para que s\u00f3lo tengas que preocuparte en disfrutarlo.<\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center px-3\"><b>Tour Valle Sagrado VIP<\/b><\/td>\r\n                    <td class=\"px-3\">El Valle Sagrado posee los pueblos m\u00e1s ic\u00f3nicos de Cusco, llenos de historia, ciudades incas y mucha naturaleza. El tour te permite conocer los lugares m\u00e1s importantes como Ollantaytambo, Pisac, Chinchero, Maras y Moray. <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center px-3\"><b>Tour Valle Sagrado VIP<\/b><\/td>\r\n                    <td class=\"px-3\">El Valle Sagrado posee los pueblos m\u00e1s ic\u00f3nicos de Cusco, llenos de historia, ciudades incas y mucha naturaleza. El tour te permite conocer los lugares m\u00e1s importantes como Ollantaytambo, Pisac, Chinchero, Maras y Moray. <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center px-3\"><b>Tour Monta\u00f1a 7 Colores<\/b><\/td>\r\n                    <td class=\"px-3\">Una de las los atractivos naturales m\u00e1s hermosos de Cusco es la Monta\u00f1a de 7 Colores. D\u00e9jate envolver por paisajes rodeados de colores que asemejan a un arco\u00edris, te espera una vista \u00fanica en el mundo desde las alturas.<\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td class=\"text-center px-3\"><b>Tour Laguna Humantay<\/b><\/td>\r\n                    <td class=\"px-3\">Imagina estar rodeado de monta\u00f1as nevadas y poder apreciar debajo de ellas una laguna de color turquesa, un paisaje natural que te sumergir\u00e1 en un sue\u00f1o. Definitivamente es una de las mejores aventuras de un d\u00eda que encontrar\u00e1s en Cusco.<\/td>\r\n                <\/tr>                \r\n                <tr>\r\n                    <td class=\"text-center px-3\"><b>City Tour Cusco<\/b><\/td>\r\n                    <td class=\"px-3\">Si deseas recorrer todos lugares m\u00e1s importantes de la ciudad de Cusco en s\u00f3lo medio d\u00eda, este tour es para ti. Conocer\u00e1s las construcciones de Sacsayhuam\u00e1n, el templo Qoricancha, la Catedral, Qenqo, Pucapucara y Tambomachay.<\/td>\r\n                <\/tr>\r\n            <\/tbody>\r\n        <\/table>\r\n    <\/div>\r\n    <br>\r\n    <h2 class=\"section-title m-b-20 text-center\">\u00bfQu\u00e9 atractivos tur\u00edsticos ver en Cusco?<\/h2>\r\n    <p class=\"f-z-16\" style=\"margin-bottom: 30px;\">Cusco es uno de los mejores atractivos tur\u00edsticos del mundo. Machu Picchu no es solo el mejor destino tur\u00edstico del Cusco sino tambi\u00e9n del Per\u00fa. Adem\u00e1s, en Cusco se puede conocer pueblos andinos con mucha historia, paisajes naturales hermosos y templos incas de gran importancia.<\/p>\r\n    <ul class=\"text-justify\">\r\n        <li><b>Sitios arqueol\u00f3gicos incas<\/b> \u2013 Cusco es reconocida como \u2018capital arqueol\u00f3gica de Am\u00e9rica\u2019. Esto debido a la inmensa historia de la que la capital del imperio inca. En toda la regi\u00f3n existen monumentos incas como Pisac, Sacsayhuam\u00e1n, Coricancha, Ollantaytambo y, por supuesto, la ciudadela de Machu Picchu.<\/li>\r\n        <li><b>Paisajes naturales hermosos<\/b> \u2013 Cusco est\u00e1 en plena Cordillera de los Andes en Per\u00fa. La presencia de esta inmensa franja de monta\u00f1as y nevados convierte a Cusco en una de las geograf\u00edas m\u00e1s hermosas, con altos nevados como el Salkantay y el Ausangate. All\u00ed se puede fotografiar lugares hermosos como la laguna Humantay o la Monta\u00f1a de los 7 Colores.<\/li>\r\n        <li><b>Pueblos andinos con cultura y tradici\u00f3n<\/b> \u2013 Cusco fue la capital del imperio de los incas y de decenas de culturas milenarias. A\u00fan hoy, despu\u00e9s de cientos de a\u00f1os, Cusco respira cultura por doquier: danzas, religi\u00f3n, cer\u00e1mica, textiler\u00eda y m\u00e1s. Algunos de los pueblos m\u00e1s famosos son Chinchero, Ollantaytambo y Pisac.<\/li>\r\n    <\/ul>\r\n    <br>\r\n    <h2 class=\"section-title m-b-20 text-center\">As\u00ed es el tour a la Monta\u00f1a 7 Colores del Cusco<\/h2>\r\n    <p class=\"f-z-16\" style=\"margin-bottom: 30px;\">El Vinicunca o Monta\u00f1a 7 Colores es el segundo atractivo tur\u00edstico m\u00e1s visitado del Cusco, tan solo despu\u00e9s de Machu Picchu. El tour de 1 d\u00eda es la mejor opci\u00f3n para conocer este espectacular paisaje natural. Conoce c\u00f3mo es el tour, qu\u00e9 incluye, cu\u00e1nto cuesta y m\u00e1s.<\/p>\r\n    <div class=\"single-paragraph section\" style=\"margin: 0 auto;\">\r\n        <div class=\"mtc-video-wrapper\">\r\n            <span class=\"js-elemento-item element-item-ajax\" data-iden=\"plbV1F\" style=\"display:none;\">{\"iden\":\"plbV1F\",\"titulo\":\"Video: Monta\\u00f1a 7 Colores\",\"contenido\":\"\\u003Cdiv class=\\u0022mtc-video-wrapper\\u0022\\u003E\\n    \\u003Cdiv class=\\u0022mtc-video-youtube\\u0022\\u003E\\n        \\u003Ciframe class=\\u0022mtc-video__iframe\\u0022 src=\\u0022https:\\\/\\\/www.youtube.com\\\/embed\\\/QR50BVhoZQs?vq=hd720?&amp;enablejsapi=1&amp;modestbranding=1&amp;ytp-pause-overlay=0&amp;rel=0&amp;showinfo=0&amp;controls=1&amp;autoplay=0\\u0022\\u003E\\u003C\\\/iframe\\u003E                \\n    \\u003C\\\/div\\u003E\\n\\u003C\\\/div\\u003E\",\"css\":\"\",\"js\":\"\",\"ajax\":\"1\"}<\/span>\r\n        <\/div>\r\n    <\/div>\r\n    <br>\r\n    <br>\r\n    <h2 class=\"section-title m-b-20 text-center\">\u00bfPor qu\u00e9 elegir a Machupicchu Terra para un tour para Cusco y el Per\u00fa?<\/h2>\r\n    <p class=\"f-z-16\" style=\"margin-bottom: 30px;\">En Machupicchu Terra somos un operador tur\u00edstico con sede en la ciudad del Cusco, la capital arqueol\u00f3gica de Am\u00e9rica. Ofrecemos excelentes tours por los principales atractivos tur\u00edsticos de la regi\u00f3n. Todos nuestros tours son servicios todo incluidos. \u00a1Conoce qu\u00e9 incluyen!<\/p>\r\n    <p class=\"f-z-16\" style=\"margin-bottom: 30px;\">Todos nuestros tours incluyen:<\/p>\r\n    <div class=\"w-full md:w-[74%] inline-block pl-4\">\r\n        <ul class=\"flex flex-wrap list-unstyled\">\r\n            <li class=\"flex items-center w-full md:w-1\/2 my-2\">\r\n                <div class=\"w-8 h-8 flex-none\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"32\" class=\"inline-block\" data-name=\"Capa 1\" viewBox=\"0 0 315.93 398.12\">\r\n                        <path fill=\"currentColor\" d=\"M167.58 160.17c-8.7 17.15-6 35.54-6.2 53.55-.28 21-.13 42 0 63 0 3.49-.58 5.73-4.23 7.36a12.37 12.37 0 0 0-7.37 11.65c-.16 19.16-.22 38.33 0 57.49a13.82 13.82 0 0 0 12.44 13.49c3.35.41 6.79.07 10.53.07-1.26-4.23-2.91-6.57-7.37-6.6-6.14 0-9.07-3.27-9.1-9.44q-.12-26.25 0-52.49c0-6.54 3.05-9.55 9.55-9.56q44.25-.09 88.49 0c6.58 0 9.58 2.89 9.62 9.44q.17 26.49 0 53c0 6-3 8.81-8.95 9.09a69.16 69.16 0 0 1-9 0c-4.47-.37-6.77 1.7-7.86 6.1 7.63 0 15.08.68 22.34-.21 5.64-.7 10.14-7.33 10.19-13.4.15-18.83.29-37.67-.16-56.49-.09-3.41-2.34-7.34-4.76-10a11 11 0 0 1-3.34-8.3q.15-41.75 0-83.5a90.89 90.89 0 0 0-1.34-17.39c-1.1-5.44-3.55-10.6-5.45-16 .2-.08.67-.46 1-.38 11.34 2.53 22.88 4.39 33.92 7.86s15.4 13.06 16.89 23.51c2.57 18 5.61 36 6.15 54.07 1.45 48.29 1.7 96.61 2.34 144.93.09 7-.12 7-7.17 7.05h-177c-6.41 0-6.49 0-6.62-6.61q-1.22-65.73-2.39-131.47c-.21-11.5-.72-23-.78-34.48 0-3.67-1.15-4.92-4.83-5-14.49-.44-29-1.11-43.45-1.8s-26-5.93-31.41-20.36c-2.52-6.69-5-13.43-7-20.28A1224.84 1224.84 0 0 1 1.47 32.19 98.15 98.15 0 0 1 0 16.8C-.1 8.28 3.42 3.58 10.75 1.44c10.17-3 16.82-1.61 20.83 6.31 4.25 8.39 7.06 17.53 10.19 26.45q19.65 56.06 39 112.21c2.77 8.05 8.22 12.05 16.3 13.34 21.66 3.47 43.32 5.18 65.05.55a30.53 30.53 0 0 1 3.45-.52 9 9 0 0 1 2.01.39Zm37.53 212.88c18.18 0 32.59-14.16 32.57-32.11a32.36 32.36 0 1 0-32.57 32.11Zm39.09-64.35c2 0 4-.16 6 0 3.74.35 5.17-1.29 4.74-4.91a14.13 14.13 0 0 1 0-3c.39-3.6-1.11-5.2-4.79-5.05a88.57 88.57 0 0 1-10.93 0c-4.49-.35-5.72 1.66-5.61 5.85.19 7.1 0 7.1 7.16 7.08Z\" \/>\r\n                        <path fill=\"currentColor\" d=\"M213.77 137.85a63.46 63.46 0 1 1 63.76-63.27 63.39 63.39 0 0 1-63.76 63.27ZM250.2 230.14c0 15.49-.1 31 .06 46.46 0 4-1.09 5.61-5.35 5.55-16.31-.2-32.63-.11-48.95-.08-2.68 0-4.46-.25-5.51-3.53-.59-1.85-3.84-4-5.81-3.94-2.24.09-4.47 2.42-6.54 4a21.13 21.13 0 0 0-2.88 3.27c-.6-1.37-1.73-2.74-1.73-4.11-.08-31.31-.17-62.61.05-93.91.06-9.74 4.38-18 11-25a5.81 5.81 0 0 1 3.36-1.87c12.72-.88 25.25-3.52 38.26-1.51 12.08 1.87 18.38 9.16 22.24 19.45 1.41 3.78 1.61 8.16 1.66 12.28.19 14.31.08 28.63.08 42.95ZM225.94 340.7a20.62 20.62 0 0 1-41.23.31 20.62 20.62 0 0 1 41.23-.31Zm-5-1.94c-.43-5.66-2.59-9.37-7.11-11.28-1.06-.44-2.61.25-3.93.42a26.4 26.4 0 0 0 1.63 3.54c1.51 2.36 3.15 4.66 4.8 6.94.76 1 1.65 2 2.48 3Z\" \/>\r\n                    <\/svg>\r\n                <\/div>\r\n                <div class=\"ml-3\">\r\n                    <span class=\"block f-z-14\">Recojo desde la puerta del hotel del turista.<\/span>\r\n                <\/div>\r\n            <\/li>\r\n            <li class=\"flex items-center w-full md:w-1\/2 my-2\">\r\n                <svg width=\"24\" height=\"32\" class=\"inline-block\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Capa 1\" viewBox=\"0 0 365.27 374.64\">\r\n                    <path fill=\"currentColor\" d=\"M54.85 341.76c-6.42-.05-7.2-4.63-7.69-8.94-2.14-18.85-4.64-37.69-6-56.61-3.64-51.74-4.74-103.57-4-155.43.07-5.92-4.21-5.14-8.2-6.74 0 3 .07 5.46 0 7.89-.29 9.49-.51 19-1 28.47-.33 6.87-2.36 8.69-9.24 9.07-.67 0-1.33.05-2 .05-13 0-16.32-2.58-16.63-15.37-.29-12 .31-24 1.07-35.88.42-6.52 2.65-8.91 9.22-8.74 8.85.23 17.67 1.85 26.89 2.93.57-10.82.78-22.8 1.92-34.68 1.22-12.74 3.2-25.41 5.06-38.08.9-6.08 4.52-9.84 10.36-12.23 20-8.18 40.88-11.77 62.11-14a656.46 656.46 0 0 1 112.33-1.91c25.27 1.66 50.29 4.64 74.61 12.65 12.4 4.09 18.73 11.34 19.63 24.2 1.4 19.92 3.18 39.82 4.77 59.73.14 1.8 0 3.62 0 5.57 5.38-1.34 10.31-2.79 15.34-3.73a42.25 42.25 0 0 1 10.4-.72c8.28.56 10.64 2.3 11 10.47.63 13.11.38 26.26.3 39.39 0 5.56-2.87 9-8.68 9.65-1.15.12-2.27.53-3.42.64-12.22 1.17-15.2-1.22-15.72-13.39-.38-8.82-.26-17.67-.35-26.5v-4.81c-7.63.66-8.47 1.56-8.4 7.9.68 58.88-1 117.68-5.72 176.38-.95 11.92-3.1 23.75-4.68 35.62-.53 4-2.1 7-7.16 7.17v20.06c-.06 8.19-4.52 12.73-12.58 12.79q-9.75.07-19.5 0c-7.84-.07-12.32-4.5-12.55-12.38-.08-2.67 0-5.34 0-8v-7.63H99.18v15c-.06 8.93-4.21 13-13.25 13h-18.5c-8.33-.07-12.49-4.27-12.56-12.7-.06-6.5-.02-13-.02-20.16Zm131.07-108.68c36.48-1.71 76.1-3.22 115.68-5.61 16.35-1 14.43.31 15.23-16.18 1.55-31.61 1.83-63.3 2.07-95 .08-10.11-1.67-20.22-2.54-30.34-.39-4.57-3-7.23-7.18-8.59-2.21-.73-4.4-1.53-6.66-2.06-24.31-5.67-49.13-7.34-73.91-7.66-37-.48-74-.19-110.94 1.06-17.88.6-35.78 3.44-53.44 6.54-14 2.46-15.56 4.84-16.13 19-.9 22.48-1.92 45-1.64 67.46.23 19.8 2.21 39.57 3.32 59.36.21 3.82 2.25 5.16 5.69 5.5 5.14.51 10.24 1.56 15.38 1.79 37.28 1.64 74.58 3.09 115.07 4.73Zm-3.2-182.42c24 0 48-.1 71.92.09 4.84 0 7.5-2.07 7.81-6.39a125.11 125.11 0 0 0 0-18.77c-.34-4.49-3.44-6.85-8.09-7.3-10.26-1-20.48-2.62-30.75-3.26a589.18 589.18 0 0 0-113.12 3.44c-4 .53-6.83 2.62-7.14 6.42a133.29 133.29 0 0 0-.21 19.27c.28 4.6 3.17 6.6 8.16 6.56 23.83-.14 47.64-.06 71.42-.06Zm-53.86 237.2a15.19 15.19 0 0 0-30.37-.17 15.19 15.19 0 1 0 30.37.17Zm-36.41-.13a15.2 15.2 0 0 0-15.35-15 15.56 15.56 0 0 0-14.94 15.12 15.29 15.29 0 0 0 15.23 15.21 15 15 0 0 0 15.06-15.33Zm210.88-.07a15.07 15.07 0 0 0-15.35-15 15.51 15.51 0 0 0-14.83 15.18 15.21 15.21 0 0 0 15.27 15.14 14.8 14.8 0 0 0 14.91-15.32Zm-36.17.46a15.08 15.08 0 1 0-30.16-.23 15.08 15.08 0 0 0 30.16.23Zm-84.44-4.28c13.33 0 26.67.06 40-.09 1.45 0 2.9-1.26 4.34-1.93-1.47-.7-2.94-2-4.41-2q-39.75-.18-79.51 0c-1.44 0-2.88 1.37-4.32 2.1 1.46.64 2.92 1.83 4.39 1.85 13.12.14 26.29.07 39.51.07Zm.42 12.1c13.16 0 26.32.06 39.49-.08 1.48 0 2.95-1.22 4.43-1.87-1.44-.73-2.88-2.1-4.33-2.1q-39.73-.19-79.48 0c-1.48 0-2.95 1.31-4.42 2 1.44.68 2.87 1.94 4.31 2 13.28.11 26.58.05 39.95.05Z\" \/>\r\n                <\/svg>\r\n                <div class=\"ml-3\">\r\n                    <span class=\"block f-z-14\">Transporte tur\u00edstico completo (en amplio minivan).<\/span>\r\n                <\/div>\r\n            <\/li>\r\n            <li class=\"flex items-center w-full md:w-1\/2 my-2\">\r\n                <div class=\"w-8 h-8 flex-none\">\r\n                    \r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 256 256\" class=\"inline-block\">\r\n                <path fill=\"currentColor\" d=\"M256,137.594l-25.373-16.713l-25.963,28.194c-2.029,2.206-5.332,2.541-7.744,0.917l-16.186-9.476\r\n                    l-26.58,32.221l-1.074-17.486l21.637-26.227c1.826-2.262,5.082-2.908,7.668-1.393l16.729,9.794l26.143-28.389l0.008,0.009\r\n                    c1.947-2.119,5.197-2.577,7.678-0.946L256,123.288V137.594L256,137.594z\"><\/path>\r\n                <path fill=\"currentColor\" d=\"M91.668,67.837l17.654,28.559l24.174,0.694l-1.506-24.524c-0.131-2.2,1.549-4.09,3.75-4.219\r\n                    c2.199-0.129,4.088,1.55,4.219,3.75l1.549,25.223c15.834,0.454,15.588,19.057,1.232,20.066l6.516,106.063l37.789-9.325\r\n                    c0.484-0.119,0.969-0.145,1.438-0.086v-0.008l31.096,3.887l31.125-10.699c2.088-0.716,4.361,0.396,5.078,2.484\r\n                    c0.146,0.43,0.217,0.867,0.217,1.297H256v41c0,2.209-1.791,4-4,4H4c-2.209,0-4-1.791-4-4c0-2.098,1.613-3.818,3.668-3.986\r\n                    l12.603-1.801c-0.924-1.706-1.525-4.58-1.281-6.547l13.25-106.475L7.1,128.748c-4.5-0.947-7.738-4.714-6.99-9.252\r\n                    c1.674-10.15,7.818-33.136,10.479-42.943c5.103-18.82,30.029-27.282,35.09-15.33l0.082,0.201\r\n                    C59.221,45.07,80.779,50.225,91.668,67.837L91.668,67.837z M36.609,243.328l61.412-8.551c-0.352-0.729-0.625-1.508-0.816-2.329\r\n                    l-11.404-49.132l-25.889-22.707c-1.148,0.245-2.326,0.425-3.527,0.533L36.609,243.328L36.609,243.328z M118.842,230.955\r\n                    l22.535-5.561l-6.6-107.447l-31.441,2.188c-3.072,0.214-6.195-1.021-8.318-3.569l-10.047-12.049\r\n                    c-0.356,1.589-0.697,3.188-1.025,4.797c-1.77,8.682-3.143,17.621-4.104,26.825l29.059,30.638c1.814,1.708,3.062,4.04,3.379,6.71\r\n                    l6.539,55.222C118.904,229.429,118.904,230.233,118.842,230.955L118.842,230.955z M81.904,0c-12.703,0-23,10.297-23,23\r\n                    c0,12.702,10.297,23,23,23s23-10.298,23-23C104.904,10.297,94.607,0,81.904,0L81.904,0z\"><\/path>\r\n            <\/svg>\r\n        \r\n                <\/div>\r\n                <div class=\"ml-3\">\r\n                    <span class=\"block f-z-14\"><b>Gu\u00eda de turismo profesional (en espa\u00f1ol o ingl\u00e9s).<\/b><\/span>\r\n                <\/div>\r\n            <\/li>\r\n            <li class=\"flex items-center w-full md:w-1\/2 my-2\">\r\n                <div class=\"w-8 h-8 flex-none\">\r\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"32\" class=\"inline-block\" data-name=\"Capa 1\" viewBox=\"0 0 86.34 119.06\">\r\n                        <path fill=\"currentColor\" d=\"M43.66 43.42c-2.19.73-3.79 1.5-4.42 3.89-1.37 5.15-3.11 10.2-4.6 15.32-.8 2.74-2.3 4.57-5.2 5.22-.52.12-1.09 1.06-1.23 1.71-1.62 7.25-3.15 14.51-4.71 21.77l-3.91 18.17c-.5-.3-.9-.52-1.29-.78a7.27 7.27 0 0 0-10.84 3 1.73 1.73 0 0 1-2.43 1.1 6.39 6.39 0 0 1-4.88-7.65q2.64-12.75 5.5-25.45a6.36 6.36 0 0 1 7.19-4.8c2.87.48 5.7 1.16 8.56 1.74.65.14 1.31.21 2.19.35.67-3.22 1.34-6.3 1.9-9.39.07-.41-.35-1-.7-1.37a5.87 5.87 0 0 1-1.44-6.34q2.81-9.17 5.61-18.32a10.2 10.2 0 0 1 4.93-6.27q7.95-4.29 16-8.38a9.36 9.36 0 0 1 8.77-.35 9.71 9.71 0 0 1 5.2 10.21c-1.34 9.46-2.64 18.92-4 28.37a5.25 5.25 0 0 0 1.89 5.13c2.83 2.42 5.61 4.89 8.46 7.29a11.83 11.83 0 0 1 4.36 8.7c.54 8.36 1.26 16.7 1.79 25.06.32 5-3.47 8.39-8.21 7.58a6.93 6.93 0 0 1-5.63-6.53c-.6-7.67-1.12-15.34-1.78-23a4.35 4.35 0 0 0-1.34-2.61q-6.57-5.85-13.34-11.51c-4.2-3.52-5.67-7.94-4.88-13.28.82-5.52 1.58-11.05 2.35-16.58.07-.61.08-1.22.13-2Z\" \/>\r\n                        <path fill=\"currentColor\" d=\"M41.15 74.95c3.55 3.18 6.93 6.15 10.22 9.23a2.42 2.42 0 0 1 .52 2q-4.31 14-8.79 28a6.94 6.94 0 0 1-13.29-4c2.25-7.27 4.75-14.46 7.09-21.71 1.24-3.82 2.36-7.69 3.54-11.54.17-.56.41-1.24.71-1.98ZM48.41 11.24A11.2 11.2 0 0 1 59.6 0a11.07 11.07 0 0 1 11.05 11.11c.16 6.7-5.68 11.27-11.12 11.25a11.18 11.18 0 0 1-11.12-11.12ZM66.25 41.75c6.32 4.87 12.31 9.37 18.16 14a5.58 5.58 0 0 1 .83 7.58c-1.7 2.32-5.08 3.29-7.45 1.63-4.37-3-8.52-6.37-12.74-9.62a1.45 1.45 0 0 1-.51-1.09c.52-4.01 1.09-8.04 1.71-12.5ZM18.32 114.77a4.24 4.24 0 0 1-8.47 0 4.31 4.31 0 0 1 4.22-4.31 4.26 4.26 0 0 1 4.25 4.31Z\" \/>\r\n                    <\/svg>\r\n                <\/div>\r\n                <div class=\"ml-3\">\r\n                    <span class=\"block f-z-14\">Traslado al hotel del turista al final del tour.<\/span>\r\n                <\/div>\r\n            <\/li>\r\n            <li class=\"flex items-center w-full md:w-1\/2 my-2\">\r\n                <div class=\"w-8 h-8 flex-none\">\r\n                    \r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 256 256\" class=\"inline-block\">\r\n                <path fill=\"currentColor\" d=\"M4.826,94.117l5.166-1.418V53.984c0-3.314,2.686-6.001,6-6.001h156.924l46.52-12.768\r\n                    c3.183-0.873,6.523,0.997,7.337,4.196l2.178,8.572h11.057c3.314,0,6,2.687,6,6.001v61.649l9.813,38.919\r\n                    c0.834,3.306-1.362,6.43-4.647,7.332l-5.166,1.417v10.707c0,3.315-2.687,6.001-6,6.001h-11.71l-1.315,19.403\r\n                    c-0.23,3.391-3.149,5.769-6.519,5.568l-103.801-6.179l-80.099,21.984c-3.182,0.873-6.53-0.995-7.336-4.196L20,180.01h-4.007\r\n                    c-3.314,0-6-2.686-6-6.001v-33.665l-9.814-38.895C-0.658,98.133,1.539,95.019,4.826,94.117L4.826,94.117z M133.999,74.988h80.006\r\n                    V86.99h-80.006V74.988L133.999,74.988z M133.999,141.002h63.006v12.004h-63.006V141.002L133.999,141.002z M133.999,118.998\r\n                    h80.006v12.003h-80.006V118.998L133.999,118.998z M133.999,96.992h80.006v12.004h-80.006V96.992L133.999,96.992z M216.291,180.01\r\n                    h-31.16l-32.545,8.933l62.846,3.741L216.291,180.01L216.291,180.01z M139.965,180.01H32.347l6.966,27.625L139.965,180.01\r\n                    L139.965,180.01z M234.008,59.985H21.993v108.022h212.015V59.985L234.008,59.985z\"><\/path>\r\n            <\/svg>\r\n        \r\n                <\/div>\r\n                <div class=\"ml-3\">\r\n                    <span class=\"block f-z-14\">Entradas a todos los atractivos tur\u00edsticos (no colas ni pagos adicionales).<\/span>\r\n                <\/div>\r\n            <\/li>\r\n        <\/ul>\r\n    <\/div>\r\n    <br>\r\n    <br>\r\n    <br>\r\n    <h2 class=\"section-title m-b-20 text-center\">Estos son los principales atractivos tur\u00edsticos de la regi\u00f3n Cusco<\/h2>\r\n    <p class=\"f-z-16\">Cusco es famoso por Machu Picchu. Sin embargo, en la capital del imperio inca existen much\u00edsimos m\u00e1s destinos tur\u00edsticos, como: Sacsayhuam\u00e1n, Coricancha, el Valle Sagrado de los Incas (Pisac, Ollantaytambo, Chinchero), la Monta\u00f1a 7 Colores y m\u00e1s.<\/p>\r\n    <div class=\"block lg:grid lg:grid-cols-2 lg:gap-x-10 mt-4\">\r\n        <div class=\"card group\">\r\n            <div class=\"card-img sm:w-40 md:w-52 sm:rounded-l\">\r\n                <img decoding=\"async\" class=\"lazy card-img loaded\" alt=\"Coricancha\" data-ll-status=\"loaded\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/coricancha-templo-card.jpg\">\r\n            <\/div>\r\n            <div class=\"card-content\">\r\n                <h3 class=\"card-title text-xl\">El templo inca del Coricancha<\/h3>\r\n                <p class=\"text-sm\">El Coricancha fue el templo religioso m\u00e1s importante de todo el inmenso imperio inca. Es llamado el templo del sol pues all\u00ed se adoraba a esta divinidad, la m\u00e1s importante en el pante\u00f3n inca. Su decoraci\u00f3n fue hecho con l\u00e1minas de oro, por lo que su nombre se traduce como \u2018Templo dorado\u2019, en lengua quechua.<\/p>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/ciudad-cusco\/coricancha\/\" class=\"card-link\" title=\"Coricancha\" target=\"_self\" rel=\"noopener noreferrer\">Coricancha<\/a>\r\n        <\/div>\r\n        <div class=\"card group\">\r\n            <div class=\"card-img sm:w-40 md:w-52 sm:rounded-l\">\r\n                <img decoding=\"async\" class=\"lazy card-img loaded\" alt=\"Monta\u00f1a 7 Colores\" data-ll-status=\"loaded\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/i-montana-siete-colores.jpg\">\r\n            <\/div>\r\n            <div class=\"card-content\">\r\n                <h3 class=\"card-title text-xl\">El Vinicunca, la Monta\u00f1a 7 Colores<\/h3>\r\n                <p class=\"text-sm\">La monta\u00f1a 7 colores, llamado tambi\u00e9n Vinicunca, es el segundo destino tur\u00edstico m\u00e1s visitado del Cusco solo despu\u00e9s de Machu Picchu. Es famoso por su paisaje con laderas y cumbres de variados colores como fucsia, turquesa, lavanda y dorado. Se sit\u00faa por encima de los 5 mil metros de alura, lo que hace su visita todo un reto.<\/p>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/canchis\/montana-7-colores\/\" class=\"card-link\" title=\"Monta\u00f1a 7 Colores\" target=\"_self\" rel=\"noopener noreferrer\">Monta\u00f1a 7 Colores<\/a>\r\n        <\/div>\r\n        <div class=\"card group\">\r\n            <div class=\"card-img sm:w-40 md:w-52 sm:rounded-l\">\r\n                <img decoding=\"async\" class=\"lazy card-img loaded\" alt=\"Valle Sagrado\" data-ll-status=\"loaded\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/i-valle-sagrado.jpg\">\r\n            <\/div>\r\n            <div class=\"card-content\">\r\n                <h3 class=\"card-title text-xl\">El Valle Sagrado de los Incas<\/h3>\r\n                <p class=\"text-sm\">El Valle Sagrado de los Incas es un \u00e1rea tur\u00edstica famosa por sus bellos paisajes verdes, con altas monta\u00f1as, as\u00ed como por sus sitios arqueol\u00f3gicos de origen inca, como: Pisac, Chinchero, Ollantaytambo y Moray. All\u00ed adem\u00e1s est\u00e1n hoteles tur\u00edsticos y restaurantes de gran calidad. Como su nombre indica, fue un \u00e1rea de gran importancia para los incas.<\/p>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/urubamba\/valle-sagrado-incas\/\" class=\"card-link\" title=\"Valle Sagrado\" target=\"_self\" rel=\"noopener noreferrer\">Valle Sagrado<\/a>\r\n        <\/div>\r\n        <div class=\"card group\">\r\n            <div class=\"card-img sm:w-40 md:w-52 sm:rounded-l\">\r\n                <img decoding=\"async\" class=\"lazy card-img loaded\" alt=\"Machu Picchu\" data-ll-status=\"loaded\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/i-machu-picchu.jpg\">\r\n            <\/div>\r\n            <div class=\"card-content\">\r\n                <h3 class=\"card-title text-xl\">Machu Picchu, la ciudadela incaica<\/h3>\r\n                <p class=\"text-sm\">Machu Picchu es una de las maravillas del mundo moderno (seg\u00fan certamen mundial en 2007). Su belleza concuerda con su belleza paisaj\u00edstica (uno de los paisajes m\u00e1s fotografiados), su historia (fue una importante ciudadela inca) as\u00ed como por la misteriosa energ\u00eda que sienten los visitantes al pisar Machu Picchu.<\/p>\r\n            <\/div>\r\n            <a href=\"https:\/\/www.machupicchuterra.com\/es\/cusco\/machu-picchu\" class=\"card-link\" title=\"Machu Picchu\" target=\"_self\" rel=\"noopener noreferrer\">Machu Picchu<\/a>\r\n        <\/div>\r\n    <\/div>\r\n    <br>\r\n    <h2 class=\"section-title mb-6\">Preguntas y respuestas sobre los tours promocionales<\/h2>\r\n    <p class=\"f-z-16\">\u00bfEst\u00e1s interesado en realizar un viaje por Machu Picchu, Cusco y el Per\u00fa? Aprovecha los tours promocionales en Machupicchu Terra y realiza el viaje so\u00f1ado a uno de los mejores destinos del mundo. Conoce las preguntas y respuestas m\u00e1s frecuentes sobre este servicio.<\/p>\r\n    <ul class=\"text-justify\">\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfCu\u00e1les son los tours en oferta?<\/h3>\r\n            <p>Con Machupicchu Terra puedes conocer lo mejor de Cusco y el Per\u00fa con nuestros tours promocionales, como:<\/p>\r\n            <ul>\r\n                <li>Tour Laguna Salinas en Arequipa Medio D\u00eda.<\/li>\r\n                <li>Tour Circuito M\u00e1gico del Agua en Lima medio d\u00eda.<\/li>\r\n                <li>Tour Nado con tortugas en M\u00e1ncora 1 d\u00eda.<\/li>\r\n                <li>Tour Monta\u00f1a de Colores de Palcoyo en Cusco 1 d\u00eda.<\/li>\r\n                <li>Tour Ica, Paracas y Huacachina 1 d\u00eda desde Lima.<\/li>\r\n                <li>Tour Uros, Amantani y Taquile 2 d\u00edas 1 noche.<\/li>\r\n                <li>Tour Valle Sagrado con Machu Picchu 2 d\u00edas + Hotel y Buffet.<\/li>\r\n                <li>Tour Machu Picchu 2 d\u00edas Todo Incluido.<\/li>\r\n                <li>Tour Machupicchu + Monta\u00f1a 7 colores + Laguna Humantay 3 d\u00edas.<\/li>\r\n                <li>City Tour + Valle Sagrado + Machu Picchu 4 D\u00edas VIP.<\/li>\r\n            <\/ul>\r\n        <\/li>\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfHasta cu\u00e1ndo est\u00e1 vigente las promociones de los Tours?<\/h3>\r\n            <p>Las promociones de los tours est\u00e1n disponibles desde el 25 de junio hasta el 15 de julio del 2026. \u00a1Aprovecha!<\/p>\r\n        <\/li>\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfLas reservas del tour se pueden realizar para todo el a\u00f1o?<\/h3>\r\n            <p>S\u00ed, puede realizar reservas para todo el a\u00f1o 2026 (vigente para cualquier fecha del presente a\u00f1o).<\/p>\r\n        <\/li>\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfLas promociones de paquetes tur\u00edsticos tambi\u00e9n est\u00e1 disponible para turistas peruanos?<\/h3>\r\n            <p>S\u00ed, las ofertas est\u00e1n disponibles tanto para turistas peruanos como por turistas extranjeros.<\/p>\r\n        <\/li>\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfPor qu\u00e9 realizar el tour a Machu Picchu?<\/h3>\r\n            <p>El tour Machu Picchu es considerado como el mejor de Cusco y el Per\u00fa. Ofrece recojo desde el hotel, transporte completo en bus y tren tur\u00edstico (servicio Expedition), bus Consettur Aguas Calientes \u2013 Machu Picchu \u2013 Aguas Calientes, entrada Machupicchu circuito 2 y servicio de gu\u00eda tur\u00edstico profesional.<\/p>\r\n        <\/li>\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfPor qu\u00e9 realizar el tour Valle Sagrado VIP?<\/h3>\r\n            <p>El tour Valle Sagrado VIP ofrece la visita a todos los atractivos tur\u00edsticos m\u00e1s importantes del Valle Sagrado como: Chinchero, Moray, Maras, Ollantaytambo y Pisac. El tour adem\u00e1s ofrece almuerzo buffet en el prestigioso restaurante Tunupa, uno de los mejores de todo el Cusco.<\/p>\r\n        <\/li>\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfC\u00f3mo realizo la compra de los tours promocionales?<\/h3>\r\n            <p>Para realizar la compra de uno de los tours promocionales se debe hacer clic en la opci\u00f3n \u2018reservar\u2019 en nuestra p\u00e1gina web. La compra es online mediante cualquier tarjeta: Visa, MasterCard, American Express, Diners Club.<\/p>\r\n        <\/li>\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfC\u00f3mo comunicarme para m\u00e1s informaci\u00f3n sobre las ofertas en los paquetes tur\u00edsticos?<\/h3>\r\n            <p>\u00bfBuscas ofertas para viajar a Cusco? Comun\u00edcate con Machupicchu Terra a los tel\u00e9fonos de WhatsApp (+51) 982 108 083 y al (+51) 994 349 441.<\/p>\r\n        <\/li>\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfHay disponibilidad vigente para visitar Machu Picchu?<\/h3>\r\n            <p>Machu Picchu posee disponibilidad limitada. Por lo tanto, se recomienda realizar la compra del tour con anticipaci\u00f3n de 2 \u00f3 3 meses. De lo contrario, se corre el riesgo de no encontrar disponibilidad.<\/p>\r\n        <\/li>\r\n        <li>\r\n            <h3 class=\"text-lg\">\u00bfC\u00f3mo es el clima en Cusco?<\/h3>\r\n            <p>Cusco posee un clima templado con d\u00edas soleadas y noches fr\u00edas. La temperatura m\u00e1xima en el d\u00eda puede alcanzar los 22\u00baC. La temperatura m\u00ednima por las noches puede descender hasta los 0\u00baC. Las lluvias son m\u00e1s intensas en enero, febrero y marzo.<\/p>\r\n        <\/li>\r\n    <\/ul>\r\n    <br>\r\n    <h2 class=\"section-title mb-6\">Disfruta de las mejores experiencias en Cusco<\/h2>\r\n    <p class=\"f-z-16\">Contamos con diversas p\u00e1ginas aliadas que nos permiten ofrecerte las mejores experiencias en tours y servicios. Gracias a nuestra red de colaboradores, podemos brindarte opciones exclusivas y personalizadas, adaptadas a tus intereses y necesidades.<\/p>\r\n    <div class=\"wrapper-4\">\r\n        <div class=\"card flex-col group\">\r\n            <div class=\"card-img\"><img decoding=\"async\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/tourmachupicchu.jpg\" class=\"card-img\" alt=\"Machu Picchu\"><\/div>\r\n            <div class=\"p-5\">\r\n                <h3 class=\"font-bold\">Tu Aventura a Machu Picchu Comienza Aqu\u00ed <\/h3>\r\n                <p class=\"f-z-14 text-left mb-0\">Encuentra los mejores tours y paquetes para visitar la maravilla inca con total comodidad y seguridad. Encuentra opciones de viaje en tren, caminatas guiadas y recorridos exclusivos para descubrir este destino m\u00e1gico.<\/p> <a href=\"https:\/\/tourmachupicchu.com\/\" target=\"_blank\" class=\"card-link\" rel=\"noopener\">ver m\u00e1s<\/a>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"card flex-col group\">\r\n            <div class=\"card-img\"><img decoding=\"async\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/tour-7-colores.jpg\" class=\"card-img\" alt=\"Monta\u00f1a 7 Colores\"><\/div>\r\n            <div class=\"p-5\">\r\n                <h3 class=\"font-bold\">Conquista la incre\u00edble Monta\u00f1a de 7 Colores<\/h3>\r\n                <p class=\"f-z-14 text-left\">Disfruta de una excursi\u00f3n inolvidable a Vinicunca, un para\u00edso natural de colores vibrantes en los Andes de Cusco. Conoce las mejores rutas, recomendaciones y servicios de gu\u00eda para una experiencia incre\u00edble.<\/p> <a href=\"https:\/\/www.tour7colores.com\/\" target=\"_blank\" class=\"card-link\" rel=\"noopener\">ver m\u00e1s<\/a>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"card flex-col group\">\r\n            <div class=\"card-img\"><img decoding=\"async\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/guiamachupicchu.jpg\" class=\"card-img\" alt=\"Guia Machupicchu\"><\/div>\r\n            <div class=\"p-5\">\r\n                <h3 class=\"font-bold\">Planifica tu recorrido por Machu Picchu con nosotros<\/h3>\r\n                <p class=\"f-z-14 text-left\">Explora Machu Picchu de la mano de nuestros gu\u00edas expertos, quienes te llevar\u00e1n a conocer la fascinante historia, los secretos ocultos y los rincones m\u00e1s impresionantes de esta maravilla.<\/p> <a href=\"https:\/\/www.guiamachupicchu.com\/\" target=\"_blank\" class=\"card-link\" rel=\"noopener\">ver m\u00e1s<\/a>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"wrapper-4\">\r\n        <div class=\"card flex-col group\">\r\n            <div class=\"card-img\"><img decoding=\"async\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/sacred-valley.jpg\" class=\"card-img\"><\/div>\r\n            <div class=\"p-5\">\r\n                <h3 class=\"font-bold\">Descubre los secretos del Valle Sagrado de los incas<\/h3>\r\n                <p class=\"f-z-14 text-left\">Ad\u00e9ntrate en el coraz\u00f3n de Cusco con un tour por el Valle Sagrado de los Incas. Explora templos, complejos arqueol\u00f3gicos, mercados tradicionales y paisajes encantadores, mientras nuestros expertos gu\u00edas te revelan la historia y los secretos de este lugar sagrado.<\/p>\r\n                <a href=\"https:\/\/thesacredvalley.com\/es\/\" target=\"_blank\" class=\"card-link\" rel=\"noopener\">ver m\u00e1s<\/a>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"card flex-col group\">\r\n            <div class=\"card-img\"><img decoding=\"async\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/railmachupicchu.jpg\" class=\"card-img\"><\/div>\r\n            <div class=\"p-5\">\r\n                <h3 class=\"font-bold\">Viaja en primera clase hacia Machu Picchu<\/h3>\r\n                <p class=\"f-z-14 text-left\">Disfruta de una traves\u00eda en tren que fusiona comodidad, tradici\u00f3n y aventura. Reserva tu tour completo y experimenta el placer de recorrer los impresionantes paisajes andinos llev\u00e1ndote directamente a la puerta de la ciudadela hist\u00f3rica de Machu Picchu.<\/p> <a href=\"https:\/\/railmachupicchu.com\/es\/\" target=\"_blank\" class=\"card-link\" rel=\"noopener\">ver m\u00e1s<\/a>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"card flex-col group\">\r\n            <div class=\"card-img\"><img decoding=\"async\" src=\"https:\/\/www.machupicchuterra.com\/wp-content\/uploads\/entrada-inti-raymi-v2.jpg\" class=\"card-img\" alt=\"Inti Raymi\"><\/div>\r\n            <div class=\"p-5\">\r\n                <h3 class=\"font-bold\">Vive la fiesta del Inti Raymi en Primera Fila<\/h3>\r\n                <p class=\"f-z-14 text-left\">Compra tus boletos y descubre todo sobre la majestuosa fiesta del Sol en Cusco. Sum\u00e9rgete en la cultura inca y disfruta de una experiencia \u00fanica con desfiles, rituales ancestrales y un escenario impresionante en Sacsayhuam\u00e1n.<\/p>\r\n                <a href=\"https:\/\/www.entradaintiraymi.com\/\" target=\"_blank\" class=\"card-link\" rel=\"noopener\">ver m\u00e1s<\/a>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <br>\r\n<\/div>","protected":false},"excerpt":{"rendered":"Paquetes tur\u00edsticos en promoci\u00f3n Descubre todos nuestros paquetes tur\u00edsticos en los principales tours por Machu Picchu, Cusco y el Per\u00fa. Disfruta del tour al Valle Sagrado de los Incas, el tour a la laguna Humantay, la Monta\u00f1a de los 7 Colores y Machu Picchu. Adem\u00e1s, vive la experiencia del tour a la isla de Uros, [&hellip;]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-banner-video.php","meta":{"footnotes":""},"class_list":["post-17332","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.machupicchuterra.com\/es\/wp-json\/wp\/v2\/pages\/17332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.machupicchuterra.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.machupicchuterra.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.machupicchuterra.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.machupicchuterra.com\/es\/wp-json\/wp\/v2\/comments?post=17332"}],"version-history":[{"count":25,"href":"https:\/\/www.machupicchuterra.com\/es\/wp-json\/wp\/v2\/pages\/17332\/revisions"}],"predecessor-version":[{"id":19199,"href":"https:\/\/www.machupicchuterra.com\/es\/wp-json\/wp\/v2\/pages\/17332\/revisions\/19199"}],"wp:attachment":[{"href":"https:\/\/www.machupicchuterra.com\/es\/wp-json\/wp\/v2\/media?parent=17332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}